{"id":1473084,"date":"2026-04-12T17:03:48","date_gmt":"2026-04-13T00:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/"},"modified":"2026-04-12T17:03:48","modified_gmt":"2026-04-13T00:03:48","slug":"mapa-resultados-primera-vuelta-elecciones-peru-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","title":{"rendered":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato"},"content":{"rendered":"<p>Los peruanos acudieron a las urnas este 12 de abril para elegir presidente en una jornada que marcar\u00e1 el rumbo pol\u00edtico y econ\u00f3mico del pa\u00eds en los pr\u00f3ximos a\u00f1os.<\/p>\n<p>En medio de un escenario de alta fragmentaci\u00f3n y descontento ciudadano, los votantes decidieron entre diversas propuestas que buscaban responder a desaf\u00edos persistentes como la estabilidad institucional, la seguridad y la recuperaci\u00f3n econ\u00f3mica.<\/p>\n<p>Tras el cierre de urnas, consulta aqu\u00ed los candidatos que lideran el conteo de votos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los peruanos acudieron a las urnas este 12 de abril para elegir presidente en una jornada que marcar\u00e1 el rumbo pol\u00edtico y econ\u00f3mico del pa\u00eds en los pr\u00f3ximos a\u00f1os. En medio de un escenario de alta fragmentaci\u00f3n y descontento ciudadano, los votantes decidieron entre diversas propuestas que buscaban responder a desaf\u00edos persistentes como la estabilidad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473084","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los peruanos acudieron a las urnas este 12 de abril para elegir presidente en una jornada que marcar\u00e1 el rumbo pol\u00edtico y econ\u00f3mico del pa\u00eds en los pr\u00f3ximos a\u00f1os. En medio de un escenario de alta fragmentaci\u00f3n y descontento ciudadano, los votantes decidieron entre diversas propuestas que buscaban responder a desaf\u00edos persistentes como la estabilidad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T00:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato\",\"datePublished\":\"2026-04-13T00:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/\"},\"wordCount\":119,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/\",\"name\":\"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-13T00:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato - Noticias","og_description":"Los peruanos acudieron a las urnas este 12 de abril para elegir presidente en una jornada que marcar\u00e1 el rumbo pol\u00edtico y econ\u00f3mico del pa\u00eds en los pr\u00f3ximos a\u00f1os. En medio de un escenario de alta fragmentaci\u00f3n y descontento ciudadano, los votantes decidieron entre diversas propuestas que buscaban responder a desaf\u00edos persistentes como la estabilidad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-13T00:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/"},"author":{"name":"","@id":""},"headline":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato","datePublished":"2026-04-13T00:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/"},"wordCount":119,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","name":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-13T00:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato","url":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-13T00:03:48Z","datePublished":"2026-04-13T00:03:48Z","dateModified":"2026-04-13T00:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\\u00fa 2026: d\\u00f3nde gana cada candidato\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/12\\\/mapa-resultados-primera-vuelta-elecciones-peru-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/12\\\/mapa-resultados-primera-vuelta-elecciones-peru-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-13T00:03:48Z\",\"datePublished\":\"2026-04-13T00:03:48Z\",\"dateModified\":\"2026-04-13T00:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471807,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/03\/cuando-cierran-urnas-primarias-ee-uu-trax\/","url_meta":{"origin":1473084,"position":0},"title":"\u00bfCu\u00e1ndo cierran las urnas y cu\u00e1ndo deber\u00edamos esperar los resultados de las primarias en EE.UU.?","author":"","date":"marzo 3, 2026","format":false,"excerpt":"Comenzaremos a ver los primeros votos de las cruciales primarias de Texas a las 8:00 p.m. hora de Miami, cuando cierran las urnas en la mayor parte del estado.Sin embargo, el extremo occidental de Texas, incluyendo El Paso, est\u00e1 en una zona horaria diferente, por lo que all\u00ed las urnas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455535,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/03\/asi-se-desarrollara-la-noche-electoral-hora-a-hora-trax\/","url_meta":{"origin":1473084,"position":1},"title":"As\u00ed se desarrollar\u00e1 la noche electoral hora a hora","author":"","date":"noviembre 3, 2024","format":false,"excerpt":"(CNN) -- La noche de las elecciones en Estados Unidos se desarrollar\u00e1 siguiendo el sol y las horas de cierre de las urnas de este a oeste, en t\u00e9rminos generales.CNN proyecta qui\u00e9nes ganar\u00e1n las carreras a medida que haya datos disponibles.Si bien algunos estados no competitivos podr\u00edan proyectarse poco despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473081,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/12\/elecciones-hungria-viktor-orban-trax\/","url_meta":{"origin":1473084,"position":2},"title":"Hungr\u00eda cerr\u00f3 una elecci\u00f3n clave con participaci\u00f3n r\u00e9cord","author":"","date":"abril 12, 2026","format":false,"excerpt":"Las urnas cerraron este domingo en Hungr\u00eda tras una re\u00f1ida elecci\u00f3n parlamentaria marcada por la mayor participaci\u00f3n desde la ca\u00edda del comunismo en el pa\u00eds.Seg\u00fan la Oficina Electoral Nacional, casi el 78 % de los votantes habilitados ya hab\u00eda participado en la elecci\u00f3n hasta las 6:30 p.m., hora local, poco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455565,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/04\/cuando-cierran-urnas-contaran-boletas-trax\/","url_meta":{"origin":1473084,"position":3},"title":"\u00bfCu\u00e1ndo cierran las urnas en los estados clave y cu\u00e1ndo se contar\u00e1n las boletas?","author":"","date":"noviembre 4, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Millones de estadounidenses votaron de forma anticipada, ya sea de forma presencial o por correo, y millones m\u00e1s lo har\u00e1n el d\u00eda de las elecciones. A la hora del recuento de votos, cada estado tiene un proceso y un conjunto de reglas diferentes.Aqu\u00ed se explica cu\u00e1ndo cerrar\u00e1n las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450872,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/07\/04\/votantes-reino-unido-urnas-reino-unido-trax\/","url_meta":{"origin":1473084,"position":4},"title":"Los votantes de Reino Unido acuden a las urnas para una elecci\u00f3n trascendental","author":"","date":"julio 4, 2024","format":false,"excerpt":"Londres (CNN) --\u00a0Los votantes brit\u00e1nicos acudir\u00e1n a las urnas este jueves para una elecci\u00f3n general crucial que se considera un refer\u00e9ndum sobre 14 a\u00f1os de gobierno conservador.La votaci\u00f3n anticipada, convocada por el primer ministro Rishi Sunak, se est\u00e1 celebrando meses antes de lo necesario y tom\u00f3 por sorpresa a gran\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460404,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/25\/peru-dina-boluarte-convoca-elecciones-generales-orix\/","url_meta":{"origin":1473084,"position":5},"title":"Presidenta Dina Boluarte convoca a elecciones generales en Per\u00fa","author":"","date":"marzo 25, 2025","format":false,"excerpt":"La presidenta de Per\u00fa, Dina Boluarte, convoc\u00f3 este martes a elecciones generales para el 12 de abril del 2026, \u201ca fin de que podamos elegir democr\u00e1ticamente en las urnas a nuestro pr\u00f3ximo presidente o pr\u00f3xima presidenta\u201d.Seg\u00fan el cronograma del Jurado Nacional de Elecciones, Boluarte ten\u00eda plazo hasta el 12 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1473084"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473084\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1473084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1473084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1473084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}