{"id":1473091,"date":"2026-04-13T02:03:44","date_gmt":"2026-04-13T09:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/"},"modified":"2026-04-13T02:03:44","modified_gmt":"2026-04-13T09:03:44","slug":"lynette-hooker-desaparecida-bahamas-hechos-clave-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/","title":{"rendered":"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave"},"content":{"rendered":"<p>Ha pasado m\u00e1s de una semana desde que Lynette Hooker, una madre y marinera de 55 a\u00f1os, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/11\/eeuu\/madre-sigue-desaparecida-mientras-marido-permanece-detenido-trax\">desapareci\u00f3 en el mar en las Bahamas<\/a>, lo que desencaden\u00f3 una b\u00fasqueda urgente que desde entonces se ha transformado en una investigaci\u00f3n compleja con una persona en el centro: su esposo desde hace 25 a\u00f1os.<\/p>\n<p>Brian Hooker, de 58 a\u00f1os, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/10\/mundo\/hija-relacion-mujer-marido-bahamas-trax\">fue detenido<\/a> por la Fuerza Policial Real de las Bahamas el mi\u00e9rcoles en relaci\u00f3n con su desaparici\u00f3n y permanece bajo custodia despu\u00e9s de que se concediera una pr\u00f3rroga hasta la noche de este lunes, confirm\u00f3 a CNN su abogado.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/08\/eeuu\/claves-rescate-mujer-estadounidense-mar-bahamas-trax\">Brian Hooker<\/a> no ha sido acusado formalmente, y su abogado dice que \u201cniega categ\u00f3rica e inequ\u00edvocamente cualquier irregularidad\u201d.<\/p>\n<p>Lo que ocurra a continuaci\u00f3n sigue siendo incierto. La Polic\u00eda solicit\u00f3 otra entrevista con Hooker este lunes, dijo su abogado a CNN. Para la noche, las autoridades podr\u00edan optar por liberarlo o acusarlo formalmente. A\u00fan no est\u00e1 claro si podr\u00eda permanecer detenido por m\u00e1s tiempo conforme a la ley bahame\u00f1a.<\/p>\n<p>Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave:<\/p>\n<p><strong>Desaparici\u00f3n en el mar:<\/strong> D\u00edas despu\u00e9s de su \u00faltima publicaci\u00f3n en redes sociales, Lynette Hooker y su esposo, Brian Hooker, viajan en un bote auxiliar de 2,4 metros con fondo r\u00edgido cerca de Elbow Cay mientras regresan a su velero, \u201cSoulmate\u201d, seg\u00fan el relato de Brian Hooker a la Polic\u00eda.<\/p>\n<p>Les dijo a las autoridades que las condiciones adversas \u2014incluidos fuertes vientos y oleaje\u2014 hicieron que su esposa cayera por la borda.<\/p>\n<p>\u201cLas fuertes corrientes posteriormente se la llevaron\u201d y \u201c\u00e9l la perdi\u00f3 de vista\u201d, dicen que Brian Hooker les cont\u00f3 a los polic\u00edas. Lynette Hooker llevaba las llaves, tambi\u00e9n conocidas como el cord\u00f3n de seguridad del motor: un cable dise\u00f1ado para cortar la energ\u00eda si el operador cae por la borda, seg\u00fan su relato compartido por la Polic\u00eda.<\/p>\n<p>\u00c9l dice que la \u00faltima vez que vio a su esposa, ella estaba nadando hacia la orilla, seg\u00fan Richard Cook, jefe del equipo de bomberos de Hope Town Volunteer Fire and Rescue.<\/p>\n<p><strong>Aviso a las autoridades y comienza la b\u00fasqueda:<\/strong> Sin energ\u00eda en el bote auxiliar, Brian Hooker intenta remar hasta la orilla y la peque\u00f1a embarcaci\u00f3n finalmente se aleja a la deriva, y horas despu\u00e9s aparece varada cerca de Marsh Harbour, seg\u00fan su relato compartido por la Polic\u00eda.<\/p>\n<p>Finalmente se abre paso entre la maleza hasta llegar a un astillero, donde contacta a la Polic\u00eda, seg\u00fan Cook.<\/p>\n<p>Las autoridades bahame\u00f1as y los equipos locales de bomberos y rescate inician una b\u00fasqueda por mar. M\u00e1s tarde, la Guardia Costera de Estados Unidos se suma con recursos a\u00e9reos.<\/p>\n<p><strong>Notifican a la familia:<\/strong> Karli Aylesworth, hija de Lynette Hooker, dijo a CNN que su padrastro la llama el domingo por la noche \u201calrededor de las 8:00 p.m. a las 8:30 p.m.\u201d y le dice que su madre est\u00e1 desaparecida.<\/p>\n<p>\u201c\u00c9l dijo\u2026 como si fuera algo normal: \u2018Oye, tu mam\u00e1 est\u00e1 desaparecida. No sabemos d\u00f3nde est\u00e1. Est\u00e1 desaparecida desde anoche, pero vamos a ir para all\u00e1 pronto para verte\u2019\u201d, cont\u00f3 Aylesworth a CNN.<\/p>\n<p>Aylesworth dijo que estaba asimilando lo que \u00e9l dijo y sinti\u00f3 como si \u201cme hubiera soltado una bomba\u201d, y luego \u00e9l empez\u00f3 a hablar de nuevo antes de terminar la llamada de repente. \u201cY yo solo pensaba: \u2018OK, \u00bfqu\u00e9?\u2019 \u00bfC\u00f3mo se te pierde mi mam\u00e1 as\u00ed?\u201d<\/p>\n<p><strong>Mensaje de voz sobre un dispositivo de flotaci\u00f3n:<\/strong> Aylesworth le dice a CNN el martes que Brian Hooker le dej\u00f3 un mensaje de voz diciendo que las autoridades encontraron un dispositivo de flotaci\u00f3n que, seg\u00fan \u00e9l, le hab\u00eda arrojado a su esposa.<\/p>\n<p>\u201cHola, cari\u00f1o, acabo de recibir una llamada de Hope Town Search and Rescue, y han encontrado un dispositivo de flotaci\u00f3n que le tir\u00e9 a mam\u00e1 cuando cay\u00f3 por la borda\u201d, dice Brian Hooker en el mensaje de voz compartido con CNN. \u201cA\u00fan no la han encontrado, pero ahora pueden concentrar todos sus esfuerzos en un \u00e1rea m\u00e1s peque\u00f1a\u201d.<\/p>\n<p><strong>La b\u00fasqueda pasa a recuperaci\u00f3n:<\/strong> Tras d\u00edas sin localizarla, los funcionarios confirman el martes que el operativo pas\u00f3 de un rescate activo a una misi\u00f3n de recuperaci\u00f3n.<\/p>\n<p><strong>Detienen al esposo:<\/strong> La Polic\u00eda bahame\u00f1a detiene a Brian Hooker para interrogarlo. Un funcionario de la Fuerza Policial Real de las Bahamas dijo a Reuters que la detenci\u00f3n se basa en \u201calguna causa probable\u201d. Las autoridades anuncian que no hay cargos. El abogado de Hooker dice que \u00e9l \u201cniega categ\u00f3rica e inequ\u00edvocamente cualquier irregularidad\u201d.<\/p>\n<p>Antes de su arresto el mi\u00e9rcoles, Brian Hooker describe el incidente en un comunicado a CNN como un accidente n\u00e1utico ocurrido en condiciones que se deterioraban r\u00e1pidamente.<\/p>\n<p>\u201cEstoy destrozado por el reciente accidente de barco en mares impredecibles y fuertes vientos que hicieron que mi amada Lynette cayera de nuestro peque\u00f1o bote auxiliar\u201d, dijo Brian Hooker en un comunicado. \u201cA pesar de los intentos desesperados por alcanzarla, los vientos y las corrientes nos separaron cada vez m\u00e1s. Seguimos busc\u00e1ndola y ese es mi \u00fanico enfoque\u201d.<\/p>\n<p><strong>Se confirma una investigaci\u00f3n penal en EE.UU.:<\/strong> La Guardia Costera dice que abri\u00f3 una investigaci\u00f3n penal sobre el caso. Ese mismo d\u00eda, la agencia entrevista a Aylesworth durante dos horas, seg\u00fan su abogado. El Departamento de Estado de EE.UU. dice que est\u00e1 al tanto de los reportes sobre una estadounidense desaparecida cerca de Elbow Cay y que est\u00e1 brindando asistencia consular mientras trabaja con funcionarios bahame\u00f1os.<\/p>\n<p><strong>Salen a la luz acusaciones previas de violencia dom\u00e9stica:<\/strong> La hija de Lynette Hooker, en una entrevista con CNN, plantea <a href=\"https:\/\/www.cnn.com\/2026\/04\/09\/us\/lynette-hooker-bahamas-husband-arrest-hnk\">acusaciones de abuso<\/a>. La pareja se preocupa el uno por el otro, dice, pero han tenido un matrimonio turbulento que en ocasiones se ha vuelto violento. Aylesworth dice que su madre le confi\u00f3 anteriormente que Brian Hooker <a href=\"https:\/\/www.cnn.com\/2026\/04\/09\/us\/lynette-hooker-bahamas-husband-arrest-hnk\">la estrangul\u00f3<\/a>.<\/p>\n<p>CNN no ha podido confirmar el incidente con las fuerzas del orden.<\/p>\n<p>En 2015, Lynette Hooker fue <a href=\"https:\/\/www.cnn.com\/2026\/04\/11\/us\/lynette-hooker-brian-bahamas-investigation\">detenida en Michigan<\/a> bajo sospecha de \u201cagresi\u00f3n y lesiones\/agresi\u00f3n simple\u201d, seg\u00fan un informe policial de Kentwood. Brian Hooker le dijo a un agente que hab\u00eda sido agredido por su esposa, quien lo golpe\u00f3 varias veces, seg\u00fan el informe, que se\u00f1ala que fue encontrado con la nariz hinchada y ensangrentada.<\/p>\n<p>Lynette Hooker, a quien un agente describi\u00f3 como \u201caltamente intoxicada\u201d, tambi\u00e9n dijo a la Polic\u00eda que hab\u00eda sido \u201cgolpeada en la frente por su esposo Brian\u201d, aunque no se documentaron lesiones visibles en ella.<\/p>\n<p>Un fiscal revis\u00f3 el caso y determin\u00f3 que hab\u00eda \u201cpruebas insuficientes sobre qui\u00e9n inici\u00f3 la agresi\u00f3n\u201d, seg\u00fan el informe policial. El caso fue desestimado sin que se presentaran cargos.<\/p>\n<p><strong>Segunda ronda de interrogatorios:<\/strong> Brian Hooker vuelve a ser interrogado por los investigadores. Butler, su abogado, le dice a CNN que la Polic\u00eda se centr\u00f3 en la vida personal de la pareja y no pregunt\u00f3 sobre pruebas del bote ni de dispositivos electr\u00f3nicos.<\/p>\n<p>\u201cEstaba abrumado, estaba alterado, y segu\u00eda reiterando: \u2018Necesito saber qu\u00e9 est\u00e1 pasando con la b\u00fasqueda de mi esposa\u2019\u201d, dice Butler el viernes.<\/p>\n<p>Un magistrado aprueba una pr\u00f3rroga que permite a la Polic\u00eda seguir reteniendo a Brian Hooker hasta la noche de este lunes conforme a la ley bahame\u00f1a, seg\u00fan su abogado. No ha sido acusado.<\/p>\n<p>Seg\u00fan la ley bahame\u00f1a, un magistrado puede autorizar hasta 72 horas adicionales de detenci\u00f3n si los investigadores necesitan m\u00e1s tiempo para reunir o preservar pruebas, evitar interferencias o avanzar la investigaci\u00f3n.<\/p>\n<p>Butler ha rechazado la creciente especulaci\u00f3n p\u00fablica, argumentando que, sin encontrar a Lynette Hooker, sacar conclusiones sobre un posible delito es prematuro, dijo el viernes.<\/p>\n<p>En un comunicado emitido m\u00e1s temprano ese d\u00eda, Butler dijo que su cliente \u201cparece completamente desconsolado y profundamente angustiado\u201d, y que el trauma por la desaparici\u00f3n de su esposa y su detenci\u00f3n como sospechoso lo han dejado en un \u201cestado extremadamente fr\u00e1gil\u201d.<\/p>\n<p>Brian Hooker sigue bajo custodia y sin cargos. Lynette Hooker no ha sido encontrada. Las autoridades bahame\u00f1as dicen que la investigaci\u00f3n sigue activa, con una investigaci\u00f3n penal paralela de la Guardia Costera de Estados Unidos en curso.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha pasado m\u00e1s de una semana desde que Lynette Hooker, una madre y marinera de 55 a\u00f1os, desapareci\u00f3 en el mar en las Bahamas, lo que desencaden\u00f3 una b\u00fasqueda urgente que desde entonces se ha transformado en una investigaci\u00f3n compleja con una persona en el centro: su esposo desde hace 25 a\u00f1os. Brian Hooker, de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473091","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ha pasado m\u00e1s de una semana desde que Lynette Hooker, una madre y marinera de 55 a\u00f1os, desapareci\u00f3 en el mar en las Bahamas, lo que desencaden\u00f3 una b\u00fasqueda urgente que desde entonces se ha transformado en una investigaci\u00f3n compleja con una persona en el centro: su esposo desde hace 25 a\u00f1os. Brian Hooker, de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T09:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave\",\"datePublished\":\"2026-04-13T09:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/\"},\"wordCount\":1452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/\",\"name\":\"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-13T09:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave - Noticias","og_description":"Ha pasado m\u00e1s de una semana desde que Lynette Hooker, una madre y marinera de 55 a\u00f1os, desapareci\u00f3 en el mar en las Bahamas, lo que desencaden\u00f3 una b\u00fasqueda urgente que desde entonces se ha transformado en una investigaci\u00f3n compleja con una persona en el centro: su esposo desde hace 25 a\u00f1os. Brian Hooker, de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-13T09:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/"},"author":{"name":"","@id":""},"headline":"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave","datePublished":"2026-04-13T09:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/"},"wordCount":1452,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/","name":"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-13T09:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Lynette Hooker desapareci\u00f3 en las Bahamas hace m\u00e1s de una semana. Aqu\u00ed tienes una cronolog\u00eda de los acontecimientos clave","url":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/13\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-13T09:03:44Z","datePublished":"2026-04-13T09:03:44Z","dateModified":"2026-04-13T09:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Lynette Hooker desapareci\\u00f3 en las Bahamas hace m\\u00e1s de una semana. Aqu\\u00ed tienes una cronolog\\u00eda de los acontecimientos clave\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/13\\\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/13\\\/lynette-hooker-desaparecida-bahamas-hechos-clave-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-13T09:03:44Z\",\"datePublished\":\"2026-04-13T09:03:44Z\",\"dateModified\":\"2026-04-13T09:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473050,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/11\/madre-sigue-desaparecida-mientras-marido-permanece-detenido-trax\/","url_meta":{"origin":1473091,"position":0},"title":"Seis d\u00edas despu\u00e9s, una madre, marinera y amante del mar sigue desaparecida, mientras su marido permanece detenido","author":"","date":"abril 11, 2026","format":false,"excerpt":"Ha pasado casi una semana desde que Lynette Hooker desapareci\u00f3 en el mar y su esposo, con quien estuvo casada durante 25 a\u00f1os, ha pasado los \u00faltimos d\u00edas detenido en las Bahamas, donde ha sido interrogado en relaci\u00f3n con el caso.Desde el principio, Brian Hooker se ha mantenido fiel a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473013,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/09\/claves-rescate-mujer-estadounidense-mar-bahamas-trax\/","url_meta":{"origin":1473091,"position":1},"title":"El arresto del esposo de una mujer estadounidense desaparecida en las Bahamas pone su versi\u00f3n bajo escrutinio","author":"","date":"abril 9, 2026","format":false,"excerpt":"El arresto de un hombre de Estados Unidos cuya esposa lleva cinco d\u00edas desaparecida en las Bahamas ha puesto bajo mayor escrutinio su relato de que ella cay\u00f3 de su bote auxiliar y fue arrastrada por aguas agitadas.Brian Hooker fue arrestado el mi\u00e9rcoles por la Real Fuerza de Polic\u00eda de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473034,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/10\/hija-relacion-mujer-marido-bahamas-trax\/","url_meta":{"origin":1473091,"position":2},"title":"La hija de la mujer estadounidense desaparecida en las Bahamas arroja nueva luz sobre la relaci\u00f3n de su madre con su marido","author":"","date":"abril 10, 2026","format":false,"excerpt":"Mientras los investigadores buscan respuestas sobre la desaparici\u00f3n de una mujer estadounidense en las Bahamas \u2014el esposo afirma que cay\u00f3 por la borda mientras viajaban en una lancha auxiliar\u2014, su familia comparti\u00f3 detalles sobre la relaci\u00f3n de la pareja e intenta dar sentido a lo sucedido.\u201cSolo quiero saber la verdad.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472957,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/08\/claves-rescate-mujer-estadounidense-cayo-borda-bahamas-trax\/","url_meta":{"origin":1473091,"position":3},"title":"Claves sobre la misi\u00f3n de rescate de la mujer estadounidense que, seg\u00fan los informes, cay\u00f3 por la borda en las Bahamas","author":"","date":"abril 8, 2026","format":false,"excerpt":"Las autoridades de las Bahamas han puesto en marcha una operaci\u00f3n de rescate en relaci\u00f3n con la b\u00fasqueda de una mujer estadounidense que, seg\u00fan los informes, cay\u00f3 por la borda durante un paseo en barco con su marido el s\u00e1bado por la noche, inform\u00f3 la polic\u00eda local.Lynette Hooker, de 55\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452374,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/02\/james-darren-actor-gidget-y-tj-hooker-muere-a-los-88-anos-informa-variety-trax\/","url_meta":{"origin":1473091,"position":4},"title":"James Darren, actor de &#8216;Gidget&#8217; y &#8216;TJ Hooker&#8217;, muere a los 88 a\u00f1os, informa Variety","author":"","date":"septiembre 2, 2024","format":false,"excerpt":"(CNN)\u00a0 \u2014 James Darren, actor, director y cantante que tuvo su papel destacado de Moondoggie en la pel\u00edcula de 1959 \u201cGidget\u201d, muri\u00f3 este\u00a0 lunes a los 88 a\u00f1os, inform\u00f3 Variety.El artista muri\u00f3 en el hospital Cedars-Sinai de Los \u00c1ngeles, seg\u00fan Variety, citando a su hijo Jim Moret, corresponsal jefe de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450679,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/25\/desaparece-estadounidense-taylor-casey-bahamas-retiro-yoga-trax\/","url_meta":{"origin":1473091,"position":5},"title":"Desaparece una estadounidense en las Bahamas tras viajar a un retiro de yoga, seg\u00fan su familia","author":"","date":"junio 25, 2024","format":false,"excerpt":"(CNN) -- La familia de una mujer de Chicago desaparecida en las Bahamas dice estar \"profundamente preocupada\" por la seguridad de la mujer, de 41 a\u00f1os, que hab\u00eda viajado a las islas para asistir a un retiro de yoga.La mujer, Taylor Casey, fue vista por \u00faltima vez el 19 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1473091"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473091\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1473091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1473091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1473091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}