{"id":1473128,"date":"2026-04-14T05:03:39","date_gmt":"2026-04-14T12:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/"},"modified":"2026-04-14T05:03:39","modified_gmt":"2026-04-14T12:03:39","slug":"nuevo-juicio-muerte-diego-maradona-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/","title":{"rendered":"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo"},"content":{"rendered":"<p>No es un d\u00e9j\u00e0 vu. Es la evidencia de una deuda judicial <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/05\/30\/argentina\/cronologia-escandalo-anulacion-juicio-muerte-diego-maradona-orix\">que todav\u00eda no se sald\u00f3<\/a>. \u201cEmpieza el juicio por la muerte de Diego Maradona\u201d fue el titular que acapar\u00f3 la atenci\u00f3n de los medios del mundo hace un a\u00f1o. Y ahora vuelve a escribirse. Este martes, en los Tribunales de la provincia de Buenos Aires, inicia un nuevo juicio. Desde cero, la justicia intentar\u00e1 no solo esclarecer los \u00faltimos d\u00edas del \u00eddolo del f\u00fatbol argentino, sino tambi\u00e9n determinar qui\u00e9nes deben asumir responsabilidades por su muerte.<\/p>\n<p>Maradona <a href=\"https:\/\/cnnespanol.cnn.com\/2020\/11\/25\/muere-diego-armando-maradona-el-mundo-pierde-a-una-leyenda-del-futbol-mundial\">muri\u00f3 el 25 de noviembre de 2020 <\/a>por una falla card\u00edaca, durante la internaci\u00f3n domiciliaria en su casa de un barrio privado bonaerense, dos semanas despu\u00e9s de haber sido sometido a una intervenci\u00f3n quir\u00fargica por un hematoma subdural en el cerebro. \u201cEsperamos que el Tribunal est\u00e9 a la altura, que entienda la gravedad del hecho que se investig\u00f3, de lo que tienen que juzgar y, sobre todo, lo que represent\u00f3 Diego para los argentinos y para el mundo del f\u00fatbol\u201d, dijo Mario Baudry, el abogado de Diego Fernando Maradona, el menor de sus hijos. La muerte de Maradona gener\u00f3 conmoci\u00f3n internacional y<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/11\/argentina\/comenzo-juicio-muerte-diego-maradona-orix\"> miles de hinchas se movilizaron en Argentina<\/a> y en distintas partes del mundo pidiendo justicia, incluso lo hicieron afuera de los Tribunales en el primer juicio, con banderas, camisetas, c\u00e1nticos y carteles que clamaban \u201cJusticia por D10S\u201d.<\/p>\n<p>Diego Maradona fue uno de los futbolistas m\u00e1s influyentes y carism\u00e1ticos de la historia, cuya carrera trascendi\u00f3 fronteras. Nacido en el seno de una familia humilde en Buenos Aires, alcanz\u00f3 la cima del deporte con una habilidad extraordinaria y una fuerte personalidad dentro y fuera de la cancha. Su consagraci\u00f3n lleg\u00f3 en el Mundial de M\u00e9xico 1986, donde llev\u00f3 a Argentina a conseguir el t\u00edtulo de campe\u00f3n, con actuaciones memorables conocidas bajo el nombre de \u201cEl Gol del Siglo\u201d y \u201cLa Mano de Dios\u201d. M\u00e1s all\u00e1 de los logros deportivos, Maradona fue una figura con luces y sombras a nivel personal, con una vida marcada por excesos y una relaci\u00f3n intensa con la fama.<\/p>\n<p>El debate oral anterior, que dur\u00f3 casi tres meses, qued\u00f3 anulado tras un esc\u00e1ndalo: la entonces jueza <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/05\/27\/argentina\/apartan-jueza-juicio-muerte-diego-armando-maradona-orix\">Julieta Makintach fue recusada<\/a> y luego destituida por presunta falta de imparcialidad y por haber autorizado a personas cercanas a grabar videos de las audiencias para un documental. La suspensi\u00f3n temporal y la posterior nulidad del juicio dejaron el caso en pausa hasta este nuevo comienzo.<\/p>\n<p>Los siete profesionales m\u00e9dicos, imputados por homicidio simple con dolo eventual, volver\u00e1n a sentarse ante el Tribunal. Leopoldo Luque, neurocirujano; Agustina Cosachov, psiquiatra; Carlos D\u00edaz, psic\u00f3logo; Mariano Perroni, supervisor de enfermeros; Ricardo Almir\u00f3n, enfermero; Nancy Forlini, coordinadora m\u00e9dica; y Pedro Di Spagna, m\u00e9dico cl\u00ednico, deber\u00e1n presentarse a las 10 de la ma\u00f1ana en la primera audiencia. Todos ellos se han declarado inocentes y llegan al debate oral en libertad. En caso de ser condenados, enfrentan penas de entre 8 y 25 a\u00f1os de prisi\u00f3n.<\/p>\n<p><em>\u201c<\/em>Empezamos este juicio para demostrar la ausencia de responsabilidad penal en cada uno de los siete imputados, porque es claro que no hubo un plan criminal doloso para matar a Maradona\u201d, afirm\u00f3 Vadim Mischanchuk, abogado de Cosachov.<\/p>\n<p>En tanto, Baudry, dijo: \u201cEspero que los declaren culpables, independientemente de la pena que les apliquen. Y que con Luque, Cosachov y D\u00edaz, los m\u00e1ximos responsables, los jueces sean severos. No hicieron lo que ten\u00edan que hacer como profesionales m\u00e9dicos y con la responsabilidad que ellos hab\u00edan asumido\u201d.<\/p>\n<p>La enfermera Dahiana Madrid es la octava imputada, pero como pidi\u00f3 un juicio por jurados, ser\u00e1 juzgada en un proceso diferente que todav\u00eda no tiene fecha de inicio. \u201cNosotros creemos que este juicio no se puede hacer en paralelo con el juicio de Madrid. Tendr\u00eda que haber un juicio \u00fanico y tendr\u00eda que ser por jurados\u201d, dijo Nicol\u00e1s D\u2019\u00c1lbora, abogado de Forlini.<\/p>\n<p>Quienes dirigir\u00e1n el juicio, escuchar\u00e1n a unos 100 testigos, valorar\u00e1n la prueba y, finalmente, dictar\u00e1n sentencia ser\u00e1n los jueces Alberto Gaig, Alberto Ortolani y Pablo Rol\u00f3n, integrantes del Tribunal Oral en lo Criminal n\u00famero 7 de San Isidro, provincia de Buenos Aires. La primera audiencia ser\u00e1 transmitida en vivo a trav\u00e9s de YouTube, al igual que las etapas finales de alegatos y sentencia.<\/p>\n<p>\u201cCreo que todo el Poder Judicial de San Isidro va a estar bajo la lupa en este juicio\u201d, sostuvo Baudry, haciendo referencia al antecedente que marc\u00f3 el punto final del juicio del a\u00f1o pasado, luego de la recusaci\u00f3n de Makintach. A pesar de que la exjueza neg\u00f3 las acusaciones y dijo no tener v\u00ednculo con la realizaci\u00f3n de un documental de seis cap\u00edtulos de nombre \u201cJusticia Divina\u201d, el esc\u00e1ndalo fue tal que fue sometida a un juicio pol\u00edtico que result\u00f3 en su destituci\u00f3n en noviembre de ese mismo a\u00f1o. A diferencia de Baudry, Mischanchuk opin\u00f3: \u201cPara m\u00ed hubo un punto final. Estos son tres jueces nuevos con una trayectoria comprobada\u201d, y agreg\u00f3 que no tomar\u00e1 ninguna precauci\u00f3n al respecto.<\/p>\n<p>\u201cDespu\u00e9s de lo que pas\u00f3 con Makintach, Luque no confiaba en ning\u00fan juez, no confiaba en el Poder Judicial, as\u00ed que lo que quer\u00eda era un juicio por jurados. Pero se le fue denegado\u201d, cont\u00f3 Julio Rivas, abogado de Luque. A pesar de la voluntad de su defendido, Rivas conf\u00eda en la realizaci\u00f3n de un juicio t\u00e9cnico y en el nuevo Tribunal: \u201cConsidero que son tres jueces imparciales\u201d.<\/p>\n<p>La defensa de Forlini sostiene que quienes salieron perjudicados por el esc\u00e1ndalo de la jueza son los imputados. \u201cEste juicio no deber\u00eda empezar. La pregunta que hay que hacerse es por qu\u00e9 mi clienta se tiene que someter a un nuevo juicio porque a una jueza se le ocurri\u00f3 hacer un documental. \u00bfPor qu\u00e9 los imputados pagan los platos rotos?\u201d, dijo D\u2019\u00c1lbora.<\/p>\n<p>Un centenar de personas ser\u00e1n llamadas a declarar, en lo que representa un recorte de la lista de testigos de alrededor de 300 del juicio anterior. \u201cTodas las partes hemos hecho un gran esfuerzo para acordar cu\u00e1les son realmente los testigos \u00fatiles\u201d, dijo Mischanchuk. El objetivo es circunscribe al per\u00edodo de tiempo que va desde el 11 hasta el 25 de noviembre del 2020 para reconstruir c\u00f3mo transcurrieron esos 14 d\u00edas de internaci\u00f3n domiciliaria, antes de la muerte de Maradona. \u201cPara nosotros los testigos m\u00e1s importantes son los que puedan opinar con respecto a la autopsia, al an\u00e1lisis toxicol\u00f3gico y a las historias cl\u00ednicas, en el per\u00edodo que los fiscales determinaron que debe ser juzgado\u201d, agrega.<\/p>\n<p>Adem\u00e1s de peritos y diversos especialistas m\u00e9dicos, en la lista de testigos figuran familiares de Maradona, como sus hijas, Dalma, Giannina y Jana, y su expareja Ver\u00f3nica Ojeda, que declar\u00f3 en el juicio anterior y particip\u00f3 en varias audiencias como p\u00fablico. \u201cVer\u00f3nica lo vive con dolor, como toda la familia. Te pod\u00e9s imaginar que para las v\u00edctimas revivir todo es dif\u00edcil, y m\u00e1s por tener que contener a su hijo de 13 a\u00f1os\u201d, relat\u00f3 Baudry, que es tambi\u00e9n su pareja.<\/p>\n<p>Tras el esc\u00e1ndalo del proceso anterior, hay incertidumbre sobre que este nuevo juicio pueda desarrollarse con normalidad y llegue a su final. La estimaci\u00f3n es que, antes de la feria judicial de invierno, es decir, a mediados de a\u00f1o, ya pueda haber una sentencia. \u201cEste juicio se tiene que hacer por respeto a los familiares de Maradona y por respeto a todos los imputados. Este juicio tiene que empezar y tiene que terminar. Y yo estoy seguro de que este tribunal as\u00ed lo va a llevar adelante\u201d, dijo Mischanchuk, y agreg\u00f3 que, una vez concluido el debate oral, si las partes se consideran agraviadas por la sentencia, tendr\u00e1n la posibilidad de recurrirla.<\/p>\n<p>\u201cLa expectativa es que no sean m\u00e1s de 30 jornadas, o sea en dos meses, se deber\u00eda poder terminarlo y que se haga justicia: llegar a una sentencia condenatoria para los responsables que mataron a Diego\u201d, dijo Baudry. Por su lado, Rivas cree que el proceso ser\u00e1 \u00e1gil dado que el n\u00famero de testigo se redujo significativamente.<\/p>\n<p>Con el antecedente del juicio anulado, todo ser\u00e1 observado con m\u00e1s atenci\u00f3n esta vez, desde las declaraciones de los testigos hasta las decisiones del tribunal. No solo por el impacto medi\u00e1tico, sino por la posibilidad de que finalmente se arroje luz sobre una de las muertes m\u00e1s controvertidas del deporte argentino. En las pr\u00f3ximas horas, las partes volver\u00e1n a verse las caras para que el juicio comience.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No es un d\u00e9j\u00e0 vu. Es la evidencia de una deuda judicial que todav\u00eda no se sald\u00f3. \u201cEmpieza el juicio por la muerte de Diego Maradona\u201d fue el titular que acapar\u00f3 la atenci\u00f3n de los medios del mundo hace un a\u00f1o. Y ahora vuelve a escribirse. Este martes, en los Tribunales de la provincia de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473128","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo - Noticias\" \/>\n<meta property=\"og:description\" content=\"No es un d\u00e9j\u00e0 vu. Es la evidencia de una deuda judicial que todav\u00eda no se sald\u00f3. \u201cEmpieza el juicio por la muerte de Diego Maradona\u201d fue el titular que acapar\u00f3 la atenci\u00f3n de los medios del mundo hace un a\u00f1o. Y ahora vuelve a escribirse. Este martes, en los Tribunales de la provincia de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T12:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo\",\"datePublished\":\"2026-04-14T12:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/\"},\"wordCount\":1509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/\",\"name\":\"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-14T12:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo - Noticias","og_description":"No es un d\u00e9j\u00e0 vu. Es la evidencia de una deuda judicial que todav\u00eda no se sald\u00f3. \u201cEmpieza el juicio por la muerte de Diego Maradona\u201d fue el titular que acapar\u00f3 la atenci\u00f3n de los medios del mundo hace un a\u00f1o. Y ahora vuelve a escribirse. Este martes, en los Tribunales de la provincia de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-14T12:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/"},"author":{"name":"","@id":""},"headline":"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo","datePublished":"2026-04-14T12:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/"},"wordCount":1509,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/","name":"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-14T12:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\u00f3 en esc\u00e1ndalo","url":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/nuevo-juicio-muerte-diego-maradona-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-14T12:03:39Z","datePublished":"2026-04-14T12:03:39Z","dateModified":"2026-04-14T12:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Comienza un nuevo juicio por la muerte de Diego Maradona tras un proceso que termin\\u00f3 en esc\\u00e1ndalo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/14\\\/nuevo-juicio-muerte-diego-maradona-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/14\\\/nuevo-juicio-muerte-diego-maradona-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-14T12:03:39Z\",\"datePublished\":\"2026-04-14T12:03:39Z\",\"dateModified\":\"2026-04-14T12:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462863,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/27\/apartan-jueza-juicio-muerte-diego-armando-maradona-orix\/","url_meta":{"origin":1473128,"position":0},"title":"Apartan a jueza del juicio por la muerte de Diego Armando Maradona","author":"","date":"mayo 27, 2025","format":false,"excerpt":"Un tribunal argentino apart\u00f3 a la jueza Julieta Makintach del proceso penal por la muerte del futbolista argentino Diego Armando Maradona.El abogado de uno de los acusados hab\u00eda pedido la recusaci\u00f3n por posible falta de imparcialidad y por presunta autorizaci\u00f3n de Makintach para la filmaci\u00f3n de un documental en las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463025,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/30\/cronologia-escandalo-anulacion-juicio-muerte-diego-maradona-orix\/","url_meta":{"origin":1473128,"position":1},"title":"&#171;Justicia Divina&#187;: cronolog\u00eda del esc\u00e1ndalo que llev\u00f3 a la anulaci\u00f3n del juicio por la muerte de Diego Maradona","author":"","date":"mayo 30, 2025","format":false,"excerpt":"Podr\u00eda haber sido un d\u00eda m\u00e1s del debate que hab\u00eda iniciado dos meses antes y en el que ya hab\u00edan declarado alrededor de 40 testigos. Pero la audiencia del 15 de mayo del juicio por la muerte de Diego Armando Maradona se transform\u00f3 en un punto de quiebre y llev\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450042,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","url_meta":{"origin":1473128,"position":2},"title":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Tribunal oral en lo criminal N\u00b03 de San Isidro, Buenos Aires, decidi\u00f3 suspender la audiencia de debate en el juicio por la muerte de Diego Maradona, que estaba prevista para el 4 de junio, y la reprogram\u00f3 para el 1 de octubre de 2024.El fallo al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460113,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/19\/juicio-muerte-maradona-declaraciones-orix\/","url_meta":{"origin":1473128,"position":3},"title":"Con una lista de m\u00e1s de 100 testigos, comienzan las declaraciones en el juicio por la muerte de Maradona","author":"","date":"marzo 19, 2025","format":false,"excerpt":"Mientras habla el abogado de una de las personas acusadas por la muerte del futbolista argentino Diego Maradona, se escucha un grito con una frase de dif\u00edcil traducci\u00f3n, pero que en la voz de cualquier argentino tiene un solo significado, y es el apoyo incondicional a Maradona: \u201c\u00a1Aguante el Diego!\u201d.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459783,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/11\/comenzo-juicio-muerte-diego-maradona-orix\/","url_meta":{"origin":1473128,"position":4},"title":"Entre c\u00e1nticos, banderas y camisetas con el n\u00famero 10, comenz\u00f3 el juicio por la muerte de Maradona","author":"","date":"marzo 11, 2025","format":false,"excerpt":"Las canciones futboleras se escuchaban en la puerta del tribunal por parte de los simpatizantes argentinos, que portaban camisetas de la selecci\u00f3n con el n\u00famero 10 en sus espaldas. Como en las \u00e9pocas de las grandes epopeyas, los fan\u00e1ticos coreaban el apellido \u201cMaradona\u201d, pero, esta vez, las l\u00e1grimas que brotaban\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462643,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/21\/suspenden-juicio-de-maradona-por-siete-dias-orix\/","url_meta":{"origin":1473128,"position":5},"title":"Suspenden juicio de Maradona por siete d\u00edas, dice el abogado de las hijas","author":"","date":"mayo 21, 2025","format":false,"excerpt":"El juicio sobre las circunstancias que rodearon la muerte del exfutbolista argentino Diego Armando Maradona (1960 \u2013 2020) fue suspendido este martes por decisi\u00f3n del Tribunal Oral en lo Criminal N\u00b03 de San Isidro, inform\u00f3 Fernando Burlando, abogado de las hijas del astro, Dalma y Giannina Maradona.\u201cMe parece prudente y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1473128"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473128\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1473128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1473128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1473128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}