{"id":1473182,"date":"2026-04-14T23:03:48","date_gmt":"2026-04-15T06:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/"},"modified":"2026-04-14T23:03:48","modified_gmt":"2026-04-15T06:03:48","slug":"periodista-detenido-kuwait-video-guerra-iran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/","title":{"rendered":"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas"},"content":{"rendered":"<p>Ahmed Shihab-Eldin, periodista kuwait\u00ed-estadounidense conocido por su trabajo en VICE, HuffPost y Al Jazeera, ha sido detenido en Kuwait, seg\u00fan defensores de la libertad de prensa, tras compartir videos relacionados con la guerra de Ir\u00e1n.<\/p>\n<p>La detenci\u00f3n se produce en un momento en que Kuwait y otros estados del Golfo han intensificado la represi\u00f3n contra quienes publican im\u00e1genes de ataques con misiles iran\u00edes y otros temas considerados delicados.<\/p>\n<p>Organizaciones de vigilancia ciudadana han criticado duramente estas leyes tan estrictas.<\/p>\n<p>En el caso de Shihab-Eldin, hab\u00eda estado compartiendo informaci\u00f3n en su Substack y en las redes sociales cuando comenz\u00f3 la guerra, pero de repente dej\u00f3 de publicar el 2 de marzo.<\/p>\n<p>En ese momento se encontraba en Kuwait, visitando a su familia. Sus amigos creen que lleva casi seis semanas detenido. El martes, hicieron p\u00fablico su caso con la esperanza de que la publicidad contribuyera a su liberaci\u00f3n.<\/p>\n<p>\u201cInstamos a Kuwait a liberar a Ahmed Shihab-Eldin y retirar todos los cargos en su contra\u201d, declar\u00f3 Sara Qudah, directora regional del Comit\u00e9 para la Protecci\u00f3n de los Periodistas, en un comunicado. \u201cEl periodismo no es un delito, y el caso de Shihab-Eldin refleja un patr\u00f3n m\u00e1s amplio de uso de las leyes de seguridad nacional para sofocar el escrutinio y controlar la narrativa\u201d.<\/p>\n<p>El grupo de defensa de los derechos civiles tambi\u00e9n afirm\u00f3 que \u201cse entiende que las autoridades lo han acusado de difundir informaci\u00f3n falsa, perjudicar la seguridad nacional y hacer un uso indebido de su tel\u00e9fono m\u00f3vil; acusaciones vagas y demasiado generales que se utilizan habitualmente para silenciar a los periodistas independientes\u201d.<\/p>\n<p>CNN se ha puesto en contacto con el Gobierno kuwait\u00ed para obtener comentarios al respecto.<\/p>\n<p>Los amigos de Shihab-Eldin han se\u00f1alado que las im\u00e1genes y los videos que comparti\u00f3 en Substack ya eran de dominio p\u00fablico. Por ejemplo, comparti\u00f3 uno de CNN sobre el accidente de un avi\u00f3n de combate de la Fuerza A\u00e9rea estadounidense sobre Kuwait.<\/p>\n<p>Sin embargo, las autoridades kuwait\u00edes advirtieron a los ciudadanos que no fotografiaran ni publicaran \u201cning\u00fan video ni informaci\u00f3n relacionada con misiles o lugares relevantes\u201d.<\/p>\n<p>\u201cEstas acciones est\u00e1n siendo monitoreadas de cerca y se est\u00e1n tomando medidas en\u00e9rgicas contra ellas, y los infractores son remitidos a las autoridades pertinentes para que se emprendan acciones legales\u201d, inform\u00f3 el Kuwait Times a principios de este mes.<\/p>\n<p>El Centro del Golfo para los Derechos Humanos afirm\u00f3 en un informe reciente que los estados del Golfo han utilizado la guerra \u201cpara reprimir la libertad de expresi\u00f3n, confiscar las libertades p\u00fablicas de los ciudadanos y atacar a periodistas, blogueros y activistas en l\u00ednea que expresan opiniones que no se ajustan a las pol\u00edticas gubernamentales\u201d.<\/p>\n<p>\u201cEstas personas son sometidas a encarcelamiento y detenci\u00f3n arbitrarios, as\u00ed como a juicios injustos con cargos fabricados mediante el uso de leyes antiterroristas y de ciberdelincuencia\u201d, declar\u00f3 el grupo.<\/p>\n<p>En los Emiratos \u00c1rabes Unidos, se han registrado numerosos casos de personas arrestadas por compartir fotos de ataques con misiles.<\/p>\n<p>La noticia de la detenci\u00f3n de Shihab-Eldin sali\u00f3 a la luz el martes, en parte porque ha sido una figura medi\u00e1tica muy conocida durante m\u00e1s de una d\u00e9cada.<\/p>\n<p>En 2011, fue cocreador y copresentador de \u201cThe Stream\u201d, un programa pionero en Al Jazeera English, y posteriormente ayud\u00f3 a lanzar la red de transmisi\u00f3n en vivo de HuffPost. Ha participado como invitado en CNN y en numerosas otras cadenas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ahmed Shihab-Eldin, periodista kuwait\u00ed-estadounidense conocido por su trabajo en VICE, HuffPost y Al Jazeera, ha sido detenido en Kuwait, seg\u00fan defensores de la libertad de prensa, tras compartir videos relacionados con la guerra de Ir\u00e1n. La detenci\u00f3n se produce en un momento en que Kuwait y otros estados del Golfo han intensificado la represi\u00f3n contra [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473182","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ahmed Shihab-Eldin, periodista kuwait\u00ed-estadounidense conocido por su trabajo en VICE, HuffPost y Al Jazeera, ha sido detenido en Kuwait, seg\u00fan defensores de la libertad de prensa, tras compartir videos relacionados con la guerra de Ir\u00e1n. La detenci\u00f3n se produce en un momento en que Kuwait y otros estados del Golfo han intensificado la represi\u00f3n contra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T06:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas\",\"datePublished\":\"2026-04-15T06:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/\"},\"wordCount\":625,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/\",\"name\":\"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-15T06:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas - Noticias","og_description":"Ahmed Shihab-Eldin, periodista kuwait\u00ed-estadounidense conocido por su trabajo en VICE, HuffPost y Al Jazeera, ha sido detenido en Kuwait, seg\u00fan defensores de la libertad de prensa, tras compartir videos relacionados con la guerra de Ir\u00e1n. La detenci\u00f3n se produce en un momento en que Kuwait y otros estados del Golfo han intensificado la represi\u00f3n contra [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-15T06:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/"},"author":{"name":"","@id":""},"headline":"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas","datePublished":"2026-04-15T06:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/"},"wordCount":625,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/","name":"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-15T06:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\u00e1n, denuncian activistas","url":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/14\/periodista-detenido-kuwait-video-guerra-iran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-15T06:03:48Z","datePublished":"2026-04-15T06:03:48Z","dateModified":"2026-04-15T06:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un periodista fue detenido en Kuwait tras publicar un video sobre la guerra de Ir\\u00e1n, denuncian activistas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/14\\\/periodista-detenido-kuwait-video-guerra-iran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/14\\\/periodista-detenido-kuwait-video-guerra-iran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-15T06:03:48Z\",\"datePublished\":\"2026-04-15T06:03:48Z\",\"dateModified\":\"2026-04-15T06:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472200,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/14\/kuwait-medio-oriente-atrapada-guerra-analisis-trax\/","url_meta":{"origin":1473182,"position":0},"title":"Una peque\u00f1a naci\u00f3n de Medio Oriente, en el centro de una guerra de d\u00e9cadas, se encuentra atrapada en otra","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Para los habitantes del golfo P\u00e9rsico, ricos en petr\u00f3leo y en su mayor\u00eda privilegiados, el ataque de Ir\u00e1n ha sido tan inesperado como aterrador. Muchos expatriados han regresado a sus hogares, mientras Ir\u00e1n lanzaba andanadas de misiles y drones, arrasando aeropuertos, edificios de apartamentos y terminales petroleras.Para la gente de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471945,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/06\/israel-iran-libano-teheran-beirut-ataque-trax\/","url_meta":{"origin":1473182,"position":1},"title":"Israel sigue bombardeando Ir\u00e1n y L\u00edbano: fue la &#171;peor noche&#187; en Teher\u00e1n y Beirut recibe nueva oleada de ataques","author":"","date":"marzo 6, 2026","format":false,"excerpt":"Israel bombarde\u00f3 Ir\u00e1n y L\u00edbano durante la noche, mientras que la preocupaci\u00f3n por el suministro energ\u00e9tico aumentaba e Ir\u00e1n respond\u00eda atacando a sus vecinos del Golfo.Israel lanz\u00f3 otra oleada de ataques contra Ir\u00e1n, que los residentes de Teher\u00e1n describieron como \u201cla peor noche\u201d desde el inicio de la guerra. Un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472018,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/09\/identifican-septimo-militar-eeuu-muerto-guerra-iran-trax\/","url_meta":{"origin":1473182,"position":2},"title":"Identifican al s\u00e9ptimo militar de EE.UU. muerto en la guerra contra Ir\u00e1n como un sargento del Ej\u00e9rcito","author":"","date":"marzo 9, 2026","format":false,"excerpt":"Un soldado estadounidense falleci\u00f3 tras sufrir heridas durante un ataque la semana pasada en Arabia Saudita, informaron las fuerzas armadas, lo que eleva a siete la cifra de soldados de Estados Unidos muertos en la guerra contra Ir\u00e1n.El lunes, los militares identificaron al soldado como el sargento del ej\u00e9rcito Benjamin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472093,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/11\/cuantos-muertos-iran-medio-oriente-guerra-trax\/","url_meta":{"origin":1473182,"position":3},"title":"\u00bfCu\u00e1ntas personas han muerto en Ir\u00e1n y otros pa\u00edses de Medio Oriente durante la guerra?","author":"","date":"marzo 11, 2026","format":false,"excerpt":"Estados Unidos, Israel e Ir\u00e1n contin\u00faan intercambiando ataques en Medio Oriente, donde la cifra de muertos por la guerra va en aumento.A continuaci\u00f3n, los n\u00fameros m\u00e1s recientes seg\u00fan un recuento de CNN basado en fuentes regionales.Ir\u00e1n: el embajador de Ir\u00e1n ante las Naciones Unidas declar\u00f3 el martes que m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471783,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/02\/defensa-kuwait-aviones-militares-estados-unidos-sobrevivientes-trax\/","url_meta":{"origin":1473182,"position":4},"title":"Ministerio de Defensa de Kuwait afirma que &#171;varios&#187; aviones militares estadounidenses se estrellaron y todos sobrevivieron","author":"","date":"marzo 2, 2026","format":false,"excerpt":"El Ministerio de Defensa de Kuwait dijo que \u201cvarios aviones militares de Estados Unidos se estrellaron\u201d el lunes y que \u201ctodos los miembros de la tripulaci\u00f3n sobrevivieron\u201d.La declaraci\u00f3n llega despu\u00e9s de que unos v\u00eddeos geolocalizados por CNN mostraran un avi\u00f3n de combate estrell\u00e1ndose en Kuwait y a un piloto saltando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471821,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/03\/mapas-graficos-ataques-eeuu-israel-iran-trax\/","url_meta":{"origin":1473182,"position":5},"title":"Mapas y gr\u00e1ficos para entender la guerra entre EE.UU., Israel e Ir\u00e1n","author":"","date":"marzo 3, 2026","format":false,"excerpt":"La guerra en Medio Oriente se est\u00e1 expandiendo despu\u00e9s de que Estados Unidos e Israel atacaran a Ir\u00e1n el s\u00e1bado, y Teher\u00e1n respondiera con ataques contra varios de sus vecinos, incluidos estados del golfo P\u00e9rsico aliados de Estados Unidos. Israel y Hezbollah tambi\u00e9n est\u00e1n intercambiando ataques a medida que el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1473182"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473182\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1473182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1473182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1473182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}