{"id":1473242,"date":"2026-04-16T10:03:46","date_gmt":"2026-04-16T17:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/"},"modified":"2026-04-16T10:03:46","modified_gmt":"2026-04-16T17:03:46","slug":"hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/","title":{"rendered":"Aplazan la sentencia del &#171;Pollo&#187; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &#171;detalles&#187; contra Maduro"},"content":{"rendered":"<p>La sentencia contra el exdirector de la Direcci\u00f3n de Inteligencia Militar de Venezuela (DIM), Hugo Carvajal, conocido como \u201cEl Pollo\u201d, fue aplazada nuevamente, seg\u00fan confirm\u00f3 un portavoz de la Fiscal\u00eda del Distrito Sur de Nueva York. Hasta ahora no se ha fijado una nueva fecha.<\/p>\n<p>Carvajal fue jefe de inteligencia militar bajo los gobiernos de Hugo Ch\u00e1vez y Nicol\u00e1s Maduro, lo que lo convirti\u00f3 en una figura clave del chavismo durante m\u00e1s de una d\u00e9cada.<\/p>\n<p>La audiencia ha sido pospuesta en varias ocasiones desde que Carvajal se declar\u00f3 culpable en junio de 2025 de cuatro cargos federales, entre ellos narcoterrorismo y delitos de narcotr\u00e1fico.<\/p>\n<p>El abogado defensor Renato Stabile, con experiencia en casos federales de narcotr\u00e1fico de alto perfil, incluida la representaci\u00f3n del expresidente de Honduras Juan Orlando Hern\u00e1ndez, quien fue indultado por Trump el a\u00f1o pasado tras ser condenado por cargos relacionados con drogas, dijo a CNN que, cuando un acusado coopera, la sentencia suele posponerse hasta que ese proceso concluye.<\/p>\n<p>\u201cM\u00faltiples aplazamientos podr\u00edan ser un indicio, aunque no una confirmaci\u00f3n, de que existe un acuerdo o que hay negociaciones en curso. Si Carvajal est\u00e1 cooperando y su sentencia sigue adelante, eso ser\u00eda altamente inusual\u201d, se\u00f1al\u00f3 Stabile.<\/p>\n<p>En tanto, el abogado de Carvajal, Robert Feitel, dijo a CNN que no ten\u00eda comentarios sobre esa posibilidad.<\/p>\n<p>Feitel comparti\u00f3 con CNN una carta que el \u201cPollo\u201d le envi\u00f3 a Donald Trump en diciembre pasado, aproximadamente un mes antes de la captura del depuesto presidente de Venezuela, Nicol\u00e1s Maduro en Caracas por fuerzas estadounidenses.<\/p>\n<p>El documento, es hasta ahora la se\u00f1al m\u00e1s clara de que Carvajal est\u00e1 dispuesto a \u201cproporcionar detalles\u201d y a compartir lo que describe como conocimiento interno sobre lo que califica como el \u201cr\u00e9gimen criminal\u201d de Maduro.<\/p>\n<p>\u201cDurante muchos a\u00f1os, fui un miembro de alto rango del r\u00e9gimen venezolano. Fui un general de tres estrellas en quien confiaron tanto Hugo Ch\u00e1vez como Nicol\u00e1s Maduro\u2026 Hoy estoy en una prisi\u00f3n en Estados Unidos porque me declar\u00e9 culpable voluntariamente de los delitos que se me imputan: una conspiraci\u00f3n de narcoterrorismo. Escribo para expiar, diciendo toda la verdad, para que Estados Unidos pueda protegerse de los peligros que presenci\u00e9 durante tantos a\u00f1os\u2026 Hoy veo la necesidad de dirigirme al pueblo estadounidense para hablar sobre la verdadera naturaleza del r\u00e9gimen venezolano\u201d, escribi\u00f3.<\/p>\n<p>Carvajal, quien se declar\u00f3 culpable de conspiraci\u00f3n de narcoterrorismo, conspiraci\u00f3n para introducir coca\u00edna en el pa\u00eds y delitos vinculados al uso de armas, era, seg\u00fan fiscales, \u201clos ojos y o\u00eddos\u201d del chavismo dentro de la Fuerza Armada Nacional Bolivariana durante m\u00e1s de una d\u00e9cada y estuvo en el centro de una estructura de altos funcionarios venezolanos que habr\u00edan facilitado el env\u00edo de droga hacia territorio estadounidense.<\/p>\n<p>Como figura clave dentro del aparato de inteligencia venezolano, Carvajal fue una de las piedras angulares del r\u00e9gimen chavista y uno de los asesores m\u00e1s cercanos a Maduro con acceso directo a las operaciones m\u00e1s sensibles del r\u00e9gimen.<\/p>\n<p>En julio de 2014, fue detenido en Aruba, una isla bajo jurisdicci\u00f3n del Reino de los Pa\u00edses Bajos ubicada frente a las costas occidentales de Venezuela, a pedido de las autoridades de Estados Unidos, que lo vinculaban con el narcotr\u00e1fico y las hoy extintas Fuerzas Armadas Revolucionarias de Colombia.<\/p>\n<p>Mediante una intensa presi\u00f3n diplom\u00e1tica, el Gobierno de Maduro logr\u00f3 evitar que lo extraditaran a Estados Unidos aludiendo a la inmunidad diplom\u00e1tica que entonces ten\u00eda Carvajal, quien hab\u00eda sido nombrado c\u00f3nsul en Aruba tras su paso por la jefatura de la inteligencia militar. Caracas logr\u00f3 traerlo de vuelta a Venezuela, donde fue recibido por el propio Maduro y la plana mayor del gobierno en un acto pol\u00edtico, un episodio tens\u00f3 las relaciones con Washington.<\/p>\n<p>Feitel se\u00f1al\u00f3 que no tiene certeza de que Trump haya le\u00eddo la carta.<\/p>\n<p>Consultada por CNN, la Casa Blanca no respondi\u00f3 si el presidente estadounidense hab\u00eda respondido a la misiva, pero dijo: \u201cNicol\u00e1s Maduro orquest\u00f3 muchos cr\u00edmenes contra Estados Unidos, incluidos el env\u00edo de drogas y terroristas a nuestro pa\u00eds para matar a estadounidenses. Afortunadamente, el Departamento de Justicia del presidente Trump arrest\u00f3 a Maduro por sus numerosas acciones malvadas e ilegales, y ahora est\u00e1 a la espera de la justicia en el Distrito Sur de Nueva York\u201d.<\/p>\n<p>En el documento, Carvajal va m\u00e1s all\u00e1 y alega que esta operaci\u00f3n, conocida como el Cartel de los Soles, fue dise\u00f1ada para utilizar las drogas como un arma contra Estados Unidos. Sostiene que lo que comenz\u00f3 bajo el fallecido expresidente Ch\u00e1vez evolucion\u00f3 hacia una estructura organizada con fines criminales liderada por Maduro y otros altos funcionarios:<\/p>\n<p>\u201cLas drogas que llegaron a sus ciudades a trav\u00e9s de nuevas rutas no fueron producto de actos aislados de corrupci\u00f3n ni obra de traficantes independientes; fueron pol\u00edticas deliberadas coordinadas por el r\u00e9gimen venezolano contra Estados Unidos\u201d, expres\u00f3.<\/p>\n<p>CNN contact\u00f3 al abogado de Maduro y al Gobierno venezolano para solicitar comentarios, pero no ha recibido respuesta. Maduro ha rechazado reiteradamente estas acusaciones.<\/p>\n<p>Carvajal asegura que rompi\u00f3 con el r\u00e9gimen en 2017. Tras esa ruptura, afirma que se vio obligado a abandonar Venezuela y vivir como pr\u00f3fugo durante a\u00f1os, hasta ser arrestado en Espa\u00f1a en 2021 y luego extraditado a Estados Unidos.<\/p>\n<p>En la acusaci\u00f3n federal presentada en 2019, la primera que menciona directamente a Nicol\u00e1s Maduro, fiscales estadounidenses describen una estructura casi id\u00e9ntica con lo que Carvajal detalla en su carta: una red integrada por altos funcionarios y grupos armados, con el objetivo de enviar grandes cantidades de coca\u00edna a Estados Unidos y, seg\u00fan la acusaci\u00f3n, \u201cinundar\u201d el pa\u00eds con droga.<\/p>\n<p>\u201cEl Pollo\u201d alega en el documento que este plan fue propuesto por el r\u00e9gimen cubano a Ch\u00e1vez a mediados de los a\u00f1os 2000 y ejecutado mediante presuntas alianzas con grupos armados y bandas criminales como el Tren de Aragua que operan dentro y fuera de Venezuela:<em> <\/em><\/p>\n<p>\u201cEl r\u00e9gimen ha proporcionado armas, pasaportes e impunidad para que estas organizaciones terroristas operen libremente desde Venezuela contra Estados Unidos\u201d, escribi\u00f3 Carvajal.<\/p>\n<p>CNN solicit\u00f3 comentarios a la presidencia de Cuba sobre estas declaraciones sin obtener respuesta, aunque el Gobierno cubano ha negado este tipo de acusaciones reiteradamente.<\/p>\n<p>El exdirector de la DIM tambi\u00e9n describe presuntas operaciones de espionaje y cooperaci\u00f3n en materia de inteligencia con Rusia y asegura que advirti\u00f3 a Maduro sobre permitir la instalaci\u00f3n de una base de escucha rusa en territorio venezolano.<\/p>\n<p>\u201cEstuve presente cuando la inteligencia rusa lleg\u00f3 a Caracas para proponer a Hugo Ch\u00e1vez intervenir cables submarinos de internet que conectan gran parte de Sudam\u00e9rica y el Caribe con Estados Unidos, con el objetivo de penetrar comunicaciones del gobierno estadounidense. En 2015, advert\u00ed a Maduro que permitir que la inteligencia rusa construyera y operara una base secreta de escucha en la isla de La Orchila alg\u00fan d\u00eda provocar\u00eda bombardeos estadounidenses. Me ignor\u00f3\u201d, se\u00f1al\u00f3.<\/p>\n<p>El Kremlin no respondi\u00f3 a las consultas de CNN sobre las afirmaciones de Carvajal, aunque las autoridades estadounidenses han advertido reiteradamente sobre operaciones de espionaje e influencia por parte de gobiernos extranjeros, incluida Rusia, dirigida a Estados Unidos, acusaciones que el Kremlin ha negado<\/p>\n<p>Hasta ahora, ni su defensa ni el Departamento de Justicia han confirmado p\u00fablicamente si Carvajal est\u00e1 cooperando con fiscales.  Sin embargo, expertos legales se\u00f1alan que el patr\u00f3n en su caso plantea interrogantes.<\/p>\n<p>Adem\u00e1s de las mencionadas demoras en la sentencia, otros elementos, como la falta de informaci\u00f3n p\u00fablica sobre la ubicaci\u00f3n actual de Carvajal dentro del sistema penitenciario federal, tambi\u00e9n podr\u00edan apuntar a una posible cooperaci\u00f3n, seg\u00fan el abogado defensor Stabile.<\/p>\n<p>\u201cSi un acusado no aparece en el sistema de localizaci\u00f3n de reclusos del Bur\u00f3 de Prisiones, eso tambi\u00e9n podr\u00eda ser una se\u00f1al de que est\u00e1 cooperando. En algunos casos, estos acusados son mantenidos fuera del registro p\u00fablico\u201d, sostuvo el experto.<\/p>\n<p>El abogado de Carvajal no respondi\u00f3 a preguntas de CNN sobre el lugar donde se encuentra detenido actualmente su cliente.<\/p>\n<p>Estos desarrollos dejan abierta la posibilidad de que Carvajal pueda convertirse en un testigo clave contra su antiguo jefe y aliado. Sus propias palabras confirman que est\u00e1 dispuesto a hablar y revelar informaci\u00f3n que podr\u00eda implicar directamente al r\u00e9gimen de Nicol\u00e1s Maduro en una presunta red criminal de narcotr\u00e1fico:<\/p>\n<p>\u201cApoyo plenamente la pol\u00edtica del presidente Trump hacia Venezuela, porque es una medida de autodefensa y est\u00e1 basada en la verdad. Estoy dispuesto a proporcionar detalles adicionales sobre estos asuntos al gobierno de Estados Unidos\u201d.<\/p>\n<p><em>Alfredo Meza, Mauricio Torres y Nina Subkhanberdina colaboraron con este reporte.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sentencia contra el exdirector de la Direcci\u00f3n de Inteligencia Militar de Venezuela (DIM), Hugo Carvajal, conocido como \u201cEl Pollo\u201d, fue aplazada nuevamente, seg\u00fan confirm\u00f3 un portavoz de la Fiscal\u00eda del Distrito Sur de Nueva York. Hasta ahora no se ha fijado una nueva fecha. Carvajal fue jefe de inteligencia militar bajo los gobiernos de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473242","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aplazan la sentencia del &quot;Pollo&quot; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &quot;detalles&quot; contra Maduro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aplazan la sentencia del &quot;Pollo&quot; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &quot;detalles&quot; contra Maduro - Noticias\" \/>\n<meta property=\"og:description\" content=\"La sentencia contra el exdirector de la Direcci\u00f3n de Inteligencia Militar de Venezuela (DIM), Hugo Carvajal, conocido como \u201cEl Pollo\u201d, fue aplazada nuevamente, seg\u00fan confirm\u00f3 un portavoz de la Fiscal\u00eda del Distrito Sur de Nueva York. Hasta ahora no se ha fijado una nueva fecha. Carvajal fue jefe de inteligencia militar bajo los gobiernos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T17:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Aplazan la sentencia del &#171;Pollo&#187; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &#171;detalles&#187; contra Maduro\",\"datePublished\":\"2026-04-16T17:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/\"},\"wordCount\":1528,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/\",\"name\":\"Aplazan la sentencia del \\\"Pollo\\\" Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar \\\"detalles\\\" contra Maduro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-16T17:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aplazan la sentencia del &#171;Pollo&#187; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &#171;detalles&#187; contra Maduro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aplazan la sentencia del \"Pollo\" Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar \"detalles\" contra Maduro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Aplazan la sentencia del \"Pollo\" Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar \"detalles\" contra Maduro - Noticias","og_description":"La sentencia contra el exdirector de la Direcci\u00f3n de Inteligencia Militar de Venezuela (DIM), Hugo Carvajal, conocido como \u201cEl Pollo\u201d, fue aplazada nuevamente, seg\u00fan confirm\u00f3 un portavoz de la Fiscal\u00eda del Distrito Sur de Nueva York. Hasta ahora no se ha fijado una nueva fecha. Carvajal fue jefe de inteligencia militar bajo los gobiernos de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-16T17:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Aplazan la sentencia del &#171;Pollo&#187; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &#171;detalles&#187; contra Maduro","datePublished":"2026-04-16T17:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/"},"wordCount":1528,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/","name":"Aplazan la sentencia del \"Pollo\" Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar \"detalles\" contra Maduro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-16T17:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Aplazan la sentencia del &#171;Pollo&#187; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &#171;detalles&#187; contra Maduro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Aplazan la sentencia del &#171;Pollo&#187; Carvajal, ex jefe chavista que, en una carta, ofreci\u00f3 a Trump dar &#171;detalles&#187; contra Maduro","url":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-16T17:03:46Z","datePublished":"2026-04-16T17:03:46Z","dateModified":"2026-04-16T17:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Aplazan la sentencia del &#171;Pollo&#187; Carvajal, ex jefe chavista que, en una carta, ofreci\\u00f3 a Trump dar &#171;detalles&#187; contra Maduro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/16\\\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/16\\\/hugo-pollo-carvajal-chavismo-audiencia-maduro-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-16T17:03:46Z\",\"datePublished\":\"2026-04-16T17:03:46Z\",\"dateModified\":\"2026-04-16T17:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463975,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/26\/quien-es-hugo-pollo-carvajal-chavez-orix\/","url_meta":{"origin":1473242,"position":0},"title":"\u00bfQui\u00e9n es Hugo \u2018Pollo\u2019 Carvajal, el hombre de confianza de Hugo Ch\u00e1vez?","author":"","date":"junio 26, 2025","format":false,"excerpt":"Hugo \u201cPollo\u201d Carvajal, exdirector de Inteligencia de Venezuela, fue hombre de confianza de Hugo Ch\u00e1vez y uno de sus colaboradores m\u00e1s cercanos. Tras un largo periplo, fue apresado en Espa\u00f1a en 2021 y luego extraditado a Estados Unidos en 2023. El 25 de junio se declar\u00f3 culpable de narcoterrorismo y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463962,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/25\/carvajal-inteligencia-venezuela-culpable-ee-uu-narcoterrorismo-narcotrafico-orix\/","url_meta":{"origin":1473242,"position":1},"title":"Hugo Carvajal, exdirector de Inteligencia Militar de Venezuela, se declara culpable de narcoterrorismo y narcotr\u00e1fico","author":"","date":"junio 25, 2025","format":false,"excerpt":"El general Hugo Armando Carvajal Barrios, exdirector de Inteligencia Militar de Venezuela arrestado en 2021, se declar\u00f3 culpable en Estados Unidos de narcoterrorismo y narcotr\u00e1fico, delitos por los que puede enfrentar una pena de cadena perpetua, inform\u00f3 este jueves el Departamento de Justicia de EE.UU.Tambi\u00e9n conocido como \u201cel Pollo\u201d, Carvajal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464875,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/26\/eeuu-cartel-soles-organizacion-terrorista-orix\/","url_meta":{"origin":1473242,"position":2},"title":"Estados Unidos designa al Cartel de los Soles como organizaci\u00f3n terrorista internacional","author":"","date":"julio 26, 2025","format":false,"excerpt":"El Departamento del Tesoro de EE.UU. design\u00f3 este viernes al Cartel de los Soles como una organizaci\u00f3n terrorista internacional, seg\u00fan declaraciones del Departamento y de la Oficina de Control de Activos Extranjeros (OFAC, en ingl\u00e9s).El Cartel de los Soles es un presunto grupo criminal que, seg\u00fan Washington, ha corrompido las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465413,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/12\/la-recompensa-por-maduro-alcanzo-un-nivel-inedito-por-que-ahora\/","url_meta":{"origin":1473242,"position":3},"title":"La recompensa por Maduro alcanz\u00f3 un nivel in\u00e9dito. \u00bfPor qu\u00e9 ahora?","author":"","date":"agosto 12, 2025","format":false,"excerpt":"La tensa relaci\u00f3n entre Estados Unidos y Venezuela acaba de inaugurar un nuevo cap\u00edtulo. En la m\u00e1s reciente confrontaci\u00f3n, el Gobierno del presidente Donald Trump reiter\u00f3 su acusaci\u00f3n al mandatario de Venezuela, Nicol\u00e1s Maduro, de ser el l\u00edder del grupo criminal del Cartel de los Soles y subi\u00f3 la recompensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465907,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/27\/gestos-guerra-maduro-trump-venezuela-eeuu-orix\/","url_meta":{"origin":1473242,"position":4},"title":"Maduro y Trump intercambian gestos de guerra: \u00bfHasta d\u00f3nde llegar\u00e1n?","author":"","date":"agosto 27, 2025","format":false,"excerpt":"El choque y la tensi\u00f3n entre los gobiernos de Estados Unidos y Venezuela alcanzaron un punto m\u00e1ximo esta semana, cuando ambos pa\u00edses involucraron activos militares en su disputa.Por un lado, EE.UU. ha endurecido su ret\u00f3rica sobre narcotr\u00e1fico contra el presidente de Venezuela, Nicol\u00e1s Maduro, y su gobierno. Por el otro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466042,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/01\/maduro-cartel-soles-acusacion-narcotrafico-amenaza-eeuu-analisis-orix\/","url_meta":{"origin":1473242,"position":5},"title":"Trump acusa a Maduro de amenazar la seguridad nacional por narcotr\u00e1fico. Pero \u00bfqu\u00e9 dicen los datos realmente?","author":"","date":"septiembre 1, 2025","format":false,"excerpt":"La reciente escalada de tensiones entre Washington y Caracas, por la que Estados Unidos anunci\u00f3 el env\u00edo de al menos siete buques de guerra al Caribe meridional, tiene una fecha de comienzo precisa.El 7 de agosto, la secretaria de Justicia de EE.UU., Pam Bondi, anunci\u00f3 una recompensa de US$ 50\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1473242"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473242\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1473242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1473242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1473242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}