{"id":1473265,"date":"2026-04-16T20:03:41","date_gmt":"2026-04-17T03:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/"},"modified":"2026-04-16T20:03:41","modified_gmt":"2026-04-17T03:03:41","slug":"semifinales-copa-campeones-concacaf-2026-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/","title":{"rendered":"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf"},"content":{"rendered":"<p>Solo cuatro equipos siguen en carrera en la lucha por el t\u00edtulo de la Copa de Campeones de la Concacaf. Y lo que sigue en el torneo promete mucha tensi\u00f3n y emoci\u00f3n, al enfrentar en dos duelos mano a mano a la Liga MX y a la MLS. Dos choques que elevar\u00e1n a\u00fan m\u00e1s la disputa que vienen manteniendo los equipos de las dos ligas m\u00e1s importantes de Norteam\u00e9rica.<\/p>\n<p>Uno de esos enfrentamientos ser\u00e1 entre el bicampe\u00f3n de M\u00e9xico, el Toluca, y el Los Angeles FC de Heung-Min Son y Hugo Lloris.<\/p>\n<p>Los Diablos Rojos le pegaron una paliza para el recuerdo a Los Angeles Galaxy en cuartos de final (7-2 en el global) y vienen siendo una aplanadora ofensiva: 13 tantos en cuatro partidos, m\u00e1s de tres anotaciones en promedio por juego. Antes lo sufri\u00f3 el San Diego FC (global de 6-3), otro elenco de la MLS.<\/p>\n<p>Los angelinos, por su parte, superaron con \u00e9xito la primera prueba exigente que se les present\u00f3 en el torneo, al eliminar al Cruz Azul mexicano (vigente campe\u00f3n) por un global de 4-1. La serie se defini\u00f3 en la ida en Estados Unidos, donde no hubo equivalencias (3-0). El LAFC, que el a\u00f1o pasado jug\u00f3 el Mundial de Clubes, hab\u00eda dejado en el camino previamente al hondure\u00f1o Real CD Espa\u00f1a (7-1) y ag\u00f3nicamente al LD Alajuelense (3-2) de Costa Rica.<\/p>\n<p>El otro cruce pondr\u00e1 frente a frente al Nashville SC y al U.A.N.L. Tigres. El cuadro estadounidense volvi\u00f3 a ser un emblema del orden y el trabajo defensivo. En octavos ya lo hab\u00eda demostrado al eliminar al Inter Miami de Lionel Messi por gol de visitante (1-1) y en semis volvi\u00f3 a dejarlo en claro: no est\u00e1 aqu\u00ed por el \u201cjogo bonito\u201d, pero s\u00ed por la solidez en su \u00faltima l\u00ednea. Su m\u00e1s reciente v\u00edctima fue el gigante Club Am\u00e9rica, que celebr\u00f3 un empate (0-0) en Estados Unidos para luego caer como local (0-1). El Nashville ya jug\u00f3 seis partidos (elimin\u00f3 en primera rueda al Atl\u00e9tico Ottawa por global de 7-0) y apenas recibi\u00f3 un gol.<br \/>Solo Messi pudo convertirle en esta competencia.<\/p>\n<p>Su pr\u00f3ximo rival promete elevar la vara. El Tigres de la U.A.N.L. borde\u00f3 el precipicio ante el Seattle Sounders, pero sobrevivi\u00f3. Tras una buena producci\u00f3n como local en M\u00e9xico, donde gan\u00f3 2-0, la revancha fue muy diferente. Los estadounidenses igualaron la serie en el final, pero el gol de visitante de Joaquim meti\u00f3 a Tigres en la semifinal.<br \/>Los mexicanos ya ven\u00edan de protagonizar una entretenida serie de octavos, cuando lograron revertir un 0-3 ante el FC Cincinnati al minuto 98.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo cuatro equipos siguen en carrera en la lucha por el t\u00edtulo de la Copa de Campeones de la Concacaf. Y lo que sigue en el torneo promete mucha tensi\u00f3n y emoci\u00f3n, al enfrentar en dos duelos mano a mano a la Liga MX y a la MLS. Dos choques que elevar\u00e1n a\u00fan m\u00e1s la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473265","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf - Noticias\" \/>\n<meta property=\"og:description\" content=\"Solo cuatro equipos siguen en carrera en la lucha por el t\u00edtulo de la Copa de Campeones de la Concacaf. Y lo que sigue en el torneo promete mucha tensi\u00f3n y emoci\u00f3n, al enfrentar en dos duelos mano a mano a la Liga MX y a la MLS. Dos choques que elevar\u00e1n a\u00fan m\u00e1s la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T03:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf\",\"datePublished\":\"2026-04-17T03:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/\"},\"wordCount\":495,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/\",\"name\":\"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-17T03:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf - Noticias","og_description":"Solo cuatro equipos siguen en carrera en la lucha por el t\u00edtulo de la Copa de Campeones de la Concacaf. Y lo que sigue en el torneo promete mucha tensi\u00f3n y emoci\u00f3n, al enfrentar en dos duelos mano a mano a la Liga MX y a la MLS. Dos choques que elevar\u00e1n a\u00fan m\u00e1s la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-17T03:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/"},"author":{"name":"","@id":""},"headline":"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf","datePublished":"2026-04-17T03:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/"},"wordCount":495,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/","name":"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-17T03:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9xico vs. Estados Unidos: as\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf","url":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/16\/semifinales-copa-campeones-concacaf-2026-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-17T03:03:41Z","datePublished":"2026-04-17T03:03:41Z","dateModified":"2026-04-17T03:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e9xico vs. Estados Unidos: as\\u00ed quedaron las semifinales de la Copa de Campeones de la Concacaf\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/16\\\/semifinales-copa-campeones-concacaf-2026-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/16\\\/semifinales-copa-campeones-concacaf-2026-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-17T03:03:41Z\",\"datePublished\":\"2026-04-17T03:03:41Z\",\"dateModified\":\"2026-04-17T03:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473551,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/27\/semifinales-ida-copa-campeones-concacaf-orix\/","url_meta":{"origin":1473265,"position":0},"title":"La Copa de Campeones de la Concacaf busca finalistas: as\u00ed se juegan las semifinales","author":"","date":"abril 27, 2026","format":false,"excerpt":"La Concacaf busca nuevo rey y este martes y mi\u00e9rcoles comenzar\u00e1 a desandar el camino de unas semifinales que prometen levantar a\u00fan m\u00e1s la temperatura entre los clubes de la Liga MX y los de la MLS. Ser\u00e1n dos duelos M\u00e9xico vs. Estados Unidos y en ambos casos la serie\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472039,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/09\/octavos-concacaf-champions-cup-2026-calendario-orix\/","url_meta":{"origin":1473265,"position":1},"title":"Comienzan los octavos de final de la Concacaf Champions Cup 2026: calendario con todos los cruces, d\u00edas y horarios","author":"","date":"marzo 9, 2026","format":false,"excerpt":"La competici\u00f3n m\u00e1s importante de Norteam\u00e9rica, Centroam\u00e9rica y el Caribe a nivel clubes est\u00e1 lista para comenzar a disputar los octavos de final. A diferencia de otros torneos continentales como la Champions League en Europa o la Copa Libertadores en Sudam\u00e9rica, la Concacaf Champions Cup no tuvo una fase de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470823,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/03\/concacaf-champions-cup-2026-formato-cruces-orix\/","url_meta":{"origin":1473265,"position":2},"title":"Comienza la Concacaf Champions Cup 2026, uno de los dos \u00fanicos torneos que Messi nunca gan\u00f3","author":"","date":"febrero 3, 2026","format":false,"excerpt":"La primera gran emoci\u00f3n del a\u00f1o para el f\u00fatbol de Norteam\u00e9rica, Centroam\u00e9rica y el Caribe est\u00e1 a punto de comenzar. Con el Clausura de la Liga MX ya caminando sus primeros pasos y la MLS a\u00fan en el horizonte (comenzar\u00e1 el 21 de febrero), la Concacaf Champions Cup tendr\u00e1 su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472408,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/20\/cuartos-final-concacaf-champions-cup-2026-orix\/","url_meta":{"origin":1473265,"position":3},"title":"MLS vs. Liga MX: as\u00ed quedaron los enfrentamientos de los cuartos de final en la Concacaf Champions Cup 2026","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Concluy\u00f3 la instancia de los octavos de final de la Concacaf Champions Cup 2026 con los dos \u00faltimos encuentros de vuelta de este jueves. Los \u00c1ngeles Galaxy complet\u00f3 la obra en la revancha, logrando una victoria de 3-0 sobre el Mount Pleasant y goleando nuevamente al equipo jamaicano por 0-3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453283,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/10\/02\/inter-miami-supporters-shield-mls-messi-titulo-orix\/","url_meta":{"origin":1473265,"position":4},"title":"Inter Miami est\u00e1 a un triunfo de conquistar el Supporters&#8217; Shield: \u00bfpodr\u00eda Messi estar en el Mundial de Clubes de 2025?","author":"","date":"octubre 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Inter Miami juega un partido decisivo este mi\u00e9rcoles en su visita al Columbus Crew: una victoria le dar\u00eda al equipo capitaneado por Lionel Messi el t\u00edtulo del Supporters' Shield, que premia al mejor equipo de la temporada regular en la Major League Soccer (MLS).Ser\u00eda el segundo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461577,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/24\/inter-miami-whitecaps-messi-mascherano-orix\/","url_meta":{"origin":1473265,"position":5},"title":"El Inter Miami visita a los Whitecaps para jugar un partido clave en la historia del equipo, seg\u00fan Mascherano","author":"","date":"abril 24, 2025","format":false,"excerpt":"El Inter Miami de Lionel Messi y compa\u00f1\u00eda est\u00e1 en las semifinales de la Copa de Campeones de la Concacaf y tiene como rival a los Whitecaps de Vancouver, club que se encuentra en un gran momento en la Major League Soccer (MLS).Los Whitecaps en la MLS comandan la Conferencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1473265"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473265\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1473265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1473265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1473265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}