{"id":1473267,"date":"2026-04-17T00:03:53","date_gmt":"2026-04-17T07:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/"},"modified":"2026-04-17T00:03:53","modified_gmt":"2026-04-17T07:03:53","slug":"primer-papa-estadounidense-administracion-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","title":{"rendered":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump"},"content":{"rendered":"<p>Al volar a Argelia el lunes para dar inicio a su hist\u00f3rica gira por \u00c1frica, el papa Le\u00f3n XIV ten\u00eda que tomar una decisi\u00f3n. Pod\u00eda ignorar la extraordinaria diatriba que Donald Trump le lanz\u00f3 en las redes sociales durante la noche, o pod\u00eda enfrentarla directamente.<\/p>\n<p>Finalmente, opt\u00f3 por la segunda opci\u00f3n, dando el paso, sumamente inusual, de criticar al Gobierno de Trump.<\/p>\n<p>En declaraciones a los periodistas a bordo del avi\u00f3n papal, el papa afirm\u00f3 no temer al Gobierno y que continuar\u00eda manifest\u00e1ndose en\u00e9rgicamente en contra de la guerra.<\/p>\n<p>\u201cNo creo que el mensaje del Evangelio deba ser mal utilizado, como algunos lo est\u00e1n haciendo\u201d, declar\u00f3, y agreg\u00f3: \u201cSe han perdido demasiadas vidas inocentes\u2026 Creo que alguien debe alzar la voz y decir que hay una mejor manera\u201d.<\/p>\n<p>Las declaraciones de Le\u00f3n XIV lo han consolidado como el contrapeso internacional m\u00e1s visible a Trump y han propiciado un enfrentamiento sin precedentes entre el primer papa estadounidense y un presidente de Estados Unidos que le ha lanzado repetidos ataques.<\/p>\n<p>Sin embargo, el pont\u00edfice, nacido en Chicago y conocido por su estilo amable y discreto, no busc\u00f3 esta confrontaci\u00f3n.<\/p>\n<p>Habiendo dedicado gran parte de su vida adulta a la Orden de San Agust\u00edn, cuyos frailes y monjas hacen votos de pobreza, castidad y obediencia, con \u00e9nfasis en la unidad y la comunidad, sus prioridades son la unidad y la construcci\u00f3n de puentes.<\/p>\n<p>En lugar de asumir el cargo con una avalancha de decretos ejecutivos o iniciativas sensacionalistas, el papa ha dedicado gran parte de su primer a\u00f1o a escuchar y realizar cambios graduales.<\/p>\n<p>Tambi\u00e9n ha enfatizado la importancia de las instituciones multilaterales como las Naciones Unidas y el respeto al derecho internacional, en un momento en que el presidente de Estados Unidos ha insinuado que no se siente obligado por dichas normas.<\/p>\n<p>Aunque es una persona m\u00e1s reservada que su predecesor, el papa Francisco, la operaci\u00f3n militar estadounidense en Ir\u00e1n ha sacado a relucir la firmeza de Le\u00f3n XIV y su disposici\u00f3n a expresarse con franqueza.<\/p>\n<p>Decidi\u00f3 nombrar a Trump personalmente, algo que los papas rara vez hacen. Si bien no ha mencionado a otros miembros de la administraci\u00f3n Trump, sus declaraciones de que \u201cDios no escucha las oraciones de quienes hacen la guerra\u201d parecieron aludir al af\u00e1n del secretario de Defensa estadounidense, Pete Hegseth, por enmarcar el conflicto en Medio Oriente en t\u00e9rminos religiosos.<\/p>\n<p>Que los papas aboguen por la paz y se opongan a la guerra no es nada nuevo. El papa Juan Pablo II se opuso firmemente a la invasi\u00f3n de Iraq liderada por Estados Unidos en 2003. Sin embargo, con un papa estadounidense, la situaci\u00f3n es diferente.<\/p>\n<p>Le\u00f3n XIV habla ingl\u00e9s como lengua materna, algo que no ocurr\u00eda desde el siglo XII, y sus palabras calan hondo en el p\u00fablico estadounidense, en la Casa Blanca y m\u00e1s all\u00e1.<\/p>\n<p>Le\u00f3n XIV tambi\u00e9n es conocido en el Vaticano por su impasibilidad: posee una cierta enigm\u00e1tica cualidad que dificulta su comprensi\u00f3n, y su estilo cuidadoso y deliberado, sin duda, otorga mayor peso a sus palabras.<\/p>\n<p>Durante su estancia en \u00c1frica, Le\u00f3n XIV ha seguido pronunci\u00e1ndose, afirmando que su tiempo en el continente ofrece un mensaje de paz que el mundo necesita escuchar.<\/p>\n<p>Durante una reuni\u00f3n por la paz en Bamenda, Camer\u00fan, Le\u00f3n XIV pronunci\u00f3 un discurso que tuvo repercusiones a nivel mundial.<\/p>\n<p>\u201cEl mundo est\u00e1 siendo asolado por un pu\u00f1ado de tiranos, pero se mantiene unido gracias a una multitud de hermanos y hermanas que nos apoyan\u201d, declar\u00f3.<\/p>\n<p>Y agreg\u00f3: \u201c\u00a1Ay de aquellos que manipulan la religi\u00f3n y el mism\u00edsimo nombre de Dios para su propio beneficio militar, econ\u00f3mico o pol\u00edtico, arrastrando lo sagrado a la oscuridad y la inmundicia!\u201d.<\/p>\n<p>Las tensiones entre el papa y Trump han estado latentes desde antes del \u00faltimo enfrentamiento.<\/p>\n<p>Antes del c\u00f3nclave que eligi\u00f3 al papa Le\u00f3n XIV el a\u00f1o pasado, el presidente caus\u00f3 revuelo al publicar una imagen de s\u00ed mismo creada con inteligencia artificial, en la que aparec\u00eda como el pont\u00edfice.<\/p>\n<p>Esta imagen recordaba a la que Trump public\u00f3 \u2014y luego elimin\u00f3\u2014 en la que se representaba como una figura similar a Jes\u00fas poco despu\u00e9s de atacar al papa.<\/p>\n<p>Tambi\u00e9n resulta llamativo que, si bien los cardenales eligieron al primer papa estadounidense en los 2.000 a\u00f1os de historia de la Iglesia Cat\u00f3lica, Trump no ha tenido \u2014seg\u00fan consta en los registros p\u00fablicos\u2014 ning\u00fan contacto directo con Le\u00f3n XIV desde entonces.<\/p>\n<p>En cambio, el vicepresidente J.D. Vance, quien se convirti\u00f3 al catolicismo en 2019, asisti\u00f3 a la investidura de Le\u00f3n XIV y le entreg\u00f3 una invitaci\u00f3n para visitar Estados Unidos.<\/p>\n<p>El Vaticano ha declarado que el papa no visitar\u00e1 Estados Unidos en 2026 y que, en su lugar, planea pasar el 4 de julio \u2014el 250 aniversario de la independencia estadounidense\u2014 en la isla de Lampedusa, al sur de Italia, un importante punto de llegada para inmigrantes.<\/p>\n<p> Es dif\u00edcil imaginar que el papa visite Estados Unidos mientras Trump sea presidente.<\/p>\n<p>El martes, Vance intervino en la pol\u00e9mica, diciendo que el papa debe ser \u201ccuidadoso\u201d al hablar de teolog\u00eda y que deber\u00eda recordar la teor\u00eda de la \u201cguerra justa\u201d cuando hable del conflicto con Ir\u00e1n.<\/p>\n<p>La menci\u00f3n que hace Vance de la teor\u00eda de la guerra justa resulta llamativa. Desarrollada a lo largo de los siglos, esta doctrina es frecuentemente utilizada por analistas militares como criterio \u00e9tico y moral para los conflictos armados.<\/p>\n<p>Uno de sus principales art\u00edfices es San Agust\u00edn de Hipona, padre espiritual de la orden religiosa cat\u00f3lica a la que pertenece Le\u00f3n XIV.<\/p>\n<p>Durante su estancia en Argelia, el papa realiz\u00f3 una peregrinaci\u00f3n personal al lugar donde Agust\u00edn fue obispo a finales del siglo IV y principios del V, y ha se\u00f1alado que la gente no considera justa la guerra en Ir\u00e1n.<\/p>\n<p>Vatican News argument\u00f3 en un editorial publicado un d\u00eda despu\u00e9s de las declaraciones de Vance que, en las \u00faltimas d\u00e9cadas, la ense\u00f1anza cat\u00f3lica ha demostrado \u201clo cada vez m\u00e1s dif\u00edcil que resulta afirmar que existe una \u2018guerra justa\u2019\u201d, particularmente en una \u201cera at\u00f3mica\u201d.<\/p>\n<p>El director editorial Andrea Tornielli insisti\u00f3 en que Le\u00f3n XIV, \u201cante la locura de la escalada del conflicto y el gasto desproporcionado en rearme\u201d, contin\u00faa \u201cpor el camino abierto por sus predecesores, abogando por la paz, el di\u00e1logo y la negociaci\u00f3n con realismo y claridad prof\u00e9tica\u201d.<\/p>\n<p>Es probable que el Vaticano tome m\u00e1s en serio las cr\u00edticas de Vance al papa.<\/p>\n<p>Como converso al catolicismo, ya ha utilizado una ense\u00f1anza de San Agust\u00edn para defender la represi\u00f3n inmigratoria del Gobierno de Trump. Le\u00f3n XIV, por su parte, ha criticado el trato que reciben los inmigrantes en Estados Unidos.<\/p>\n<p>\u201cDesde que Vance ingres\u00f3 en la Iglesia, se ha alineado con un grupo de fil\u00f3sofos, te\u00f3logos y expertos de extrema derecha que afirman ser los int\u00e9rpretes aut\u00e9nticos de La <em>Ciudad de Dios<\/em> de Agust\u00edn [una obra fundamental]\u201d, declar\u00f3 a CNN Dawn Eden Goldstein, autora y acad\u00e9mica cat\u00f3lica.<\/p>\n<p>Seg\u00fan ella, la \u201cinnegable pericia del papa Le\u00f3n en el pensamiento de Agust\u00edn\u2026 supone una amenaza directa para los esfuerzos del vicepresidente y sus amigos posliberales por presentarse ante los cat\u00f3licos como int\u00e9rpretes autorizados de las ense\u00f1anzas sociales y pol\u00edticas de la Iglesia\u201d.<\/p>\n<p>Le\u00f3n XIV se convirti\u00f3 en papa pocos meses despu\u00e9s de la reelecci\u00f3n de Trump como presidente. Anteriormente, la idea de un papa estadounidense se consideraba imposible, ya que los cardenales no quer\u00edan aliarse con la potencia dominante mundial.<\/p>\n<p>Sin embargo, el regreso de Trump a la Casa Blanca cambi\u00f3 la percepci\u00f3n que los cardenales ten\u00edan de Estados Unidos en el escenario internacional. Les abri\u00f3 la puerta a romper con la tradici\u00f3n, y la figura de Robert Prevost, con su dilatada experiencia en Latinoam\u00e9rica, lo convirti\u00f3 en una figura atractiva.<\/p>\n<p>La hist\u00f3rica decisi\u00f3n no fue muy diferente a la del c\u00f3nclave de 1978 que eligi\u00f3 a Juan Pablo II. El primer papa polaco, y el primer pont\u00edfice no italiano en 400 a\u00f1os, fue elegido en plena Guerra Fr\u00eda y desempe\u00f1ar\u00eda un papel crucial en la ca\u00edda del comunismo en Europa del Este.<\/p>\n<p>\u201cEste \u00faltimo incidente me recuerda a Harold Macmillan [ex primer ministro del Reino Unido], quien dijo que entre las tres instituciones que ninguna persona sensata deber\u00eda atacar est\u00e1 el Vaticano\u201d, declar\u00f3 Gerard O\u2019Connell, corresponsal del Vaticano para la revista America, un medio cat\u00f3lico, y observador experimentado de los asuntos eclesi\u00e1sticos.<\/p>\n<p>\u201cMe imagino que el Vaticano lo ver\u00e1 desde la perspectiva hist\u00f3rica, sabiendo que los imperios van y vienen\u201d, se\u00f1al\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al volar a Argelia el lunes para dar inicio a su hist\u00f3rica gira por \u00c1frica, el papa Le\u00f3n XIV ten\u00eda que tomar una decisi\u00f3n. Pod\u00eda ignorar la extraordinaria diatriba que Donald Trump le lanz\u00f3 en las redes sociales durante la noche, o pod\u00eda enfrentarla directamente. Finalmente, opt\u00f3 por la segunda opci\u00f3n, dando el paso, sumamente [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473267","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al volar a Argelia el lunes para dar inicio a su hist\u00f3rica gira por \u00c1frica, el papa Le\u00f3n XIV ten\u00eda que tomar una decisi\u00f3n. Pod\u00eda ignorar la extraordinaria diatriba que Donald Trump le lanz\u00f3 en las redes sociales durante la noche, o pod\u00eda enfrentarla directamente. Finalmente, opt\u00f3 por la segunda opci\u00f3n, dando el paso, sumamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T07:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump\",\"datePublished\":\"2026-04-17T07:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/\"},\"wordCount\":1558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/\",\"name\":\"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-17T07:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump - Noticias","og_description":"Al volar a Argelia el lunes para dar inicio a su hist\u00f3rica gira por \u00c1frica, el papa Le\u00f3n XIV ten\u00eda que tomar una decisi\u00f3n. Pod\u00eda ignorar la extraordinaria diatriba que Donald Trump le lanz\u00f3 en las redes sociales durante la noche, o pod\u00eda enfrentarla directamente. Finalmente, opt\u00f3 por la segunda opci\u00f3n, dando el paso, sumamente [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-17T07:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump","datePublished":"2026-04-17T07:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/"},"wordCount":1558,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","name":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-17T07:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump","url":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-17T07:03:53Z","datePublished":"2026-04-17T07:03:53Z","dateModified":"2026-04-17T07:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo el primer papa estadounidense est\\u00e1 recuperando los valores cristianos frente a las cr\\u00edticas de la administraci\\u00f3n Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/17\\\/primer-papa-estadounidense-administracion-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/04\\\/17\\\/primer-papa-estadounidense-administracion-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-17T07:03:53Z\",\"datePublished\":\"2026-04-17T07:03:53Z\",\"dateModified\":\"2026-04-17T07:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461943,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/03\/rixio-portillo-yo-creo-que-tiene-que-haber-la-continuidad-de-la-sensibilidad-de-papa-francisco\/","url_meta":{"origin":1473267,"position":0},"title":"Rixio Portillo: &#171;Yo creo que tiene que haber la continuidad de la sensibilidad de Papa Francisco&#187;","author":"","date":"mayo 3, 2025","format":false,"excerpt":"Rixio Portillo, profesor e investigador de la Universidad de Monterrey habl\u00f3 este s\u00e1bado con CNN Radio sobre el c\u00f3nclave para elegir al sucesor del Papa Francisco.En Dicen que Dicen con Alberto Lotuf indic\u00f3: \u201cYo creo que todav\u00eda no hay claridad, porque seg\u00fan lo que nos han dicho y lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472867,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/04\/nombre-dios-papa-leon-xiv-opone-justificacion-guerra-trax\/","url_meta":{"origin":1473267,"position":1},"title":"No en nombre de Dios: c\u00f3mo el papa Le\u00f3n XIV se opone a la justificaci\u00f3n divina de la guerra","author":"","date":"abril 4, 2026","format":false,"excerpt":"El martes por la noche, en un ventoso Castel Gandolfo, le hice una pregunta al papa Le\u00f3n XIV. Con la guerra potencialmente escalando en Medio Oriente, quer\u00eda saber si ten\u00eda un mensaje para el presidente Donald Trump y otros l\u00edderes de Estados Unidos e Israel.Su respuesta fue reveladora. El primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461515,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","url_meta":{"origin":1473267,"position":2},"title":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano","author":"","date":"abril 22, 2025","format":false,"excerpt":"El 13 de marzo de 2013, Oscar Crespo estaba viendo la televisi\u00f3n en su natal Buenos Aires cuando vio el humo blanco apareciendo sobre la Capilla Sixtina en el Vaticano: se hab\u00eda elegido un nuevo papa.Al igual que millones de cat\u00f3licos en Latinoam\u00e9rica, ten\u00eda curiosidad por saber qui\u00e9n suceder\u00eda al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473093,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/13\/papa-leon-xiv-miedo-trump-guerra-trax\/","url_meta":{"origin":1473267,"position":3},"title":"El papa dice que &#171;no tiene miedo de la administraci\u00f3n Trump&#187; tras las cr\u00edticas del presidente a su posici\u00f3n sobre la guerra","author":"","date":"abril 13, 2026","format":false,"excerpt":"El papa Le\u00f3n XIV rechaz\u00f3 con firmeza este lunes las cr\u00edticas del presidente de Estados Unidos, Donald Trump, y defendi\u00f3 su postura de buscar la paz y rechazar la violencia en medio de la guerra con Ir\u00e1n.\u201cNo tengo miedo de la administraci\u00f3n Trump ni de hablar en voz alta del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473309,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","url_meta":{"origin":1473267,"position":4},"title":"\u00bfCu\u00e1ndo una guerra puede considerarse &#171;justa&#187;?","author":"","date":"abril 18, 2026","format":false,"excerpt":"Un resultado interesante de la extra\u00f1a y, en gran medida, unilateral disputa del presidente Donald Trump con el papa es que existe cierto debate \u2014visto a trav\u00e9s del prisma de la teolog\u00eda cat\u00f3lica\u2014 sobre si la guerra de Estados Unidos e Israel contra Ir\u00e1n constituye una \u201cguerra justa\u201d.Sin volver a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471221,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/14\/bannon-cortejo-epstein-derribar-papa-francisco-trax\/","url_meta":{"origin":1473267,"position":5},"title":"Steve Bannon cortej\u00f3 a Epstein en sus esfuerzos por &#171;derribar&#187; al papa Francisco","author":"","date":"febrero 14, 2026","format":false,"excerpt":"Steve Bannon, exasesor de la Casa Blanca del presidente Donald Trump, discuti\u00f3 estrategias de oposici\u00f3n con el delincuente sexual convicto Jeffrey Epstein contra el papa Francisco, y Bannon afirm\u00f3 que esperaba \u201cderribar\u201d al pont\u00edfice, seg\u00fan archivos recientemente publicados por el Departamento de Justicia de Estados Unidos.Los mensajes enviados entre ambos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1473267"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1473267\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1473267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1473267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1473267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}