{"id":1438644,"date":"2023-04-12T15:15:50","date_gmt":"2023-04-12T22:15:50","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1438644"},"modified":"2024-03-11T15:15:24","modified_gmt":"2024-03-11T22:15:24","slug":"participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/","title":{"rendered":"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude"},"content":{"rendered":"<p><span style=\"font-weight: 400\">DENVER, CO. (Abril de 2023) &#8211; El Sorteo de <\/span><a href=\"https:\/\/noticiasya.com\/colorado\/articulos-relacionados\/3408992027\/St.%20Jude%20Dream%20Home\/es\/\"><span style=\"font-weight: 400\">St. Jude Dream Home<\/span><\/a><span style=\"font-weight: 400\"> se est\u00e1 construyendo por Covington Homes en Banning Lewis Ranch y los boletos ya est\u00e1n a la venta para ganar la casa de ensue\u00f1o de 5 rec\u00e1maras, 3.5 ba\u00f1os y una superficie estimada de 2,615 pies cuadrados, valorada en aproximadamente $685,000 d\u00f3lares.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Con s\u00f3lo $100, usted tendr\u00e1 la oportunidad de ganar la casa del Sorteo St. Jude Dream Home y otros grandes premios. \u00a1Y marcar la diferencia en la vida de los ni\u00f1os con c\u00e1ncer! Los ganadores se dar\u00e1n a conocer el 28 de Junio del 2023.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Usted puede reservar su boleto llamando al 1-800-276-7695 o visitando la p\u00e1gina <\/span><a href=\"https:\/\/www.stjude.org\/es\/como-donar\/dream-home\/colorado-springs.html\"><span style=\"font-weight: 400\">http:\/\/www.sorteodreamhome.org<\/span><\/a><span style=\"font-weight: 400\">. <\/span><\/p>\n<p><span style=\"font-weight: 400\">El Sorteo de St. Jude Dream Home beneficia a St. Jude Children\u2019s Research Hospital\u00ae. St. Jude Children\u2019s Research Hospital est\u00e1 a la vanguardia de la investigaci\u00f3n y el tratamiento del c\u00e1ncer infantil y otras enfermedades terminales a nivel mundial.\u00a0 St. Jude tiene las mejores tasas de supervivencia en el mundo para los c\u00e1nceres infantiles m\u00e1s agresivos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Este sorteo se ha convertido en una de las campa\u00f1as de recaudaci\u00f3n de fondos m\u00e1s exitosas de St. Jude, recaudando m\u00e1s de $545 millones para el hospital desde su creaci\u00f3n en 1991.\u00a0 \u00a1Forma parte de este gran movimiento!<\/span><\/p>\n<p><span style=\"font-weight: 400\">Inf\u00f3rmese visitando <\/span><a href=\"http:\/\/www.sorteodreamhome.org\/\"><span style=\"font-weight: 400\">http:\/\/www.sorteodreamhome.org<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<h3><i><span style=\"font-weight: 400\">\u00a1CON ESTE SORTEO, LOS NI\u00d1OS SON LOS QUE GANAN!<\/span><\/i><\/h3>\n<p><span style=\"font-weight: 400\">Acerca de St. Jude Children&#8217;s Research Hospital<\/span><\/p>\n<p><span style=\"font-weight: 400\">St. Jude Children\u2019s Research Hospital est\u00e1 a la vanguardia de la investigaci\u00f3n y el tratamiento del c\u00e1ncer infantil y otras enfermedades terminales a nivel mundial. St. Jude tienen las mejores tasas de supervivencia en el mundo para los canceres infantiles m\u00e1s agresivos. Los tratamientos descubiertos en St. Jude han ayudado a incrementar la tasa de supervivencia del c\u00e1ncer infantil, de un 20 por ciento cuando el hospital abri\u00f3 sus puertas hace m\u00e1s de 50 a\u00f1os, a un 80 por ciento en la actualidad. St. Jude est\u00e1 trabajando para incrementar la tasa de supervivencia del c\u00e1ncer infantil a un 90 por ciento. Asimismo, St. Jude comparte libremente sus descubrimientos, ya <\/span><span style=\"font-weight: 400\">que un ni\u00f1o salvado en St. Jude significa que los m\u00e9dicos y cient\u00edficos alrededor del mundo pueden utilizar dicho conocimiento para salvar a miles de ni\u00f1os.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Las familias nunca reciben una factura por parte de St. Jude, incluyendo su tratamiento, transporte, hospedaje o alimentaci\u00f3n, porque en St. Jude las familias se dedican cien por ciento en ayudar a sus hijos a vivir. \u00danase a la misi\u00f3n de St. Jude visitando <a href=\"http:\/\/www.hospitalsanjudas.org\">hospitalsanjudas.org<\/a> o s\u00edganos en <a href=\"http:\/\/www.facebook.com\/stjude\">facebook.com\/stjude<\/a> y <a href=\"http:\/\/www.twitter.com\/stjude\">twitter.com\/stjude<\/a>.<\/span><\/p>\n<p><strong>ACTUALIZACI\u00d3N: FELICIDADES A LOS GANADORES<\/strong><\/p>\n<ul>\n<li><em>St.\u00a0Jude Dream Home Giveaway<\/em>\u00a0House:\u00a0<strong>Davina Cain of Colorado Springs, CO<\/strong><\/li>\n<li>Tickets on Sale: $7,500 VISA gift card:\u00a0<strong>Robert Peter of Pueblo, CO<\/strong><\/li>\n<li>Early Bird: HotSpot Pace 5-person hot tub with cover, coverlifter and step:\u00a0<strong>Daryl Mergen of Colorado Springs, CO<\/strong><\/li>\n<li>Bonus Prize: American Airlines AAdvantage<sup>\u00ae<\/sup>\u00a0miles, valued at $5,000:\u00a0<strong>Joyce Gonzales of Santa Fe, NM<\/strong><\/li>\n<li>$10,000 shopping spree at Furniture Row:\u00a0<strong>Dale Wilburn of Colorado Springs, CO<\/strong><\/li>\n<\/ul>\n<p><strong>Raised: $1,150,000<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"Felicidades a los ganadores de St Jude Dream Home\" frameborder=\"0\" width=\"500\" height=\"281\" src=\"https:\/\/geo.dailymotion.com\/player.html?video=x8m68b2&#038;\" allowfullscreen allow=\"autoplay; fullscreen; picture-in-picture; web-share\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contribuya a la misi\u00f3n de salvar la vida de ni\u00f1os con c\u00e1ncer y otras enfermedades terminales<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[36],"tags":[],"class_list":["post-1438644","post","type-post","status-publish","format-video","hentry","category-comunidad","post_format-post-format-video","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude - Noticias\" \/>\n<meta property=\"og:description\" content=\"Contribuya a la misi\u00f3n de salvar la vida de ni\u00f1os con c\u00e1ncer y otras enfermedades terminales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-12T22:15:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T22:15:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude\",\"datePublished\":\"2023-04-12T22:15:50+00:00\",\"dateModified\":\"2024-03-11T22:15:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/\"},\"wordCount\":544,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/\",\"name\":\"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-04-12T22:15:50+00:00\",\"dateModified\":\"2024-03-11T22:15:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/hartford\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude - Noticias","og_description":"Contribuya a la misi\u00f3n de salvar la vida de ni\u00f1os con c\u00e1ncer y otras enfermedades terminales","og_url":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/","og_site_name":"Noticias","article_published_time":"2023-04-12T22:15:50+00:00","article_modified_time":"2024-03-11T22:15:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/"},"author":{"name":"","@id":""},"headline":"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude","datePublished":"2023-04-12T22:15:50+00:00","dateModified":"2024-03-11T22:15:24+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/"},"wordCount":544,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Comunidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/","url":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/","name":"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-04-12T22:15:50+00:00","dateModified":"2024-03-11T22:15:24+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/hartford\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ganadores del Sorteo de la Casa de los Sue\u00f1os del Hospital Infantil St. Jude","url":"http:\/\/noticiasya.com\/hartford\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/04\/12\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Comunidad","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-04-12T22:15:50Z","datePublished":"2023-04-12T22:15:50Z","dateModified":"2024-03-11T22:15:24Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ganadores del Sorteo de la Casa de los Sue\\u00f1os del Hospital Infantil St. Jude\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/04\\\/12\\\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/04\\\/12\\\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-2023\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Comunidad\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-04-12T22:15:50Z\",\"datePublished\":\"2023-04-12T22:15:50Z\",\"dateModified\":\"2024-03-11T22:15:24Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1421707,"url":"https:\/\/noticiasya.com\/hartford\/2022\/08\/23\/participa-para-ganar-la-casa-del-sorteo-st-jude-dream-home-y-otros-grandes-premios\/","url_meta":{"origin":1438644,"position":0},"title":"Participa para ganar la casa del Sorteo St. Jude Dream Home","author":"agomez","date":"agosto 23, 2022","format":"video","excerpt":"Usted puede reservar su boleto llamando al 1-800-276-7695 o visitando la p\u00e1gina http:\/\/www.sorteodreamhome.org.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/hartford\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1440499,"url":"https:\/\/noticiasya.com\/hartford\/2023\/08\/23\/unete-a-la-noble-causa-de-st-jude-compra-un-boleto-para-la-casa-de-los-suenos-de-st-jude\/","url_meta":{"origin":1438644,"position":1},"title":"\u00a1Felicidades a todos los ganadores del sorteo St Jude!","author":"","date":"agosto 23, 2023","format":"video","excerpt":"Usted puede reservar su boleto llamando al 1-800-276-7695 o visitando la p\u00e1gina http:\/\/www.sorteodreamhome.org.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/hartford\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1385979,"url":"https:\/\/noticiasya.com\/hartford\/2022\/04\/18\/ayude-y-participe-por-la-casa-de-sus-suenos-con-st-jude-dream-home\/","url_meta":{"origin":1438644,"position":2},"title":"Ayude y participe por la casa de sus sue\u00f1os, con St. Jude Dream Home\u00ae","author":"agomez","date":"abril 18, 2022","format":"video","excerpt":"Con s\u00f3lo $100 usted tiene la oportunidad de ganar una casa nueva y ayudar a ni\u00f1os con c\u00e1ncer.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/hartford\/categoria\/comunidad"},"img":{"alt_text":"","src":"http:\/\/dailymotion.com\/thumbnail\/video\/x8a54g9?autoplay=1","width":350,"height":200},"classes":[]},{"id":1450950,"url":"https:\/\/noticiasya.com\/hartford\/2024\/07\/08\/felicidades-a-los-ganadores-de-st-jude-2024\/","url_meta":{"origin":1438644,"position":3},"title":"\u00a1Felicidades a los ganadores de St. Jude 2024!","author":"Cintli Luna","date":"julio 8, 2024","format":false,"excerpt":"Queremos expresar nuestro m\u00e1s sincero agradecimiento a todas las personas que generosamente hicieron sus donaciones. Su apoyo es fundamental para nosotros y nos permite seguir adelante con nuestra misi\u00f3n. Gracias a su compromiso y solidaridad logramos recaudar m\u00e1s de 1.2 millones de d\u00f3lares para St.Jude. Felicitamos calurosamente a los ganadores\u2026","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/hartford\/categoria\/comunidad"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Screen-Shot-2024-07-08-at-15.54.22.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Screen-Shot-2024-07-08-at-15.54.22.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Screen-Shot-2024-07-08-at-15.54.22.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Screen-Shot-2024-07-08-at-15.54.22.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Screen-Shot-2024-07-08-at-15.54.22.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Screen-Shot-2024-07-08-at-15.54.22.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1415596,"url":"https:\/\/noticiasya.com\/hartford\/2022\/07\/26\/los-lugares-que-han-vendido-boletos-ganadores-de-mega-millions-en-colorado\/","url_meta":{"origin":1438644,"position":4},"title":"Los lugares que han vendido boletos ganadores de Mega Millions en Colorado","author":"agomez","date":"julio 26, 2022","format":false,"excerpt":"Nunca alguien en el estado se ha ganado el premio mayor y este martes hay r\u00e9cord en el bote a entregar.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/hartford\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447819,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/07\/powerball-estos-son-los-numeros-ganadores-del-sorteo-del-sabado-trax\/","url_meta":{"origin":1438644,"position":5},"title":"Powerball: estos son los n\u00fameros ganadores del sorteo del s\u00e1bado, que tiene un bote estimado en US$ 1.300 millones","author":"agomez","date":"abril 7, 2024","format":false,"excerpt":"(CNN) -- Ya se han extra\u00eddo los n\u00fameros ganadores del sorteo de Powerball, que tiene un bote estimado en US$ 1.300 millones, el cuarto m\u00e1s grande de la historia de la loter\u00eda.Los n\u00fameros ganadores del s\u00e1bado son 44, 27, 52, 22, 69 y Powerball 9.El sorteo hab\u00eda sido retrasado durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1438644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1438644"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1438644\/revisions"}],"predecessor-version":[{"id":1446820,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1438644\/revisions\/1446820"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1438644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1438644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1438644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}