{"id":1442423,"date":"2023-12-21T11:33:39","date_gmt":"2023-12-21T19:33:39","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442423"},"modified":"2023-12-21T11:33:39","modified_gmt":"2023-12-21T19:33:39","slug":"guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/","title":{"rendered":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s"},"content":{"rendered":"<p>\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed<\/p>\n<p>Columnas de humo tras un ataque israel\u00ed sobre Rafah, Gaza, el 20 de diciembre. Said Khatib\/AFP\/Getty Images<\/p>\n<p>Un muro en Tel Aviv est\u00e1 cubierto de im\u00e1genes de rehenes retenidos en Gaza. (Amir Levy\/Getty Images)<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Columnas de humo tras un ataque israel\u00ed sobre Rafah, Gaza, el 20 de diciembre. Said Khatib\/AFP\/Getty Images Un muro en Tel Aviv est\u00e1 cubierto de im\u00e1genes de rehenes retenidos en Gaza. (Amir Levy\/Getty Images) The-CNN-Wire\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442423","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Columnas de humo tras un ataque israel\u00ed sobre Rafah, Gaza, el 20 de diciembre. Said Khatib\/AFP\/Getty Images Un muro en Tel Aviv est\u00e1 cubierto de im\u00e1genes de rehenes retenidos en Gaza. (Amir Levy\/Getty Images) The-CNN-Wire\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T19:33:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s\",\"datePublished\":\"2023-12-21T19:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/\"},\"wordCount\":79,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/\",\"url\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/\",\"name\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-21T19:33:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/","og_locale":"es_ES","og_type":"article","og_title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias","og_description":"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Columnas de humo tras un ataque israel\u00ed sobre Rafah, Gaza, el 20 de diciembre. Said Khatib\/AFP\/Getty Images Un muro en Tel Aviv est\u00e1 cubierto de im\u00e1genes de rehenes retenidos en Gaza. (Amir Levy\/Getty Images) The-CNN-Wire\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery [&hellip;]","og_url":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/","og_site_name":"Noticias","article_published_time":"2023-12-21T19:33:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/"},"author":{"name":"","@id":""},"headline":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","datePublished":"2023-12-21T19:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/"},"wordCount":79,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/","url":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/","name":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-21T19:33:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-21T19:33:39Z","datePublished":"2023-12-21T19:33:39Z","dateModified":"2023-12-21T19:33:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\\u00f3n de los civiles y m\\u00e1s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/21\\\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/21\\\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-6\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-21T19:33:39Z\",\"datePublished\":\"2023-12-21T19:33:39Z\",\"dateModified\":\"2023-12-21T19:33:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442420,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-5\/","url_meta":{"origin":1442423,"position":0},"title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","author":"","date":"diciembre 21, 2023","format":false,"excerpt":"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edColumnas de humo tras un ataque israel\u00ed sobre Rafah, Gaza, el 20 de diciembre. Said Khatib\/AFP\/Getty ImagesUn muro en Tel Aviv est\u00e1 cubierto de im\u00e1genes de rehenes retenidos en Gaza. (Amir Levy\/Getty Images)The-CNN-Wire\u2122 & \u00a9 2023 Cable News Network, Inc., a Warner\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442431,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/21\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-7\/","url_meta":{"origin":1442423,"position":1},"title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","author":"","date":"diciembre 21, 2023","format":false,"excerpt":"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edColumnas de humo tras un ataque israel\u00ed sobre Rafah, Gaza, el 20 de diciembre. Said Khatib\/AFP\/Getty ImagesUn muro en Tel Aviv est\u00e1 cubierto de im\u00e1genes de rehenes retenidos en Gaza. (Amir Levy\/Getty Images)The-CNN-Wire\u2122 & \u00a9 2023 Cable News Network, Inc., a Warner\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442889,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/30\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-24\/","url_meta":{"origin":1442423,"position":2},"title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edMomentos posteriores a un ataque israel\u00ed en Rafah, en el sur de Gaza, a \u00faltima hora del 27 de diciembre de 2023. (Cr\u00e9dito: Said Khatib\/ AFP\/ Getty Images)Ciudadanos palestinos buscan comida que es distribuida el 28 de diciembre en Rafah, Gaza.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442891,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/30\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-25\/","url_meta":{"origin":1442423,"position":3},"title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edMomentos posteriores a un ataque israel\u00ed en Rafah, en el sur de Gaza, a \u00faltima hora del 27 de diciembre de 2023. (Cr\u00e9dito: Said Khatib\/ AFP\/ Getty Images)Ciudadanos palestinos buscan comida que es distribuida el 28 de diciembre en Rafah, Gaza.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442896,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/30\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-26\/","url_meta":{"origin":1442423,"position":4},"title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edMomentos posteriores a un ataque israel\u00ed en Rafah, en el sur de Gaza, a \u00faltima hora del 27 de diciembre de 2023. (Cr\u00e9dito: Said Khatib\/ AFP\/ Getty Images)Ciudadanos palestinos buscan comida que es distribuida el 28 de diciembre en Rafah, Gaza.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444776,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/01\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-64\/","url_meta":{"origin":1442423,"position":5},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"febrero 1, 2024","format":false,"excerpt":"Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Las personas que huyeron de los combates en Gaza se reunieron en una calle abarrotada en Rafah, en la parte sur del territorio palestino, el 1 de febrero de 2024. Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty ImagesAl fondo se muestra una excavadora militar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442423"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442423\/revisions"}],"predecessor-version":[{"id":1442440,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442423\/revisions\/1442440"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}