{"id":1442471,"date":"2023-12-22T02:33:35","date_gmt":"2023-12-22T10:33:35","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442471"},"modified":"2023-12-22T02:33:35","modified_gmt":"2023-12-22T10:33:35","slug":"auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/","title":{"rendered":"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 La Auditor\u00eda que la Conferencia Episcopal Espa\u00f1ola (CEE) encarg\u00f3 al bufete de abogados Cremades &amp; Calvo Sotelo en febrero de 2022 refleja que en Espa\u00f1a se habr\u00edan presentado 1.383 denuncias por casos de abusos sexuales a menores en el seno de la Iglesia, de las que se deducen 2.056 v\u00edctimas.<\/p>\n<p>As\u00ed lo confirma la propia CEE en el informe de m\u00e1s de 1.000 p\u00e1ginas, titulado \u201cPara dar luz\u201d, que present\u00f3 este jueves y en el que recoge parcialmente los resultados de este encargo, que fue entregado a las autoridades eclesi\u00e1sticas este s\u00e1bado 16 de diciembre.<\/p>\n<p>Del an\u00e1lisis de las denuncias recogidas por Cremades &amp; Calvo Sotelo se deduce que el perfil de las v\u00edctimas es mayoritariamente masculino, que el grueso de los hechos denunciados abarcan el per\u00edodo de 1905 a la actualidad, que el lugar m\u00e1s repetido donde se produc\u00edan los hechos denunciados son los colegios y los seminario mayores y menores, y que el perfil de la persona victimaria corresponde en un 99% a la figura del sacerdote, religioso\/a, profesor\/a responsable acad\u00e9mico.<\/p>\n<p>No obstante, la CEE considera que la auditoria \u201crealiza b\u00e1sicamente una recopilaci\u00f3n de casos aparecidos en estudios previos, sin realizar un estudio en profundidad de los mismos y comete errores de concepto como el de considerar como denuncias distintas las realizadas en las di\u00f3cesis y las del Dicasterio\u201d, dando lugar a duplicidades.<\/p>\n<p>Debido a esas duplicidades, la instituci\u00f3n eclesi\u00e1stica reduce el n\u00famero de denuncias de 1.383 a 1.302.<\/p>\n<p>\u201cPara dar luz\u201d es considerado por sus autores como el informe \u201cm\u00e1s completo de los existentes\u201d y en el que hacen \u201cun recorrido sobre la realidad de los abusos en la Iglesia y en la sociedad desde diversos puntos de vista (eclesial, hist\u00f3rico, sociol\u00f3gico y legal)\u201d. En ese sentido, recoge tambi\u00e9n los aportes de otros estudios realizados hasta la fecha abordando la misma tem\u00e1tica. Ahora bien, destacan que no ofrecen los datos agregados de estos dado que estiman que varios de los casos contemplados se encuentren repetidos.<\/p>\n<p>Las cifras de la Conferencia Episcopal Espa\u00f1ola<\/p>\n<p>Por su parte, la CEE tambi\u00e9n comparte sus propias cifras sobre los abusos sexuales cometidos contra menores de edad o personas mayores de edad vulnerables tras recopilar datos de diferentes organismos que forman parte de la instituci\u00f3n, como por ejemplo las Oficinas diocesanas de protecci\u00f3n de menores, as\u00ed como de casos de abusos sexuales recogidos en los tribunales eclesi\u00e1sticos, tribunales civiles y en los medios de comunicaci\u00f3n.<\/p>\n<p>Hasta el momento y tras auditar las diferentes instituciones eclesi\u00e1sticas afirman tener contabilizados:<\/p>\n<p>806 casos de abusos sexuales registrados; es decir, denunciados, comunicados o conocidos por la Iglesia<br \/>\n205 casos probados<br \/>\n70 casos no probados pero veros\u00edmiles<br \/>\n280 casos no probados<br \/>\n75 casos con investigaci\u00f3n en curso y\/o pendientes de resoluci\u00f3n<br \/>\n13 casos archivados por apreciar la prescripci\u00f3n del delito o el fallecimiento del denunciado o imputado<br \/>\n3 casos con denuncias falsas o manifiestamente infundadas<\/p>\n<p>\u201cEllo no implica, como es obvio, que no puedan existir m\u00e1s casos, como m\u00e1s delitos de los formalmente constatados se cometen siempre en la sociedad\u201d, reconocen los autores en el informe. En cualquier caso, desde la CEE destacan que \u201c la proporci\u00f3n de casos de abuso sexual constatados en el seno de la Iglesia [\u2026] se mantiene dentro de una proporci\u00f3n minoritaria respecto de las cifras globales de abusos sexuales en la sociedad\u201d.<\/p>\n<p>En su reflexi\u00f3n final, los autores del informe se\u00f1alan que los abusos sexuales contra menores \u201chan producido dolor y verg\u00fcenza en todos sus miembros\u201d y que son \u201cson un problema grave en la vida de la Iglesia\u201d pero no exclusivo de la instituci\u00f3n religiosa. Oportunidad en la que ponen en valor sus esfuerzos para atajar el problema a trav\u00e9s de la creaci\u00f3n de \u201clas Oficinas de protecci\u00f3n de menores y de prevenci\u00f3n de abusos en las di\u00f3cesis y en las congregaciones religiosas y otras instituciones de la Iglesia\u201d.<\/p>\n<p>El informe completo puede ser consultado a trav\u00e9s del siguiente enlace.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 La Auditor\u00eda que la Conferencia Episcopal Espa\u00f1ola (CEE) encarg\u00f3 al bufete de abogados Cremades &amp; Calvo Sotelo en febrero de 2022 refleja que en Espa\u00f1a se habr\u00edan presentado 1.383 denuncias por casos de abusos sexuales a menores en el seno de la Iglesia, de las que se deducen 2.056 v\u00edctimas. As\u00ed lo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442471","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013\u2013 La Auditor\u00eda que la Conferencia Episcopal Espa\u00f1ola (CEE) encarg\u00f3 al bufete de abogados Cremades &amp; Calvo Sotelo en febrero de 2022 refleja que en Espa\u00f1a se habr\u00edan presentado 1.383 denuncias por casos de abusos sexuales a menores en el seno de la Iglesia, de las que se deducen 2.056 v\u00edctimas. As\u00ed lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-22T10:33:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores\",\"datePublished\":\"2023-12-22T10:33:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/\"},\"wordCount\":719,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/\",\"name\":\"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-22T10:33:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/","og_locale":"es_ES","og_type":"article","og_title":"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013\u2013 La Auditor\u00eda que la Conferencia Episcopal Espa\u00f1ola (CEE) encarg\u00f3 al bufete de abogados Cremades &amp; Calvo Sotelo en febrero de 2022 refleja que en Espa\u00f1a se habr\u00edan presentado 1.383 denuncias por casos de abusos sexuales a menores en el seno de la Iglesia, de las que se deducen 2.056 v\u00edctimas. As\u00ed lo [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/","og_site_name":"Noticias","article_published_time":"2023-12-22T10:33:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/"},"author":{"name":"","@id":""},"headline":"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores","datePublished":"2023-12-22T10:33:35+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/"},"wordCount":719,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/","url":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/","name":"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-22T10:33:35+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Auditor\u00eda encargada por la Iglesia espa\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/22\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-22T10:33:35Z","datePublished":"2023-12-22T10:33:35Z","dateModified":"2023-12-22T10:33:35Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Auditor\\u00eda encargada por la Iglesia espa\\u00f1ola cifra en 1.383 las denuncias por abusos sexuales a menores\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/22\\\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/22\\\/auditoria-encargada-por-la-iglesia-espanola-cifra-en-1-383-las-denuncias-por-abusos-sexuales-a-menores\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-22T10:33:35Z\",\"datePublished\":\"2023-12-22T10:33:35Z\",\"dateModified\":\"2023-12-22T10:33:35Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450436,"url":"https:\/\/noticiasya.com\/hartford\/2024\/06\/17\/pastor-robert-morris-megaiglesia-dallas-comportamiento-sexual-inapropiado-1980-trax\/","url_meta":{"origin":1442471,"position":0},"title":"Pastor principal de la megaiglesia del \u00e1rea de Dallas admite haber tenido un comportamiento sexual inapropiado en el pasado con una &#171;jovencita&#187; luego de ser acusado de abusar de una menor de 12 a\u00f1os en la d\u00e9cada de 1980","author":"","date":"junio 17, 2024","format":false,"excerpt":"(CNN) -- El pastor Robert Morris, l\u00edder de una megaiglesia del \u00e1rea de Dallas, admiti\u00f3 haber tenido \"un comportamiento sexual inapropiado con una joven\" cuando ten\u00eda poco m\u00e1s de 20 a\u00f1os, seg\u00fan una declaraci\u00f3n obtenida por WFAA, afiliada de CNN.La admisi\u00f3n se produce despu\u00e9s de que la acusadora, Cindy Clemishire,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455183,"url":"https:\/\/noticiasya.com\/hartford\/2024\/10\/17\/arquidiocesis-los-angeles-victimas-abusos-sexuales-clero-ap\/","url_meta":{"origin":1442471,"position":1},"title":"La arquidi\u00f3cesis de Los \u00c1ngeles acuerda pagar US$ 880 millones a las v\u00edctimas de abusos sexuales del clero","author":"","date":"octubre 17, 2024","format":false,"excerpt":"(AP) -- La arquidi\u00f3cesis de Los \u00c1ngeles acord\u00f3 pagar US$ 880 millones a las v\u00edctimas de abusos sexuales por parte del clero que se remontan a d\u00e9cadas atr\u00e1s, en lo que un abogado dijo que era el mayor acuerdo individual de abuso sexual infantil con una arquidi\u00f3cesis cat\u00f3lica, seg\u00fan se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447399,"url":"https:\/\/noticiasya.com\/hartford\/2024\/03\/26\/12-mujeres-demandan-fbi-abusos-sexuales-jeffrey-epstein-trax\/","url_meta":{"origin":1442471,"position":2},"title":"Al menos 12 mujeres demandan al FBI por no protegerlas de los abusos sexuales de Jeffrey Epstein","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Los \"repetidos y continuos fallos, retrasos e inacci\u00f3n\" del FBI permitieron a Jeffrey Epstein mantener su operaci\u00f3n de tr\u00e1fico sexual durante m\u00e1s de 20 a\u00f1os, afirman 12 presuntas v\u00edctimas en una demanda presentada este mi\u00e9rcoles.La demanda, dirigida contra Estados Unidos en el Distrito Sur de Nueva York, afirma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467427,"url":"https:\/\/noticiasya.com\/hartford\/2025\/10\/16\/iglesia-catolica-victimas-abuso-sexual-informe-trax\/","url_meta":{"origin":1442471,"position":3},"title":"Contundente informe interno del Vaticano dice que la Iglesia debe hacer m\u00e1s para ayudar a los supervivientes de abuso sexual","author":"","date":"octubre 16, 2025","format":false,"excerpt":"Una comisi\u00f3n del Vaticano para la protecci\u00f3n de los ni\u00f1os ha dicho que el mal manejo por parte de los l\u00edderes de la Iglesia cat\u00f3lica de las acusaciones de abuso sexual que involucran al clero est\u00e1 causando un \u201cda\u00f1o continuo\u201d a las v\u00edctimas, en un contundente informe publicado el jueves.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461562,"url":"https:\/\/noticiasya.com\/hartford\/2025\/04\/24\/papa-francisco-reformas-abuso-sexual-iglesia-trax\/","url_meta":{"origin":1442471,"position":4},"title":"El papa Francisco impuls\u00f3 reformas clave contra el abuso, pero su sucesor deber\u00e1 asegurarse de aplicarlas","author":"","date":"abril 24, 2025","format":false,"excerpt":"Aunque fue un pont\u00edfice muy sensible a las preocupaciones de los cat\u00f3licos comunes, el papa Francisco mostr\u00f3 una sorprendente ceguera ante la crisis de abusos. No habl\u00f3 mucho sobre el tema durante sus primeros meses en el Vaticano, y cuando lo hizo, en 2014, se mostr\u00f3 a la defensiva, diciendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461586,"url":"https:\/\/noticiasya.com\/hartford\/2025\/04\/24\/cardenal-estadounidense-abusos-sexuales-cerrar-ataud-papa-trax\/","url_meta":{"origin":1442471,"position":5},"title":"Cardenal estadounidense acusado de encubrir esc\u00e1ndalo de abusos sexuales ayudar\u00e1 a cerrar el ata\u00fad del papa Francisco","author":"","date":"abril 24, 2025","format":false,"excerpt":"Un cardenal estadounidense acusado de gestionar mal los casos de abuso sexual clerical fue incluido en la lista de personas que desempe\u00f1ar\u00e1n un papel oficial en las ceremonias para cerrar el f\u00e9retro del papa Francisco y su entierro.El cardenal Roger Mahony, arzobispo retirado de Los \u00c1ngeles, se encuentra entre un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442471"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442471\/revisions"}],"predecessor-version":[{"id":1442487,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442471\/revisions\/1442487"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}