{"id":1442530,"date":"2023-12-23T07:33:32","date_gmt":"2023-12-23T15:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442530"},"modified":"2023-12-23T07:33:32","modified_gmt":"2023-12-23T15:33:32","slug":"medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/","title":{"rendered":"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &#171;centro de mando&#187; de Hamas"},"content":{"rendered":"<p>(CNN) &#8212; Los soldados israel\u00edes que asaltaron un hospital en el norte de Gaza profanaron los cad\u00e1veres de pacientes con topadoras, dejaron que un perro militar maltratara a un hombre en silla de ruedas y dispararon a varios m\u00e9dicos incluso despu\u00e9s de descartar que tuvieran v\u00ednculos con el terrorismo, seg\u00fan denuncias del personal y de pacientes.<\/p>\n<p>Las denuncias se refieren a una operaci\u00f3n de ocho d\u00edas de duraci\u00f3n llevada a cabo por las Fuerzas de Defensa de Israel (FDI) en el hospital Kamal Adwan la semana pasada, que seg\u00fan los militares estaba siendo utilizado como centro de mando y control por Hamas. CNN habl\u00f3 con dos altos cargos del personal m\u00e9dico, otro m\u00e9dico y un paciente del hospital, que aportaron testimonios que corroboran lo sucedido. CNN tambi\u00e9n revis\u00f3 las pruebas de video de algunas de las afirmaciones.<\/p>\n<p>La evidencia pinta un cuadro inquietante de c\u00f3mo las FDI llevaron a cabo la operaci\u00f3n, mientras los m\u00e9dicos eran interrogados por sus conexiones con Hamas y el personal luchaba por tratar a los pacientes atrapados en el interior.<\/p>\n<p>Las FDI afirman que Hamas oculta infraestructura terrorista en las instituciones civiles de Gaza como los hospitales, y en torno a ellas, y que es esencial atacarlas para eliminar a Hamas de Gaza. Pero sus operaciones son pol\u00e9micas, y las organizaciones humanitarias afirman que las instalaciones m\u00e9dicas de Gaza son incapaces de prestar servicios b\u00e1sicos.<\/p>\n<p>La mitad de la poblaci\u00f3n de Gaza est\u00e1 hambrienta, seg\u00fan Naciones Unidas<\/p>\n<p>Una de las acusaciones m\u00e1s graves relacionadas con las operaciones de las FDI en Kamal Adwan es que, cuando las tropas abandonaban el complejo hospitalario, utilizaron excavadoras para desenterrar cad\u00e1veres que hab\u00edan sido enterrados recientemente en cementerios improvisados en el patio del hospital.<\/p>\n<p>&#171;Los soldados desenterraron las tumbas esta ma\u00f1ana y arrastraron los cad\u00e1veres con topadoras, y luego los aplastaron con las topadoras&#187;, dijo el jefe de servicios pedi\u00e1tricos del hospital, Hossam Abu Safiya, en una entrevista telef\u00f3nica el s\u00e1bado. &#171;Nunca hab\u00eda visto algo as\u00ed&#187;.<\/p>\n<p>Los videos e im\u00e1genes que comparti\u00f3 con CNN muestran restos humanos en descomposici\u00f3n esparcidos por los terrenos del hospital.<\/p>\n<p>La denuncia fue apoyada por el jefe de enfermer\u00eda del hospital, Eid Sabbah, y otra enfermera, Asmaa Tanteesh.<\/p>\n<p>&#171;Los cuerpos que estaban fuera, en el patio, fueron arados delante de nuestros ojos&#187;, dijo Tanteesh a CNN. &#171;Todo el tiempo les grit\u00e1bamos y chill\u00e1bamos, pero nuestros gritos ca\u00edan en o\u00eddos sordos&#187;.<\/p>\n<p>Im\u00e1genes satelitales tomadas el 15 de diciembre \u2014justo antes de que las FDI se retiraran de la zona del hospital\u2014 muestran terrenos arrasados fuera del complejo hospitalario.<\/p>\n<p>Las FDI no se refirieron directamente a las acusaciones cuando CNN les pidi\u00f3 que hicieran comentarios, pero reconocieron que hab\u00edan llevado a cabo una operaci\u00f3n en el hospital. &#171;Las tropas detuvieron a 80 terroristas, algunos de los cuales participaron en la atroz masacre del 7 de octubre&#187;, declararon a CNN.<\/p>\n<p>A principios de esta semana, las FDI difundieron un video del interrogatorio al director del hospital y publicaron una declaraci\u00f3n que lo acompa\u00f1aba en la que admit\u00eda que estaba siendo utilizado con fines militares. No estaba claro si la declaraci\u00f3n se hab\u00eda obtenido bajo coacci\u00f3n.<\/p>\n<p>Abu Safiya, director de pediatr\u00eda, y Sabbah, jefe de enfermer\u00eda, replicaron que el hospital solo prestaba servicios m\u00e9dicos y que los detenidos eran civiles y trabajadores m\u00e9dicos.<\/p>\n<p>Im\u00e1genes satelitales del 15 de diciembre muestran los terrenos arrasados del hospital. (Cr\u00e9dito: Maxar Technologies)<\/p>\n<p>Lo que sabemos de la operaci\u00f3n en Kamal Adwan<\/p>\n<p>La operaci\u00f3n del ej\u00e9rcito israel\u00ed en el hospital Kamal Adwan, en el norte de Gaza, parece haber comenzado hace m\u00e1s de una semana, con ataques y bombardeos en la zona del hospital, cuya p\u00e1gina de Facebook dice que depende del Ministerio del Interior, que en Gaza est\u00e1 dirigido por Hamas.<\/p>\n<p>Desde que comenz\u00f3 la guerra entre Israel y Hamas, el hospital tambi\u00e9n ha albergado y tratado a civiles de Gaza heridos y desplazados, seg\u00fan sus cuentas en las redes sociales y testigos presenciales. La operaci\u00f3n se intensific\u00f3 el lunes 11 de diciembre, el mismo d\u00eda en que el director del hospital, Dr. Ahmed Al Kahlot, dijo a CNN que el centro hab\u00eda sido cercado por las fuerzas israel\u00edes.<\/p>\n<p>Al d\u00eda siguiente, las fuerzas israel\u00edes derribaron el muro occidental del complejo hospitalario, seg\u00fan Abu Safiya, quien afirm\u00f3 que los soldados se dirigieron al hospital con altavoces, ordenando a los hombres que se refugiaban en su interior que salieran.<\/p>\n<p>Lo que ocurri\u00f3 despu\u00e9s fue &#171;m\u00e1s all\u00e1 de una pesadilla&#187; para quienes permanecieron en el hospital, dijo.<\/p>\n<p>Seg\u00fan Abu Safiya, a \u00e9l y a otros cuatro m\u00e9dicos se les permiti\u00f3 permanecer en el hospital y atender a 62 personas, entre ellas varios beb\u00e9s. Mientras describ\u00eda la semana, se apresur\u00f3 a hablar, temiendo que la se\u00f1al del tel\u00e9fono m\u00f3vil se cortara, como ocurre a menudo en Gaza estos d\u00edas. Rodeado por las tropas israel\u00edes, y con partes del complejo gravemente da\u00f1adas por los bombardeos, no hab\u00eda atenci\u00f3n que pudiera ofrecer, dijo. El hospital carec\u00eda de alimentos, agua, electricidad y leche para los ni\u00f1os, y apenas le quedaban medicamentos que administrar.<\/p>\n<p>Tanteesh, la enfermera, recuerda haber pedido agua en vano. Las tropas israel\u00edes estaban &#171;a medio metro de nosotros y nos rodeaban en el patio. No ten\u00edamos agua, nuestras gargantas estaban secas y est\u00e1bamos sedientos y rog\u00e1ndoles solo por un vaso de agua desde la ma\u00f1ana hasta la noche&#187;, dijo.<\/p>\n<p>Algunos ni\u00f1os murieron durante la operaci\u00f3n israel\u00ed en el hospital, dijo, y a\u00f1adi\u00f3 que las enfermeras intentaron diluir la leche con una soluci\u00f3n salina para tratar de alimentar a m\u00e1s de los pacientes m\u00e1s j\u00f3venes del hospital.<\/p>\n<p>Consejo de Seguridad de la ONU aprueba resoluci\u00f3n sobre Gaza que incluye pausas y corredores humanitarios<\/p>\n<p>El Ministerio de Sanidad de Gaza, controlado por Hamas, pidi\u00f3 a las organizaciones de derechos humanos que abrieran urgentemente una investigaci\u00f3n sobre lo que calific\u00f3 de &#171;masacre del hospital Kamal Adwan, donde los ni\u00f1os fueron asediados sin agua, alimentos, electricidad ni agua durante largos periodos&#187;.<\/p>\n<p>El jefe de la Organizaci\u00f3n Mundial de la Salud, Tedros Adhanom Ghebreyesus, denunci\u00f3 el domingo que la &#171;destrucci\u00f3n efectiva&#187; de Kamal Adwan por parte de las fuerzas israel\u00edes en los \u00faltimos d\u00edas hab\u00eda causado la muerte de al menos ocho pacientes, entre ellos un ni\u00f1o de nueve a\u00f1os.<\/p>\n<p>Palestinos inspeccionan los da\u00f1os tras una incursi\u00f3n israel\u00ed en el hospital Kamal Adwan. (Cr\u00e9dito: Fadi Alwhidifa\/Reuters)<\/p>\n<p>Por qu\u00e9 Israel lleva a cabo operaciones en hospitales<\/p>\n<p>Israel ha centrado una enorme atenci\u00f3n en los hospitales de Gaza desde que comenz\u00f3 su ofensiva terrestre a finales de octubre. Como justificaci\u00f3n, ha tratado de presentar lo que dice que son pruebas del uso por parte de Hamas de instalaciones m\u00e9dicas como centros militares y ha invitado a los medios de comunicaci\u00f3n a filmar t\u00faneles con salas subterr\u00e1neas situados bajo el mayor hospital de Gaza, Shifa. Tambi\u00e9n ha mostrado a los periodistas armas que dice haber encontrado en otros hospitales.<\/p>\n<p>Las pruebas de actividad de los combatientes halladas en Kamal Adwan, seg\u00fan las FDI, inclu\u00edan &#171;numerosas armas, entre ellas AK-47, RPG, artefactos explosivos, equipo militar de Nukhba (comando de Hamas), equipo tecnol\u00f3gico y documentos de inteligencia de Hamas&#187;.<\/p>\n<p>El martes, las FDI y el servicio de seguridad israel\u00ed hicieron p\u00fablico un video editado del interrogatorio al director de Kamal Adwan, Al Kahlot, bajo custodia israel\u00ed. En una declaraci\u00f3n que acompa\u00f1aba al video se afirmaba que Al Kahlot hab\u00eda admitido que Hamas utilizaba hospitales con fines militares y que formaba parte de la organizaci\u00f3n. Sin embargo, no est\u00e1 claro c\u00f3mo obtuvieron los funcionarios israel\u00edes la declaraci\u00f3n de Al Kahlot y si fue veraz o se hizo bajo coacci\u00f3n.<\/p>\n<p>En general, el Comit\u00e9 Internacional de la Cruz Roja considera que la difusi\u00f3n de im\u00e1genes de interrogatorios de prisioneros de guerra constituye una violaci\u00f3n del estatuto de la Convenci\u00f3n de Ginebra que protege a los prisioneros de guerra de la &#171;curiosidad p\u00fablica&#187;.<\/p>\n<p>La semana pasada, las FDI tambi\u00e9n publicaron fotos y videos en los que se ve\u00eda a unos j\u00f3venes con las armas en alto, que seg\u00fan dijeron eran combatientes que entregaban las armas tras su rendici\u00f3n en el hospital de Kamal Adwan. Sin embargo, el personal entrevistado por CNN afirm\u00f3 que los hombres eran en realidad civiles que se refugiaban en el hospital tras haber sido desplazados de otras partes de Gaza.<\/p>\n<p>&#171;Les dijimos que no hab\u00eda combatientes de la resistencia en el hospital y nadie nos hizo caso&#187;, declar\u00f3 Tanteesh.<\/p>\n<p>Seg\u00fan Abu Safiya y Sabbah, las armas con las que los fotografiaron pertenec\u00edan a los guardias de seguridad del hospital. &#171;Vi con mis propios ojos que el ej\u00e9rcito pidi\u00f3 a los j\u00f3venes civiles desplazados y al equipo m\u00e9dico que llevaran las armas de los guardias de seguridad que hab\u00edan quedado en la sala de guardia del hospital, y les hicieron fotos delante de m\u00ed&#187;, dijo Abu Safiya.<\/p>\n<p>Un coche aplastado sobre los escombros frente al hospital Kamal Adwan. (Cr\u00e9dito: Fadi Alwhidifa\/Reuters)<\/p>\n<p>&#171;Me dispararon y se rieron&#187;<\/p>\n<p>Abu Safiya tambi\u00e9n describi\u00f3 m\u00faltiples incidentes en los que, seg\u00fan afirma, las tropas israel\u00edes atormentaron deliberadamente a personas que sab\u00edan que no eran sospechosas.<\/p>\n<p>Abu Safiya relat\u00f3 a CNN que los soldados liberaron a un m\u00e9dico, el Dr. Ayman Rajab, tras interrogarlo, y luego le dispararon en el pecho cuando intentaba regresar al hospital. Sobrevivi\u00f3 al tiroteo y regres\u00f3 con su familia que hab\u00eda sido desplazada. Otro m\u00e9dico recibi\u00f3 un disparo en la pierna, y el propio hijo de Abu Safiya recibi\u00f3 un disparo en el abdomen, dijo. El Ministerio de Sanidad de Gaza se ha hecho eco de la denuncia, afirmando que al menos cinco detenidos fueron tiroteados por tropas de las FDI despu\u00e9s de que se les dijera que regresaran al hospital.<\/p>\n<p>Atrapado en el interior de Kamal Adwan, Abu Safiya afirma que vio c\u00f3mo sus dos compa\u00f1eros heridos y su hijo se arrastraban por la carretera hasta que una ambulancia lleg\u00f3 hasta ellos y los traslad\u00f3 a otro hospital.<\/p>\n<p>En otro caso, Abu Safiya afirma que \u00e9l mismo se convirti\u00f3 en objetivo despu\u00e9s de que los soldados le llamaran en la madrugada del viernes para que comprobara si hab\u00eda alg\u00fan movimiento fuera del hospital para ellos.<\/p>\n<p>Siguiendo sus \u00f3rdenes, encontr\u00f3 a un anciano herido tendido en el suelo frente al edificio. Pero cuando Abu Safiya intent\u00f3 acercarse al hombre, dice, los soldados que lo observaban empezaron a disparar. &#171;Me dispararon, se rieron y se mofaron&#187;, dijo.<\/p>\n<p>&#171;Escap\u00e9 de sus disparos, pero volvieron a llamarme y me pidieron que lo llevara dentro de nuevo&#187;, cont\u00f3. Finalmente lo llev\u00f3 dentro, pero ya era demasiado tarde. El hombre no pudo ser atendido en el hospital debido a la falta de recursos m\u00e9dicos, y m\u00e1s tarde muri\u00f3 a causa de sus heridas, dijo Abu Safiya.<\/p>\n<p>En otro incidente, seg\u00fan Abu Safiya, perros militares israel\u00edes con c\u00e1maras fueron enviados al hospital para realizar labores de reconocimiento. Uno de los perros &#171;atac\u00f3 y mutil\u00f3&#187; a un anciano en silla de ruedas antes que lo llamaran para que saliera, dijo.<\/p>\n<p>&#171;El hombre grit\u00f3 de dolor. Los ni\u00f1os y las mujeres lloraban del horror de la escena. No pude ayudar a nadie. La escena superaba las pesadillas&#187;, afirm\u00f3. &#171;Uno de sus soldados vino a llevarse al perro y se re\u00eda del anciano y de lo que el perro le hab\u00eda hecho&#187;.<\/p>\n<p>Un ni\u00f1o del hospital, que recib\u00eda tratamiento por una pierna rota, tambi\u00e9n record\u00f3 que unos perros entraron en el hospital y atacaron a un anciano. &#171;Los israel\u00edes dejaron que los perros vinieran y nos atacaran. Nos torturaron. Disparaban contra nosotros. Las noches eran horribles, nunca hemos dormido desde que llegamos aqu\u00ed&#187;, dijo a CNN. &#171;Dejaron que los perros atacaran a un anciano, no dejaba de morderle&#187;.<\/p>\n<p>Las FDI no se refirieron a esas afirmaciones en su comunicado, pero dijeron que su operaci\u00f3n en torno al hospital iba dirigida contra Hamas.<\/p>\n<p>Otro hospital sitiado<\/p>\n<p>Aunque los hospitales como categor\u00eda est\u00e1n protegidos por el derecho internacional, pueden considerarse objetivos militares leg\u00edtimos si se descubre que albergan combatientes sanos y armas.<\/p>\n<p>Pero incluso cuando ese es el caso, los soldados tienen limitaciones \u00e9ticas y legales en su trato con los civiles. La presencia de armamento o de combatientes heridos en un hospital no lo convierte necesariamente en un objetivo militar legal.<\/p>\n<p>El art\u00edculo 19 de la Convenci\u00f3n de Ginebra establece que &#171;el hecho de que en dichos hospitales se atienda a miembros de las fuerzas armadas enfermos o heridos, o la presencia de armas ligeras y municiones tomadas de dichos combatientes que a\u00fan no hayan sido entregadas al servicio competente, no se considerar\u00e1n actos perjudiciales para el enemigo&#187;.<\/p>\n<p>En su declaraci\u00f3n, las FDI dijeron que hab\u00edan interrogado a trabajadores del hospital. &#171;Los trabajadores confesaron que hab\u00eda armas escondidas en las incubadoras de la UCIN, incubadoras que supuestamente se utilizaban para tratar a beb\u00e9s prematuros. Tras el interrogatorio, las tropas de las FDI localizaron armas, documentos clasificados y equipos de comunicaciones t\u00e1cticas&#187;.<\/p>\n<p>La repetida acci\u00f3n militar de Israel en los hospitales de Gaza y sus alrededores se enfrenta a cr\u00edticas cada vez m\u00e1s feroces, en las que trabajadores m\u00e9dicos y ONG advierten que las redadas ponen en peligro a los pacientes y dejan a los hospitales sin poder funcionar.<\/p>\n<p>&#171;El sistema sanitario de Gaza ya estaba de rodillas, y la p\u00e9rdida de otro hospital, aunque funcione m\u00ednimamente, es un duro golpe. Los ataques contra hospitales, personal sanitario y pacientes deben terminar&#187;, declar\u00f3 el domingo Ghebreyesus, jefe de la OMS, refiri\u00e9ndose a Kamal Adwan.<\/p>\n<p>A pesar de las crecientes cr\u00edticas internacionales de algunos de los aliados m\u00e1s firmes de Israel por el creciente n\u00famero de v\u00edctimas civiles en los hospitales y en otros lugares de Gaza, Israel no ha cambiado de rumbo en su persecuci\u00f3n militar de Hamas. El martes, la organizaci\u00f3n ben\u00e9fica M\u00e9dicos Sin Fronteras declar\u00f3 que otro hospital del norte de Gaza, Al-Awda, estaba sitiado por las tropas israel\u00edes con pacientes a\u00fan en su interior.<\/p>\n<p>Gianluca Mezzofiore e Ibahim Dahmin, de CNN, contribuyeron a este reportaje.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los soldados israel\u00edes que asaltaron un hospital en el norte de Gaza profanaron los cad\u00e1veres de pacientes con topadoras, dejaron que un perro militar maltratara a un hombre en silla de ruedas y dispararon a varios m\u00e9dicos incluso despu\u00e9s de descartar que tuvieran v\u00ednculos con el terrorismo, seg\u00fan denuncias del personal y de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442530","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &quot;centro de mando&quot; de Hamas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &quot;centro de mando&quot; de Hamas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los soldados israel\u00edes que asaltaron un hospital en el norte de Gaza profanaron los cad\u00e1veres de pacientes con topadoras, dejaron que un perro militar maltratara a un hombre en silla de ruedas y dispararon a varios m\u00e9dicos incluso despu\u00e9s de descartar que tuvieran v\u00ednculos con el terrorismo, seg\u00fan denuncias del personal y de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-23T15:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &#171;centro de mando&#187; de Hamas\",\"datePublished\":\"2023-12-23T15:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/\"},\"wordCount\":2538,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/\",\"url\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/\",\"name\":\"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era \\\"centro de mando\\\" de Hamas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-23T15:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &#171;centro de mando&#187; de Hamas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era \"centro de mando\" de Hamas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era \"centro de mando\" de Hamas - Noticias","og_description":"(CNN) &#8212; Los soldados israel\u00edes que asaltaron un hospital en el norte de Gaza profanaron los cad\u00e1veres de pacientes con topadoras, dejaron que un perro militar maltratara a un hombre en silla de ruedas y dispararon a varios m\u00e9dicos incluso despu\u00e9s de descartar que tuvieran v\u00ednculos con el terrorismo, seg\u00fan denuncias del personal y de [&hellip;]","og_url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/","og_site_name":"Noticias","article_published_time":"2023-12-23T15:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/"},"author":{"name":"","@id":""},"headline":"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &#171;centro de mando&#187; de Hamas","datePublished":"2023-12-23T15:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/"},"wordCount":2538,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/","url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/","name":"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era \"centro de mando\" de Hamas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-23T15:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &#171;centro de mando&#187; de Hamas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9dicos acusan a las tropas israel\u00edes de profanar cad\u00e1veres y disparar contra civiles en un hospital que, seg\u00fan Israel, era &#171;centro de mando&#187; de Hamas","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-23T15:33:32Z","datePublished":"2023-12-23T15:33:32Z","dateModified":"2023-12-23T15:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e9dicos acusan a las tropas israel\\u00edes de profanar cad\\u00e1veres y disparar contra civiles en un hospital que, seg\\u00fan Israel, era &#171;centro de mando&#187; de Hamas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/medicos-acusan-a-las-tropas-israelies-de-profanar-cadaveres-y-disparar-contra-civiles-en-un-hospital-que-segun-israel-era-centro-de-mando-de-hamas\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-23T15:33:32Z\",\"datePublished\":\"2023-12-23T15:33:32Z\",\"dateModified\":\"2023-12-23T15:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451713,"url":"https:\/\/noticiasya.com\/hartford\/2024\/08\/10\/israeli-school-strike-gaza-trax\/","url_meta":{"origin":1442530,"position":0},"title":"Al menos 90 palestinos muertos en un ataque israel\u00ed contra una escuela de Gaza, seg\u00fan portavoz de la Defensa Civil","author":"","date":"agosto 10, 2024","format":false,"excerpt":"(CNN) -- Al menos 90 palestinos murieron en un ataque israel\u00ed contra la escuela de Al-Tabi'in, en la ciudad de Gaza, seg\u00fan declar\u00f3 o a CNN el portavoz de la Defensa Civil de Gaza, Mahmoud Basal.\"Hemos recuperado al menos 90\" personas muertas, ha dicho Basal, a\u00f1adiendo que \"muchas de ellas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447908,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/09\/exhuman-cadaveres-fosas-comunes-hospital-al-shifa-trax\/","url_meta":{"origin":1442530,"position":1},"title":"Exhuman los primeros cad\u00e1veres de las fosas comunes del hospital Al-Shifa tras el asedio israel\u00ed","author":"","date":"abril 9, 2024","format":false,"excerpt":"(CNN) -- Trabajadores sanitarios del norte de Gaza exhumaron este martes los primeros cad\u00e1veres de las fosas comunes del hospital Al-Shifa y sus alrededores, despu\u00e9s de que las fuerzas israel\u00edes mataran a cientos de palestinos y dejaran sus cuerpos en descomposici\u00f3n durante las dos semanas de asedio al complejo.Al menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464180,"url":"https:\/\/noticiasya.com\/hartford\/2025\/07\/03\/decenas-muertos-gaza-ataques-israelies-trax\/","url_meta":{"origin":1442530,"position":2},"title":"Decenas de muertos en Gaza a medida que Israel intensifica sus ataques sobre el enclave palestino","author":"","date":"julio 3, 2025","format":false,"excerpt":"M\u00e1s de 80 palestinos murieron en Gaza este jueves, seg\u00fan funcionarios de Salud, en el contexto de una intensificaci\u00f3n de los ataques de Israel en el enclave.Las muertes, que seg\u00fan las autoridades inclu\u00edan a decenas de personas que buscaban ayuda, se producen mientras avanzan las negociaciones para alcanzar un alto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457181,"url":"https:\/\/noticiasya.com\/hartford\/2025\/01\/03\/israel-paradero-director-hospital-gaza-detenido-trax\/","url_meta":{"origin":1442530,"position":3},"title":"El gobierno israel\u00ed es instado a revelar el paradero del director del hospital de Gaza detenido","author":"","date":"enero 3, 2025","format":false,"excerpt":"Un grupo de derechos humanos interpuso una petici\u00f3n ante el Tribunal Supremo de Israel exigiendo conocer el paradero de un reconocido director de hospital palestino detenido por las fuerzas armadas israel\u00edes.No se ha visto p\u00fablicamente al Dr. Hussam Abu Safiya desde que fue detenido durante una redada israel\u00ed la semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460628,"url":"https:\/\/noticiasya.com\/hartford\/2025\/03\/31\/cadaveres-trabajadores-humanitarios-desaparecidos-trax\/","url_meta":{"origin":1442530,"position":4},"title":"Hallan cad\u00e1veres de trabajadores humanitarios desaparecidos en una fosa com\u00fan de Gaza tras ataques israel\u00edes","author":"","date":"marzo 31, 2025","format":false,"excerpt":"Los cuerpos de m\u00e1s de una decena de trabajadores humanitarios han sido recuperados en el sur de Gaza de lo que una agencia de las Naciones Unidas describi\u00f3 como una \u201cfosa com\u00fan\u201d, una semana despu\u00e9s de que desaparecieran durante ataques de las fuerzas israel\u00edes.Ocho de los 14 cad\u00e1veres recuperados este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460318,"url":"https:\/\/noticiasya.com\/hartford\/2025\/03\/23\/israel-bombardea-hospital-nasser-gaza-trax\/","url_meta":{"origin":1442530,"position":5},"title":"Israel bombardea el hospital Nasser de Gaza para golpear a &#171;un terrorista clave&#187;","author":"","date":"marzo 23, 2025","format":false,"excerpt":"Un ataque a\u00e9reo israel\u00ed impact\u00f3 un hospital en el sur de Gaza el domingo por la noche, seg\u00fan informaron a CNN dos m\u00e9dicos que trabajan en el hospital. Una parte del hospital qued\u00f3 en llamas y caus\u00f3 m\u00faltiples v\u00edctimas.Las fuerzas israel\u00edes confirmaron la autor\u00eda del ataque, afirmando que \u201cgolpe\u00f3 con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442530"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442530\/revisions"}],"predecessor-version":[{"id":1442546,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442530\/revisions\/1442546"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}