{"id":1442534,"date":"2023-12-23T09:33:41","date_gmt":"2023-12-23T17:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442534"},"modified":"2023-12-23T09:33:41","modified_gmt":"2023-12-23T17:33:41","slug":"retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","title":{"rendered":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea"},"content":{"rendered":"<p>(CNN) &#8212; Una nueva obra de Banksy fue retirada de una calle de Londres poco despu\u00e9s de que el artista la publicara en Instagram, seg\u00fan reportes.<\/p>\n<p>El artista public\u00f3 una serie de fotos de la obra \u2014que consiste en tres drones en una se\u00f1al de alto\u2014 en las redes sociales alrededor del mediod\u00eda del viernes hora local (7 a.m. hora de Miami).<\/p>\n<p>Pero a las 12.30 p.m. dos hombres fueron vistos quitando la se\u00f1al de un cruce en Peckham, al sureste de Londres, dijeron testigos a la agencia de noticias PA Media.<\/p>\n<p>&#171;Abr\u00ed Instagram y vi que lo hab\u00edan publicado cuatro minutos antes y estaba a punto de irme a mi hora de comer. Hab\u00eda unas dos personas cuando llegu\u00e9. Todos est\u00e1bamos como admir\u00e1ndolo y haciendo fotos&#187;, cont\u00f3 Alex, de 26 a\u00f1os, a PA.<\/p>\n<p>&#171;Nos quedamos mirando at\u00f3nitos c\u00f3mo lo destrozaban&#187;, a\u00f1adi\u00f3 Alex, que relat\u00f3 c\u00f3mo el hombre no consigui\u00f3 quitar el cartel con las manos y se march\u00f3 unos minutos antes de volver con una cizalla.<\/p>\n<p>&#171;Dijimos: &#8216;\u00bfQu\u00e9 haces?&#8217;, pero nadie sab\u00eda qu\u00e9 hacer, nos quedamos mirando. Todos est\u00e1bamos un poco perplejos&#187;, continu\u00f3 el testigo.<\/p>\n<p>&#171;Lo arranc\u00f3, cruz\u00f3 la carretera y huy\u00f3. No dijo nada. No parec\u00eda importarle mucho el arte en s\u00ed&#187;, a\u00f1adi\u00f3 Alex.<\/p>\n<p>(Cr\u00e9dito: Aaron Chown\/AP)<\/p>\n<p>Otro testigo, que dijo a PA que prefer\u00eda permanecer en el anonimato, expres\u00f3 su decepci\u00f3n por la retirada del cartel.<\/p>\n<p>&#171;Es extra\u00f1o, estas obras de arte son bonitas, estar\u00eda bien que hubieran permanecido all\u00ed un tiempo&#187;, dijo.<\/p>\n<p>PA inform\u00f3 que no se cree que el propio Banksy est\u00e9 detr\u00e1s de la retirada de la obra de arte.<\/p>\n<p>El misterioso artista es conocido por confirmar sus obras en las redes sociales sin hacer m\u00e1s comentarios.<\/p>\n<p>Algunos han interpretado la \u00faltima obra como un llamamiento al alto el fuego en el conflicto entre Israel y Hamas, dado que Banksy es conocido por apoyar la causa palestina.<\/p>\n<p>El artista es propietario de un hotel en la ciudad de Bel\u00e9n, que se encuentra a pocos pasos de la imponente barrera de separaci\u00f3n israel\u00ed que atraviesa la Ribera Occidental.<\/p>\n<p>Banksy inaugur\u00f3 el Walled Off Hotel en 2017 para llamar la atenci\u00f3n sobre el conflicto palestino-israel\u00ed, y se autodenomina el hotel con las &#171;peores vistas del mundo&#187;.<\/p>\n<p>Aunque el valor de mercado de su obra se ha disparado en los \u00faltimos a\u00f1os, Banksy sigue produciendo obras en espacios p\u00fablicos que hacen casi imposible su conservaci\u00f3n, e incluso invitan al robo o la desfiguraci\u00f3n.<\/p>\n<p>&#171;Spy booth&#187;, uno de los murales m\u00e1s famosos de Banksy, que representa a tres agentes secretos rodeando una cabina telef\u00f3nica con equipos de grabaci\u00f3n, fue destruido en 2016.<\/p>\n<p>Y en febrero de este a\u00f1o, un congelador abandonado que formaba parte de una obra de arte aparecida en la localidad inglesa de Margate fue retirado pocas horas despu\u00e9s de que Banksy confirmara que la pieza era suya.<\/p>\n<p>En 2018, el artista destruy\u00f3 famosamente una de sus propias obras: su pintura de una ni\u00f1a con un globo rojo se autodestruy\u00f3 momentos despu\u00e9s de venderse en una subasta por US$ 1,4 millones.<\/p>\n<p>Lianne Kolirin, Zeena Saifi y Nadeem Muaddi de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Una nueva obra de Banksy fue retirada de una calle de Londres poco despu\u00e9s de que el artista la publicara en Instagram, seg\u00fan reportes. El artista public\u00f3 una serie de fotos de la obra \u2014que consiste en tres drones en una se\u00f1al de alto\u2014 en las redes sociales alrededor del mediod\u00eda del viernes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442534","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Una nueva obra de Banksy fue retirada de una calle de Londres poco despu\u00e9s de que el artista la publicara en Instagram, seg\u00fan reportes. El artista public\u00f3 una serie de fotos de la obra \u2014que consiste en tres drones en una se\u00f1al de alto\u2014 en las redes sociales alrededor del mediod\u00eda del viernes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-23T17:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea\",\"datePublished\":\"2023-12-23T17:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/\"},\"wordCount\":588,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/\",\"name\":\"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-23T17:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","og_locale":"es_ES","og_type":"article","og_title":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea - Noticias","og_description":"(CNN) &#8212; Una nueva obra de Banksy fue retirada de una calle de Londres poco despu\u00e9s de que el artista la publicara en Instagram, seg\u00fan reportes. El artista public\u00f3 una serie de fotos de la obra \u2014que consiste en tres drones en una se\u00f1al de alto\u2014 en las redes sociales alrededor del mediod\u00eda del viernes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","og_site_name":"Noticias","article_published_time":"2023-12-23T17:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/"},"author":{"name":"","@id":""},"headline":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea","datePublished":"2023-12-23T17:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/"},"wordCount":588,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","url":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","name":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-23T17:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-23T17:33:41Z","datePublished":"2023-12-23T17:33:41Z","dateModified":"2023-12-23T17:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Retiran de la calle una obra de Banksy menos de una hora despu\\u00e9s de que la publicara en l\\u00ednea\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-23T17:33:41Z\",\"datePublished\":\"2023-12-23T17:33:41Z\",\"dateModified\":\"2023-12-23T17:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473698,"url":"https:\/\/noticiasya.com\/hartford\/2026\/05\/01\/nueva-estatua-banksy-satiriza-patriotismo-ciego-trax\/","url_meta":{"origin":1442534,"position":0},"title":"La nueva estatua londinense de Banksy, que ondea una bandera, satiriza el patriotismo ciego","author":"","date":"mayo 1, 2026","format":false,"excerpt":"Banksy ha confirmado que \u00e9l es el autor de una gran estatua que apareci\u00f3 misteriosamente en el centro de Londres, la cual representa a un hombre trajeado que desciende de un pedestal con una bandera que le cubre el rostro.El enigm\u00e1tico artista se atribuy\u00f3 el m\u00e9rito de la obra en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468368,"url":"https:\/\/noticiasya.com\/hartford\/2025\/11\/14\/hombre-robo-obra-nina-globo-banksy-londres-trax\/","url_meta":{"origin":1442534,"position":1},"title":"Encarcelan a un hombre por robar la obra &#171;Girl with Balloon&#187; de Banksy en un robo rel\u00e1mpago en Londres","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Un hombre fue condenado a m\u00e1s de un a\u00f1o de prisi\u00f3n por robar una copia firmada de la obra \u201cGirl with Balloon\u201d (Ni\u00f1a con globo) de Banksy en un robo rel\u00e1mpago en una galer\u00eda de Londres.Larry Fraser, de 49 a\u00f1os, fue condenado el viernes a 13 meses de prisi\u00f3n por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472437,"url":"https:\/\/noticiasya.com\/hartford\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","url_meta":{"origin":1442534,"position":2},"title":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte?","author":"","date":"marzo 21, 2026","format":false,"excerpt":"El mayor misterio del mundo del arte aparentemente fue resuelto: Banksy fue desenmascarado como un hombre de mediana edad, con gafas, de Bristol, Inglaterra, llamado Robin Gunningham.Su nombre fue revelado en una amplia investigaci\u00f3n de Reuters, aunque muchos dicen que ha sido un secreto a voces durante a\u00f1os, ya que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463472,"url":"https:\/\/noticiasya.com\/hartford\/2025\/06\/12\/avion-se-estrella-aeropuerto-ahmedabad-india-trax\/","url_meta":{"origin":1442534,"position":3},"title":"Un avi\u00f3n se estrella en el aeropuerto de Ahmedabad, en el oeste de India","author":"","date":"junio 12, 2025","format":false,"excerpt":"Un avi\u00f3n de pasajeros de Air India se estrell\u00f3 este jueves poco despu\u00e9s de despegar en un aeropuerto de la ciudad de Ahmedabad, en el oeste de la India.Las im\u00e1genes del lugar mostraron una espesa columna de humo negro elev\u00e1ndose hacia el cielo.No estaba inmediatamente claro cu\u00e1ntas personas hab\u00eda a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463482,"url":"https:\/\/noticiasya.com\/hartford\/2025\/06\/12\/que-paso-por-que-avion-se-estrello-air-india-londres-trax\/","url_meta":{"origin":1442534,"position":4},"title":"\u00bfQu\u00e9 pas\u00f3 y por qu\u00e9 se produjo el accidente de un avi\u00f3n de Air India que volaba hacia Londres?","author":"","date":"junio 12, 2025","format":false,"excerpt":"Un avi\u00f3n de Air India con destino a Londres, en el que viajaban 242 personas, se estrell\u00f3 el jueves en el oeste de India poco despu\u00e9s de despegar.Los videos muestran una enorme columna de humo negro que se eleva hacia el cielo. Los equipos de rescate trabajan para apagar el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455031,"url":"https:\/\/noticiasya.com\/hartford\/2024\/10\/10\/scooter-braun-dejar-hablar-grabaciones-maestras-taylor-swift-trax\/","url_meta":{"origin":1442534,"position":5},"title":"Scooter Braun dice que es hora de &#171;dejar de hablar&#187; de la venta de las grabaciones maestras de Taylor Swift","author":"","date":"octubre 10, 2024","format":false,"excerpt":"(CNN) --\u00a0A Scooter Braun le gustar\u00eda cambiar de tema.Al ejecutivo musical le gustar\u00eda en particular que la gente dejara de hablar sobre su muy p\u00fablica y controvertida venta de las grabaciones maestras de la megaestrella Taylor Swift, y dijo que \"cinco a\u00f1os despu\u00e9s, creo que es hora de dejar atr\u00e1s\"\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442534"}],"version-history":[{"count":2,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442534\/revisions"}],"predecessor-version":[{"id":1442552,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442534\/revisions\/1442552"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}