{"id":1442555,"date":"2023-12-23T19:33:32","date_gmt":"2023-12-24T03:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442555"},"modified":"2023-12-23T19:33:32","modified_gmt":"2023-12-24T03:33:32","slug":"el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/","title":{"rendered":"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La vicepresidenta de Nicaragua, Rosario Murillo, confirm\u00f3 que son 16 las personas que perdieron la vida este s\u00e1bado cuando un autob\u00fas con aproximadamente 70 pasajeros cay\u00f3 de un puente. El accidente se registr\u00f3 en horas de la ma\u00f1ana en la ruta que une Waslala y Matagalpa, en el norte del pa\u00eds.<\/p>\n<p>En una comunicaci\u00f3n telef\u00f3nica con el canal 6, Murillo inform\u00f3 que adem\u00e1s hay m\u00e1s de 20 personas heridas, algunas de gravedad.<\/p>\n<p>Noticia en desarrollo&#8230;<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La vicepresidenta de Nicaragua, Rosario Murillo, confirm\u00f3 que son 16 las personas que perdieron la vida este s\u00e1bado cuando un autob\u00fas con aproximadamente 70 pasajeros cay\u00f3 de un puente. El accidente se registr\u00f3 en horas de la ma\u00f1ana en la ruta que une Waslala y Matagalpa, en el norte del pa\u00eds. En [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442555","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La vicepresidenta de Nicaragua, Rosario Murillo, confirm\u00f3 que son 16 las personas que perdieron la vida este s\u00e1bado cuando un autob\u00fas con aproximadamente 70 pasajeros cay\u00f3 de un puente. El accidente se registr\u00f3 en horas de la ma\u00f1ana en la ruta que une Waslala y Matagalpa, en el norte del pa\u00eds. En [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-24T03:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito\",\"datePublished\":\"2023-12-24T03:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/\"},\"wordCount\":111,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/\",\"url\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/\",\"name\":\"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-24T03:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La vicepresidenta de Nicaragua, Rosario Murillo, confirm\u00f3 que son 16 las personas que perdieron la vida este s\u00e1bado cuando un autob\u00fas con aproximadamente 70 pasajeros cay\u00f3 de un puente. El accidente se registr\u00f3 en horas de la ma\u00f1ana en la ruta que une Waslala y Matagalpa, en el norte del pa\u00eds. En [&hellip;]","og_url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/","og_site_name":"Noticias","article_published_time":"2023-12-24T03:33:32+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito","datePublished":"2023-12-24T03:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/"},"wordCount":111,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/","url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/","name":"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-24T03:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/nacional\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\u00e1nsito","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-24T03:33:32Z","datePublished":"2023-12-24T03:33:32Z","dateModified":"2023-12-24T03:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Nicaragua confirma la muerte de 16 personas en accidente de tr\\u00e1nsito\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/el-gobierno-de-nicaragua-confirma-la-muerte-de-16-personas-en-accidente-de-transito\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-24T03:33:32Z\",\"datePublished\":\"2023-12-24T03:33:32Z\",\"dateModified\":\"2023-12-24T03:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473263,"url":"https:\/\/noticiasya.com\/hartford\/2026\/04\/16\/eeuu-sanciones-hijos-ortega-murillo-nicaragua-orix\/","url_meta":{"origin":1442555,"position":0},"title":"EE.UU. sanciona a dos hijos de Ortega y Murillo en Nicaragua por su presunto papel en una red ligada al oro","author":"","date":"abril 16, 2026","format":false,"excerpt":"El Departamento del Tesoro de EE.UU. sancion\u00f3 este jueves a dos hijos de la pareja presidencial de Nicaragua, Daniel Ortega, y su esposa y copresidenta Rosario Murillo, por su papel dentro del aparato gubernamental y sus v\u00ednculos con una red ligada al negocio de extracci\u00f3n de oro que, seg\u00fan Washington,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451047,"url":"https:\/\/noticiasya.com\/hartford\/2024\/07\/11\/gobierno-daniel-ortega-excarcelara-1-500-presos-orix\/","url_meta":{"origin":1442555,"position":1},"title":"El Gobierno de Daniel Ortega dice que excarcelar\u00e1 a unos 1.500 presos","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Unos 1.500 presos que se encuentran detenidos en distintas c\u00e1rceles de Nicaragua pasar\u00e1n a ser parte del r\u00e9gimen de convivencia familiar, un mecanismo que les permite a los beneficiados regresaras a sus hogares y reincorporarse a la sociedad inform\u00f3 este mi\u00e9rcoles la vicepresidenta y vocera del gobierno,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469969,"url":"https:\/\/noticiasya.com\/hartford\/2026\/01\/10\/nicaragua-liberacion-decenas-personas-orix\/","url_meta":{"origin":1442555,"position":2},"title":"Nicaragua anuncia la liberaci\u00f3n de &#171;decenas de personas&#187; cuando se cumplen 19 a\u00f1os de que Daniel Ortega asumi\u00f3 la presidencia","author":"","date":"enero 10, 2026","format":false,"excerpt":"El Gobierno de Nicaragua anunci\u00f3 este s\u00e1bado la liberaci\u00f3n de \u201cdecenas de personas\u201d que estaban en prisi\u00f3n, una medida que coincide con el 19\u00b0 aniversario de la llegada de Daniel Ortega a la presidencia del pa\u00eds centroamericano.Mediante un breve comunicado, el Ministerio del Interior dijo que estas liberaciones muestran \u201cla\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455044,"url":"https:\/\/noticiasya.com\/hartford\/2024\/10\/11\/nicaragua-rompe-relaciones-diplomaticas-israel-orix\/","url_meta":{"origin":1442555,"position":3},"title":"Nicaragua rompe relaciones diplom\u00e1ticas con Israel por su guerra en Gaza","author":"","date":"octubre 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La vicepresidenta de Nicaragua, Rosario Murillo, inform\u00f3 este viernes que su pa\u00eds rompe elaciones diplom\u00e1ticas con Israel por su guerra en Gaza.Murillo se\u00f1al\u00f3 que la Asamblea Nacional realiz\u00f3 este viernes una sesi\u00f3n especial de solidaridad con el pueblo palestino, donde el parlamento exhort\u00f3 al gobierno a valorar esa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471687,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/26\/eeuu-sanciona-funcionarios-nicaragua-ortega-murillo-orix\/","url_meta":{"origin":1442555,"position":4},"title":"Departamento del Tesoro de EE.UU. sanciona a cinco funcionarios de Nicaragua por &#171;facilitar la represi\u00f3n&#187; de Ortega y Murillo","author":"","date":"febrero 26, 2026","format":false,"excerpt":"La Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s) del Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a cinco funcionarios del Gobierno de Nicaragua al se\u00f1alarlos por presuntamente \u201cfacilitar la represi\u00f3n popular\u201d de los copresidentes del pa\u00eds, Daniel Ortega y Rosario Murillo.Se trata de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449491,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/15\/estados-unidos-restricciones-funcionarios-entidades-nicaragua-orix\/","url_meta":{"origin":1442555,"position":5},"title":"Estados Unidos anuncia restricciones a funcionarios y entidades con sede en Nicaragua","author":"","date":"mayo 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Estados Unidos anunci\u00f3 este mi\u00e9rcoles nuevas restricciones para funcionarios del Gobierno de Nicaragua por \"su rol en el apoyo al r\u00e9gimen Ortega-Murillo en sus ataques a los derechos humanos y las libertades fundamentales\u201d, as\u00ed como tambi\u00e9n por \u201cla represi\u00f3n de las organizaciones de la sociedad civil y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442555"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442555\/revisions"}],"predecessor-version":[{"id":1442571,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442555\/revisions\/1442571"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}