{"id":1442561,"date":"2023-12-23T22:33:32","date_gmt":"2023-12-24T06:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442561"},"modified":"2023-12-23T22:33:32","modified_gmt":"2023-12-24T06:33:32","slug":"excarcelan-en-venezuela-al-estudiante-john-alvarez-3","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","title":{"rendered":"Excarcelan en Venezuela al estudiante John \u00c1lvarez"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad.<\/p>\n<p>El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas (DAET) de la Polic\u00eda Nacional Bolivariana (PNB) y se encontraba detenido en el Centro de Control y Resguardo de Detenidos de La Yaguara, en el oeste de Caracas, junto con presos comunes. \u00c1lvarez fue condenado en septiembre a 16 a\u00f1os de prisi\u00f3n junto con seis sindicalistas, que fueron liberados el mi\u00e9rcoles.<\/p>\n<p>Todos estaban acusados de asociaci\u00f3n para delinquir y terrorismo.<\/p>\n<p>Estadounidenses que estuvieron presos en Venezuela hablan al regresar a EE.UU.: &#171;Tratan de volverte loco&#187;<\/p>\n<p>Los familiares del joven informaron a CNN que a \u00c1lvarez lo excarcelaron bajo medidas cautelares, entre ellas, la presentaci\u00f3n ante tribunales cada 15 d\u00edas y la prohibici\u00f3n de salir del pa\u00eds.<\/p>\n<p>Esto habr\u00eda sucedido en el marco de las negociaciones anunciadas entre Estados Unidos y Venezuela, que contemplaron la liberaci\u00f3n del empresario colombiano nacionalizado venezolano, Alex Saab, quien fue canjeado por 10 ciudadanos estadounidenses. Seg\u00fan las organizaciones no gubernamentales defensoras de Derechos Humanos, al menos 18 personas fueron excarceladas como resultado de esas negociaciones.<\/p>\n<p>CNN no ha podido confirmar de forma independiente si esta medida est\u00e1 vinculada o no con esas tratativas.<\/p>\n<p>\u00c1lvarez fue aprehendido el pasado 30 de agosto y, desde entonces, familiares y organizaciones no gubernamentales denunciaron que el joven fue sometido a torturas.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad. El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas (DAET) de la Polic\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442561","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Excarcelan en Venezuela al estudiante John \u00c1lvarez - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Excarcelan en Venezuela al estudiante John \u00c1lvarez - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad. El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas (DAET) de la Polic\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-24T06:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Excarcelan en Venezuela al estudiante John \u00c1lvarez\",\"datePublished\":\"2023-12-24T06:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/\",\"name\":\"Excarcelan en Venezuela al estudiante John \u00c1lvarez - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-24T06:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Excarcelan en Venezuela al estudiante John \u00c1lvarez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Excarcelan en Venezuela al estudiante John \u00c1lvarez - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","og_locale":"es_ES","og_type":"article","og_title":"Excarcelan en Venezuela al estudiante John \u00c1lvarez - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad. El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas (DAET) de la Polic\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","og_site_name":"Noticias","article_published_time":"2023-12-24T06:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/"},"author":{"name":"","@id":""},"headline":"Excarcelan en Venezuela al estudiante John \u00c1lvarez","datePublished":"2023-12-24T06:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","url":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","name":"Excarcelan en Venezuela al estudiante John \u00c1lvarez - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-24T06:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Excarcelan en Venezuela al estudiante John \u00c1lvarez"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Excarcelan en Venezuela al estudiante John \u00c1lvarez","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-24T06:33:32Z","datePublished":"2023-12-24T06:33:32Z","dateModified":"2023-12-24T06:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Excarcelan en Venezuela al estudiante John \\u00c1lvarez\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/23\\\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-24T06:33:32Z\",\"datePublished\":\"2023-12-24T06:33:32Z\",\"dateModified\":\"2023-12-24T06:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442557,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez\/","url_meta":{"origin":1442561,"position":0},"title":"Excarcelan en Venezuela al estudiante John \u00c1lvarez","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad.El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442560,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-2\/","url_meta":{"origin":1442561,"position":1},"title":"Excarcelan en Venezuela al estudiante John \u00c1lvarez","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad.El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470727,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/01\/excarcelan-activista-javier-tarazona-helicoide-orix\/","url_meta":{"origin":1442561,"position":2},"title":"Excarcelan al activista venezolano Javier Tarazona tras pasar m\u00e1s de cuatro a\u00f1os detenido en El Helicoide","author":"","date":"febrero 1, 2026","format":false,"excerpt":"El activista venezolano de derechos humanos Javier Tarazona fue excarcelado este domingo en Caracas, seg\u00fan anunci\u00f3 su familia, despu\u00e9s de pasar m\u00e1s de cuatro a\u00f1os detenido.\u201cLuego de 1.675 d\u00edas, 4 a\u00f1os y 7 meses, lleg\u00f3 este tan anhelado d\u00eda, mi hermano Javier Tarazona est\u00e1 en libertad\u201d, public\u00f3 en X Rafael\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462930,"url":"https:\/\/noticiasya.com\/hartford\/2025\/05\/28\/ice-venezolano-escuela-secundaria-nueva-york-trax\/","url_meta":{"origin":1442561,"position":3},"title":"ICE detiene a un joven venezolano inscrito en un bachillerato de Nueva York","author":"","date":"mayo 28, 2025","format":false,"excerpt":"Un joven venezolano de 20 a\u00f1os, inscrito en un bachillerato de la ciudad de Nueva York que atiende a estudiantes inmigrantes mayores, se encuentra detenido por el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s), convirti\u00e9ndose en uno de los primeros estudiantes del sistema escolar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451643,"url":"https:\/\/noticiasya.com\/hartford\/2024\/08\/07\/entre-detenidos-de-venezuela-figuran-personas-con-discapacidad-dice-confederacion-de-sordos-de-venezuela-orix\/","url_meta":{"origin":1442561,"position":4},"title":"Entre los detenidos de Venezuela figuran personas con discapacidad, dice Confederaci\u00f3n de Sordos de Venezuela","author":"","date":"agosto 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Al menos tres personas con discapacidad est\u00e1n siendo procesadas judicialmente en Venezuela, dijo este lunes en un comunicado la Confederaci\u00f3n Sordos de Venezuela (Consorven), en el que manifest\u00f3 su preocupaci\u00f3n ante los arrestos de las \u00faltimas horas en el pa\u00eds.El movimiento pol\u00edtico opositor Vente Venezuela se hizo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469992,"url":"https:\/\/noticiasya.com\/hartford\/2026\/01\/11\/excarcelaciones-venezuela-gobierno-reporta-muerte-policia-detenido-orix\/","url_meta":{"origin":1442561,"position":5},"title":"En medio de las excarcelaciones anunciadas por Venezuela, el Gobierno reporta la muerte de un pol\u00edcia detenido","author":"","date":"enero 11, 2026","format":false,"excerpt":"El Ministerio P\u00fablico de Venezuela inform\u00f3 este domingo que el 10 de enero de 2026 muri\u00f3 un ciudadano que se encontraba preso desde el 11 de diciembre de 2025, d\u00edas despu\u00e9s de que el presidente de la Asamblea Nacional anunciara la excarcelaci\u00f3n de \u201cun n\u00famero importante\u201d de detenidos.A trav\u00e9s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442561"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442561\/revisions"}],"predecessor-version":[{"id":1442577,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442561\/revisions\/1442577"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}