{"id":1442631,"date":"2023-12-25T08:33:34","date_gmt":"2023-12-25T16:33:34","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442631"},"modified":"2023-12-25T08:33:34","modified_gmt":"2023-12-25T16:33:34","slug":"este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/","title":{"rendered":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023"},"content":{"rendered":"<p>(CNN) &#8212; Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao japon\u00e9s de m\u00fasica synth el que realmente despert\u00f3 la curiosidad de los amantes de la m\u00fasica de todo el mundo en 2023.<\/p>\n<p>En una era en la que el K-pop ha estado a la vanguardia de las exportaciones musicales de Asia durante a\u00f1os, Yoasobi, que combina pegadizas pistas de sintetizador con espect\u00e1culos el\u00e9ctricos en vivo y tradiciones anime, est\u00e1 liderando un renacimiento del J-pop.<\/p>\n<p>Su tema \u201cIdol (\u30a2\u30a4\u30c9\u30eb)\u201d apareci\u00f3 en una de las series de anime m\u00e1s importantes del a\u00f1o, \u201cOshi no ko\u201d, y desat\u00f3 una tendencia de baile en TikTok japon\u00e9s, llev\u00e1ndolo a la cima de la lista anual de Google en la categor\u00eda de canciones global.<\/p>\n<p>Yoasobi lider\u00f3 b\u00fasquedas en Google (Li Zhihua\/China News Service\/VCG\/Getty Images)<\/p>\n<p>Las canciones no son necesariamente las \u201cm\u00e1s buscadas\u201d en Google. Pero la lista identifica las consultas de b\u00fasqueda que experimentaron altos picos de tr\u00e1fico durante un per\u00edodo sostenido en comparaci\u00f3n con el a\u00f1o anterior y, por lo tanto, ofrece una ventana a los temas que se convirtieron en zeitgeists, tendencias del momento.<\/p>\n<p>Es el segundo a\u00f1o consecutivo que un artista de Asia encabeza la lista mundial despu\u00e9s de que la cantante indonesia Keisya Levronka encabezara la categor\u00eda de canciones de 2022.<\/p>\n<p>Formado durante la pandemia de coronavirus como un proyecto de estudio y liderado por el vocalista Ikura y el productor Ayase, el d\u00fao Yoasobi es conocido por sus canciones inspiradas en cuentos.<\/p>\n<p>Su sencillo debut, &#171;Yoru ni Kakeru&#187;, est\u00e1 basado en un cuento original de Mayo Hoshino, titulado &#171;Thanatos no yuuwaku&#187; (Tentaci\u00f3n de Thanatos), sobre un joven que se enamora de una mujer que intenta suicidarse repetidamente.<\/p>\n<p>\u201cYoru ni Kakeru\u201d encabez\u00f3 la lista Hot 100 de Billboard Jap\u00f3n durante seis semanas no consecutivas y se convirti\u00f3 en la primera canci\u00f3n en recibir una certificaci\u00f3n de transmisi\u00f3n diamante de la Asociaci\u00f3n de la Industria de la Grabaci\u00f3n de Jap\u00f3n, reconociendo que la canci\u00f3n hab\u00eda sido reproducida al menos 500 millones de veces.<\/p>\n<p>Sus shows en vivo, respaldados por una banda, son famosos por el uso desenfrenado de l\u00e1seres y vertiginosas proyecciones digitales.<\/p>\n<p>Otros dos representantes de Asia llegaron a la lista de los 10 mejores de Google en la categor\u00eda de canciones globales.<\/p>\n<p>A Yoasobi se uni\u00f3 el grupo femenino de K-pop Fifty-Fifty, cuyo debut en coreano-ingl\u00e9s, \u201cCupid\u201d, fue la quinta canci\u00f3n m\u00e1s buscada en tendencia.<\/p>\n<p>La canci\u00f3n salt\u00f3 a la fama mundial en parte gracias a su versi\u00f3n \u201cTwin\u201d, grabada \u00edntegramente en ingl\u00e9s. Fifty-Fifty, que debut\u00f3 apenas el a\u00f1o pasado, se convirti\u00f3 en el grupo de K-pop que m\u00e1s r\u00e1pido entr\u00f3 en la lista Billboard Hot 100 de Estados Unidos con \u201cCupid\u201d.<\/p>\n<p>El sencillo \u201cSeven\u201d del excantante de BTS Jung Kook, con el rapero estadounidense Latto, complet\u00f3 la representaci\u00f3n asi\u00e1tica en la lista en el puesto n\u00famero 10.<\/p>\n<p>Lanzado despu\u00e9s de que la popular banda coreana anunciara que se centrar\u00eda en proyectos individuales, \u201cSeven\u201d debut\u00f3 en la cima del Billboard Hot 100 y Global 200 de EE. UU., convirti\u00e9ndose en la canci\u00f3n que m\u00e1s r\u00e1pido alcanz\u00f3 los mil millones de reproducciones en Spotify.<\/p>\n<p>Tambi\u00e9n hubo una versi\u00f3n con letras m\u00e1s expl\u00edcitamente sexuales, algo poco com\u00fan en el mundo tradicionalmente m\u00e1s conservador del K-pop, lo que contribuy\u00f3 al factor de shock de la canci\u00f3n y a su viralidad en internet.<\/p>\n<p>Detr\u00e1s de \u201cIdol\u201d de Yoasobi en el puesto n\u00famero 2 a nivel mundial estaba la controvertida canci\u00f3n \u201cTry That in a Small Town\u201d de Jason Aldean, y \u201cBZRP Music Sessions #53\u201d, la canci\u00f3n viral de Shakira dirigida a su ex Gerard Piqu\u00e9.<\/p>\n<p>Otras canciones que lideran las consultas de b\u00fasqueda de tendencias en 2023 incluyen \u201cRich Men North of Richmond\u201d en el puesto 8. El lamento de Oliver Anthony por la clase trabajadora y la rabia contra la \u00e9lite pol\u00edtica de Washington se convirti\u00f3 en la primera canci\u00f3n de un artista sin historial en las listas en alcanzar el puesto 1 en cartelera.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao japon\u00e9s de m\u00fasica synth el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442631","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao japon\u00e9s de m\u00fasica synth el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-25T16:33:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023\",\"datePublished\":\"2023-12-25T16:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/\"},\"wordCount\":783,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/\",\"name\":\"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-25T16:33:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/","og_locale":"es_ES","og_type":"article","og_title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023 - Noticias","og_description":"(CNN) &#8212; Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao japon\u00e9s de m\u00fasica synth el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/","og_site_name":"Noticias","article_published_time":"2023-12-25T16:33:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/"},"author":{"name":"","@id":""},"headline":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","datePublished":"2023-12-25T16:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/"},"wordCount":783,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/","url":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/","name":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-25T16:33:34+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-25T16:33:34Z","datePublished":"2023-12-25T16:33:34Z","dateModified":"2023-12-25T16:33:34Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Este d\\u00fao japon\\u00e9s que encabez\\u00f3 la lista de b\\u00fasquedas de canciones m\\u00e1s populares de Google en 2023\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-9\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-25T16:33:34Z\",\"datePublished\":\"2023-12-25T16:33:34Z\",\"dateModified\":\"2023-12-25T16:33:34Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442614,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023\/","url_meta":{"origin":1442631,"position":0},"title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442617,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-2\/","url_meta":{"origin":1442631,"position":1},"title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442619,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-3\/","url_meta":{"origin":1442631,"position":2},"title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442621,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-4\/","url_meta":{"origin":1442631,"position":3},"title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442622,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-5\/","url_meta":{"origin":1442631,"position":4},"title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442624,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/este-duo-japones-que-encabezo-la-lista-de-busquedas-de-canciones-mas-populares-de-google-en-2023-6\/","url_meta":{"origin":1442631,"position":5},"title":"Este d\u00fao japon\u00e9s que encabez\u00f3 la lista de b\u00fasquedas de canciones m\u00e1s populares de Google en 2023","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Fue el a\u00f1o en el que Taylor Swift y Beyonc\u00e9 lanzaron giras mundiales, Olivia Rodrigo estren\u00f3 su \u00e1lbum \u201cGUTS\u201d y Jason Aldean se sum\u00f3 a la controversia por la guerra cultural en el g\u00e9nero country. Pero seg\u00fan el resumen anual de Google Year in Search, fue un d\u00fao\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442631"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442631\/revisions"}],"predecessor-version":[{"id":1442646,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442631\/revisions\/1442646"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}