{"id":1442642,"date":"2023-12-25T14:33:26","date_gmt":"2023-12-25T22:33:26","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442642"},"modified":"2023-12-25T14:33:26","modified_gmt":"2023-12-25T22:33:26","slug":"cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/","title":{"rendered":"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto"},"content":{"rendered":"<p>(CNN) &#8212; Los conocedores de caf\u00e9 han sostenido durante mucho tiempo la creencia de que agregar un poco de agua a los granos antes de molerlos podr\u00eda marcar la diferencia. Un nuevo estudio realizado por investigadores de la Universidad de Oregon parece confirmar exactamente por qu\u00e9.<\/p>\n<p>La investigaci\u00f3n explor\u00f3 c\u00f3mo la t\u00e9cnica, que comenz\u00f3 como un intento de abordar el proceso de elaboraci\u00f3n del caf\u00e9, a menudo complicado, tambi\u00e9n afectaba el sabor.<\/p>\n<p>&#171;Cuando se muele caf\u00e9, sale para todos lados&#187;, dijo el coautor del estudio Christopher Hendon, profesor asociado de qu\u00edmica computacional de materiales en la Universidad de Oregon. \u201cDel molinillo sale polvo, es como una erupci\u00f3n que lo cubre todo. Pero si le a\u00f1ades un poco de agua, parece que no llega a todas partes. Es m\u00e1s limpio. Esa fue la raz\u00f3n principal por la que la gente lo hizo\u201d.<\/p>\n<p>El desorden es causado por la electricidad est\u00e1tica, que se crea por la fricci\u00f3n cuando los granos se aplastan. Esta carga est\u00e1tica hace que las part\u00edculas de caf\u00e9 molido se repelan entre s\u00ed, como imanes de la misma polaridad, envi\u00e1ndolas en todas direcciones.<\/p>\n<p>CosMc&#8217;s: por qu\u00e9 McDonald&#8217;s quiere su propia cadena de caf\u00e9<\/p>\n<p>El agua act\u00faa como un aislante, amortiguando este efecto, un proceso conocido como t\u00e9cnica de la \u201cgota de Ross\u201d. &#171;Fue propuesto por primera vez por un entusiasta en un foro de baristas caseros&#187;, dijo Hendon. &#171;La idea existe desde hace varios a\u00f1os y originalmente se tom\u00f3 prestada de la industria de producci\u00f3n de materiales, como la pulpa de madera&#187;.<\/p>\n<p>Sin embargo, lo que comenz\u00f3 como una forma de reducir el desorden poco a poco se transform\u00f3 en una forma m\u00e1s sofisticada de obtener una mejor bebida, o al menos eso pensaba la gente. La teor\u00eda era que al reducir la electricidad est\u00e1tica, el agua no solo evitaba que el caf\u00e9 molido volara o se pegara al interior del molinillo, sino que tambi\u00e9n evitaba que se formaran grumos microsc\u00f3picos durante la preparaci\u00f3n.<\/p>\n<p>\u00bfPor qu\u00e9 son malos los grumos? Porque el agua fluye a su alrededor, dejando intacto el caf\u00e9 y, por lo tanto, el sabor. En lenguaje barista, disminuyen el rendimiento de extracci\u00f3n, o la cantidad de caf\u00e9 que termina en la taza, disuelto en el l\u00edquido.<\/p>\n<p>&#171;Si se forman grumos, habr\u00e1 cantidades significativas de espacio vac\u00edo, algo as\u00ed como cuando se apilan sand\u00edas&#187;, dijo Hendon. &#171;Como resultado, cuando le pones agua, terminas con menos superficie que toca el agua y, por lo tanto, menor extracci\u00f3n&#187;.<\/p>\n<p>El estudio, publicado el 6 de diciembre en la revista Matter, prob\u00f3 este beneficio potencial m\u00e1s sutil y dif\u00edcil de ver de agregar agua a los granos: deshacerse de los microgrumos que roban el sabor.<\/p>\n<p>Poniendo a prueba la &#8216;gota de Ross&#8217;<\/p>\n<p>El equipo de investigaci\u00f3n incluy\u00f3 a dos vulcan\u00f3logos, que reutilizaron una herramienta normalmente empleada para medir cargas el\u00e9ctricas en incendios forestales y cenizas volc\u00e1nicas. Pesaron el caf\u00e9 antes de agregarle agua (usando una pipeta para lograr una precisi\u00f3n de microgramos) y luego lo molieron en un molinillo profesional, uno de los m\u00e1s r\u00e1pidos del mercado y una opci\u00f3n popular en las cafeter\u00edas.<\/p>\n<p>&#171;La adici\u00f3n de peque\u00f1as cantidades de agua, desde una gota hacia arriba, disminuye o desactiva la carga est\u00e1tica y lo hace de manera que el caf\u00e9 sale del molinillo sin haber recibido carga el\u00e9ctrica&#187;, dijo Hendon. No est\u00e1 claro qu\u00e9 hace exactamente el agua, pero dijo que tal vez est\u00e9 absorbiendo la carga o cambiando la temperatura dentro del molinillo, reduciendo los efectos de la fricci\u00f3n.<\/p>\n<p>China, una naci\u00f3n bebedora de t\u00e9, ahora tiene m\u00e1s cafeter\u00edas de marca que Estados Unidos<\/p>\n<p>\u201cSi se a\u00f1ade suficiente agua, tambi\u00e9n se puede eliminar la formaci\u00f3n de grumos\u201d, a\u00f1ade. \u201cEn principio se conseguir\u00e1n mayores extracciones o menos residuos. Eso es exactamente lo que hace, porque ahora se proporciona m\u00e1s superficie disponible para la misma cantidad de agua\u201d.<\/p>\n<p>Sin grumos, toda el agua de preparaci\u00f3n entra en contacto con los granos molidos, lo que reduce la cantidad de caf\u00e9 que efectivamente no se utiliza y brinda una preparaci\u00f3n m\u00e1s consistente.<\/p>\n<p>La cantidad ideal de agua puede cambiar seg\u00fan par\u00e1metros como el tipo de tueste y el grado de molienda, por lo que no existe una regla \u00fanica para todos, pero en promedio, el estudio encontr\u00f3 que agregar agua aumenta el rendimiento de extracci\u00f3n en un 10%. Hendon advirti\u00f3 que esto no necesariamente equivale a una diferencia tangible en el sabor, pero s\u00ed confirma el beneficio de la t\u00e9cnica de la \u201cgota de Ross\u201d.<\/p>\n<p>&#171;(Desde que se public\u00f3 el estudio) he recibido muchos correos electr\u00f3nicos de personas que me dicen lo agradecidas que est\u00e1n, porque desde el punto de vista de la limpieza, esta es una mejora enorme, enorme&#187;, dijo Hendon. &#171;Lo que recomendar\u00eda al usuario dom\u00e9stico es comenzar con una sola gota de agua y aumentar a partir de ah\u00ed; hay una gran cantidad de matices en este proceso&#187;.<\/p>\n<p>Tambi\u00e9n hay un inconveniente: el agua mejora la limpieza independientemente del m\u00e9todo de preparaci\u00f3n, pero el beneficio de preparaci\u00f3n solo se produce con el espresso y, en menor medida, con el caf\u00e9 filtrado. Cuando se utiliza una cafetera, una prensa francesa o un AeroPress, nada cambia mucho porque, dado el molido m\u00e1s grueso que se requiere con estos, &#171;toda el agua ya est\u00e1 tocando todo el caf\u00e9&#187;, dijo Hendon.<\/p>\n<p>Los bebedores de caf\u00e9 caminan m\u00e1s, pero duermen menos, seg\u00fan un estudio<\/p>\n<p>Buscando la mejor forma de preparar caf\u00e9<\/p>\n<p>Lance Hendrix, un experto en caf\u00e9 y barista profesional que no particip\u00f3 en el estudio, intent\u00f3 replicar los hallazgos del estudio y discuti\u00f3 sus resultados en una inmersi\u00f3n profunda en Youtube. Dijo que el trabajo es un valiente intento de desmitificar lo que sucede cuando los granos se roc\u00edan con agua, pero para obtener evidencia m\u00e1s concluyente, se deben realizar m\u00e1s pruebas con diferentes modelos de molinillos.<\/p>\n<p>Sin embargo, bas\u00e1ndose en sus propias pruebas, cree que los beneficios son plausibles.<\/p>\n<p>&#171;Descubr\u00ed que la cantidad de agua necesaria para obtener los supuestos beneficios variaba enormemente de un molinillo a otro&#187;, a\u00f1adi\u00f3. \u201cEntonces, aunque no creo que actualmente exista una implicaci\u00f3n pr\u00e1ctica general del estudio para mejorar inmediatamente la preparaci\u00f3n del caf\u00e9 en casa, creo que es una adici\u00f3n importante a los intentos que tenemos entre manos para tratar de comprender el proceso extremadamente complejo de molienda, que es posiblemente el aspecto m\u00e1s importante de preparar una taza de caf\u00e9\u201d.<\/p>\n<p>Fran\u00e7ois Knopes del Independent Coffee Lab, un tostador y catador de caf\u00e9 profesional que tampoco particip\u00f3 en el estudio, dijo que rutinariamente roc\u00eda sus granos antes de molerlos para evaluar su sabor y recomendar\u00eda hacerlo a cualquier persona en el hogar. Sin embargo, cree que hacerlo en otros lugares podr\u00eda resultar poco pr\u00e1ctico.<\/p>\n<p>&#171;Consumir\u00eda mucho tiempo para la mayor\u00eda de las instalaciones profesionales, como una cafeter\u00eda que sirve cientos de bebidas a base de espresso al d\u00eda&#187;, dijo Knopes. &#171;Para mejorar y aumentar la extracci\u00f3n, es mejor que los baristas profesionales busquen tecnolog\u00edas de molienda mejoradas o dispositivos de &#171;desaglomeraci\u00f3n&#187;, peque\u00f1as agujas que se utilizan para batir los granos molidos y romper las peque\u00f1as rocas generadas durante la molienda&#187;.<\/p>\n<p>Hendon estuvo de acuerdo. &#171;Por el momento, es un poco impr\u00e1ctico en el sentido de que habr\u00eda que dar un paso m\u00e1s&#187;, dijo. &#171;Pero sospecho que se desarrollar\u00e1n tecnolog\u00edas en torno a esta idea de que agregar agua a demanda es una t\u00e9cnica muy poderosa&#187;.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los conocedores de caf\u00e9 han sostenido durante mucho tiempo la creencia de que agregar un poco de agua a los granos antes de molerlos podr\u00eda marcar la diferencia. Un nuevo estudio realizado por investigadores de la Universidad de Oregon parece confirmar exactamente por qu\u00e9. La investigaci\u00f3n explor\u00f3 c\u00f3mo la t\u00e9cnica, que comenz\u00f3 como [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442642","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los conocedores de caf\u00e9 han sostenido durante mucho tiempo la creencia de que agregar un poco de agua a los granos antes de molerlos podr\u00eda marcar la diferencia. Un nuevo estudio realizado por investigadores de la Universidad de Oregon parece confirmar exactamente por qu\u00e9. La investigaci\u00f3n explor\u00f3 c\u00f3mo la t\u00e9cnica, que comenz\u00f3 como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-25T22:33:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto\",\"datePublished\":\"2023-12-25T22:33:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/\"},\"wordCount\":1354,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/\",\"name\":\"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-25T22:33:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto - Noticias","og_description":"(CNN) &#8212; Los conocedores de caf\u00e9 han sostenido durante mucho tiempo la creencia de que agregar un poco de agua a los granos antes de molerlos podr\u00eda marcar la diferencia. Un nuevo estudio realizado por investigadores de la Universidad de Oregon parece confirmar exactamente por qu\u00e9. La investigaci\u00f3n explor\u00f3 c\u00f3mo la t\u00e9cnica, que comenz\u00f3 como [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/","og_site_name":"Noticias","article_published_time":"2023-12-25T22:33:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/"},"author":{"name":"","@id":""},"headline":"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto","datePublished":"2023-12-25T22:33:26+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/"},"wordCount":1354,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/","url":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/","name":"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-25T22:33:26+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfCu\u00e1l es el secreto para una mejor taza de caf\u00e9? Los cient\u00edficos podr\u00edan haberlo descubierto","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-25T22:33:26Z","datePublished":"2023-12-25T22:33:26Z","dateModified":"2023-12-25T22:33:26Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfCu\\u00e1l es el secreto para una mejor taza de caf\\u00e9? Los cient\\u00edficos podr\\u00edan haberlo descubierto\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/cual-es-el-secreto-para-una-mejor-taza-de-cafe-los-cientificos-podrian-haberlo-descubierto\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-25T22:33:26Z\",\"datePublished\":\"2023-12-25T22:33:26Z\",\"dateModified\":\"2023-12-25T22:33:26Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463105,"url":"https:\/\/noticiasya.com\/hartford\/2025\/06\/02\/taza-diaria-cafe-vivir-mas-mejor-salud-trax\/","url_meta":{"origin":1442642,"position":0},"title":"Tu taza diaria de caf\u00e9 podr\u00eda ayudarte a vivir m\u00e1s tiempo y con mejor salud, seg\u00fan un nuevo estudio","author":"","date":"junio 2, 2025","format":false,"excerpt":"\u00bfQuieres llegar a una edad avanzada con una mente \u00e1gil y un cuerpo sano? Parte de la respuesta podr\u00eda estar en tu taza de caf\u00e9, seg\u00fan un nuevo estudio.\u201cLas mujeres que beb\u00edan de una a tres tazas de caf\u00e9 con cafe\u00edna al d\u00eda entre los 50 y los 60 a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457347,"url":"https:\/\/noticiasya.com\/hartford\/2025\/01\/08\/limitar-consumo-cafe-periodo-reducir-riesgo-muerte-trax\/","url_meta":{"origin":1442642,"position":1},"title":"Un estudio sugiere limitar el consumo de caf\u00e9 a este per\u00edodo para reducir el riesgo de muerte prematura","author":"","date":"enero 8, 2025","format":false,"excerpt":"Beber caf\u00e9 se ha relacionado repetidamente con una mejor salud card\u00edaca y una vida m\u00e1s larga. Pero los beneficios del consumo de caf\u00e9 podr\u00edan depender del momento en que se lo toma, seg\u00fan un nuevo estudio.Limitar el consumo de caf\u00e9 a la ma\u00f1ana puede ser lo mejor, independientemente de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471050,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/09\/cafe-te-cafeina-proteccion-contra-demencia-beneficios-salud-trax\/","url_meta":{"origin":1442642,"position":2},"title":"\u00bfPor qu\u00e9 una taza diaria de caf\u00e9 y t\u00e9 con cafe\u00edna podr\u00eda protegerte contra la demencia?","author":"","date":"febrero 9, 2026","format":false,"excerpt":"No tienes que dejar la dosis matutina de cafe\u00edna para proteger tu cerebro contra la demencia en el futuro. Nuevas investigaciones muestran que el consumo diario de caf\u00e9 o t\u00e9 \u2014y s\u00ed, del tipo con cafe\u00edna\u2014 est\u00e1 asociado con una mejor salud cognitiva a largo plazo.Aquellos que disfrutaron de dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457969,"url":"https:\/\/noticiasya.com\/hartford\/2025\/01\/28\/precios-cafe-suben-cancelacion-arancel-colombia-trax\/","url_meta":{"origin":1442642,"position":3},"title":"Precios del caf\u00e9 suben pese a cancelaci\u00f3n de arancel de Trump a Colombia","author":"","date":"enero 28, 2025","format":false,"excerpt":"Los precios del caf\u00e9 alcanzaron un nuevo m\u00e1ximo el lunes, un d\u00eda despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara (y luego diera marcha atr\u00e1s) con aplicar un arancel del 25% a Colombia durante una disputa sobre los vuelos de deportaci\u00f3n desde EE.UU. Y el precio sigue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451560,"url":"https:\/\/noticiasya.com\/hartford\/2024\/08\/01\/cultivo-cafe-precios-lujo-no-hay-escapatoria-trax\/","url_meta":{"origin":1442642,"position":4},"title":"El caf\u00e9 se est\u00e1 convirtiendo en un lujo y es culpa del cambio clim\u00e1tico","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN) -- Escondidos en los altos de las monta\u00f1as de Chiapas, en el sur de M\u00e9xico, unos 150 productores de caf\u00e9 de la finca familiar Edelmann trabajan con sus manos durante horas y horas. La sombra de los \u00e1rboles es la \u00fanica barrera entre sus cuerpos y el sol del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466328,"url":"https:\/\/noticiasya.com\/hartford\/2025\/09\/10\/brad-pitt-comercial-cafe-expreso-taika-waititi-trax\/","url_meta":{"origin":1442642,"position":5},"title":"Brad Pitt protagoniza un anuncio de Taika Waititi para una m\u00e1quina de caf\u00e9 expreso que cuesta casi US$ 1.500","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Si te encanta el olor del comercialismo por la ma\u00f1ana, aqu\u00ed tienes algo para disfrutar.Brad Pitt, el actor, productor y cultivador de barbas favorito de todos a sus 61 a\u00f1os, es la estrella de un nuevo anuncio de m\u00e1quina de caf\u00e9 expreso de De\u2019Longhi dirigido por el ganador del Oscar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442642"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442642\/revisions"}],"predecessor-version":[{"id":1442658,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442642\/revisions\/1442658"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}