{"id":1442650,"date":"2023-12-25T18:33:34","date_gmt":"2023-12-26T02:33:34","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442650"},"modified":"2023-12-25T18:33:34","modified_gmt":"2023-12-26T02:33:34","slug":"guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/","title":{"rendered":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s"},"content":{"rendered":"<p>\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed<\/p>\n<p>Palestinos lloran a sus familiares, muertos en un ataque israel\u00ed nocturno en el campo de refugiados de Al-Maghazi, el 25 de diciembre de 2023. (Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty Images)<\/p>\n<p>TOPSHOT &#8211; Palestinos inspeccionan los da\u00f1os en el campo de refugiados de Al-Maghazi tras un ataque israel\u00ed nocturno el 25 de diciembre de 2023. (Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty Images)<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Palestinos lloran a sus familiares, muertos en un ataque israel\u00ed nocturno en el campo de refugiados de Al-Maghazi, el 25 de diciembre de 2023. (Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty Images) TOPSHOT &#8211; Palestinos inspeccionan los da\u00f1os en el campo de refugiados de Al-Maghazi tras un ataque [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442650","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s - Noticias\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Palestinos lloran a sus familiares, muertos en un ataque israel\u00ed nocturno en el campo de refugiados de Al-Maghazi, el 25 de diciembre de 2023. (Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty Images) TOPSHOT &#8211; Palestinos inspeccionan los da\u00f1os en el campo de refugiados de Al-Maghazi tras un ataque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-26T02:33:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s\",\"datePublished\":\"2023-12-26T02:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/\"},\"wordCount\":103,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/\",\"name\":\"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-26T02:33:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/","og_locale":"es_ES","og_type":"article","og_title":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s - Noticias","og_description":"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Palestinos lloran a sus familiares, muertos en un ataque israel\u00ed nocturno en el campo de refugiados de Al-Maghazi, el 25 de diciembre de 2023. (Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty Images) TOPSHOT &#8211; Palestinos inspeccionan los da\u00f1os en el campo de refugiados de Al-Maghazi tras un ataque [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/","og_site_name":"Noticias","article_published_time":"2023-12-26T02:33:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/"},"author":{"name":"","@id":""},"headline":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s","datePublished":"2023-12-26T02:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/"},"wordCount":103,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/","url":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/","name":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-26T02:33:34+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-26T02:33:34Z","datePublished":"2023-12-26T02:33:34Z","dateModified":"2023-12-26T02:33:34Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\\u00e1s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-4\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-26T02:33:34Z\",\"datePublished\":\"2023-12-26T02:33:34Z\",\"dateModified\":\"2023-12-26T02:33:34Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442648,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-3\/","url_meta":{"origin":1442650,"position":0},"title":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edPalestinos lloran a sus familiares, muertos en un ataque israel\u00ed nocturno en el campo de refugiados de Al-Maghazi, el 25 de diciembre de 2023. (Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty Images)TOPSHOT - Palestinos inspeccionan los da\u00f1os en el campo de refugiados de Al-Maghazi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442652,"url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-5\/","url_meta":{"origin":1442650,"position":1},"title":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edPalestinos lloran a sus familiares, muertos en un ataque israel\u00ed nocturno en el campo de refugiados de Al-Maghazi, el 25 de diciembre de 2023. (Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty Images)TOPSHOT - Palestinos inspeccionan los da\u00f1os en el campo de refugiados de Al-Maghazi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444776,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/01\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-64\/","url_meta":{"origin":1442650,"position":2},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"febrero 1, 2024","format":false,"excerpt":"Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Las personas que huyeron de los combates en Gaza se reunieron en una calle abarrotada en Rafah, en la parte sur del territorio palestino, el 1 de febrero de 2024. Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty ImagesAl fondo se muestra una excavadora militar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444779,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/02\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-65\/","url_meta":{"origin":1442650,"position":3},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"febrero 2, 2024","format":false,"excerpt":"Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Las personas que huyeron de los combates en Gaza se reunieron en una calle abarrotada en Rafah, en la parte sur del territorio palestino, el 1 de febrero de 2024. Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty ImagesAl fondo se muestra una excavadora militar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444795,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/02\/resumen-de-noticias-de-la-guerra-entre-israel-y-hamas-del-1-de-febrero\/","url_meta":{"origin":1442650,"position":4},"title":"Resumen de noticias de la guerra entre Israel y Hamas del 1 de febrero","author":"","date":"febrero 2, 2024","format":false,"excerpt":"Este seguimiento en vivo finaliz\u00f3. Sigue aqu\u00ed las actualizaciones m\u00e1s recientes.Las personas que huyeron de los combates en Gaza se reunieron en una calle abarrotada en Rafah, en la parte sur del territorio palestino, el 1 de febrero de 2024. Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty ImagesAl fondo se muestra una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445124,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/08\/guerra-entre-israel-y-hamas-en-vivo-noticias-ataques-represalia-de-ee-uu-en-iraq-y-siria-tension-en-medio-oriente-y-mas-21\/","url_meta":{"origin":1442650,"position":5},"title":"Guerra entre Israel y Hamas en vivo: noticias, ataques represalia de EE.UU. en Iraq y Siria, tensi\u00f3n en Medio Oriente y m\u00e1s","author":"","date":"febrero 8, 2024","format":false,"excerpt":"\ud83d\udd04\u00a0Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edTanques del ej\u00e9rcito israel\u00ed avanzan por el sur de Israel a lo largo de la frontera con la Franja de Gaza el 7 de febrero de 2024, en medio de batallas en curso entre Israel y el grupo militante palestino Ham\u00e1s. (Cr\u00e9dito:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442650"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442650\/revisions"}],"predecessor-version":[{"id":1442666,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442650\/revisions\/1442666"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}