{"id":1442655,"date":"2023-12-25T20:33:31","date_gmt":"2023-12-26T04:33:31","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442655"},"modified":"2023-12-25T20:33:31","modified_gmt":"2023-12-26T04:33:31","slug":"recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/","title":{"rendered":"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos"},"content":{"rendered":"<p>(CNN) &#8212; Imagina, por un momento, el banquete festivo m\u00e1s glorioso, con un pavo enorme, dos rellenos, jam\u00f3n, las guarniciones de rigor y al menos media docena de tartas y pasteles. Todo esto puede sonar grandioso, hasta que nos fijamos en las extravagantes exhibiciones del antiguo banquete romano.<\/p>\n<p>Los miembros de las clases altas romanas sol\u00edan darse fastuosos banquetes de horas de duraci\u00f3n que serv\u00edan para difundir su riqueza y estatus de una forma que eclipsa nuestra noci\u00f3n de una comida resplandeciente. &#171;Comer era el acto supremo de civilizaci\u00f3n y celebraci\u00f3n de la vida&#187;, afirma Alberto Jori, catedr\u00e1tico de Filosof\u00eda Antigua de la Universidad de Ferrara, Italia.<\/p>\n<p>Un antiguo palacio romano &#171;perdido&#187; reabre despu\u00e9s de 50 a\u00f1os de abandono<\/p>\n<p>Los antiguos romanos disfrutaban con preparaciones dulces y saladas. La lagane, una pasta corta r\u00fastica que suele servirse con garbanzos, tambi\u00e9n se utilizaba para hacer un pastel de miel con queso ricotta fresco. Los romanos utilizaban el garum, una salsa de pescado fermentada, picante y salada, para dar sabor umami a todos los platos, incluso como guarnici\u00f3n de postres. (Para contextualizar, el garum tiene un perfil de sabor y una composici\u00f3n similares a las salsas de pescado asi\u00e1ticas actuales, como la nuoc mam de Vietnam y la nam pla de Tailandia). El preciado condimento se elaboraba dejando fermentar carne, sangre y v\u00edsceras de pescado en recipientes bajo el sol mediterr\u00e1neo.<\/p>\n<p>&#171;Las rosas de Heliog\u00e1balo&#187;, de Lawrence Alma-Tadema (1888), ilustra a los celestiales comensales romanos en un banquete. Cr\u00e9dito: Museo Activo\/Alamy Stock Photo<\/p>\n<p>La carne de caza, como el venado, el jabal\u00ed, el conejo y el fais\u00e1n, junto con productos del mar como las ostras crudas, el marisco y la langosta, eran algunos de los alimentos m\u00e1s caros que aparec\u00edan regularmente en los banquetes romanos.<\/p>\n<p>Adem\u00e1s, los anfitriones jugaban a ser mejores sirviendo platillos ex\u00f3ticos y exagerados, como estofado de lengua de loro y lirones rellenos. &#171;El lir\u00f3n era un manjar que los campesinos engordaban durante meses en ollas y luego vend\u00edan en los mercados&#187;, explica Jori. &#171;Tambi\u00e9n se mataban enormes cantidades de loros para tener suficientes lenguas para hacer fricas\u00e9&#187;.<\/p>\n<p>Giorgio Franchetti, historiador de la alimentaci\u00f3n y estudioso de la historia romana antigua, recuper\u00f3 recetas perdidas de estos festines, que comparte en &#171;Dining with the Ancient Romans&#187;, escrito con la &#171;arqueococinera&#187; Cristina Conte. Juntos organizan experiencias gastron\u00f3micas en sitios arqueol\u00f3gicos de Italia que permiten a los visitantes saborear la comida de los nobles romanos. Estas visitas culturales tambi\u00e9n profundizan en los sorprendentes rituales que acompa\u00f1aban a estas comidas.<\/p>\n<p>Entre las recetas inusuales que prepara Conte figura el salsum sine salso, inventado por el famoso gastr\u00f3nomo romano Marcus Gavius Apicius. Se trataba de una &#171;broma gastron\u00f3mica&#187; hecha para asombrar y enga\u00f1ar a los invitados. El pescado se presentaba con cabeza y cola, pero el interior estaba relleno de h\u00edgado de vaca. Los juegos de manos, combinados con el factor sorpresa, contaban mucho en estas competiciones.<\/p>\n<p>La dieta ser\u00eda el secreto de los antiguos romanos para mantener su salud dental<\/p>\n<p>Funciones corporales<\/p>\n<p>Atiborrarse de comida durante horas y horas tambi\u00e9n exig\u00eda lo que nosotros considerar\u00edamos un comportamiento social inadecuado para dar cabida a tales indulgencias glotonas.<\/p>\n<p>&#171;Ten\u00edan extra\u00f1os h\u00e1bitos culinarios que no encajan bien con la etiqueta moderna, como comer recostados y vomitar entre platillos&#187;, explica Franchetti.<\/p>\n<p>Estas pr\u00e1cticas contribu\u00edan a mantener activa la fiesta. Dado que los banquetes eran un s\u00edmbolo de estatus y duraban horas hasta bien entrada la noche, vomitar era una pr\u00e1ctica habitual necesaria para hacer sitio en el est\u00f3mago para m\u00e1s comida. Los antiguos romanos eran hedonistas y buscaban los placeres de la vida&#187;, explica Jori, autor de varios libros sobre la cultura culinaria de Roma.<\/p>\n<p>De hecho, era costumbre levantarse de la mesa para vomitar en una habitaci\u00f3n cercana al comedor. Con una pluma, los asistentes al fest\u00edn se hac\u00edan cosquillas en la parte posterior de la garganta para estimular el impulso de regurgitar, explica Jori. En consonancia con su elevado estatus social, definido por no tener que realizar trabajos manuales, los invitados simplemente regresaban a la sala del banquete mientras los esclavos limpiaban su desastre.<\/p>\n<p>Grabado de un banquete en casa de Lucio Licinio L\u00faculo, alrededor del a\u00f1o 80 a.C. Cr\u00e9dito: Ullstein Bild\/Getty Images<\/p>\n<p>La obra maestra literaria de Cayo Petronio Arbiter &#171;El Satyricon&#187; capta esta din\u00e1mica social t\u00edpica de la sociedad romana de mediados del siglo I d.C. con el personaje del rico Trimalchio, que le dice a un esclavo que le traiga un &#171;orinal&#187;. En otras palabras, cuando la naturaleza llamaba, los invitados no ten\u00edan por qu\u00e9 ir al ba\u00f1o; a menudo el retrete ven\u00eda a ellos, impulsado de nuevo por el trabajo de los esclavos.<\/p>\n<p>Tambi\u00e9n se consideraba normal echar gases en la comida, porque se cre\u00eda que atrapar gases en el interior de los intestinos pod\u00eda causar la muerte, explic\u00f3 Jori. Se dice que el emperador Claudio, que rein\u00f3 entre el 41 y el 54 d.C., incluso promulg\u00f3 un edicto para fomentar las flatulencias en la mesa, seg\u00fan consta en la &#171;Vida de Claudio&#187; del historiador romano Suetonio.<\/p>\n<p>Comodidades y privilegios de los ricos<\/p>\n<p>La hinchaz\u00f3n se reduc\u00eda comiendo tumbado en una c\u00f3moda chaise longue acolchada. Se cre\u00eda que la posici\u00f3n horizontal facilitaba la digesti\u00f3n y era la m\u00e1xima expresi\u00f3n de una posici\u00f3n de \u00e9lite.<\/p>\n<p>&#171;En realidad, los romanos com\u00edan tumbados sobre el vientre para que el peso del cuerpo se repartiera uniformemente y les ayudara a relajarse. Con la mano izquierda sosten\u00edan la cabeza y con la derecha recog\u00edan los bocados de la mesa y se los llevaban a la boca. As\u00ed com\u00edan con las manos y la comida ten\u00eda que estar ya cortada por los esclavos&#187;, dec\u00eda Jori.<\/p>\n<p>Siete pa\u00edses, siete comidas tradicionales de Navidad<\/p>\n<p>Los restos de comida y los huesos de carne y pescado eran arrojados al suelo por los invitados. Para hacerte una idea de la escena, considera un mosaico hallado en una villa romana de Aquileia, que representa restos de pescado y comida esparcidos por el suelo. A los romanos les gustaba decorar los suelos de las salas de banquetes con este tipo de im\u00e1genes para camuflar la comida real esparcida por el suelo. Esta t\u00e1ctica de trampantojo, o efecto de &#171;suelo sin barrer&#187;, era una ingeniosa t\u00e9cnica de mosaico.<\/p>\n<p>Este mosaico del siglo II d.C. representa un suelo sin barrer despu\u00e9s de un banquete, para disimular el desorden real causado en la celebraci\u00f3n. Cr\u00e9dito: De\u00a0Agostini\/Getty Images<\/p>\n<p>Acostarse tambi\u00e9n permit\u00eda a los comensales echarse una siesta entre plato y plato, dando un respiro al est\u00f3mago.<br \/>\nSin embargo, el acto de reclinarse mientras se cenaba era un privilegio reservado solo a los hombres. Las mujeres com\u00edan en otra mesa o se arrodillaban o sentaban junto a su marido mientras \u00e9ste disfrutaba de la comida.<\/p>\n<p>Un antiguo fresco romano de una escena de banquete en la Casa dei Casti Amanti de Pompeya, por ejemplo, representa a un hombre reclinado mientras dos mujeres se arrodillan a ambos lados. Una de las mujeres atiende al hombre ayud\u00e1ndole a sostener un recipiente para beber en forma de cuerno llamado rhyton. Otro fresco de Herculano, expuesto en el Museo Arqueol\u00f3gico Nacional de N\u00e1poles, representa a una mujer sentada cerca de un hombre que est\u00e1 tumbado mientras levanta tambi\u00e9n un rhyton.<\/p>\n<p>&#171;La posici\u00f3n horizontal de los hombres para comer era un s\u00edmbolo de dominio sobre las mujeres. Las mujeres romanas establecieron el derecho a comer con sus maridos en una etapa muy posterior de la historia de la antigua Roma; fue su primera conquista social y victoria contra la discriminaci\u00f3n sexual&#187;, explica Jori.<\/p>\n<p>El emperador Ner\u00f3n participando en una bacanal, un festival romano que celebraba a Baco. Cr\u00e9dito: Universal Images Group\/Getty Images<\/p>\n<p>Supersticiones en la mesa<\/p>\n<p>Los romanos tambi\u00e9n eran muy supersticiosos. Todo lo que se ca\u00eda de la mesa pertenec\u00eda al m\u00e1s all\u00e1 y no deb\u00eda recuperarse por miedo a que los muertos vinieran en busca de venganza, mientras que derramar sal era un mal presagio, dec\u00eda Franchetti. El pan solo deb\u00eda tocarse con las manos y las c\u00e1scaras de huevo y los moluscos deb\u00edan partirse. Si un gallo cantaba a una hora inusual, se enviaba a los criados a buscar uno, matarlo y servirlo enseguida.<\/p>\n<p>Seg\u00fan Franchetti, el banquete era una forma de mantener a raya a la muerte. Los banquetes terminaban con un ritual de borrachera en el que los comensales hablaban de la muerte para recordarse a s\u00ed mismos que deb\u00edan vivir plenamente y disfrutar de la vida; en resumen, carpe diem.<\/p>\n<p>Encuentran en Roma un mosaico de 2.300 a\u00f1os de antig\u00fcedad hecho con conchas y corales<\/p>\n<p>En consonancia con esta visi\u00f3n del mundo, los objetos de la mesa, como los saleros y pimenteros, ten\u00edan forma de calavera. Seg\u00fan Jori, era costumbre invitar a la comida a los difuntos queridos y servirles platos llenos de comida. Las esculturas que representaban a los muertos se sentaban a la mesa con los vivos.<\/p>\n<p>Mosaico de un esqueleto de la Casa de las Vestales de Pompeya sosteniendo jarras de vino. Cr\u00e9dito: Archivo Werner Forman\/Shutterstock<\/p>\n<p>El vino no siempre se beb\u00eda solo, sino mezclado con otros ingredientes. El agua se utilizaba para diluir la potencia del alcohol y permitir que los invitados bebieran m\u00e1s, mientras que el agua de mar se a\u00f1ad\u00eda para que la sal conservara los barriles de vino procedentes de rincones lejanos del imperio.<\/p>\n<p>&#171;Incluso el alquitr\u00e1n era una sustancia habitual mezclada con el vino, que con el tiempo se mezclaba con el alcohol. Los romanos apenas pod\u00edan percibir el sabor desagradable&#187;, explica Jori.<\/p>\n<p>Tal vez el \u00faltimo s\u00edmbolo del exceso, el epic\u00fareo Apicio se suicid\u00f3 supuestamente porque se hab\u00eda arruinado tras celebrar demasiados banquetes fastuosos. Sin embargo, dej\u00f3 un legado gastron\u00f3mico que incluye su famoso pastel de Apicio, elaborado con una mezcla de pescado y carne, como entra\u00f1as de aves y pechugas de cerdo. Un platillo que, hoy en d\u00eda, podr\u00eda no resultar tan seductor en las mesas de los banquetes modernos.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Imagina, por un momento, el banquete festivo m\u00e1s glorioso, con un pavo enorme, dos rellenos, jam\u00f3n, las guarniciones de rigor y al menos media docena de tartas y pasteles. Todo esto puede sonar grandioso, hasta que nos fijamos en las extravagantes exhibiciones del antiguo banquete romano. Los miembros de las clases altas romanas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442655","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Imagina, por un momento, el banquete festivo m\u00e1s glorioso, con un pavo enorme, dos rellenos, jam\u00f3n, las guarniciones de rigor y al menos media docena de tartas y pasteles. Todo esto puede sonar grandioso, hasta que nos fijamos en las extravagantes exhibiciones del antiguo banquete romano. Los miembros de las clases altas romanas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-26T04:33:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos\",\"datePublished\":\"2023-12-26T04:33:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/\"},\"wordCount\":1806,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/\",\"name\":\"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-26T04:33:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/","og_locale":"es_ES","og_type":"article","og_title":"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos - Noticias","og_description":"(CNN) &#8212; Imagina, por un momento, el banquete festivo m\u00e1s glorioso, con un pavo enorme, dos rellenos, jam\u00f3n, las guarniciones de rigor y al menos media docena de tartas y pasteles. Todo esto puede sonar grandioso, hasta que nos fijamos en las extravagantes exhibiciones del antiguo banquete romano. Los miembros de las clases altas romanas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/","og_site_name":"Noticias","article_published_time":"2023-12-26T04:33:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/"},"author":{"name":"","@id":""},"headline":"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos","datePublished":"2023-12-26T04:33:31+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/"},"wordCount":1806,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/","url":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/","name":"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-26T04:33:31+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Recostarse y vomitar entre platillos: as\u00ed era el fest\u00edn de los antiguos romanos","url":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2023\/12\/25\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-26T04:33:31Z","datePublished":"2023-12-26T04:33:31Z","dateModified":"2023-12-26T04:33:31Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Recostarse y vomitar entre platillos: as\\u00ed era el fest\\u00edn de los antiguos romanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2023\\\/12\\\/25\\\/recostarse-y-vomitar-entre-platillos-asi-era-el-festin-de-los-antiguos-romanos\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-26T04:33:31Z\",\"datePublished\":\"2023-12-26T04:33:31Z\",\"dateModified\":\"2023-12-26T04:33:31Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456961,"url":"https:\/\/noticiasya.com\/hartford\/2024\/12\/25\/festines-banquetes-antiguos-romanos-trax\/","url_meta":{"origin":1442655,"position":0},"title":"Comer recostados y vomitar entre platos: as\u00ed eran los festines de los antiguos romanos","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"Imaginen el banquete festivo m\u00e1s glorioso, con un pavo enorme relleno, jam\u00f3n festivo, los aderezos necesarios y al menos media docena de tartas y pasteles. Todo eso puede parecer grandioso, es decir, hasta que piensas en las extravagantes y no tan agradables exhibiciones del antiguo banquete romano.Los miembros de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469437,"url":"https:\/\/noticiasya.com\/hartford\/2025\/12\/19\/yacimiento-pompeya-revela-receta-hormigon-romano-trax\/","url_meta":{"origin":1442655,"position":1},"title":"Un yacimiento de Pompeya revela la receta del hormig\u00f3n romano y contradice lo escrito por un famoso arquitecto","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"Junto con muchas otras innovaciones, el Imperio romano revolucion\u00f3 la arquitectura con caracter\u00edsticas nunca antes vistas, como arcos de gran escala y techos abovedados. Y muchas de estas estructuras todav\u00eda se mantienen en pie hoy, a pesar de tener m\u00e1s de 2.000 a\u00f1os de antig\u00fcedad.Nada de esto habr\u00eda sido posible\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451166,"url":"https:\/\/noticiasya.com\/hartford\/2024\/07\/16\/testiculos-tigre-banquetes-miticos-emperadores-chinos-ciudad-prohibida-trax\/","url_meta":{"origin":1442655,"position":2},"title":"Test\u00edculos de tigre y banquetes m\u00edticos: qu\u00e9 com\u00edan realmente los emperadores chinos en la secreta Ciudad Prohibida de Beijing","author":"","date":"julio 16, 2024","format":false,"excerpt":"(CNN) --\u00a0La Ciudad Prohibida fue en su d\u00eda uno de los lugares m\u00e1s poderosos del planeta. En 1420, mientras Europa estaba inmersa en la Guerra de los Cien A\u00f1os y a\u00fan no hab\u00eda llegado a Am\u00e9rica, el gobernante de la dinast\u00eda Ming de China se mudaba a su nuevo hogar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447999,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/11\/descubren-frescos-personajes-mitologicos-pompeya-trax\/","url_meta":{"origin":1442655,"position":3},"title":"Descubren impactantes frescos de personajes mitol\u00f3gicos en Pompeya","author":"","date":"abril 11, 2024","format":false,"excerpt":"(CNN) -- Los antiguos romanos disfrutaban de algo m\u00e1s que la comida durante sus fiestas, o eso parece demostrar un nuevo descubrimiento en el sitio arqueol\u00f3gico de Pompeya.Los arque\u00f3logos que trabajan en este sitio mundialmente conocido descubrieron una sala de banquetes con paredes pintadas de negro y cubiertas con frescos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451614,"url":"https:\/\/noticiasya.com\/hartford\/2024\/08\/05\/como-apilaron-antiguos-egipcios-las-piedras-de-la-piramide-nueva-teoria-trax\/","url_meta":{"origin":1442655,"position":4},"title":"\u00bfC\u00f3mo apilaron los antiguos egipcios las pesadas piedras de la pir\u00e1mide m\u00e1s antigua? Los cient\u00edficos plantean una nueva teor\u00eda","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) --\u00a0Los egipt\u00f3logos llevan a\u00f1os debatiendo acaloradamente c\u00f3mo se construyeron las enormes pir\u00e1mides del antiguo Egipto hace m\u00e1s de 4.000 a\u00f1os. Ahora, un equipo de ingenieros y ge\u00f3logos pone sobre la mesa una nueva teor\u00eda: un dispositivo de elevaci\u00f3n hidr\u00e1ulica que habr\u00eda hecho flotar las pesadas piedras por el centro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450282,"url":"https:\/\/noticiasya.com\/hartford\/2024\/06\/12\/analisis-adn-antiguos-mayas-sacrificios-trax\/","url_meta":{"origin":1442655,"position":5},"title":"An\u00e1lisis de ADN revela que los antiguos mayas no solo sacrificaban mujeres j\u00f3venes","author":"","date":"junio 12, 2024","format":false,"excerpt":"(CNN) -- La antigua ciudad maya de Chich\u00e9n Itz\u00e1, en la pen\u00ednsula de Yucat\u00e1n, M\u00e9xico, ha estado asociada durante mucho tiempo a los sacrificios humanos, por los cientos de huesos que se han encontrado en templos, un pozo sagrado y otras cavernas subterr\u00e1neas.Una idea err\u00f3nea que se ha mantenido durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1442655"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442655\/revisions"}],"predecessor-version":[{"id":1442671,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1442655\/revisions\/1442671"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1442655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1442655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1442655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}