{"id":1448668,"date":"2024-04-29T13:03:44","date_gmt":"2024-04-29T20:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/"},"modified":"2024-04-29T13:03:44","modified_gmt":"2024-04-29T20:03:44","slug":"pepe-mujica-expresidente-uruguay-tumor-esofago-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/","title":{"rendered":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El expresidente de Uruguay Jose \u201cPepe\u201d Mujica, de 88 a\u00f1os, anunci\u00f3 este lunes en una rueda de prensa que le fue detectado un tumor en el es\u00f3fago.<\/p>\n<p>Ahora puedes seguirnos en\u00a0WhatsApp Channel<\/p>\n<p>\u201cNecesito informarles que el viernes pasado concurr\u00ed al Casmu a hacerme un chequeo. Resultado del cual se descubri\u00f3 que tengo un tumor en el es\u00f3fago, que es algo obviamente muy comprometido y que es doblemente complejo en mi caso, porque padezco una enfermedad inmunol\u00f3gica hace m\u00e1s de 20 a\u00f1os que me afect\u00f3, entre otras cosas, los ri\u00f1ones. Lo cual crea obvias dificultades para t\u00e9cnicas de quimioterapia o de cirug\u00eda. Todo eso lo est\u00e1n evaluando los galenos, haciendo an\u00e1lisis celular, para ver c\u00f3mo sigue esta historia\u201d.<\/p>\n<p>Mujica, quien fue presidente de Uruguay entre 2010 y 2015, se\u00f1al\u00f3 durante su mensaje que su intenci\u00f3n es \u201cseguir militando, mientras pueda\u201d.<\/p>\n<p>\u201cEntretenido con mis verduras, con mis gallinas. Porque no se cambia de matungo al final del r\u00edo. Siempre he sido un terr\u00f3n con patas y amo a la tierra. Y mientras el rollo aguante, voy a estar\u201d, se\u00f1al\u00f3.<\/p>\n<p>Al final de su mensaje, transmitido en el canal de YouTube del Movimiento de Participaci\u00f3n Popular (MPP), el partido que integra Mujica, el expresidente se dirigi\u00f3 a los j\u00f3venes de su pa\u00eds. \u201cQuiero agradecerles y, adem\u00e1s, transmitirles a las pibas y pibes de este pa\u00eds, a los j\u00f3venes, que la vida es hermosa, que se gasta y se va. El quid de la cuesti\u00f3n de triunfar en la vida es volver a empezar cada vez que uno cae. Y que, si hay bronca, que la transformen en esperanza\u201d, dijo.<\/p>\n<p>\u201cLa vida es tan hermosa que no tiene sentido que la sacrifiquen por estupideces. Por lo dem\u00e1s, estoy agradecido. Y, al fin y al cabo, que me quiten lo bailado\u201d.<\/p>\n<p>CNN est\u00e1 intentando contactar a la familia de Mujica as\u00ed como a representantes del MPP para conocer m\u00e1s detalles sobre el estado de salud del expresidente.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El expresidente de Uruguay Jose \u201cPepe\u201d Mujica, de 88 a\u00f1os, anunci\u00f3 este lunes en una rueda de prensa que le fue detectado un tumor en el es\u00f3fago. Ahora puedes seguirnos en\u00a0WhatsApp Channel \u201cNecesito informarles que el viernes pasado concurr\u00ed al Casmu a hacerme un chequeo. Resultado del cual se descubri\u00f3 que tengo un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448668","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0El expresidente de Uruguay Jose \u201cPepe\u201d Mujica, de 88 a\u00f1os, anunci\u00f3 este lunes en una rueda de prensa que le fue detectado un tumor en el es\u00f3fago. Ahora puedes seguirnos en\u00a0WhatsApp Channel \u201cNecesito informarles que el viernes pasado concurr\u00ed al Casmu a hacerme un chequeo. Resultado del cual se descubri\u00f3 que tengo un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T20:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago\",\"datePublished\":\"2024-04-29T20:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/\"},\"wordCount\":381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/\",\"name\":\"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-29T20:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0El expresidente de Uruguay Jose \u201cPepe\u201d Mujica, de 88 a\u00f1os, anunci\u00f3 este lunes en una rueda de prensa que le fue detectado un tumor en el es\u00f3fago. Ahora puedes seguirnos en\u00a0WhatsApp Channel \u201cNecesito informarles que el viernes pasado concurr\u00ed al Casmu a hacerme un chequeo. Resultado del cual se descubri\u00f3 que tengo un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-29T20:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/"},"author":{"name":"","@id":""},"headline":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago","datePublished":"2024-04-29T20:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/"},"wordCount":381,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/","name":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-29T20:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica anuncia que tiene un tumor en el es\u00f3fago","url":"http:\/\/noticiasya.com\/hartford\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2024\/04\/29\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-29T20:03:44Z","datePublished":"2024-04-29T20:03:44Z","dateModified":"2024-04-29T20:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El expresidente de Uruguay Jos\\u00e9 \\u201cPepe\\u201d Mujica anuncia que tiene un tumor en el es\\u00f3fago\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/04\\\/29\\\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/04\\\/29\\\/pepe-mujica-expresidente-uruguay-tumor-esofago-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-29T20:03:44Z\",\"datePublished\":\"2024-04-29T20:03:44Z\",\"dateModified\":\"2024-04-29T20:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456926,"url":"https:\/\/noticiasya.com\/hartford\/2024\/12\/24\/expresidente-uruguay-jose-mujica-internado-cirugia-esofago-orix\/","url_meta":{"origin":1448668,"position":0},"title":"El expresidente de Uruguay Jos\u00e9 Mujica ser\u00e1 internado de nuevo para una cirug\u00eda de es\u00f3fago","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"El expresidente de Uruguay Jos\u00e9 Mujica, de 89 a\u00f1os, ser\u00e1 operado a finales de esta semana para colocarle un stent en el es\u00f3fago, que ayudar\u00e1 a mantener la alimentaci\u00f3n, inform\u00f3 este martes a CNN su m\u00e9dica personal, Raquel Pannone.El exmandatario ha sido ingresado al hospital en m\u00faltiples ocasiones desde que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452210,"url":"https:\/\/noticiasya.com\/hartford\/2024\/08\/27\/jose-pepe-mujica-hospitalizado-cancer-orix\/","url_meta":{"origin":1448668,"position":1},"title":"Jos\u00e9 &#171;Pepe&#187; Mujica, hospitalizado para continuar el tratamiento contra el c\u00e1ncer","author":"","date":"agosto 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Jos\u00e9 \"Pepe\" Mujica, expresidente de Uruguay (2010-2015), fue ingresado a un hospital para continuar con su tratamiento por el c\u00e1ncer de es\u00f3fago que padece, dijo a CNN su m\u00e9dica tratante, Raquel Panone.Mujica, de 89 a\u00f1os, anunci\u00f3 en abril de este a\u00f1o que ten\u00eda un tumor.\u00bfC\u00f3mo ser\u00e1 el tratamiento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448680,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/29\/que-problemas-salud-ha-tenido-jose-pepe-mujica-orix\/","url_meta":{"origin":1448668,"position":2},"title":"\u00bfQu\u00e9 problemas de salud ha tenido Jos\u00e9 &#171;Pepe&#187; Mujica?","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Jos\u00e9 \"Pepe\" Mujica, expresidente de Uruguay entre 2010 y 2015, dio a conocer este lunes que le fue detectado un tumor en el es\u00f3fago, en el m\u00e1s reciente episodio de su historial de salud.La m\u00e9dica que trata a Mujica, Raquel Pannone, indic\u00f3 a CNN que \u201cpor las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448816,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/03\/jose-pepe-mujica-padece-cancer-de-esofago-dice-medica-orix\/","url_meta":{"origin":1448668,"position":3},"title":"Jos\u00e9 \u201cPepe\u201d Mujica padece c\u00e1ncer de es\u00f3fago, confirma su m\u00e9dica tratante","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El expresidente de Uruguay, Jos\u00e9 \u201cPepe\u201d Mujica, padece c\u00e1ncer de es\u00f3fago, inform\u00f3 este jueves su m\u00e9dica tratante Raquel Pannone en conferencia de prensa. El exmandatario fue sometido a una endoscop\u00eda digestiva y el resultado \u201cmostr\u00f3 que tiene un tumor al nivel del es\u00f3fago\", dijo Pannone. \"Ten\u00edamos la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457389,"url":"https:\/\/noticiasya.com\/hartford\/2025\/01\/09\/jose-mujica-cancer-me-estoy-muriendo-orix\/","url_meta":{"origin":1448668,"position":4},"title":"Mujica dice que el c\u00e1ncer se le expandi\u00f3 al h\u00edgado: &#171;Me estoy muriendo&#187;","author":"","date":"enero 9, 2025","format":false,"excerpt":"El expresidente de Uruguay Jos\u00e9 \u201cPepe\u201d Mujica dijo este jueves que el c\u00e1ncer de es\u00f3fago que se le diagnostic\u00f3 en abril de 2024 se expandi\u00f3 a su h\u00edgado.\u201cEl c\u00e1ncer en el es\u00f3fago me est\u00e1 colonizando el h\u00edgado. No lo paro con nada\u201d, dijo Mujica en una entrevista con el medio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462301,"url":"https:\/\/noticiasya.com\/hartford\/2025\/05\/13\/pepe-mujica-problemas-salud-orix\/","url_meta":{"origin":1448668,"position":5},"title":"\u00bfQu\u00e9 problemas de salud tuvo Jos\u00e9 &#171;Pepe&#187; Mujica?","author":"","date":"mayo 13, 2025","format":false,"excerpt":"Jos\u00e9 \u201cPepe\u201d Mujica, expresidente de Uruguay entre 2010 y 2015, padeci\u00f3 varios problemas de salud a lo largo de su vida.Mujica no vot\u00f3 en las \u00faltimas elecciones departamentales y municipales de Uruguay celebradas el pasado domingo 11 de mayo de 2025. Al ser consultado ese d\u00eda sobre la salud del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1448668"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448668\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1448668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1448668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1448668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}