{"id":1448681,"date":"2024-04-29T18:03:51","date_gmt":"2024-04-30T01:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/"},"modified":"2024-04-29T18:03:51","modified_gmt":"2024-04-30T01:03:51","slug":"ataque-aereo-israeli-rafah-22-muertos-hospital-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","title":{"rendered":"&#171;Toda mi familia muri\u00f3&#187;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital"},"content":{"rendered":"<p>Nota del editor: Advertencia: Esta historia tiene contenido expl\u00edcito.<\/p>\n<p>(CNN) &#8212; Al menos 22 personas, entre ellas al menos un beb\u00e9 y un ni\u00f1o, murieron en un ataque a\u00e9reo israel\u00ed sobre Rafah, Gaza, durante la madrugada de este lunes, seg\u00fan fuentes de un hospital.<\/p>\n<p>Tras el ataque, los fallecidos fueron trasladados al hospital Abu Youssef Al Najjar de Rafah, donde sus seres queridos se reunieron para darles un \u00faltimo adi\u00f3s.<\/p>\n<p>Un video grabado para CNN en el patio del hospital muestra varias bolsas con cad\u00e1veres tendidas en el suelo con decenas de personas angustiadas, entre ellas hombres, mujeres y ni\u00f1os, reunidos alrededor de sus seres queridos fallecidos.<\/p>\n<p>Se ve a la gente agachada sobre las bolsas de cad\u00e1veres, y a algunos acariciando los cuerpos sin vida de sus seres queridos. Tambi\u00e9n se puede ver al menos la cabeza de un beb\u00e9 que se asoma por una bolsa, mientras la mujer que est\u00e1 a su lado grita: &#171;Toda mi familia muri\u00f3&#187;.<\/p>\n<p>Hamas considera una propuesta de alto el fuego y liberaci\u00f3n de rehenes que, seg\u00fan fuentes israel\u00edes, podr\u00eda evitar la invasi\u00f3n de Rafah<\/p>\n<p>El t\u00edo del beb\u00e9, Mahmoud Abu Taha, cargaba el cuerpo sin vida del ni\u00f1o de un a\u00f1o mientras hablaba a la c\u00e1mara, y dec\u00eda que sus padres intentaron tener hijos durante 10 a\u00f1os antes de que naciera.<\/p>\n<p>&#171;Est\u00e1bamos sentados en nuestras casas, sin hacer nada. Fue inesperado cuando impactaron la casa. Todos dorm\u00edan en sus camas&#8230; la mayor\u00eda de las personas que murieron eran desplazados&#8230; eran mujeres y ni\u00f1os&#187;, dijo.<\/p>\n<p>Al levantar el cuerpo del beb\u00e9 hacia la c\u00e1mara, Mahmoud Abu Taha grit\u00f3: &#171;Este es su objetivo. Este es su objetivo. Esta es la generaci\u00f3n que buscan. Esta es la Rafah segura de la que hablan&#187;.<\/p>\n<p>En respuesta a una petici\u00f3n de CNN para que comentaran el ataque de Rafah de este lunes, las Fuerzas de Defensa de Israel (FDI) dijeron en un comunicado que sus aviones de combate &#171;atacaron objetivos donde los terroristas estaban operando dentro de una zona civil en el sur de Gaza&#187;.<\/p>\n<p>&#171;Las FDI continuar\u00e1n frustrando la actividad terrorista y protegiendo a los civiles israel\u00edes, de acuerdo con el derecho internacional&#187;, a\u00f1adi\u00f3.<\/p>\n<p>CNN no puede verificar de forma independiente estas afirmaciones.<\/p>\n<p>Una escena del Hospital Al-Najar de Rafah este lunes. (Cr\u00e9dito: Abed Rahim Khatib\/Anadolu\/Getty Images)<\/p>\n<p>Otro miembro de la familia Abu Taha afirma en el video que 10 de sus parientes murieron en el ataque a\u00e9reo. Algunos de sus familiares fueron desplazados de Khan Younis, donde varios de ellos murieron en un ataque a\u00e9reo israel\u00ed previo. Los pocos que huyeron de Khan Younis para refugiarse en Rafah murieron durante la noche en Rafah.<\/p>\n<p>&#171;Estaban durmiendo en sus casas cuando ocurri\u00f3 el ataque a\u00e9reo sobre las 12:20 de la ma\u00f1ana&#8230; no hay ning\u00fan lugar seguro. Toda Gaza es un objetivo&#187;, declar\u00f3 a CNN.<\/p>\n<p>Pidi\u00f3 al primer ministro de Israel, Benjamin Netanyahu, que detenga la guerra: &#171;Queremos vivir. Queremos la paz. Basta de derramamiento de sangre \u00e1rabe&#187;.<\/p>\n<p>Vea los mensajes de agradecimiento de ni\u00f1os de Gaza 0:22<\/p>\n<p>Otro testigo afirma que un ni\u00f1o de cinco d\u00edas llamado Ghaith Abu Rayya muri\u00f3 en el ataque a\u00e9reo. En las im\u00e1genes se le ve abriendo una peque\u00f1a bolsa para cad\u00e1veres en la que se ve la cabeza del beb\u00e9, y dice que su cuerpo fue desmembrado.<\/p>\n<p>&#171;Estamos solos. Nadie se preocupa por nosotros&#187;, grita.<\/p>\n<p>Se le ve abriendo otra bolsa para cad\u00e1veres junto a la de Ghaith, sollozando y diciendo &#171;mi querido Ramy&#187;, que dice que es el padre de Ghaith, de 33 a\u00f1os.<\/p>\n<p>Se ve a varios hombres trayendo otra bolsa para cad\u00e1veres con el nombre &#171;Ahmad Saleem Abu Taha&#187; escrito en ella, y la multitud empieza a llorar desconsolada.<\/p>\n<p>Una mujer acaricia el rostro sin vida, que ha quedado al descubierto, y dice: &#171;Oh, su olor. Oh Dios. Adi\u00f3s, mi amado&#187;.<\/p>\n<p>El n\u00famero de muertos en Gaza aument\u00f3 a por lo menos 34.454 tras 205 d\u00edas de guerra entre Israel y Hamas, seg\u00fan inform\u00f3 el domingo el Ministerio de Sanidad de Gaza. El ministerio no distingue entre v\u00edctimas civiles y combatientes de Hamas.<\/p>\n<p>CNN no puede verificar de forma independiente las cifras de v\u00edctimas del ministerio debido a la falta de acceso de los medios de comunicaci\u00f3n internacionales a Gaza.<\/p>\n<p>Tareq Elhelou inform\u00f3 para CNN desde Rafah, Kareem Khadder de CNN, Zeena Saifi y Abeer Salman reportaron desde Jerusal\u00e9n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota del editor: Advertencia: Esta historia tiene contenido expl\u00edcito. (CNN) &#8212; Al menos 22 personas, entre ellas al menos un beb\u00e9 y un ni\u00f1o, murieron en un ataque a\u00e9reo israel\u00ed sobre Rafah, Gaza, durante la madrugada de este lunes, seg\u00fan fuentes de un hospital. Tras el ataque, los fallecidos fueron trasladados al hospital Abu Youssef [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448681","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Toda mi familia muri\u00f3&quot;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Toda mi familia muri\u00f3&quot;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nota del editor: Advertencia: Esta historia tiene contenido expl\u00edcito. (CNN) &#8212; Al menos 22 personas, entre ellas al menos un beb\u00e9 y un ni\u00f1o, murieron en un ataque a\u00e9reo israel\u00ed sobre Rafah, Gaza, durante la madrugada de este lunes, seg\u00fan fuentes de un hospital. Tras el ataque, los fallecidos fueron trasladados al hospital Abu Youssef [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T01:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Toda mi familia muri\u00f3&#187;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital\",\"datePublished\":\"2024-04-30T01:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/\"},\"wordCount\":806,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/\",\"name\":\"\\\"Toda mi familia muri\u00f3\\\": ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-30T01:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Toda mi familia muri\u00f3&#187;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Toda mi familia muri\u00f3\": ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"Toda mi familia muri\u00f3\": ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital - Noticias","og_description":"Nota del editor: Advertencia: Esta historia tiene contenido expl\u00edcito. (CNN) &#8212; Al menos 22 personas, entre ellas al menos un beb\u00e9 y un ni\u00f1o, murieron en un ataque a\u00e9reo israel\u00ed sobre Rafah, Gaza, durante la madrugada de este lunes, seg\u00fan fuentes de un hospital. Tras el ataque, los fallecidos fueron trasladados al hospital Abu Youssef [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-30T01:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;Toda mi familia muri\u00f3&#187;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital","datePublished":"2024-04-30T01:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/"},"wordCount":806,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","name":"\"Toda mi familia muri\u00f3\": ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-30T01:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Toda mi familia muri\u00f3&#187;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Toda mi familia muri\u00f3&#187;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital","url":"http:\/\/noticiasya.com\/hartford\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-30T01:03:51Z","datePublished":"2024-04-30T01:03:51Z","dateModified":"2024-04-30T01:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Toda mi familia muri\\u00f3&#187;: ataque a\\u00e9reo israel\\u00ed en Rafah mat\\u00f3 a 22 personas, seg\\u00fan el personal de un hospital\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/04\\\/29\\\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/04\\\/29\\\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-30T01:03:51Z\",\"datePublished\":\"2024-04-30T01:03:51Z\",\"dateModified\":\"2024-04-30T01:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451476,"url":"https:\/\/noticiasya.com\/hartford\/2024\/07\/28\/ataques-israelies-matan-palestinos-gaza-trax\/","url_meta":{"origin":1448681,"position":0},"title":"Al menos 19 palestinos muertos, incluidos ni\u00f1os, tras ataque de Israel en Gaza","author":"","date":"julio 28, 2024","format":false,"excerpt":"(CNN) -- Ataques israel\u00edes mataron al menos a 19 palestinos, incluidos ni\u00f1os, e hirieron a muchos otros en Gaza este domingo, de acuerdo funcionarios de Salud y la Defensa Civil de Gaza.Al menos 10 personas murieron en un ataque a\u00e9reo contra una casa en el centro de Khan Younis, le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448996,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/07\/palestinos-huyen-rafah-gaza-temor-desesperacion-ataque-israel-trax\/","url_meta":{"origin":1448681,"position":1},"title":"&#171;Me voy hacia lo desconocido&#187;: palestinos que huyen de Rafah describen su miedo y desesperaci\u00f3n tras el ataque de Israel","author":"","date":"mayo 7, 2024","format":false,"excerpt":"(CNN) -- Civiles palestinos a los que el Ej\u00e9rcito israel\u00ed orden\u00f3 evacuar la zona oriental de Rafah describieron el miedo y la desesperaci\u00f3n que sienten al verse desarraigados de sus hogares y refugios, mientras la aviaci\u00f3n israel\u00ed bombardea la ciudad m\u00e1s meridional de Gaza.\"Nos fuimos porque distribuyeron panfletos\", dijo Mohammed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447908,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/09\/exhuman-cadaveres-fosas-comunes-hospital-al-shifa-trax\/","url_meta":{"origin":1448681,"position":2},"title":"Exhuman los primeros cad\u00e1veres de las fosas comunes del hospital Al-Shifa tras el asedio israel\u00ed","author":"","date":"abril 9, 2024","format":false,"excerpt":"(CNN) -- Trabajadores sanitarios del norte de Gaza exhumaron este martes los primeros cad\u00e1veres de las fosas comunes del hospital Al-Shifa y sus alrededores, despu\u00e9s de que las fuerzas israel\u00edes mataran a cientos de palestinos y dejaran sus cuerpos en descomposici\u00f3n durante las dos semanas de asedio al complejo.Al menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448666,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/29\/hamas-propuesta-alto-fuego-liberacion-rehenes-rafah-trax\/","url_meta":{"origin":1448681,"position":3},"title":"Hamas considera una propuesta de alto el fuego y liberaci\u00f3n de rehenes que, seg\u00fan fuentes israel\u00edes, podr\u00eda evitar la invasi\u00f3n de Rafah","author":"","date":"abril 29, 2024","format":false,"excerpt":"Riad y Jerusal\u00e9n (CNN) -- Hamas est\u00e1 considerando un nuevo marco propuesto por Egipto que pide al grupo liberar hasta 33 rehenes secuestrados en Israel a cambio de una pausa en las hostilidades en Gaza, dijo a CNN una fuente israel\u00ed familiarizada con las negociaciones y una fuente diplom\u00e1tica extranjera.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451713,"url":"https:\/\/noticiasya.com\/hartford\/2024\/08\/10\/israeli-school-strike-gaza-trax\/","url_meta":{"origin":1448681,"position":4},"title":"Al menos 90 palestinos muertos en un ataque israel\u00ed contra una escuela de Gaza, seg\u00fan portavoz de la Defensa Civil","author":"","date":"agosto 10, 2024","format":false,"excerpt":"(CNN) -- Al menos 90 palestinos murieron en un ataque israel\u00ed contra la escuela de Al-Tabi'in, en la ciudad de Gaza, seg\u00fan declar\u00f3 o a CNN el portavoz de la Defensa Civil de Gaza, Mahmoud Basal.\"Hemos recuperado al menos 90\" personas muertas, ha dicho Basal, a\u00f1adiendo que \"muchas de ellas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449828,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/29\/ultima-hora-guerra-entre-israel-y-hamas-rafah-en-vivo-orix\/","url_meta":{"origin":1448681,"position":5},"title":"Guerra de Israel y Hamas en Gaza, en vivo: \u00faltimas noticias del ataque mortal en Rafah","author":"","date":"mayo 29, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edPalestinos en un veh\u00edculo lloran la p\u00e9rdida de sus seres queridos junto a sus cuerpos tras el ataque israel\u00ed en Rafah el lunes. (Cr\u00e9dito: Mohammed Salem\/Reuters)Los palestinos huyen de Rafah debido a una operaci\u00f3n militar israel\u00ed el 28 de mayo (Cr\u00e9dito:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1448681"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448681\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1448681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1448681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1448681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}