{"id":1448910,"date":"2024-05-05T18:03:39","date_gmt":"2024-05-06T01:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/"},"modified":"2024-05-05T18:03:39","modified_gmt":"2024-05-06T01:03:39","slug":"estudiante-volante-autobus-escolar-conductora-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/","title":{"rendered":"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia"},"content":{"rendered":"<p>(CNN) &#8212; Era un final normal del d\u00eda escolar a finales de abril para Acie Holland III, estudiante de octavo grado en la escuela secundaria Glen Hills en Glendale, Wisconsin.<\/p>\n<p>Continu\u00f3 su rutina y se subi\u00f3 al autob\u00fas escolar para volver a casa. La conductora del autob\u00fas brome\u00f3 con los estudiantes, dijo Holland, antes de ponerse los auriculares.<\/p>\n<p>Fue entonces cuando la situaci\u00f3n cambi\u00f3 repentinamente.<\/p>\n<p>Desde su asiento, m\u00e1s all\u00e1 de la mitad del autob\u00fas, Holland dijo que la conductora parec\u00eda un poco enferma o cansada y que ten\u00eda la cabeza gacha. Supo que algo andaba mal cuando ella sigui\u00f3 presionando el acelerador y se pas\u00f3 una calle.<\/p>\n<p>Un estudiante de s\u00e9ptimo grado de Michigan evit\u00f3 que su autob\u00fas escolar chocara despu\u00e9s de que la conductora perdiera el conocimiento<\/p>\n<p>\u201cDobl\u00f3 en una esquina y hay otra calle por la que normalmente doblamos. Presion\u00f3 el acelerador y pas\u00f3 esa esquina, y mir\u00e9 hacia arriba\u201d, dijo Holland a CNN.<\/p>\n<p>Camin\u00f3 hasta el frente del autob\u00fas para ver c\u00f3mo estaba, pero ella no respondi\u00f3, dijo. Perdi\u00f3 temporalmente la consciencia mientras que el autob\u00fas se desviaba hacia el tr\u00e1fico que ven\u00eda en sentido contrario. Holland se apresur\u00f3 a quitar el pie del acelerador. Dijo que apret\u00f3 los frenos y estacion\u00f3 el autob\u00fas de manera segura.<\/p>\n<p>&#171;No estaba realmente asustado, s\u00f3lo trat\u00e9 de hacer que el autob\u00fas se detuviera&#187;, coment\u00f3.<\/p>\n<p>Despu\u00e9s de detener el autob\u00fas, Holland se comunic\u00f3 con el 911 y con su abuela, quien es asistente de enfermer\u00eda. Tambi\u00e9n orden\u00f3 a los otros 13 a 15 estudiantes a bordo que llamaran a sus familias.<\/p>\n<p>\u201cTodos dec\u00edan &#8216;gracias&#8217; porque les salv\u00e9 la vida\u201d, dijo Holland, quien espera alg\u00fan d\u00eda tener una barber\u00eda o un taller mec\u00e1nico.<\/p>\n<p>La directora de la escuela secundaria Glen Hills, Anna Young, escribi\u00f3 en una nota a las familias que \u201cla comunidad no podr\u00eda estar m\u00e1s orgullosa de Acie\u201d.<\/p>\n<p>Kendrick Castillo, el estudiante que muri\u00f3 tratando de detener al atacante de la escuela de Colorado<\/p>\n<p>\u201cLa compasi\u00f3n y el liderazgo que lo vemos exhibir a diario fueron llevados al siguiente nivel ayer en su viaje en autob\u00fas a casa. Estamos agradecidos de que todos nuestros estudiantes de Glen Hills est\u00e9n seguros y deseamos a su conductora una recuperaci\u00f3n saludable\u201d, continu\u00f3.<\/p>\n<p>Finalmente, la conductora recuper\u00f3 el conocimiento y llam\u00f3 a la compa\u00f1\u00eda de autobuses, Riteway, que envi\u00f3 a otro conductor para llevar a los estudiantes a casa sanos y salvos.<\/p>\n<p>Seg\u00fan el director de la escuela, la conductora sufri\u00f3 una emergencia m\u00e9dica y recibi\u00f3 atenci\u00f3n.<\/p>\n<p>Los padres de Holland est\u00e1n muy orgullosos y aliviados.<\/p>\n<p>Al principio, el padre de Holland, Acie Holland II, no le crey\u00f3 cuando escuch\u00f3 la historia ese mismo d\u00eda.<\/p>\n<p>\u201cPap\u00e1, salv\u00e9 el autob\u00fas escolar de estrellarse\u201d, le dijo. Al final, la historia no le sorprendi\u00f3.<\/p>\n<p>\u201cSiempre fue una persona muy r\u00e1pida. Esa es una de las cosas de las que s\u00e9 que \u00e9l es capaz, no en el autob\u00fas escolar, sino en general, poder ayudar a alguien que lo necesita\u201d, dijo el padre de Holland a CNN. &#171;Pero estoy orgulloso de lo que hizo&#187;.<\/p>\n<p>Salvado por la conductora del autob\u00fas escolar<\/p>\n<p>La peque\u00f1a y unida comunidad contin\u00faa mostrando su orgullo desde el incidente. En una reuni\u00f3n de la junta escolar a principios de esta semana, Holland obtuvo reconocimiento mediante una proclamaci\u00f3n del alcalde y el concejo municipal. El Departamento de Polic\u00eda de Glendale y el Departamento de Bomberos de Milwaukee tambi\u00e9n elogiaron su hero\u00edsmo.<\/p>\n<p>Holland hab\u00eda tenido alguna experiencia previa con veh\u00edculos. Desde peque\u00f1o trabaja con su padre, un t\u00e9cnico automotriz certificado.<\/p>\n<p>\u201cEra como si estuviera en el lugar correcto en el momento correcto. As\u00ed fue, deb\u00eda ser por una variedad de razones, la m\u00e1s importante fue la seguridad de los dem\u00e1s\u201d, dijo Young.<\/p>\n<p>Holland agradece todo el reconocimiento que recibi\u00f3. Dice que se alegra de haber podido llevar a todos a casa sanos y salvos, y que esta experiencia le dio m\u00e1s seguridad en s\u00ed mismo.<\/p>\n<p>&#171;Me siento m\u00e1s seguro para enfrentarme a un momento de luchar o escapar&#187;, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Era un final normal del d\u00eda escolar a finales de abril para Acie Holland III, estudiante de octavo grado en la escuela secundaria Glen Hills en Glendale, Wisconsin. Continu\u00f3 su rutina y se subi\u00f3 al autob\u00fas escolar para volver a casa. La conductora del autob\u00fas brome\u00f3 con los estudiantes, dijo Holland, antes de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448910","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Era un final normal del d\u00eda escolar a finales de abril para Acie Holland III, estudiante de octavo grado en la escuela secundaria Glen Hills en Glendale, Wisconsin. Continu\u00f3 su rutina y se subi\u00f3 al autob\u00fas escolar para volver a casa. La conductora del autob\u00fas brome\u00f3 con los estudiantes, dijo Holland, antes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T01:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia\",\"datePublished\":\"2024-05-06T01:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/\"},\"wordCount\":760,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/\",\"name\":\"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-06T01:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia - Noticias","og_description":"(CNN) &#8212; Era un final normal del d\u00eda escolar a finales de abril para Acie Holland III, estudiante de octavo grado en la escuela secundaria Glen Hills en Glendale, Wisconsin. Continu\u00f3 su rutina y se subi\u00f3 al autob\u00fas escolar para volver a casa. La conductora del autob\u00fas brome\u00f3 con los estudiantes, dijo Holland, antes de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-06T01:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/"},"author":{"name":"","@id":""},"headline":"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia","datePublished":"2024-05-06T01:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/"},"wordCount":760,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/","name":"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-06T01:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estudiante de octavo grado de Wisconsin toma el volante de su autob\u00fas escolar despu\u00e9s de que la conductora perdiera la consciencia","url":"http:\/\/noticiasya.com\/hartford\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2024\/05\/05\/estudiante-volante-autobus-escolar-conductora-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-06T01:03:39Z","datePublished":"2024-05-06T01:03:39Z","dateModified":"2024-05-06T01:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estudiante de octavo grado de Wisconsin toma el volante de su autob\\u00fas escolar despu\\u00e9s de que la conductora perdiera la consciencia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/05\\\/05\\\/estudiante-volante-autobus-escolar-conductora-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/05\\\/05\\\/estudiante-volante-autobus-escolar-conductora-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-06T01:03:39Z\",\"datePublished\":\"2024-05-06T01:03:39Z\",\"dateModified\":\"2024-05-06T01:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1427695,"url":"https:\/\/noticiasya.com\/hartford\/2022\/09\/21\/ceremonia-para-honrar-a-los-estudiantes-del-accidente-mortal-en-alton\/","url_meta":{"origin":1448910,"position":0},"title":"Ceremonia para honrar a los estudiantes del accidente mortal en Alton","author":"agomez","date":"septiembre 21, 2022","format":false,"excerpt":"Ya pasaron 33 a\u00f1os, donde perdieron la vida 21 alumnos que iban a bordo de un autob\u00fas escolar","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/hartford\/categoria\/comunidad"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2022\/09\/33f2d556-d401-468e-864d-8d3e6e401bfe.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1445916,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/22\/homenaje-audrii-cunningham-sospechoso-don-steven-mcdougal-trax\/","url_meta":{"origin":1448910,"position":1},"title":"Recuerdan a Audrii Cunningham como una ni\u00f1a radiante y amigable; un amigo de la familia est\u00e1 acusado de su asesinato","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN) -- Familiares y amigos de Audrii Cunningham, la ni\u00f1a de 11 a\u00f1os del este de Texas que fue encontrada muerta despu\u00e9s de desaparecer camino a la escuela, la recuerdan como una ni\u00f1a brillante y amigable durante una vigilia este mi\u00e9rcoles por la noche cerca del r\u00edo donde su cuerpo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453274,"url":"https:\/\/noticiasya.com\/hartford\/2024\/10\/01\/20-ninos-profesores-muerto-incendio-autobus-escolar-bangkok-ap\/","url_meta":{"origin":1448910,"position":2},"title":"Se teme que al menos 20 ni\u00f1os y profesores hayan muerto en el incendio de un autob\u00fas escolar en Bangkok","author":"","date":"octubre 1, 2024","format":false,"excerpt":"(AP) -- Un autob\u00fas que transportaba a j\u00f3venes estudiantes y sus profesores en un viaje escolar se incendi\u00f3 este martes en un suburbio de Bangkok, dejando m\u00e1s de 20 muertos, dijeron funcionarios y rescatistas.El autob\u00fas con 45 pasajeros, seis profesores y 39 estudiantes de primaria y secundaria, viajaba desde la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450683,"url":"https:\/\/noticiasya.com\/hartford\/2024\/06\/25\/apunalan-madre-nino-autobus-escolar-trax\/","url_meta":{"origin":1448910,"position":3},"title":"Apu\u00f1alan a madre y ni\u00f1o japoneses en China frente a un autob\u00fas escolar","author":"","date":"junio 25, 2024","format":false,"excerpt":"(CNN) -- Tres personas atacadas por un hombre con un \"objeto similar a un cuchillo\" en China, entre ellas una madre y un hijo japonesesEl incidente ocurri\u00f3 en una parada de autob\u00fas de Suzhou, cerca de una escuela japonesa, donde una madre esperaba para recoger a su hijo. Tanto la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445945,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/23\/causa-muerte-audrii-cunningham-trax\/","url_meta":{"origin":1448910,"position":4},"title":"Forense determina la causa de muerte de Audrii Cunningham","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) -- Audrii Cunningham, la ni\u00f1a de 11 a\u00f1os que fue encontrada muerta tras desaparecer de camino al colegio la semana pasada, muri\u00f3 por \"violencia homicida, incluido un traumatismo craneal contundente\", seg\u00fan la oficina del forense.Cunningham sali\u00f3 de su casa en Livingston, Texas, la semana pasada con un amigo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462622,"url":"https:\/\/noticiasya.com\/hartford\/2025\/05\/21\/tres-ninos-dos-adultos-mueren-ataque-suicida-atobus-escolar-pakistan-trax\/","url_meta":{"origin":1448910,"position":5},"title":"Tres ni\u00f1os y dos adultos mueren en un ataque suicida contra un autob\u00fas escolar en Pakist\u00e1n","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Un ataque suicida en un autob\u00fas escolar en el suroeste de Pakist\u00e1n mat\u00f3 el mi\u00e9rcoles a tres estudiantes de una escuela dirigida por militares, dijeron las autoridades. El incidente pone en relieve el deterioro de la situaci\u00f3n de seguridad en la regi\u00f3n.La explosi\u00f3n ocurri\u00f3 en la ciudad de Khuzdar, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1448910"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448910\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1448910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1448910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1448910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}