{"id":1448936,"date":"2024-05-06T13:03:43","date_gmt":"2024-05-06T20:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/"},"modified":"2024-05-06T13:03:43","modified_gmt":"2024-05-06T20:03:43","slug":"ucranianos-enviados-prisiones-rusas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/","title":{"rendered":"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio"},"content":{"rendered":"<p>Kyiv, Ucrania (CNNI &#8212; &#171;Queridos mam\u00e1 y pap\u00e1, estoy vivo y bien. Estoy bien, Dima&#187;.<\/p>\n<p>Escrito a mano en un peque\u00f1o trozo de papel, este es el \u00fanico mensaje que Halyna y Vasyl Khyliuk han recibido de su hijo Dmytro Khyliuk, conocido como Dima, desde que fue capturado por soldados rusos hace m\u00e1s de dos a\u00f1os.<\/p>\n<p>EE.UU. dice que Rusia us\u00f3 agentes asfixiantes contra soldados ucranianos, violando la prohibici\u00f3n de armas qu\u00edmicas<\/p>\n<p>El periodista ucraniano fue detenido en marzo de 2022 durante la ocupaci\u00f3n de su pueblo, Kozarovychi, al norte de Kyiv. Por lo que saben sus padres, el corresponsal de 49 a\u00f1os de la Agencia de Informaci\u00f3n Independiente de Ucrania fue trasladado a Rusia, donde sigue retenido a pesar de que, seg\u00fan su abogado, nunca ha sido condenado ni acusado.<\/p>\n<p>El gobierno ucraniano afirma que hay miles de personas como Dima, civiles detenidos por Rusia que llevan a\u00f1os en detenci\u00f3n arbitraria. Kyiv ha confirmado oficialmente unos 1.700 casos, pero los investigadores de derechos humanos estiman que la cifra real es entre cinco y siete veces mayor. En total, unos 37.000 ucranianos, civiles adultos y ni\u00f1os, y militares, est\u00e1n en paradero desconocido, seg\u00fan la oficina del defensor del pueblo ucraniano, que afirma que se sigue deteniendo a personas en zonas bajo ocupaci\u00f3n rusa. CNN no puede verificar de forma independiente el n\u00famero de detenidos.<\/p>\n<p>Muchos de los detenidos han sido trasladados a prisiones en el interior de Rusia, donde se les mantiene junto a criminales y prisioneros de guerra, en violaci\u00f3n del derecho internacional humanitario. Grupos de derechos humanos han identificado unos 100 centros de detenci\u00f3n en Rusia y en las zonas ocupadas de Ucrania en los que se retiene a civiles, incluidos varios que se han abierto o ampliado espec\u00edficamente para alojarlos.<\/p>\n<p>Halyna y Vasyl Khyliuk miran una foto de su hijo en su casa de Kozarovychi, Ucrania. Cr\u00e9dito: Ivana Kottasova\/CNN<\/p>\n<p>&#171;Los rusos quieren reconocer a muchos de ellos como combatientes militares y darles el estatus de prisioneros de guerra&#8230; la raz\u00f3n principal es (construir) un banco de prisioneros de guerra para intercambios&#187;, dijo a CNN en Kyiv el comisionado ucraniano de Derechos Humanos, Dmytro Lubinets. Lubinets afirm\u00f3 que reconocer a los civiles ucranianos como prisioneros de guerra ser\u00eda ilegal y peligroso, porque expondr\u00eda a los ucranianos de las zonas ocupadas a un mayor riesgo de ser detenidos para ser utilizados como moneda de cambio.<\/p>\n<p>&#171;Estas personas no son prisioneros de guerra; son rehenes civiles. Utilizo esa palabra para subrayar lo que est\u00e1 haciendo la Federaci\u00f3n Rusa: est\u00e1n reteniendo a civiles como rehenes&#187;, afirm\u00f3. Los Convenios de Ginebra, que regulan la conducta en los conflictos armados, proh\u00edben expl\u00edcitamente la toma de rehenes. Las partes beligerantes pueden internar a personas, incluidos civiles. Pero las normas sobre qui\u00e9n puede ser detenido, por qu\u00e9 y durante cu\u00e1nto tiempo son estrictas.<\/p>\n<p>&#171;La norma es que no se trata de un castigo&#187;, declar\u00f3 a la CNN Achille Despr\u00e9s, de la secci\u00f3n de Kyiv del Comit\u00e9 Internacional de la Cruz Roja (ICRC, por sus siglas en ingl\u00e9s), quien a\u00f1adi\u00f3 que solo se puede retener a civiles si es &#171;necesario&#187; por &#171;razones imperiosas de seguridad&#187;.<\/p>\n<p>El gobierno ucraniano y varias organizaciones internacionales afirman que Rusia est\u00e1 cometiendo cr\u00edmenes de guerra al retener a personas como Dima. La preocupaci\u00f3n por las detenciones arbitrarias de civiles ucranianos por parte de Rusia es tan grave que 45 miembros de la Organizaci\u00f3n para la Seguridad y la Cooperaci\u00f3n en Europa (OSCE) iniciaron en febrero una investigaci\u00f3n especial sobre el asunto con el objetivo de encontrar formas de exigir responsabilidades a Rusia.<\/p>\n<p>Exclusivo: Paul Whelan le dijo a Blinken que al quedar afuera del intercambio de prisioneros con Rusia le &#171;pintaron un blanco en la espalda&#187;<\/p>\n<p>B\u00fasqueda desesperada<\/p>\n<p>En declaraciones a CNN en su casa de Kozarovychi, que desde entonces ha sido liberada y parcialmente reparada por voluntarios ucranianos, los Khyliuk recordaron el horror de la captura de su hijo y la incertidumbre de su detenci\u00f3n continuada.<\/p>\n<p>En las primeras semanas de la guerra, los soldados rusos tomaron su casa, aparcaron el tanque en el jard\u00edn y robaron cualquier cosa de valor. Los Khyliuk se refugiaban en casa de un vecino, y s\u00f3lo de vez en cuando se aventuraban a salir para conseguir provisiones. Fue durante una de estas salidas cuando Dima y Vasyl se encontraron rodeados por un grupo de soldados rusos armados con ametralladoras.<\/p>\n<p>&#171;Nos pusieron una especie de chaquetas en la cabeza y nos taparon los ojos para que no pudi\u00e9ramos ver nada. A Dima y a m\u00ed nos separaron. Una semana despu\u00e9s, nos llevaron a Dymer. All\u00ed pasamos dos noches juntos. Hac\u00eda fr\u00edo, el suelo era de cemento, no hab\u00eda calefacci\u00f3n. Yo llevaba una chaqueta de invierno, pero Dima llevaba una chaqueta ligera y botas de agua&#187;, cuenta Vasyl, que fue liberado al cabo de ocho d\u00edas.<\/p>\n<p>Cuando no volvieron a casa, Halyna dijo que estaba fuera de s\u00ed, comprendiendo que los rusos deb\u00edan de haberlos capturado. &#171;En aquella \u00e9poca capturaban a mucha gente, cog\u00edan a quien ve\u00edan. A los que no necesitaban, los torturaban un poco y los dejaban ir. Pero Dima y otras seis personas llevan dos a\u00f1os en la c\u00e1rcel&#187;, dice llorando.<\/p>\n<p>Las autoridades rusas dijeron en repetidas ocasiones a los padres de Dmytro Khyliuk que no estaba en Rusia, a pesar de los testimonios de testigos presenciales. Cr\u00e9dito: Familia Khyliuk\/Getty Images<\/p>\n<p>Rusia se ha convertido en tal agujero negro de informaci\u00f3n que muchas familias, autoridades y organizaciones no gubernamentales (ONG) ucranianas deben confiar en el boca a boca de antiguos presos para saber de personas que siguen detenidas.<\/p>\n<p>Anastasiia Pantielieieva, investigadora y periodista que documenta casos de detenciones de civiles y desapariciones forzadas para Media Initiative for Human Rights (MIHR), una ONG ucraniana, declar\u00f3 que, seg\u00fan testimonios de testigos presenciales, Dima estuvo recluido brevemente en dos centros de detenci\u00f3n improvisados de la Ucrania ocupada antes de ser trasladado a un centro de detenci\u00f3n preventiva de Novozybkov, en la regi\u00f3n rusa de Briansk.<\/p>\n<p>Dijo que el \u00faltimo avistamiento documentado de Dima por un testigo fue en la Colonia Penal N\u00famero 7, en la regi\u00f3n rusa de Vladimir. En un momento dado, el MIHR recibi\u00f3 indicios de que podr\u00eda ser trasladado a otro centro en Mordovia, regi\u00f3n rusa al sureste de Mosc\u00fa, pero Pantielieieva dijo que las autoridades rusas no confirmaron esta informaci\u00f3n.<\/p>\n<p>Mosc\u00fa ha negado en repetidas ocasiones haber retenido a Dima, a pesar de las numerosas informaciones que lo sit\u00faan en centros de detenci\u00f3n de Rusia. Tanto la Comisi\u00f3n de Investigaci\u00f3n rusa como el Servicio de Prisiones ruso en Briansk informaron oficialmente al abogado de los Khyliuk en diciembre de 2022 y enero de 2023 de que no se encontraba en Rusia y de que no ten\u00edan informaci\u00f3n sobre \u00e9l.<\/p>\n<p>La nota manuscrita de Dima estaba fechada en abril de 2022, aunque sus padres no la recibieron hasta agosto de ese a\u00f1o. Despu\u00e9s, en mayo de 2023, los Khyliuk dijeron que el ICRC les llam\u00f3 para confirmar que su hijo estaba vivo. Pero no fue hasta este mes de marzo, dos a\u00f1os despu\u00e9s de su detenci\u00f3n, cuando el Ministerio de Defensa ruso admiti\u00f3 que Dima hab\u00eda sido detenido y que estaba retenido en Rusia, en una carta dirigida a sus padres. No facilitaron ninguna informaci\u00f3n sobre su paradero o situaci\u00f3n.<\/p>\n<p>La nota manuscrita que Halyna y Vasyl Khyliuk recibieron de su hijo Dima. Cr\u00e9dito: Ivana Kottasova\/CNN<\/p>\n<p>&#171;Hemos tenido casos en los que incluso personas sometidas a juicios, juicios p\u00fablicos, en los que hemos visto fotos de la sala del tribunal, incluso en estos casos, los familiares no tendr\u00edan documentos oficiales, nada que confirmara oficialmente que las personas se encuentran en el territorio de la Federaci\u00f3n Rusa&#187;, dijo Pantielieieva.<\/p>\n<p>Seg\u00fan el derecho internacional humanitario, en tiempos de conflicto, el ICRC debe tener acceso regular a los detenidos para verificar que reciben un trato humano y para volver a ponerlos en contacto con sus familiares. Tambi\u00e9n se debe informar a la persona del motivo de su reclusi\u00f3n y permitirle apelar la decisi\u00f3n.<\/p>\n<p>Funcionarios de la Inteligencia de Defensa ucraniana dijeron a CNN que creen que el Servicio Federal de Seguridad ruso (FSB) y la Guardia Nacional rusa son los principales impulsores de los arrestos y detenciones de civiles ucranianos. Ninguno de los dos respondi\u00f3 a las peticiones de comentarios de CNN.<\/p>\n<p>CNN tambi\u00e9n hizo m\u00faltiples solicitudes a los ministerios rusos de Defensa e Interior, a la oficina del defensor del pueblo ruso, a la Direcci\u00f3n de Programas Especiales del Presidente de la Federaci\u00f3n Rusa y a la Direcci\u00f3n Principal del Estado Mayor (GRU) para obtener informaci\u00f3n sobre los casos espec\u00edficos mencionados en esta historia. No han respondido.<\/p>\n<p>Rusia anuncia ejercicios con armas nucleares t\u00e1cticas mientras el Kremlin culpa a Occidente por la escalada de tensiones<\/p>\n<p>Detenidos en secreto durante meses<\/p>\n<p>Para las familias de los detenidos, intentar desenvolverse en el aparato de seguridad ruso forma parte de su pesadilla.<\/p>\n<p>Yulia Khrypun ha pasado m\u00e1s de dos a\u00f1os dirigi\u00e9ndose a todas las autoridades rusas en las que pod\u00eda pensar, intentando desesperadamente encontrar informaci\u00f3n sobre su padre Serhii. Cuando recib\u00eda respuestas oficiales, a menudo inclu\u00edan informaci\u00f3n contradictoria. &#171;Una instituci\u00f3n me inform\u00f3 oficialmente de que hab\u00eda sido detenido por resistirse a la &#8216;operaci\u00f3n militar especial&#8217;, mientras que otras dec\u00edan que nunca hab\u00eda cruzado la frontera con Rusia&#187;, explica. CNN ha visto algunos de los documentos que le enviaron.<\/p>\n<p>Serhii Khrypun fue detenido en Nove, un pueblo cercano a Tokmak, en el sur de Ucrania, donde trabajaba como guardia de seguridad en una granja. La zona llevaba ocupada unas dos semanas cuando, una ma\u00f1ana de marzo de 2022, Serhii llam\u00f3 a Yulia para decirle que hab\u00eda llegado un nuevo grupo de soldados rusos en dos camiones.<\/p>\n<p>&#171;Y esa fue nuestra \u00faltima conversaci\u00f3n telef\u00f3nica. Despu\u00e9s de eso no tuvimos ninguna informaci\u00f3n sobre \u00e9l durante dos d\u00edas&#187;, dijo. &#171;Me parece que en ese momento \u00e9l ya sab\u00eda que se lo iban a llevar. Llam\u00f3 a todo el mundo: a m\u00ed, a su madre y a su hermana, y a su amigo&#187;.<\/p>\n<p>Yulia pudo reconstruir lo sucedido porque la detenci\u00f3n de Serhii fue filmada por una c\u00e1mara de seguridad de la granja; dijo que se parec\u00eda mucho a un secuestro. Cuando llegaron los soldados rusos, los registraron a \u00e9l y a su colega antes de proceder a desnudarlos, seg\u00fan muestra el video. &#171;Despu\u00e9s le pusieron una bolsa en la cabeza y se lo llevaron&#187;, relat\u00f3.<\/p>\n<p>Unos ucranianos que fueron llevados al mismo centro que su padre, un edificio gubernamental en Tokmak, dijeron a Yulia que \u00e9l estuvo retenido all\u00ed unas dos semanas. Tambi\u00e9n dijeron que fue golpeado por los soldados rusos.<\/p>\n<p>&#171;Luego lo llevaron a Melit\u00f3pol, donde permaneci\u00f3 tres semanas, despu\u00e9s a Olenivka, y de all\u00ed a Kursk (en Rusia), y despu\u00e9s a Crimea&#187;, dijo, citando lo que ha escuchado de varios testigos presenciales que estuvieron retenidos con su padre. Uno de ellos se puso en contacto con ella tras su liberaci\u00f3n, y solo conoc\u00eda su nombre y el lugar de trabajo de Serhii. Otros fueron entrevistados por ONG o autoridades ucranianas. Bas\u00e1ndose en estos relatos, cree que su padre se encuentra ahora recluido en un centro de detenci\u00f3n de Kamensk-Shakhtinsky, ciudad de la regi\u00f3n rusa de Rostov cercana a la frontera ucraniana.<\/p>\n<p>Yulia Khrypun ha recibido informaci\u00f3n contradictoria sobre su padre de distintas autoridades rusas: algunas le han dicho que nunca lleg\u00f3 a Rusia, mientras que otras afirman que s\u00ed estuvo all\u00ed. Cr\u00e9dito: Yulia Khrypun<\/p>\n<p>Rusia retiene a tantos detenidos ucranianos que ha tenido que ampliar varias prisiones y centros de detenci\u00f3n preventiva existentes para alojarlos. Seg\u00fan la oficina del Defensor del Pueblo ucraniano, uno de estos centros se ha creado en Chonhar, en el extremo sur de la regi\u00f3n de Jers\u00f3n, ocupada por Rusia, junto a un puente que comunica con la pen\u00ednsula de Crimea, anexionada por Rusia.<\/p>\n<p>El FSB y otras agencias de seguridad rusas han llevado a cabo una campa\u00f1a a gran escala de detenciones y desapariciones forzadas en Crimea desde que Rusia se anexion\u00f3 ilegalmente la pen\u00ednsula en 2014, dirigida contra opositores pol\u00edticos, activistas proucranianos y prodemocr\u00e1ticos, defensores de los derechos humanos, periodistas y t\u00e1rtaros de Crimea. Entre los detenidos hay personas sin v\u00ednculos con la oposici\u00f3n o el activismo.<\/p>\n<p>El centro de detenci\u00f3n preventiva, o SIZO, de Simfer\u00f3pol, se ha convertido en sin\u00f3nimo de la campa\u00f1a rusa de terror en Crimea. Seg\u00fan organizaciones de derechos humanos de Crimea, como Zmina, el Grupo de Derechos Humanos de Crimea y Crimea SOS, cientos de personas han permanecido recluidas en el centro durante meses, sin que nadie supiera d\u00f3nde se encontraban.<\/p>\n<p>Tras la invasi\u00f3n a gran escala de Ucrania, Rusia abri\u00f3 un segundo centro de detenci\u00f3n preventiva en Simfer\u00f3pol, el SIZO n\u00b02. Pero, al parecer, no fue suficiente para albergar a todos los detenidos. Las im\u00e1genes satelitales de Maxar Technologies tomadas en julio de 2021 y noviembre de 2023 revelan la transformaci\u00f3n de un campus escolar en Chonhar de un edificio ordinario a un centro de detenci\u00f3n de alta seguridad. Alrededor del recinto se ha erigido un nuevo per\u00edmetro de seguridad con altos muros, con un punto de acceso controlado visible en las im\u00e1genes m\u00e1s recientes.<\/p>\n<p>El MIHR ha recopilado una base de datos de instalaciones en las que se detiene a civiles ucranianos, confirmada por testimonios de personas retenidas en los mismos lugares y, en algunos casos, por documentos oficiales. Incluyen prisiones, colonias penales y centros de detenci\u00f3n preventiva tan lejanos como las regiones rusas de Irkutsk y Krasnoyarsk, a miles de kil\u00f3metros de Ucrania, en Siberia.<\/p>\n<p>&#171;B\u00e1sicamente la secuestraron&#187;<\/p>\n<p>La familia de la expolic\u00eda Mariana Checheliuk lleva dos a\u00f1os intentando rastrear los movimientos de la joven de 24 a\u00f1os por Rusia y la Ucrania ocupada. Desde su detenci\u00f3n, se cree que ha sido trasladada al menos seis veces.<\/p>\n<p>Mariana y su hermana menor formaban parte de los cientos de civiles que pasaron semanas refugiadas en la planta sider\u00fargica de Azovstal, en Mari\u00fapol, durante el asedio ruso a la ciudad portuaria meridional. Finalmente se les permiti\u00f3 salir en mayo de 2022, cuando Rusia y Ucrania acordaron abrir un corredor humanitario hacia la ciudad de Zaporiyia, en manos ucranianas.<\/p>\n<p>Rescatados del infierno: M\u00e1s de 260 personas lograron salir de la planta sider\u00fargica de Azovstal<\/p>\n<p>En el camino, Mariana fue detenida en un &#171;punto de filtraci\u00f3n&#187; ruso en el pueblo ocupado de Bezimenne, seg\u00fan su madre, Natalia Checheliuk. El centro de Bezimenne se hizo famoso en los primeros meses de la guerra. Decenas de miles de evacuados de Mari\u00fapol fueron obligados a pasar all\u00ed un control de &#171;seguridad&#187;. Muchos nunca lograron salir.<\/p>\n<p>&#171;Esencialmente fue secuestrada&#187;, dijo Natalia a CNN.<\/p>\n<p>&#171;No hubo audiencias judiciales, no se le acus\u00f3 de nada e incluso recibimos un correo electr\u00f3nico del fiscal (de la autoproclamada Rep\u00fablica Popular de Donetsk) diciendo que no tienen absolutamente ninguna reclamaci\u00f3n contra Mariana, que no est\u00e1 acusada de nada y que &#8216;lo comprobar\u00e1n y la liberar\u00e1n'&#187;, dijo Natalia. &#171;Pero esto fue hace ocho meses, y no ha pasado nada&#187;.<\/p>\n<p>Un autob\u00fas con civiles evacuados de la planta sider\u00fargica de Azovstal en Mari\u00fapol llega al pueblo de Bezimenne, en la regi\u00f3n de Donetsk, el 6 de mayo de 2022. Cr\u00e9dito: Alexander Ermochenko\/Reuters<\/p>\n<p>Seg\u00fan testigos presenciales que estuvieron retenidos junto a Mariana y que hablaron con su familia, primero la llevaron a un centro de detenci\u00f3n en Donetsk, en el este ocupado de Ucrania. Despu\u00e9s la trasladaron a Olenivka, el centro de detenci\u00f3n donde murieron m\u00e1s de 50 prisioneros de guerra en una misteriosa explosi\u00f3n en julio de 2022.<\/p>\n<p>Desde Olenivka la llevaron a un centro de detenci\u00f3n en Taganrog, en el suroeste de Rusia, y despu\u00e9s a Kamyshin, en la regi\u00f3n rusa de Volgogrado. Desde all\u00ed, la enviaron de nuevo a Taganrog y luego a un centro de detenci\u00f3n en Mari\u00fapol, donde, por lo que sabe la familia, y seg\u00fan han informado grupos de derechos humanos y funcionarios ucranianos, permanece hasta el d\u00eda de hoy.<\/p>\n<p>&#171;Mi hija sufri\u00f3 mucho&#187;, dijo Natalia. &#171;En una carta de diciembre de 2023, escribi\u00f3 que se rend\u00eda, que hab\u00eda perdido la fe&#8230; Todos los d\u00edas, todo el d\u00eda, solo pienso en ella&#187;.<\/p>\n<p>Antes de la guerra, Mariana, Marianochka, como le llama su familia, era voluntaria de bienestar animal, y a menudo se levantaba temprano para preparar y entregar comida a perros vulnerables antes de ir a trabajar con la polic\u00eda. Adopt\u00f3 a una perra rescatada llamada Mila, que ahora vive con su familia.<\/p>\n<p>Testigos presenciales han contado a su familia que la detenci\u00f3n le ha pasado una gran factura. Una mujer ucraniana que estuvo recluida en el centro de detenci\u00f3n preventiva de Taganrog en mayo de 2023 dijo a CNN que Mariana hab\u00eda perdido peso y que su estado de salud era deficiente la \u00faltima vez que la vio.<\/p>\n<p>Dijo que Mariana ten\u00eda problemas en la rodilla tras una lesi\u00f3n en Olenivka y que las condiciones en la prisi\u00f3n eran terribles.<\/p>\n<p>&#171;La comida era horrible, al igual que la actitud de los guardias, que nos maltrataban psicol\u00f3gica y f\u00edsicamente. A menudo nos obligaban a hacer flexiones, sentarnos en splits, hacer sentadillas y otros ejercicios f\u00edsicos&#187;, dijo.<\/p>\n<p>&#171;A veces pod\u00edamos hacer ejercicios f\u00edsicos, cantar canciones rusas y el himno nacional de la Federaci\u00f3n Rusa todo el d\u00eda, (los guardias) nos amenazaban con enviarnos a Siberia o a otros lugares&#8230; dici\u00e9ndonos que Ucrania ya no existe, que Ucrania no quiere volver a acoger prisioneros de guerra, que nadie nos quiere&#187;.<\/p>\n<p>La prisionera, que ya fue puesta en libertad, pidi\u00f3 a CNN que no revelara su nombre por temor a represalias.<\/p>\n<p>Seg\u00fan el ICRC, Rusia considera a Mariana prisionera de guerra porque antes era polic\u00eda, dijo Natalia. Sin embargo, el gobierno ucraniano dijo a la familia que la consideraban una civil y que, como tal, no pod\u00eda ser intercambiada.<\/p>\n<p>Mariana Checheliuk, expolic\u00eda y voluntaria de bienestar animal, ha sido trasladada al menos seis veces por Rusia y la Ucrania ocupada desde que fue detenida hace dos a\u00f1os a las afueras de Mari\u00fapol. Cr\u00e9dito: Familia Checheliuk\/Getty Images<\/p>\n<p>Pantielieieva, investigadora del MIHR, cree que Rusia aprovechar\u00e1 cualquier decisi\u00f3n que reconozca a los civiles como prisioneros de guerra para detener incluso a m\u00e1s. &#171;El n\u00famero de personas que se est\u00e1n llevando ya es grande, lo hacen todos los d\u00edas&#187;, afirm\u00f3, a\u00f1adiendo que el \u00faltimo caso de un civil &#171;desaparecido&#187; hab\u00eda llegado a su mesa hac\u00eda tan solo unos d\u00edas.<\/p>\n<p>Voluntarios, periodistas y profesores se encuentran entre las personas que Rusia parece interesada en detener, seg\u00fan los grupos de derechos humanos que vigilan las detenciones, pero a menudo no hay ninguna raz\u00f3n discernible por la que se haya detenido a alguien. &#171;Algunas personas fueron detenidas porque su casa no estaba lejos de las posiciones rusas. O tal vez ten\u00edan un video de (el presidente ucraniano Volodymyr) Zelensky en sus tel\u00e9fonos. O los rusos se interesaron por sus familiares y los tomaron como rehenes&#187;, explic\u00f3 Pantielieieva.<\/p>\n<p>&#171;Tenemos ejemplos en los que una persona es detenida por un soldado y, al cabo de un mes, otro soldado entra en rotaci\u00f3n y se hace responsable de los detenidos y no sabe por qu\u00e9 se detuvo a la gente y va y pregunta a los detenidos por qu\u00e9 se les retuvo&#187;.<\/p>\n<p>&#171;No s\u00e9 c\u00f3mo cambiar esto&#187;<\/p>\n<p>Ucrania ha logrado traer a casa a cientos de soldados en intercambios de prisioneros con Rusia e incluso ha tenido cierto \u00e9xito repatriando a ni\u00f1os ucranianos que fueron deportados a la fuerza, apoy\u00e1ndose en Qatar y el Fondo de las Naciones Unidas para la Infancia (UNICEF) para ayudar a mediar en el proceso.<\/p>\n<p>Los civiles detenidos, sin embargo, est\u00e1n atrapados en el limbo. Lubinets, comisionado ucraniano para los derechos humanos, declar\u00f3 a CNN que hasta ahora solo se ha liberado a unas pocas docenas. &#171;No tenemos un mecanismo legal, no tenemos un socio, no tenemos leyes internacionales, normas internacionales&#8230; No s\u00e9 c\u00f3mo cambiar esta situaci\u00f3n&#187;, afirm\u00f3.<\/p>\n<p>El gobierno ucraniano ha admitido que no estaba preparado para manejar la situaci\u00f3n de los civiles retenidos sin fin, pero que ahora cuentan con algunos sistemas para apoyar a las familias.<\/p>\n<p>Yulia, cuyo padre Serhii sigue desaparecido, dijo que se dio cuenta muy pronto de que el sistema jur\u00eddico internacional no estaba preparado para tratar casos como el suyo.<\/p>\n<p>Las fotos de Mariana Checheliuk estaban entre las expuestas por familiares de civiles detenidos en una reciente protesta en Kyiv. Cr\u00e9dito: hurricanehank\/Global Images Ukraine\/Getty Images<\/p>\n<p>&#171;El proceso estaba claro con los prisioneros de guerra, porque para ellos hay una unidad militar, el Servicio de Seguridad de Ucrania (SBU) y el Cuartel General de Coordinaci\u00f3n de Ucrania (para el Tratamiento de los Prisioneros de Guerra). Pero con los civiles, hab\u00eda diferentes n\u00fameros de tel\u00e9fono, el Ministerio del Interior, el Ministerio de Asuntos Exteriores, la l\u00ednea directa de la Oficina Nacional de Informaci\u00f3n, el defensor del pueblo, el Ministerio de Reintegraci\u00f3n&#8230; era un c\u00edrculo infernal&#187;, dijo.<\/p>\n<p>Tras meses de llegar a callejones sin salida, Yulia y otro familiar de un detenido ucraniano crearon la organizaci\u00f3n c\u00edvica &#171;Civiles en Cautiverio&#187; para tener m\u00e1s autoridad a la hora de hablar con los funcionarios. El grupo, que ha unido a las familias de unos 400 civiles detenidos, se ha convertido en un actor clave en la sensibilizaci\u00f3n y mantiene reuniones peri\u00f3dicas con la Jefatura de Coordinaci\u00f3n y la oficina del Defensor del Pueblo.<\/p>\n<p>&#171;Todo el mundo conoce a los prisioneros de guerra, pero poca gente habla de los civiles cautivos&#187;, declar\u00f3 Yulia, quien a\u00f1adi\u00f3 que a veces se siente frustrada por la decisi\u00f3n del gobierno ucraniano de no reconocer a los civiles detenidos como prisioneros de guerra, como ha exigido Rusia.<\/p>\n<p>&#171;Como hija que lleva dos a\u00f1os esperando a su padre, no entiendo por qu\u00e9 mi padre debe pagar con su vida y su salud&#187;, afirm\u00f3.<\/p>\n<p>Lubinets dijo que comprende esa frustraci\u00f3n. &#171;Pero, \u00bfqu\u00e9 se puede hacer con (un) pa\u00eds que no respeta el derecho internacional humanitario y no se hace responsable de ello? Los Convenios de Ginebra dicen que ning\u00fan bando en un conflicto armado internacional puede detener a la poblaci\u00f3n civil. \u00bfPero Rusia? Lo hicieron y lo siguen haciendo&#187;.<\/p>\n<p>&#8212; Video de Oleksii Markin y Boglarka Kosztolanyi. Gr\u00e1ficos de Lou Robinson.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kyiv, Ucrania (CNNI &#8212; &#171;Queridos mam\u00e1 y pap\u00e1, estoy vivo y bien. Estoy bien, Dima&#187;. Escrito a mano en un peque\u00f1o trozo de papel, este es el \u00fanico mensaje que Halyna y Vasyl Khyliuk han recibido de su hijo Dmytro Khyliuk, conocido como Dima, desde que fue capturado por soldados rusos hace m\u00e1s de dos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448936","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio - Noticias\" \/>\n<meta property=\"og:description\" content=\"Kyiv, Ucrania (CNNI &#8212; &#171;Queridos mam\u00e1 y pap\u00e1, estoy vivo y bien. Estoy bien, Dima&#187;. Escrito a mano en un peque\u00f1o trozo de papel, este es el \u00fanico mensaje que Halyna y Vasyl Khyliuk han recibido de su hijo Dmytro Khyliuk, conocido como Dima, desde que fue capturado por soldados rusos hace m\u00e1s de dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T20:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio\",\"datePublished\":\"2024-05-06T20:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/\"},\"wordCount\":3948,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/\",\"name\":\"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-06T20:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio - Noticias","og_description":"Kyiv, Ucrania (CNNI &#8212; &#171;Queridos mam\u00e1 y pap\u00e1, estoy vivo y bien. Estoy bien, Dima&#187;. Escrito a mano en un peque\u00f1o trozo de papel, este es el \u00fanico mensaje que Halyna y Vasyl Khyliuk han recibido de su hijo Dmytro Khyliuk, conocido como Dima, desde que fue capturado por soldados rusos hace m\u00e1s de dos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-06T20:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/"},"author":{"name":"","@id":""},"headline":"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio","datePublished":"2024-05-06T20:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/"},"wordCount":3948,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/","name":"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-06T20:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\u00e1n siendo retenidos como moneda de cambio","url":"http:\/\/noticiasya.com\/hartford\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2024\/05\/06\/ucranianos-enviados-prisiones-rusas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-06T20:03:43Z","datePublished":"2024-05-06T20:03:43Z","dateModified":"2024-05-06T20:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Miles de ucranianos han sido enviados a prisiones rusas. Ucrania dice que est\\u00e1n siendo retenidos como moneda de cambio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/05\\\/06\\\/ucranianos-enviados-prisiones-rusas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2024\\\/05\\\/06\\\/ucranianos-enviados-prisiones-rusas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-06T20:03:43Z\",\"datePublished\":\"2024-05-06T20:03:43Z\",\"dateModified\":\"2024-05-06T20:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457465,"url":"https:\/\/noticiasya.com\/hartford\/2025\/01\/12\/zelensky-liberar-soldados-norcoreanos-por-soldados-ucranianos-rusia-trax\/","url_meta":{"origin":1448936,"position":0},"title":"Zelensky ofrece liberar a soldados norcoreanos capturados a cambio de soldados ucranianos retenidos en Rusia","author":"","date":"enero 12, 2025","format":false,"excerpt":"El presidente de Ucrania, Volodymyr Zelensky, dijo que est\u00e1 dispuesto a liberar a los soldados norcoreanos capturados por Ucrania en la regi\u00f3n rusa de Kursk a cambio de los soldados ucranianos que permanezcan cautivos en Rusia.\u201cUcrania est\u00e1 dispuesta a entregarle los soldados a (el l\u00edder norcoreano) Kim Jong Un si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463333,"url":"https:\/\/noticiasya.com\/hartford\/2025\/06\/08\/desesperada-busqueda-rusia-ucrania-trax\/","url_meta":{"origin":1448936,"position":1},"title":"Desesperada por sacar de Rusia a sus civiles detenidos ilegalmente, Kyiv ofrece a cambio colaboradores ucranianos","author":"","date":"junio 8, 2025","format":false,"excerpt":"Ucrania excarcel\u00f3 y envi\u00f3 a decenas de sus propios ciudadanos a Rusia el mes pasado, en un intento de asegurar la liberaci\u00f3n de decenas de civiles ucranianos detenidos ilegalmente en c\u00e1rceles rusas, una medida descrita por activistas de derechos humanos como desesperada y preocupante.Seg\u00fan el gobierno de Ucrania, 70 civiles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459977,"url":"https:\/\/noticiasya.com\/hartford\/2025\/03\/15\/zelensky-no-hay-cerco-tropas-ucranianas-region-rusa-kursk-acusa-putin-mentir-trax\/","url_meta":{"origin":1448936,"position":2},"title":"Zelensky dice que &#171;no hay cerco&#187; de militares ucranianos en la regi\u00f3n rusa de Kursk y acusa a Putin de mentir","author":"","date":"marzo 15, 2025","format":false,"excerpt":"El presidente de Ucrania, Volodymyr Zelensky, dijo que los militares ucranianos no han sido cercados por las fuerzas rusas en la regi\u00f3n de Kursk, y acus\u00f3 al l\u00edder de Rusia, Vladimir Putin, de \u201cmentir\u201d sobre la situaci\u00f3n en el terreno.Ucrania lanz\u00f3 su incursi\u00f3n por sorpresa en Kursk en agosto, capturando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447031,"url":"https:\/\/noticiasya.com\/hartford\/2024\/03\/16\/cientos-ucranianos-muertos-ataque-aereo-rusia-trax\/","url_meta":{"origin":1448936,"position":3},"title":"Rusia dice que cientos de soldados ucranianos murieron en un ataque a\u00e9reo con &#171;bomba de vac\u00edo&#187;, pero Kyiv lo niega","author":"","date":"marzo 16, 2024","format":false,"excerpt":"(CNN) -- Rusia dice que mat\u00f3 a un gran n\u00famero de soldados ucranianos con la llamada \"bomba de vac\u00edo\", una afirmaci\u00f3n que Ucrania r\u00e1pidamente calific\u00f3 de absurda.El sub-jefe del Estado Mayor General de las Fuerzas Armadas Rusas inform\u00f3 durante una reuni\u00f3n al Ministro de Defensa ruso, Sergei Shoigu, que hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458425,"url":"https:\/\/noticiasya.com\/hartford\/2025\/02\/07\/ucrania-kursk-moneda-de-cambio-trax\/","url_meta":{"origin":1448936,"position":4},"title":"Ucrania ve a Kursk como una posible moneda de cambio ante la presi\u00f3n de Trump por conversaciones de alto el fuego","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Ucrania ha lanzado nuevos ataques en la regi\u00f3n de Kursk, al sur de Rusia, mientras el presidente de EE.UU., Donald Trump, presiona para que se lleven a cabo conversaciones de alto el fuego.El Instituto para el Estudio de la Guerra (ISW, por sus siglas en ingl\u00e9s), un monitor de conflictos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461656,"url":"https:\/\/noticiasya.com\/hartford\/2025\/04\/26\/rusia-recupera-kursk-dice-putin-trax\/","url_meta":{"origin":1448936,"position":5},"title":"Putin dice que Rusia recuper\u00f3 el control de la regi\u00f3n de Kursk, pero Ucrania afirma que los combates contin\u00faan","author":"","date":"abril 26, 2025","format":false,"excerpt":"El presidente de Rusia Vladimir Putin asegura que ha recuperado el control de Kursk, la regi\u00f3n fronteriza donde Ucrania lanz\u00f3 una ofensiva sorpresa el a\u00f1o pasado. Pero Ucrania afirma que los combates contin\u00faan.\u201cLa aventura del r\u00e9gimen de Kyiv ha fracasado por completo\u201d, declar\u00f3 Putin este s\u00e1bado, felicitando a las fuerzas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1448936"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1448936\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1448936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1448936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1448936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}