{"id":1458634,"date":"2025-02-12T09:03:40","date_gmt":"2025-02-12T17:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/"},"modified":"2025-02-12T09:03:40","modified_gmt":"2025-02-12T17:03:40","slug":"salario-minimo-pagar-irpf-aplica-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/","title":{"rendered":"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica"},"content":{"rendered":"<p>Este martes, el Gobierno de Espa\u00f1a <a href=\"https:\/\/www.lamoncloa.gob.es\/consejodeministros\/resumenes\/Paginas\/2025\/110225-rueda-de-prensa-ministros.aspx\">anunci\u00f3<\/a> un incremento del 4,4% en el Salario M\u00ednimo Interprofesional (SMI) que recibir\u00e1n los ciudadanos, aunque quienes perciban este haber deber\u00e1n comenzar a pagar el Impuesto sobre la Renta de las Personas F\u00edsicas (IRPF).<\/p>\n<p>El SMI pasar\u00e1 a ser de 1.184 euros (US$ 1.224) mensuales en 14 pagas, lo que implica un aumento de 50 euros (US$ 51) al mes y 700 (US$ 724) al a\u00f1o respecto al del 2024, que era de 1.134 euros (US$ 1.172). Si no se contemplan los impuestos, el salario anual pasar\u00e1 a ser de 16.576 euros (US$ 17.144).<\/p>\n<p>La <a href=\"https:\/\/www.lamoncloa.gob.es\/consejodeministros\/referencias\/Paginas\/2025\/20250211-referencia-rueda-de-prensa-ministros.aspx#smi\" rel=\"noopener noreferrer\" target=\"_blank\">medida<\/a>, que afecta a 2,4 millones de trabajadores, comienza a regir con efectos retroactivos desde el 1 de enero del 2025. El SMI ha subido en Espa\u00f1a un 61% desde el 2018 mientras que la inflaci\u00f3n ha sido el 23% en el mismo per\u00edodo de tiempo.<\/p>\n<p>Sin embargo, pese al incremento, el Ministerio de Hacienda no ajust\u00f3 los pisos salariales de quienes deben pagar el IRPF. Anteriormente, al percibir la renta m\u00ednima, no se llegaba a la base necesaria para pagar el IRPF, que es de 15.876 euros (US$ 16.420) al a\u00f1o. Sin embargo, con este aumento se supera ese umbral, por lo que muchas personas que reciben la m\u00ednima deber\u00e1n comenzar a pagar este impuesto.<\/p>\n<p>El porcentaje depende, en primer lugar, de la clase de renta. La que proviene del ahorro tributa a un porcentaje menor que la que no.<\/p>\n<p>Adem\u00e1s, el monto a pagar va aumentando dependiendo de los ingresos que reciba el individuo o grupos, y tambi\u00e9n var\u00eda seg\u00fan las situaciones familiares. Por ende, quienes menos perciben pagan menos.<\/p>\n<p>De todos modos, habr\u00e1 un grupo de perceptores del SMI que no deber\u00e1n pagar el IRPF, pero depender\u00e1 del caso concreto.<\/p>\n<p>Por ejemplo, un individuo con pareja y un hijo menor de tres a\u00f1os no se ver\u00e1 afectado, mientras que a un soltero sin hijos le corresponder\u00e1n 300 euros (US$ 310) al a\u00f1o. Esto se debe a que, seg\u00fan la <a href=\"https:\/\/www.lamoncloa.gob.es\/serviciosdeprensa\/notasprensa\/hacienda\/paginas\/2023\/220323-que-es-irpf-y-cuando-se-presenta.aspx\">p\u00e1gina web<\/a> del gobierno, \u201cexiste un m\u00ednimo personal y familiar que, por destinarse a cubrir las necesidades vitales del contribuyente y de las personas que de \u00e9l dependen, no se somete a tributaci\u00f3n\u201d.<\/p>\n<p>La ley <a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2024-2249\">establece<\/a> distintos umbrales para ciertos grupos que perciben el SMI:<\/p>\n<ul>\n<li><strong>Contribuyentes solteros, viudos, divorciados o separados legalmente: <\/strong>el piso salarial para aquellos que tienen un hijo es de<strong> <\/strong>17.644 euros (US$ 18.249) mientras que, si tiene dos o m\u00e1s es de 18.694 euros (US$ 19.335).<\/li>\n<li><strong>Contribuyentes cuyo c\u00f3nyuge no percibe rentas superiores a 1.500 euros anuales: <\/strong>sin hijos, el piso es de 17.797 euros (US$ 18.407). Si tienen un hijo, de 18.130 euros (US$ 18.752). Con dos o m\u00e1s hijos, el l\u00edmite sube a 19.262 euros (US$ 19.922).<\/li>\n<li><strong>Otras situaciones: <\/strong>quienes no est\u00e1n incluidos en los grupos anteriores, como contribuyentes casados, y no separados legalmente, cuyo c\u00f3nyuge obtenga rentas superiores a 1.500 euros (US$ 1.551), el piso para quienes no tienen hijos es \u2013igual que la base general\u2013 de 15.876 euros (US$ 16.420), aunque aumenta a 16.342 (US$ 16.902) si tienen un hijo y a 16.867 euros (US$ 17.445) si tienen dos o m\u00e1s.<\/li>\n<\/ul>\n<p>La presentaci\u00f3n digital de las declaraciones del 2024 se debe hacer entre el 2 de abril y el 30 de junio de 2025.<\/p>\n<p>Para que la Agencia Tributaria arme tu declaraci\u00f3n de renta por tel\u00e9fono, debes solicitar la cita entre el 29 de abril y el 27 de junio, y el organismo se encargar\u00e1 de hacerlo entre el 6 de mayo y el 30 de junio.<\/p>\n<p>Adem\u00e1s, desde el 2 de hasta el 30 de junio la Agencia Tributaria puede confeccionar la declaraci\u00f3n de forma presencial en sus oficinas, cuya solicitud debe realizarse entre el 29 de mayo y el 27 de junio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes, el Gobierno de Espa\u00f1a anunci\u00f3 un incremento del 4,4% en el Salario M\u00ednimo Interprofesional (SMI) que recibir\u00e1n los ciudadanos, aunque quienes perciban este haber deber\u00e1n comenzar a pagar el Impuesto sobre la Renta de las Personas F\u00edsicas (IRPF). El SMI pasar\u00e1 a ser de 1.184 euros (US$ 1.224) mensuales en 14 pagas, lo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458634","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica - Noticias\" \/>\n<meta property=\"og:description\" content=\"Este martes, el Gobierno de Espa\u00f1a anunci\u00f3 un incremento del 4,4% en el Salario M\u00ednimo Interprofesional (SMI) que recibir\u00e1n los ciudadanos, aunque quienes perciban este haber deber\u00e1n comenzar a pagar el Impuesto sobre la Renta de las Personas F\u00edsicas (IRPF). El SMI pasar\u00e1 a ser de 1.184 euros (US$ 1.224) mensuales en 14 pagas, lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-12T17:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica\",\"datePublished\":\"2025-02-12T17:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/\"},\"wordCount\":646,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/\",\"name\":\"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-12T17:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica - Noticias","og_description":"Este martes, el Gobierno de Espa\u00f1a anunci\u00f3 un incremento del 4,4% en el Salario M\u00ednimo Interprofesional (SMI) que recibir\u00e1n los ciudadanos, aunque quienes perciban este haber deber\u00e1n comenzar a pagar el Impuesto sobre la Renta de las Personas F\u00edsicas (IRPF). El SMI pasar\u00e1 a ser de 1.184 euros (US$ 1.224) mensuales en 14 pagas, lo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/","og_site_name":"Noticias","article_published_time":"2025-02-12T17:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/"},"author":{"name":"","@id":""},"headline":"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica","datePublished":"2025-02-12T17:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/"},"wordCount":646,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/","url":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/","name":"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-12T17:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Aumenta el salario m\u00ednimo en Espa\u00f1a y tendr\u00e1n que pagar IRPF: cu\u00e1nto es y para qui\u00e9nes aplica","url":"http:\/\/noticiasya.com\/hartford\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2025\/02\/12\/salario-minimo-pagar-irpf-aplica-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-12T17:03:40Z","datePublished":"2025-02-12T17:03:40Z","dateModified":"2025-02-12T17:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Aumenta el salario m\\u00ednimo en Espa\\u00f1a y tendr\\u00e1n que pagar IRPF: cu\\u00e1nto es y para qui\\u00e9nes aplica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2025\\\/02\\\/12\\\/salario-minimo-pagar-irpf-aplica-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2025\\\/02\\\/12\\\/salario-minimo-pagar-irpf-aplica-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-12T17:03:40Z\",\"datePublished\":\"2025-02-12T17:03:40Z\",\"dateModified\":\"2025-02-12T17:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456761,"url":"https:\/\/noticiasya.com\/hartford\/2024\/12\/19\/salario-minimo-espana-2025-orix\/","url_meta":{"origin":1458634,"position":0},"title":"Aumento del salario m\u00ednimo en Espa\u00f1a: \u00bfde cu\u00e1nto ser\u00e1 y cu\u00e1ndo entrar\u00e1 en vigor?","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"El Gobierno espa\u00f1ol avanza en las negociaciones para actualizar el Salario M\u00ednimo Interprofesional (SMI), con miras a implementar el nuevo ajuste a partir de enero de 2025.La ministra de Trabajo y Econom\u00eda Social lleva a cabo encuentros con expertos con la consigna, dice, de proteger el poder adquisitivo frente a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450171,"url":"https:\/\/noticiasya.com\/hartford\/2024\/06\/09\/cuanto-cobra-un-eurodiputado-orix\/","url_meta":{"origin":1458634,"position":1},"title":"\u00bfCu\u00e1nto cobra un eurodiputado? Los parlamentarios europeos ganan casi cinco veces m\u00e1s que un trabajador medio en Espa\u00f1a","author":"","date":"junio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los eurodiputados cobran un salario mensual de 10.075,18 euros brutos (unos US$ 10.961,44), dietas y cuentan con un presupuesto de \u20ac 28.696 al mes (unos US$ 31.187) para contratar asistentes, de acuerdo con los datos del Parlamento Europeo.Sin embargo, una parte de este sueldo bruto est\u00e1 sujeto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455080,"url":"https:\/\/noticiasya.com\/hartford\/2024\/10\/14\/raul-morodo-exembajador-espana-venezuela-condena-pdvsa-orix\/","url_meta":{"origin":1458634,"position":2},"title":"Condenan Ra\u00fal Morodo, exembajador de Espa\u00f1a en Venezuela, a 10 meses de prisi\u00f3n por por ocultar ganancias de PDVSA","author":"","date":"octubre 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Ra\u00fal Morodo, exembajador de Espa\u00f1a en Venezuela, recibi\u00f3 este lunes una condena a 10 meses de prisi\u00f3n por un delito contra la Hacienda p\u00fablica por la ocultaci\u00f3n de ganancias de casi 4.500.000 de euros (US$ 4.911.930) que obtuvo su hijo Alejo, que fue condenado a dos a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447764,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/05\/calendario-declaracion-de-la-renta-2024-hacienda-comienzo-fechas-limite-orix\/","url_meta":{"origin":1458634,"position":3},"title":"Calendario de declaraci\u00f3n de renta en Espa\u00f1a para 2024: \u00bfcu\u00e1ndo comienza y cu\u00e1ndo termina?","author":"","date":"abril 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La campa\u00f1a de la Renta en Espa\u00f1a comienza este martes 3 de abril de 2024 con la presentaci\u00f3n de las declaraciones por internet y finaliza el pr\u00f3ximo 1 de junio de 2024, seg\u00fan el calendario del contribuyente de este a\u00f1o que publica la Agencia Estatal de Administraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465935,"url":"https:\/\/noticiasya.com\/hartford\/2025\/08\/28\/espana-gasto-militar-otan-trump-orix\/","url_meta":{"origin":1458634,"position":4},"title":"Espa\u00f1a alcanza el objetivo de gasto militar de la OTAN, aunque lejos del que desea Trump","author":"","date":"agosto 28, 2025","format":false,"excerpt":"El \u00faltimo informe de la OTAN relativo al gasto militar revela que todos los socios de la alianza -excepto Islandia, que no cuenta con fuerzas armadas- cumplen ya el objetivo de destinar el 2% del PIB en defensa. Esto incluye a Espa\u00f1a, que se manten\u00eda en la cola de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449210,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/07\/sheinbaum-salario-minimo-mexico-orix\/","url_meta":{"origin":1458634,"position":5},"title":"Claudia Sheinbaum quiere elevar el salario m\u00ednimo en M\u00e9xico a 11.287 pesos mensuales, \u00bfqu\u00e9 tan viable es la propuesta?","author":"","date":"mayo 7, 2024","format":false,"excerpt":"(CNN) -- La candidata presidencial oficialista de M\u00e9xico Claudia Sheinbaum asegur\u00f3 durante el segundo debate de este 28 de abril que, de ganar la presidencia de M\u00e9xico en las elecciones del 2 de junio, elevar\u00e1 el salario m\u00ednimo a 2,5 canastas b\u00e1sicas. Esto quiere decir que lo aumentar\u00eda a 11.287\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1458634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1458634"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1458634\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1458634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1458634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1458634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}