{"id":1471049,"date":"2026-02-09T18:03:45","date_gmt":"2026-02-10T02:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/"},"modified":"2026-02-09T18:03:45","modified_gmt":"2026-02-10T02:03:45","slug":"cabello-guanipa-detencion-excarcelacion-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/","title":{"rendered":"Diosdado Cabello dice que hay opositores que se creen &#171;intocables&#187; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n"},"content":{"rendered":"<p>El ministro del Interior y Justicia de Venezuela, Diosdado Cabello, dijo este lunes que el dirigente opositor Juan Pablo Guanipa fue detenido solo horas despu\u00e9s de ser excarcelado por \u201cviolar\u201d las condiciones de su liberaci\u00f3n.<\/p>\n<p>\u201cAlgunos pol\u00edticos creyeron que pueden hacer lo que les da la gana y embochinchar el pa\u00eds violando las propias condiciones en las cuales se les est\u00e1 dando libertad\u201d, dijo Cabello durante la rueda de prensa semanal del oficialista Partido Socialista Unido de Venezuela (PSUV), transmitida por el canal estatal VTV.<\/p>\n<p>El tambi\u00e9n secretario general del PSUV se\u00f1al\u00f3 que, desde diciembre, el Gobierno hab\u00eda liberado a 897 personas, pero ahora son 896, ya que \u201cuna persona fue detenida nuevamente por violar las condiciones sobre las cuales fue liberada\u201d.<\/p>\n<p>Adem\u00e1s, Cabello cuestion\u00f3 que haya opositores que \u201cse creen intocables\u201d.<\/p>\n<p>\u201cSi ustedes quieren hacer pol\u00edtica hagan pol\u00edtica, nadie les va a negar su derecho de hacer pol\u00edtica pero si usted quiere quemar este pa\u00eds, incendiar este pa\u00eds, el sistema de justicia, va a funcionar\u201d, a\u00f1adi\u00f3 el ministro.<\/p>\n<p>Guanipa, figura cercana a la l\u00edder opositora Mar\u00eda Corina Machado, fue \u201cemboscado por aproximadamente 10 agentes que no ten\u00edan identificaci\u00f3n alguna\u201d cuando estaba en un evento a las 11:45 p.m., hora local, seg\u00fan relat\u00f3 su hijo, Ram\u00f3n Guanipa, en un <a href=\"https:\/\/x.com\/JuanPGuanipa\/status\/2020719835659858403\">video<\/a> publicado en redes sociales.<\/p>\n<p>Familiares y aliados del dirigente denunciaron que fue \u201csecuestrado\u201d en la urbanizaci\u00f3n Los Chorros de Caracas. \u201cLes apuntaron con sus armas, estaban fuertemente armados y se llevaron a mi padre\u201d, dijo su hijo, quien exigi\u00f3 pruebas de vida.<\/p>\n<p>Durante la madrugada de este lunes, el Ministerio P\u00fablico <a href=\"https:\/\/x.com\/MinpublicoVEN\/status\/2020749794839236634\">confirm\u00f3 <\/a>la detenci\u00f3n de Guanipa y explic\u00f3 que se solicit\u00f3 \u201cante el tribunal competente la revocatoria de la medida cautelar acordada\u201d debido al incumplimiento de las condiciones impuestas, sin detallar cu\u00e1les. Tambi\u00e9n solicit\u00f3 que se eval\u00fae un r\u00e9gimen de detenci\u00f3n domiciliaria.<\/p>\n<p>CNN envi\u00f3 una consulta a la Fiscal\u00eda para saber de qu\u00e9 condiciones se trata y d\u00f3nde est\u00e1 detenido Guanipa, y espera respuesta.<\/p>\n<p>Guanipa hab\u00eda sido excarcelado m\u00e1s temprano el domingo despu\u00e9s de m\u00e1s de ocho meses en prisi\u00f3n. Poco despu\u00e9s de salir de un centro de detenci\u00f3n en Caracas, Guanipa subi\u00f3 un video a las redes sociales en el que dijo: \u201cHoy estamos siendo liberados. Mucho que discutir sobre el presente y el futuro de Venezuela, siempre con la verdad por delante\u201d.<\/p>\n<p>Fue arrestado en mayo de 2025 acusado por Cabello, que no present\u00f3 pruebas, de participar en un supuesto plan de \u201cterror\u201d contra las elecciones regionales y legislativas. Guanipa ha negado repetidamente la acusaci\u00f3n.<\/p>\n<p>La liberaci\u00f3n del dirigente opositor ocurri\u00f3 en medio del proceso de liberaciones impulsado por la presidenta encargada Delcy Rodr\u00edguez tras la captura de Nicol\u00e1s Maduro y mientras avanza en la Asamblea Nacional una <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/05\/venezuela\/asamblea-nacional-venezuela-ley-amnistia-presos-politicos-orix\">ley de amnist\u00eda<\/a>, que seg\u00fan el chavismo ser\u00eda aprobada esta semana.<\/p>\n<p>La organizaci\u00f3n no gubernamental Foro Penal calcula que en Venezuela permanecen encarceladas <a href=\"https:\/\/foropenal.com\/\">m\u00e1s de 600 personas <\/a>por motivos pol\u00edticos. Aunque la cifra ha disminuido en las \u00faltimas semanas, organizaciones civiles y familiares consideran que el ritmo de las excarcelaciones ha sido lento.<\/p>\n<p>Adem\u00e1s, persisten grandes diferencias entre las excarcelaciones confirmadas por grupos civiles, en torno a 400, y las que asegura el Gobierno, cuyo c\u00e1lculo supera los 900, sin haber difundido hasta el momento una lista oficial de personas liberadas.<\/p>\n<p>Organizaciones civiles<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/09\/venezuela\/detencion-opositor-juan-pablo-guanipa-orix\"> advierten<\/a> que las excarcelaciones no equivalen a libertad plena, ya que los beneficiarios deben cumplir medidas cautelares como prohibici\u00f3n de salida del pa\u00eds, presentaciones peri\u00f3dicas ante tribunales y restricciones para declarar p\u00fablicamente.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro del Interior y Justicia de Venezuela, Diosdado Cabello, dijo este lunes que el dirigente opositor Juan Pablo Guanipa fue detenido solo horas despu\u00e9s de ser excarcelado por \u201cviolar\u201d las condiciones de su liberaci\u00f3n. \u201cAlgunos pol\u00edticos creyeron que pueden hacer lo que les da la gana y embochinchar el pa\u00eds violando las propias condiciones [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471049","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Diosdado Cabello dice que hay opositores que se creen &quot;intocables&quot; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diosdado Cabello dice que hay opositores que se creen &quot;intocables&quot; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ministro del Interior y Justicia de Venezuela, Diosdado Cabello, dijo este lunes que el dirigente opositor Juan Pablo Guanipa fue detenido solo horas despu\u00e9s de ser excarcelado por \u201cviolar\u201d las condiciones de su liberaci\u00f3n. \u201cAlgunos pol\u00edticos creyeron que pueden hacer lo que les da la gana y embochinchar el pa\u00eds violando las propias condiciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T02:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Diosdado Cabello dice que hay opositores que se creen &#171;intocables&#187; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n\",\"datePublished\":\"2026-02-10T02:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/\"},\"wordCount\":658,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/\",\"name\":\"Diosdado Cabello dice que hay opositores que se creen \\\"intocables\\\" tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-10T02:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diosdado Cabello dice que hay opositores que se creen &#171;intocables&#187; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diosdado Cabello dice que hay opositores que se creen \"intocables\" tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Diosdado Cabello dice que hay opositores que se creen \"intocables\" tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n - Noticias","og_description":"El ministro del Interior y Justicia de Venezuela, Diosdado Cabello, dijo este lunes que el dirigente opositor Juan Pablo Guanipa fue detenido solo horas despu\u00e9s de ser excarcelado por \u201cviolar\u201d las condiciones de su liberaci\u00f3n. \u201cAlgunos pol\u00edticos creyeron que pueden hacer lo que les da la gana y embochinchar el pa\u00eds violando las propias condiciones [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-10T02:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/"},"author":{"name":"","@id":""},"headline":"Diosdado Cabello dice que hay opositores que se creen &#171;intocables&#187; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n","datePublished":"2026-02-10T02:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/"},"wordCount":658,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/","name":"Diosdado Cabello dice que hay opositores que se creen \"intocables\" tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-10T02:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Diosdado Cabello dice que hay opositores que se creen &#171;intocables&#187; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Diosdado Cabello dice que hay opositores que se creen &#171;intocables&#187; tras la detenci\u00f3n de Guanipa luego de su exarcelaci\u00f3n","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/09\/cabello-guanipa-detencion-excarcelacion-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-10T02:03:45Z","datePublished":"2026-02-10T02:03:45Z","dateModified":"2026-02-10T02:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Diosdado Cabello dice que hay opositores que se creen &#171;intocables&#187; tras la detenci\\u00f3n de Guanipa luego de su exarcelaci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/09\\\/cabello-guanipa-detencion-excarcelacion-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/09\\\/cabello-guanipa-detencion-excarcelacion-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-10T02:03:45Z\",\"datePublished\":\"2026-02-10T02:03:45Z\",\"dateModified\":\"2026-02-10T02:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471023,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/09\/detencion-opositor-juan-pablo-guanipa-orix\/","url_meta":{"origin":1471049,"position":0},"title":"\u00bfQu\u00e9 pas\u00f3 con el dirigente opositor venezolano Juan Pablo Guanipa, nuevamente detenido tras su excarcelaci\u00f3n?","author":"","date":"febrero 9, 2026","format":false,"excerpt":"El dirigente opositor venezolano Juan Pablo Guanipa fue detenido la noche del domingo en Caracas solo unas horas despu\u00e9s de ser excarcelado, en la primera vez que se conoce que uno de los presos pol\u00edticos que sali\u00f3 de prisi\u00f3n vuelve tras las rejas desde que el chavismo anunci\u00f3 el 8\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462723,"url":"https:\/\/noticiasya.com\/hartford\/2025\/05\/23\/detienen-juan-pablo-guanipa-venezuela-orix\/","url_meta":{"origin":1471049,"position":1},"title":"Detienen al opositor venezolano Juan Pablo Guanipa, uno de los l\u00edderes m\u00e1s cercanos a Mar\u00eda Corina Machado","author":"","date":"mayo 23, 2025","format":false,"excerpt":"El abogado y exdiputado venezolano Juan Pablo Guanipa, uno de los m\u00e1s cercanos colaboradores de la l\u00edder opositora Mar\u00eda Corina Machado, fue detenido este viernes, inform\u00f3 el ministro de Relaciones Interiores, Justicia y Paz, Diosdado Cabello.Cabello mostr\u00f3 en cadena de radio y TV las im\u00e1genes de la detenci\u00f3n del dirigente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449607,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/20\/asamblea-nacional-venezuela-votara-nueva-ley-regular-ong-diosdado-cabello-orix\/","url_meta":{"origin":1471049,"position":2},"title":"La Asamblea Nacional de Venezuela votar\u00e1 este martes una nueva ley para regular a las ONG, dice Diosdado Cabello","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La Asamblea Nacional de Venezuela someter\u00e1 a segunda discusi\u00f3n y votar\u00e1 este martes una propuesta de ley que plantea regular a las organizaciones no gubernamentales (ONG) que operan en el pa\u00eds, inform\u00f3 este lunes el diputado y primer vicepresidente del oficialista Partido Socialista Unido de Venezuela (PSUV), Diosdado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462733,"url":"https:\/\/noticiasya.com\/hartford\/2025\/05\/23\/detienen-mas-70-personas-amenazas-seguridad-nacional-orix\/","url_meta":{"origin":1471049,"position":3},"title":"Detienen a m\u00e1s de 70 personas en Venezuela. El Gobierno argumenta que hay amenazas a la seguridad nacional","author":"","date":"mayo 23, 2025","format":false,"excerpt":"Van m\u00e1s de 70 personas detenidas en Venezuela hasta este viernes por presuntas amenazas a la seguridad nacional, inform\u00f3 en rueda de prensa el ministro del Relaciones Interiores y Justicia, Diosdado Cabello.Agreg\u00f3 que en el grupo hay tanto venezolanos como extranjeros, pero no mostr\u00f3 prueba alguna de las acusaciones.CNN contact\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471868,"url":"https:\/\/noticiasya.com\/hartford\/2026\/03\/04\/tenemos-que-coincidir-con-ee-uu-guanipa-destaca-el-rol-fundamental-del-gobierno-de-trump-en-venezuela\/","url_meta":{"origin":1471049,"position":4},"title":"&#171;Tenemos que coincidir con EE.UU.&#187;: Guanipa destaca el &#171;rol fundamental&#187; del Gobierno de Trump en Venezuela","author":"","date":"marzo 4, 2026","format":false,"excerpt":"El l\u00edder opositor venezolano Juan Pablo Guanipa dijo este mi\u00e9rcoles que desde la oposici\u00f3n tienen que \u201ccoincidir\u201d con el Gobierno de Estados Unidos por el \u201crol fundamental\u201d que ha tenido en Venezuela durante el segundo mandato de Donald Trump.Guanipa, dirigente del partido conservador Primero Justicia, llam\u00f3 a la unidad entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471069,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/juan-pablo-guanipa-regresa-casa-detencion-domiciliaria-orix\/","url_meta":{"origin":1471049,"position":5},"title":"El l\u00edder opositor venezolano Juan Pablo Guanipa regresa a casa, donde estar\u00e1 en detenci\u00f3n domiciliaria","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El l\u00edder opositor venezolano Juan Pablo Guanipa regres\u00f3 este martes a casa de su familia en Maracaibo, en el noroeste de Venezuela, donde estar\u00e1 en detenci\u00f3n domiciliaria, dijo su hijo Ram\u00f3n Guanipa en un mensaje publicado en la cuenta de X de su padre.\u201cEstamos aliviados de saber que mi familia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471049"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471049\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}