{"id":1471072,"date":"2026-02-10T08:03:43","date_gmt":"2026-02-10T16:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/"},"modified":"2026-02-10T08:03:43","modified_gmt":"2026-02-10T16:03:43","slug":"ventas-minoristas-estables-diciembre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/","title":{"rendered":"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre"},"content":{"rendered":"<p>Los consumidores estadounidenses mantuvieron su gasto inesperadamente estable en diciembre, debido al estancamiento del mercado laboral y al debilitamiento de la percepci\u00f3n sobre la econom\u00eda.<\/p>\n<p>Las ventas minoristas se mantuvieron sin cambios en diciembre con respecto al mes anterior, seg\u00fan inform\u00f3 el Departamento de Comercio este martes, una fuerte ca\u00edda respecto al aumento del 0,6 % de noviembre. Esta cifra fue mucho menor que el aumento del 0,4 % proyectado por los economistas en una encuesta de la firma de datos FactSet.<\/p>\n<p> La lectura de diciembre se retras\u00f3 un mes debido al cierre del Gobierno del a\u00f1o pasado.<\/p>\n<p>Las ventas minoristas disminuyeron en la mayor\u00eda de las categor\u00edas que monitorea el Departamento de Comercio, siendo las que m\u00e1s cayeron en las tiendas de muebles (-0,9 %) y en las llamadas tiendas miscel\u00e1neas (-0,9 %). Mientras tanto, el gasto minorista aument\u00f3 ligeramente en varias categor\u00edas, siendo el mayor aumento en las tiendas de mejoras para el hogar (1,2 %).<\/p>\n<p>Un indicador de ventas minoristas que excluye las categor\u00edas vol\u00e1tiles y ofrece una mejor indicaci\u00f3n de la demanda subyacente \u2014conocido como el grupo de control\u2014 cay\u00f3 un 0,1 % en diciembre, seg\u00fan FactSet, muy por debajo del avance del 0,4 % pronosticado por los economistas.<\/p>\n<p>Durante el \u00faltimo a\u00f1o, la contrataci\u00f3n se ha ralentizado, la percepci\u00f3n de la gente sobre la econom\u00eda se ha desmoronado y la inflaci\u00f3n se ha mantenido persistentemente alta. Sin embargo, los consumidores no han recortado su gasto. Aun as\u00ed, el estancamiento en las ventas en diciembre sugiere que los estadounidenses podr\u00edan estar alcanzando sus l\u00edmites de gasto.<\/p>\n<p><em>Esta noticia est\u00e1 en desarrollo y se actualizar\u00e1.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los consumidores estadounidenses mantuvieron su gasto inesperadamente estable en diciembre, debido al estancamiento del mercado laboral y al debilitamiento de la percepci\u00f3n sobre la econom\u00eda. Las ventas minoristas se mantuvieron sin cambios en diciembre con respecto al mes anterior, seg\u00fan inform\u00f3 el Departamento de Comercio este martes, una fuerte ca\u00edda respecto al aumento del 0,6 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471072","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los consumidores estadounidenses mantuvieron su gasto inesperadamente estable en diciembre, debido al estancamiento del mercado laboral y al debilitamiento de la percepci\u00f3n sobre la econom\u00eda. Las ventas minoristas se mantuvieron sin cambios en diciembre con respecto al mes anterior, seg\u00fan inform\u00f3 el Departamento de Comercio este martes, una fuerte ca\u00edda respecto al aumento del 0,6 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T16:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre\",\"datePublished\":\"2026-02-10T16:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/\"},\"wordCount\":305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/\",\"name\":\"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-10T16:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre - Noticias","og_description":"Los consumidores estadounidenses mantuvieron su gasto inesperadamente estable en diciembre, debido al estancamiento del mercado laboral y al debilitamiento de la percepci\u00f3n sobre la econom\u00eda. Las ventas minoristas se mantuvieron sin cambios en diciembre con respecto al mes anterior, seg\u00fan inform\u00f3 el Departamento de Comercio este martes, una fuerte ca\u00edda respecto al aumento del 0,6 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-10T16:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/"},"author":{"name":"","@id":""},"headline":"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre","datePublished":"2026-02-10T16:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/"},"wordCount":305,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/","name":"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-10T16:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/10\/ventas-minoristas-estables-diciembre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-10T16:03:43Z","datePublished":"2026-02-10T16:03:43Z","dateModified":"2026-02-10T16:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las ventas minoristas en EE.UU. se mantuvieron inesperadamente estables en diciembre\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/10\\\/ventas-minoristas-estables-diciembre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/10\\\/ventas-minoristas-estables-diciembre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-10T16:03:43Z\",\"datePublished\":\"2026-02-10T16:03:43Z\",\"dateModified\":\"2026-02-10T16:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468686,"url":"https:\/\/noticiasya.com\/hartford\/2025\/11\/25\/inflacion-mayorista-acelero-septiembre-trax\/","url_meta":{"origin":1471072,"position":0},"title":"La inflaci\u00f3n mayorista de EE.UU. se aceler\u00f3 en septiembre y las ventas minoristas aumentaron","author":"","date":"noviembre 25, 2025","format":false,"excerpt":"La inflaci\u00f3n mayorista de Estados Unidos se aceler\u00f3 en septiembre, lo que indica que los precios para los consumidores podr\u00edan subir a\u00fan m\u00e1s en breve.El \u00edndice de precios al productor de septiembre, cuya publicaci\u00f3n se retras\u00f3 por el cierre del Gobierno, mostr\u00f3 que los precios aumentaron un 0,3 % mensual,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460016,"url":"https:\/\/noticiasya.com\/hartford\/2025\/03\/17\/ventas-minoristas-peores-economia-consumo-trax\/","url_meta":{"origin":1471072,"position":1},"title":"Las ventas minoristas fueron peores de lo esperado, otra mala se\u00f1al para la econom\u00eda de EE.UU.","author":"","date":"marzo 17, 2025","format":false,"excerpt":"El gasto de los consumidores en los comercios minoristas estadounidenses el mes pasado fue mucho menor de lo esperado, una se\u00f1al preocupante de que el comprador estadounidense podr\u00eda estar empezando a quedarse sin dinero.Las ventas minoristas aumentaron un 0,2 % en febrero con respecto al mes anterior, seg\u00fan inform\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468828,"url":"https:\/\/noticiasya.com\/hartford\/2025\/11\/29\/economia-inflacion-ventas-black-friday-trax\/","url_meta":{"origin":1471072,"position":2},"title":"La econom\u00eda en forma de K y la inflaci\u00f3n impulsan las ventas del Black Friday un 4,1 % y el gasto en l\u00ednea salta un 9,1 %","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Las ventas minoristas en EE.UU. durante el Black Friday, el d\u00eda de compras m\u00e1s activo del a\u00f1o, aumentaron un 4,1 % en comparaci\u00f3n con el a\u00f1o pasado, seg\u00fan datos publicados este s\u00e1bado por Mastercard SpendingPulse. Solo los compradores en l\u00ednea gastaron US$ 11.800 millones, un 9,1 % m\u00e1s que en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458977,"url":"https:\/\/noticiasya.com\/hartford\/2025\/02\/20\/dow-jones-walmart-inflacion-aranceles-trax\/","url_meta":{"origin":1471072,"position":3},"title":"El Dow Jones cae 600 puntos en medio de crecientes temores a la inflaci\u00f3n y los aranceles","author":"","date":"febrero 20, 2025","format":false,"excerpt":"Las acciones estadounidenses cayeron este jueves despu\u00e9s de que el minorista m\u00e1s grande del mundo advirtiera que 2025 ser\u00eda una monta\u00f1a rusa y dijera que esperaba que las ventas se desaceleraran este a\u00f1o en medio de temores de que los consumidores est\u00e9n exhaustos.El pron\u00f3stico amargo de Walmart arrastr\u00f3 al Dow\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459232,"url":"https:\/\/noticiasya.com\/hartford\/2025\/02\/26\/recesion-economia-eeuu-gobierno-trump-trax\/","url_meta":{"origin":1471072,"position":4},"title":"Los estadounidenses est\u00e1n agotados por el tema de la econom\u00eda. \u00bfEst\u00e1 en camino una recesi\u00f3n?","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Los consumidores y las empresas estadounidenses se sienten inquietos, temiendo que una mayor inflaci\u00f3n est\u00e9 acechando a la vuelta de la esquina mientras el presidente Donald Trump habla de grandes aranceles. El asunto plantea preguntas sobre qu\u00e9 significa el poco \u00e1nimo econ\u00f3mico de Estados Unidos para el gasto, la contrataci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457148,"url":"https:\/\/noticiasya.com\/hartford\/2025\/01\/02\/cierre-cadenas-estados-unidos-trax\/","url_meta":{"origin":1471072,"position":5},"title":"Por qu\u00e9 pareciera que est\u00e1n cerrando todas las cadenas de Estados Unidos","author":"","date":"enero 2, 2025","format":false,"excerpt":"El apocalipsis de las tiendas minoristas regres\u00f3 con fuerza en 2024.Los principales minoristas de EE.UU. anunciaron m\u00e1s de 7.300 cierres de tiendas el a\u00f1o pasado, un aumento del 57% respecto a 2023, seg\u00fan Coresight Research. Esa es la cifra anual m\u00e1s alta de tiendas cerradas desde 2020, cuando la pandemia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471072"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471072\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}