{"id":1471082,"date":"2026-02-10T14:03:51","date_gmt":"2026-02-10T22:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/"},"modified":"2026-02-10T14:03:51","modified_gmt":"2026-02-10T22:03:51","slug":"medalla-olimpica-bronce-confiesa-infidelidad-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","title":{"rendered":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo"},"content":{"rendered":"<p>Bueno, no estoy seguro de si es la primera vez que se celebra en los <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/09\/deportes\/medallero-juegos-olimpicos-invierno-tabla-orix\">Juegos Ol\u00edmpicos<\/a>, pero sin duda ha dado que hablar.<\/p>\n<p>El biatleta noruego Sturla Holm Laegreid, tras conseguir el bronce en la prueba individual masculina de 20 km, admiti\u00f3 en la televisi\u00f3n noruega que le hab\u00eda sido infiel a su novia.<\/p>\n<p>Tras hacer p\u00fablica la noticia, esto es lo que declar\u00f3 a los periodistas durante una conferencia de prensa:<\/p>\n<p>\u201cNo s\u00e9 si fue la decisi\u00f3n correcta, pero fue la que tom\u00e9\u201d, declar\u00f3 Laegreid. \u201cTomamos decisiones diferentes a lo largo de la vida, y as\u00ed es como se construye la vida, b\u00e1sicamente. As\u00ed que hoy decid\u00ed contarle al mundo lo que hice\u201d.<\/p>\n<p>\u201cAs\u00ed que, tal vez, tal vez exista la posibilidad de que ella vea lo que realmente significa para m\u00ed. O tal vez no, pero no quiero pensar que no lo intent\u00e9 todo para recuperarla. As\u00ed que, s\u00ed, de nuevo, no quiero robarme el protagonismo hoy.<\/p>\n<p>M\u00e1s tarde a\u00f1adi\u00f3: \u201cNo he tenido ninguna reacci\u00f3n de la chica que mencion\u00e9. Me alegro porque entonces tal vez no lo haya visto; tal vez lo vea en el momento adecuado. Espero no empeorarle las cosas, pero tal vez pueda ayudar. No lo s\u00e9. Espero que haya un final feliz al final. As\u00ed que ya veremos qu\u00e9 pasa con el tiempo\u201d.<\/p>\n<p>El compatriota de Laegrid, Johan-Olav Botn, se llev\u00f3 la medalla de oro con un tiempo de 51:31.5, seguido por el franc\u00e9s Eric Perrot, a 14,8 segundos, quien se llev\u00f3 la medalla de plata.<\/p>\n<p>Abrumado por la situaci\u00f3n y su medalla de oro, Botn lanz\u00f3 un grito de alegr\u00eda al cruzar la l\u00ednea de meta.<\/p>\n<p>\u201cPara ser sincero, no s\u00e9 exactamente c\u00f3mo me siento porque no he tenido tiempo para pensar\u201d, declar\u00f3 a los periodistas tras su victoria. \u201cEs especial. Estaba intentando recordar todo lo que ha pasado, intentando plasmarlo todo, y espero poder vivir una larga vida con todos los recuerdos que he creado hoy\u201d.<\/p>\n<p>\u201cCreo que escuchar el himno nacional con el oro alrededor del cuello es algo que siempre recordar\u00e1s\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bueno, no estoy seguro de si es la primera vez que se celebra en los Juegos Ol\u00edmpicos, pero sin duda ha dado que hablar. El biatleta noruego Sturla Holm Laegreid, tras conseguir el bronce en la prueba individual masculina de 20 km, admiti\u00f3 en la televisi\u00f3n noruega que le hab\u00eda sido infiel a su novia. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471082","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Bueno, no estoy seguro de si es la primera vez que se celebra en los Juegos Ol\u00edmpicos, pero sin duda ha dado que hablar. El biatleta noruego Sturla Holm Laegreid, tras conseguir el bronce en la prueba individual masculina de 20 km, admiti\u00f3 en la televisi\u00f3n noruega que le hab\u00eda sido infiel a su novia. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T22:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo\",\"datePublished\":\"2026-02-10T22:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/\"},\"wordCount\":390,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/\",\"name\":\"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-10T22:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo - Noticias","og_description":"Bueno, no estoy seguro de si es la primera vez que se celebra en los Juegos Ol\u00edmpicos, pero sin duda ha dado que hablar. El biatleta noruego Sturla Holm Laegreid, tras conseguir el bronce en la prueba individual masculina de 20 km, admiti\u00f3 en la televisi\u00f3n noruega que le hab\u00eda sido infiel a su novia. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-10T22:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/"},"author":{"name":"","@id":""},"headline":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo","datePublished":"2026-02-10T22:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/"},"wordCount":390,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","name":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-10T22:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-10T22:03:51Z","datePublished":"2026-02-10T22:03:51Z","dateModified":"2026-02-10T22:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ins\\u00f3lito momento en los Juegos Ol\\u00edmpicos de Invierno: gan\\u00f3 una medalla y confes\\u00f3 una infidelidad en vivo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/10\\\/medalla-olimpica-bronce-confiesa-infidelidad-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/10\\\/medalla-olimpica-bronce-confiesa-infidelidad-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-10T22:03:51Z\",\"datePublished\":\"2026-02-10T22:03:51Z\",\"dateModified\":\"2026-02-10T22:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471107,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","url_meta":{"origin":1471082,"position":0},"title":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Si has seguido los chismes de los Juegos Ol\u00edmpicos de Invierno hasta ahora, habr\u00e1s visto al biatleta noruego Sturla Holm L\u00e6greid revelar ayer en una entrevista televisiva que le hab\u00eda sido infiel a su novia.Sin embargo, el mi\u00e9rcoles, el joven de 28 a\u00f1os dijo que lamentaba haber hecho p\u00fablica la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471081,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/maxim-naumov-padres-juegos-olimpicos-invierno-trax\/","url_meta":{"origin":1471082,"position":1},"title":"Perdi\u00f3 a sus padres en un accidente de avi\u00f3n, pero Maxim Naumov los llev\u00f3 consigo a los Juegos Ol\u00edmpicos de Invierno","author":"","date":"febrero 10, 2026","format":false,"excerpt":"Cualquiera que haya perdido a un ser querido puede apreciar lo dif\u00edcil que debi\u00f3 ser para Maxim Naumov, no solo mantener la compostura, sino tambi\u00e9n lograr su mejor actuaci\u00f3n de la temporada en el escenario m\u00e1s grande de todos, los Juegos Ol\u00edmpicos de Invierno.La emoci\u00f3n estaba a flor de piel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451510,"url":"https:\/\/noticiasya.com\/hartford\/2024\/07\/30\/simone-biles-juegos-olimpicos-remontada-increible-trax\/","url_meta":{"origin":1471082,"position":2},"title":"Simone Biles gana el oro, su octava medalla ol\u00edmpica, y se convierte en la gimnasta estadounidense m\u00e1s condecorada","author":"","date":"julio 30, 2024","format":false,"excerpt":"Par\u00eds (CNN) --\u00a0Era todo lo que ella podr\u00eda haber esperado que fuera.Tres a\u00f1os despu\u00e9s de retirarse de la final de gimnasia por equipos, Simone Biles estaba sola una vez m\u00e1s en los Juegos Ol\u00edmpicos. Pero la energ\u00eda no pod\u00eda ser m\u00e1s diferente.Biles, la \u00faltima gimnasta de la noche, se subi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445827,"url":"https:\/\/noticiasya.com\/hartford\/2024\/02\/21\/helen-glover-maternidad-juegos-olimpicos-trax\/","url_meta":{"origin":1471082,"position":3},"title":"Para la atleta ol\u00edmpica Helen Glover, la maternidad significa que &#171;cada cent\u00edmetro de felicidad&#187; no depende de los \u00e9xitos en los Juegos Ol\u00edmpicos","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Cuando la remadora brit\u00e1nica Helen Glover public\u00f3 una foto de su mano en Instagram, con sangre y ampollas, la piel p\u00e1lida y muerta colgando sin fuerza de un corte, ofreci\u00f3 una instant\u00e1nea bastante espantosa de a qu\u00e9 est\u00e1 sometiendo su cuerpo antes de los Juegos Ol\u00edmpicos de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471038,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/09\/benjamin-carl-celebracion-juegos-olimpicos-invierno-trax\/","url_meta":{"origin":1471082,"position":4},"title":"Una celebraci\u00f3n que se hizo viral en los Juegos Ol\u00edmpicos de Invierno: \u00bfqu\u00e9 hay detr\u00e1s?","author":"","date":"febrero 9, 2026","format":false,"excerpt":"El snowboarder austr\u00edaco Benjamin Karl sab\u00eda exactamente lo que har\u00eda si ganaba una medalla de oro en los Juegos Ol\u00edmpicos de Invierno de este a\u00f1o; lo que no hab\u00eda previsto era la reacci\u00f3n del resto del mundo.Tras revalidar su t\u00edtulo en el eslalon gigante paralelo en Livigno el domingo, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470626,"url":"https:\/\/noticiasya.com\/hartford\/2026\/01\/29\/madre-hijo-juntos-juegos-olimpicos-invierno-orix\/","url_meta":{"origin":1471082,"position":5},"title":"Un caso \u00fanico: madre e hijo hablan antes de competir juntos en los Juegos Ol\u00edmpicos de Invierno Mil\u00e1n-Cortina 2026","author":"","date":"enero 29, 2026","format":false,"excerpt":"Cuando se encienda la llama ol\u00edmpica del pebetero ubicado en el estadio de San Siro el pr\u00f3ximo 6 de febrero, marcando el inicio de la vigesimoquinta edici\u00f3n de los Juegos Ol\u00edmpicos de Invierno, M\u00e9xico ser\u00e1 protagonista de una de las historias m\u00e1s conmovedoras y significativas del olimpismo: una madre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471082"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471082\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}