{"id":1471083,"date":"2026-02-10T14:03:51","date_gmt":"2026-02-10T22:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/"},"modified":"2026-02-10T14:03:51","modified_gmt":"2026-02-10T22:03:51","slug":"irlandes-detenido-ice-texas-teme-vida-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/","title":{"rendered":"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida"},"content":{"rendered":"<p>Un ciudadano irland\u00e9s que ha estado en detenci\u00f3n migratoria en Estados Unidos durante cinco meses afirma que teme por su vida y que est\u00e1 confinado en condiciones deplorables, mientras aumenta la atenci\u00f3n internacional sobre el trato a los inmigrantes bajo custodia de las autoridades estadounidenses.<\/p>\n<p>Seamus Culleton, originario del condado de Kilkenny, Irlanda, ha estado detenido en un centro del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Texas desde principios de septiembre.<\/p>\n<p>Culleton, quien ha vivido en Boston por m\u00e1s de 15 a\u00f1os y dirige una empresa de construcci\u00f3n, dijo<a href=\"https:\/\/www.rte.ie\/news\/ireland\/2026\/0209\/1557514-seamus-culleton-us\/\"> a la emisora irlandesa RTE<\/a> que fue detenido por agentes de ICE mientras regresaba a su casa desde Home Depot.<\/p>\n<p>Culleton se\u00f1al\u00f3 que inform\u00f3 a las autoridades de ICE que est\u00e1 casado con una ciudadana estadounidense, que est\u00e1 en proceso de solicitar la residencia permanente, que no tiene antecedentes penales y que ten\u00eda un permiso de trabajo v\u00e1lido.<\/p>\n<p>\u201cHasta donde sab\u00eda, estaba en regla\u201d, dijo desde el centro de detenci\u00f3n en El Paso, Texas, donde permanece recluido. \u201cNada de eso import\u00f3; me esposaron y me llevaron\u201d, relat\u00f3.<\/p>\n<p>En una declaraci\u00f3n a CNN, la portavoz del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), Tricia McLaughlin, dijo que Culleton ingres\u00f3 a Estados Unidos en 2009 bajo el programa de exenci\u00f3n de visa, que permit\u00eda una estad\u00eda de 90 d\u00edas, pero no sali\u00f3 del pa\u00eds al vencer el plazo.<\/p>\n<p>Culleton relat\u00f3 que est\u00e1 detenido en una habitaci\u00f3n grande y superpoblada con m\u00e1s de 70 hombres y que duerme bajo iluminaci\u00f3n artificial constante en condiciones fr\u00edas y h\u00famedas.<\/p>\n<p>Los detenidos reciben poca comida, tienen acceso restringido a atenci\u00f3n m\u00e9dica y pocas veces se les permite salir, dijo a RTE.<\/p>\n<p>\u201cHe estado encerrado en la misma sala durante cuatro meses y medio. Casi no he salido. No hay aire fresco ni sol. Podr\u00eda contar con ambas manos las veces que he estado afuera\u201d, afirm\u00f3 Culleton. \u201cEstoy encerrado aqu\u00ed todo el d\u00eda, todos los d\u00edas\u201d.<\/p>\n<p>Culleton describi\u00f3 las condiciones en el centro, a miles de kil\u00f3metros de su hogar en Boston, como \u201cinmundas\u201d, y lo llam\u00f3 una \u201cpesadilla\u201d. \u201cSinceramente, tengo miedo por mi vida aqu\u00ed\u201d, dijo.<\/p>\n<p>McLaughlin se\u00f1al\u00f3 que, tras su arresto el 9 de septiembre, Culleton \u201crecibi\u00f3 el debido proceso y un juez de inmigraci\u00f3n emiti\u00f3 una orden final de deportaci\u00f3n el 10 de septiembre de 2025. Se le ofreci\u00f3 la opci\u00f3n de ser deportado de inmediato a Irlanda, pero eligi\u00f3 permanecer bajo custodia del ICE y tom\u00f3 medidas para seguir detenido\u201d.<\/p>\n<p>\u201cUna solicitud de residencia pendiente y una autorizaci\u00f3n de trabajo no otorgan estatus legal en nuestro pa\u00eds\u201d, dijo McLaughlin.<\/p>\n<p>\u201cEstas afirmaciones de que hay condiciones inferiores en los centros de ICE son FALSAS\u201d, agreg\u00f3 el comunicado.<\/p>\n<p>CNN tambi\u00e9n se ha comunicado con ICE, que depende del DHS, para obtener comentarios.<\/p>\n<p>Culleton dijo que funcionarios del ICE intentaron persuadirlo para que firmara documentos aceptando su deportaci\u00f3n, pero \u00e9l se neg\u00f3, optando por pelear su caso basado en su solicitud de residencia a trav\u00e9s de su esposa, Tiffany Smyth.<\/p>\n<p>Smyth dijo que la sorpresa de la detenci\u00f3n repentina de su esposo fue \u201chorrible\u201d, y habl\u00f3 de la dificultad de lidiar con el sistema migratorio, describi\u00e9ndolo como opaco y en contra de las familias.<\/p>\n<p>Smyth afirm\u00f3 a RTE que pas\u00f3 casi una semana sin saber d\u00f3nde estaba o si estaba a salvo.<\/p>\n<p>\u201cNo sab\u00eda si lo hab\u00edan deportado, no sab\u00eda si estaba de vuelta en Irlanda. No ten\u00eda idea si estaba a salvo\u2026 Y no hay nadie que te ayude a obtener esta informaci\u00f3n\u201d, dijo.<\/p>\n<p>\u201cHay un rastreador en l\u00ednea para ubicar a personas bajo custodia del ICE, as\u00ed que eso fue lo que utilic\u00e9, y vi que lo trasladaron a El Paso, Texas\u201d, a\u00f1adi\u00f3 Smyth, quien a\u00fan no ha podido visitarlo.<\/p>\n<p>\u201cDicen que las visitas son viables, pero cuando intentas organizar una es casi imposible\u201d, asegur\u00f3.<\/p>\n<p>El caso de Culleton ha provocado indignaci\u00f3n en Irlanda y el Gobierno irland\u00e9s lo ha abordado p\u00fablicamente.<\/p>\n<p>Portavoces tanto del Departamento de Asuntos Exteriores como de la Oficina del Primer Ministro, o Taoiseach, dijeron a CNN que est\u00e1n al tanto del caso, que se est\u00e1 proporcionando asistencia consular y que la Embajada de Irlanda en Washington est\u00e1 \u201cinteractuando directamente\u201d con el Departamento de Seguridad Nacional.<\/p>\n<p>El Taoiseach Miche\u00e1l Martin <a href=\"https:\/\/x.com\/christinafinn8\/status\/2021152063955034620\">dijo a los periodistas<\/a> este martes: \u201cTodos los pa\u00edses tienen pol\u00edticas migratorias, pero esas instalaciones de ICE son motivo de preocupaci\u00f3n\u201d.<\/p>\n<p>Aunque los ciudadanos irlandeses siguen siendo una peque\u00f1a minor\u00eda dentro de las detenciones de ICE, <a href=\"https:\/\/www.oireachtas.ie\/en\/debates\/question\/2026-02-05\/57\/\">cifras del Gobierno irland\u00e9s <\/a>muestran un aumento del 330 % el a\u00f1o pasado en el n\u00famero de sus ciudadanos que solicitan asistencia consular relacionada con la deportaci\u00f3n por parte de las autoridades migratorias estadounidenses, llegando a 65.<\/p>\n<p>La Ministra de Asuntos Exteriores de Irlanda, Helen McEntee, dijo a los periodistas este martes que tiene conocimiento de menos <a href=\"https:\/\/www.rte.ie\/video\/id\/30670\/\">de una decena de casos similares<\/a> de ciudadanos irlandeses detenidos actualmente.<\/p>\n<p>Su caso tambi\u00e9n pone al descubierto un sistema de inmigraci\u00f3n estadounidense que rutinariamente somete a los migrantes a<a href=\"https:\/\/www.cnn.com\/2025\/12\/09\/politics\/migrant-families-ice-detention-facility-texas\"> detenciones prolongadas en condiciones severas<\/a>, uno que, seg\u00fan organizaciones de derechos humanos, atrapa de manera abrumadora a personas negras y de color lejos del ojo p\u00fablico.<\/p>\n<p>Grupos de defensa de inmigrantes han dicho que existen disparidades raciales de larga data en la aplicaci\u00f3n de la ley migratoria en Estados Unidos, que resultan en el maltrato de migrantes de Am\u00e9rica Latina, el Caribe y pa\u00edses africanos.<\/p>\n<p>Actualmente, ICE mantiene bajo custodia a unas 70.000 personas, el n\u00famero m\u00e1s alto desde la fundaci\u00f3n de la agencia y significativamente por encima de los niveles t\u00edpicos de gobiernos anteriores. La gran mayor\u00eda de esas personas detenidas \u2014el 74 %\u2014 no tiene condenas penales, de acuerdo con los datos m\u00e1s recientes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ciudadano irland\u00e9s que ha estado en detenci\u00f3n migratoria en Estados Unidos durante cinco meses afirma que teme por su vida y que est\u00e1 confinado en condiciones deplorables, mientras aumenta la atenci\u00f3n internacional sobre el trato a los inmigrantes bajo custodia de las autoridades estadounidenses. Seamus Culleton, originario del condado de Kilkenny, Irlanda, ha estado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471083","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un ciudadano irland\u00e9s que ha estado en detenci\u00f3n migratoria en Estados Unidos durante cinco meses afirma que teme por su vida y que est\u00e1 confinado en condiciones deplorables, mientras aumenta la atenci\u00f3n internacional sobre el trato a los inmigrantes bajo custodia de las autoridades estadounidenses. Seamus Culleton, originario del condado de Kilkenny, Irlanda, ha estado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T22:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida\",\"datePublished\":\"2026-02-10T22:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/\"},\"wordCount\":1044,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/\",\"name\":\"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-10T22:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida - Noticias","og_description":"Un ciudadano irland\u00e9s que ha estado en detenci\u00f3n migratoria en Estados Unidos durante cinco meses afirma que teme por su vida y que est\u00e1 confinado en condiciones deplorables, mientras aumenta la atenci\u00f3n internacional sobre el trato a los inmigrantes bajo custodia de las autoridades estadounidenses. Seamus Culleton, originario del condado de Kilkenny, Irlanda, ha estado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-10T22:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/"},"author":{"name":"","@id":""},"headline":"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida","datePublished":"2026-02-10T22:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/"},"wordCount":1044,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/","name":"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-10T22:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un ciudadano irland\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/10\/irlandes-detenido-ice-texas-teme-vida-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-10T22:03:51Z","datePublished":"2026-02-10T22:03:51Z","dateModified":"2026-02-10T22:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un ciudadano irland\\u00e9s detenido por ICE en Texas durante 5 meses teme por su vida\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/10\\\/irlandes-detenido-ice-texas-teme-vida-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/10\\\/irlandes-detenido-ice-texas-teme-vida-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-10T22:03:51Z\",\"datePublished\":\"2026-02-10T22:03:51Z\",\"dateModified\":\"2026-02-10T22:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466869,"url":"https:\/\/noticiasya.com\/hartford\/2025\/09\/26\/mexicano-critico-ataque-ice-dallas-univision-trax\/","url_meta":{"origin":1471083,"position":0},"title":"Mexicano est\u00e1 en estado cr\u00edtico tras recibir varios disparos durante el ataque a oficinas del ICE, seg\u00fan Univisi\u00f3n","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"Un ciudadano mexicano se encuentra en estado cr\u00edtico tras recibir varios disparos, incluyendo al menos uno en el cuello, durante el ataque a una instalaci\u00f3n del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas esta semana, seg\u00fan Univisi\u00f3n, afiliada de CNN.Miguel \u00c1ngel Garc\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463730,"url":"https:\/\/noticiasya.com\/hartford\/2025\/06\/19\/gregory-sanabria-activista-venezolano-detenido-ice-orix\/","url_meta":{"origin":1471083,"position":1},"title":"ICE arresta a Gregory Sanabria, activista venezolano que estuvo en El Helicoide. &#171;Su vida correr\u00eda peligro&#187; de ser deportado","author":"","date":"junio 19, 2025","format":false,"excerpt":"El activista venezolano Gregory Sanabria fue detenido la semana pasada por las autoridades inmigratorias de Estados Unidos en Houston, le dijo a CNN el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s). Sanabria ingres\u00f3 al pa\u00eds en 2022 tras huir de Venezuela, donde estuvo m\u00e1s de tres a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470133,"url":"https:\/\/noticiasya.com\/hartford\/2026\/01\/15\/aclu-minnesota-demanda-gobierno-ice-trax\/","url_meta":{"origin":1471083,"position":2},"title":"La ACLU de Minnesota demanda al Gobierno federal por las acciones de ICE en el estado","author":"","date":"enero 15, 2026","format":false,"excerpt":"La Uni\u00f3n Estadounidense por las Libertades Civiles (ACLU, por sus siglas en ingl\u00e9s) de Minnesota present\u00f3 este jueves una demanda colectiva contra el Gobierno federal donde alega que agentes de inmigraci\u00f3n arrestaron o detuvieron violentamente a ciudadanos estadounidenses que estaban ocup\u00e1ndose de sus propios asuntos.\u201cEl Gobierno de Trump ha sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469176,"url":"https:\/\/noticiasya.com\/hartford\/2025\/12\/11\/juez-ordena-liberacion-inmediata-kilmar-abrego-garcia-trax\/","url_meta":{"origin":1471083,"position":3},"title":"Jueza ordena que Kilmar \u00c1brego Garc\u00eda sea liberado de manera &#171;inmediata&#187; de la custodia de ICE","author":"","date":"diciembre 11, 2025","format":false,"excerpt":"Una jueza federal en Maryland orden\u00f3 la liberaci\u00f3n inmediata de Kilmar \u00c1brego Garc\u00eda de la custodia del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE), seg\u00fan un documento judicial presentado este jueves, lo que representa un avance significativo en el caso de este ciudadano salvadore\u00f1o que fue deportado por error\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467030,"url":"https:\/\/noticiasya.com\/hartford\/2025\/10\/01\/mexicano-fallecio-tiroteo-ice-dallas-protegio-otro-inmigrante-trax\/","url_meta":{"origin":1471083,"position":4},"title":"El mexicano que falleci\u00f3 tras tiroteo en centro de ICE en Dallas protegi\u00f3 a otro inmigrante de los disparos, dicen abogados","author":"","date":"octubre 1, 2025","format":false,"excerpt":"Una de las v\u00edctimas del tiroteo en una instalaci\u00f3n de ICE en Dallas la semana pasada us\u00f3 su cuerpo para proteger a otro inmigrante detenido despu\u00e9s de ser herido, dijeron el mi\u00e9rcoles los abogados de su viuda.Mientras era transportado a la instalaci\u00f3n de ICE el 24 de septiembre, Miguel \u00c1ngel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466797,"url":"https:\/\/noticiasya.com\/hartford\/2025\/09\/25\/ataque-instalacion-ice-texas-que-sabemos-trax\/","url_meta":{"origin":1471083,"position":5},"title":"Un detenido muri\u00f3 despu\u00e9s de un tiroteo en una instalaci\u00f3n de ICE en Texas: las claves del caso","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"Las personas detenidas por el Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos son procesadas cada d\u00eda en la oficina de campo de la agencia en Dallas, un edificio rectangular de ladrillo escondido entre una autopista muy transitada, varias oficinas de abogados y un complejo de apartamentos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471083"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471083\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}