{"id":1471107,"date":"2026-02-11T08:03:52","date_gmt":"2026-02-11T16:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/"},"modified":"2026-02-11T08:03:52","modified_gmt":"2026-02-11T16:03:52","slug":"medallista-olimpico-arrepentido-revelado-infidelidad-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","title":{"rendered":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad"},"content":{"rendered":"<p>Si has seguido los chismes de los Juegos Ol\u00edmpicos de Invierno hasta ahora, habr\u00e1s visto al biatleta noruego Sturla Holm L\u00e6greid revelar ayer en una entrevista televisiva que le hab\u00eda sido infiel a su novia.<\/p>\n<p>Sin embargo, el mi\u00e9rcoles, el joven de 28 a\u00f1os dijo que lamentaba haber hecho p\u00fablica la informaci\u00f3n.<\/p>\n<p>\u201cLamento profundamente haber compartido esta historia personal en lo que fue un d\u00eda de celebraci\u00f3n para el biatl\u00f3n noruego\u201d, declar\u00f3 L\u00e6greid en un comunicado emitido por el equipo noruego el mi\u00e9rcoles, seg\u00fan Associated Press.<\/p>\n<p>\u201c\u00daltimamente no me siento del todo bien y no pienso con claridad\u201d.<\/p>\n<p>L\u00e6greid admiti\u00f3 haberle sido infiel tras ganar el bronce en la carrera individual de biatl\u00f3n de 20 km, terminando dos puestos por detr\u00e1s del medallista de oro y compa\u00f1ero de equipo noruego, Johan-Olav Botn.<\/p>\n<p>\u201cMis disculpas a Johan-Olav, quien merec\u00eda toda la atenci\u00f3n tras ganar el oro\u201d, declar\u00f3, seg\u00fan AP.<\/p>\n<p>\u201cTambi\u00e9n a mi exnovia, quien, sin quererlo, termin\u00f3 en el foco medi\u00e1tico. Espero que est\u00e9 bien. No puedo deshacer esto, pero ahora lo dejar\u00e9 atr\u00e1s y me centrar\u00e9 en los Juegos Ol\u00edmpicos. No responder\u00e9 m\u00e1s preguntas al respecto\u201d.<\/p>\n<p>CNN Sports se ha puesto en contacto con el equipo noruego para solicitar comentarios.<\/p>\n<p>Seg\u00fan AP, el medio noruego VG afirm\u00f3 estar en contacto con la exnovia de Laegreid, quien se mostr\u00f3 firme respecto a sus sentimientos: \u201cEs dif\u00edcil perdonarlo. Incluso despu\u00e9s de una declaraci\u00f3n de amor frente a todo el mundo. No eleg\u00ed estar en esta situaci\u00f3n, y es doloroso tener que soportarlo. Hemos estado en contacto y \u00e9l sabe lo que siento al respecto\u201d.<\/p>\n<p>Seg\u00fan AP, el peri\u00f3dico no la nombr\u00f3 porque ella no quer\u00eda que la atenci\u00f3n se dirigiera a su persona y prefer\u00eda permanecer en el anonimato.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si has seguido los chismes de los Juegos Ol\u00edmpicos de Invierno hasta ahora, habr\u00e1s visto al biatleta noruego Sturla Holm L\u00e6greid revelar ayer en una entrevista televisiva que le hab\u00eda sido infiel a su novia. Sin embargo, el mi\u00e9rcoles, el joven de 28 a\u00f1os dijo que lamentaba haber hecho p\u00fablica la informaci\u00f3n. \u201cLamento profundamente haber [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471107","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad - Noticias\" \/>\n<meta property=\"og:description\" content=\"Si has seguido los chismes de los Juegos Ol\u00edmpicos de Invierno hasta ahora, habr\u00e1s visto al biatleta noruego Sturla Holm L\u00e6greid revelar ayer en una entrevista televisiva que le hab\u00eda sido infiel a su novia. Sin embargo, el mi\u00e9rcoles, el joven de 28 a\u00f1os dijo que lamentaba haber hecho p\u00fablica la informaci\u00f3n. \u201cLamento profundamente haber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T16:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad\",\"datePublished\":\"2026-02-11T16:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/\",\"name\":\"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-11T16:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad - Noticias","og_description":"Si has seguido los chismes de los Juegos Ol\u00edmpicos de Invierno hasta ahora, habr\u00e1s visto al biatleta noruego Sturla Holm L\u00e6greid revelar ayer en una entrevista televisiva que le hab\u00eda sido infiel a su novia. Sin embargo, el mi\u00e9rcoles, el joven de 28 a\u00f1os dijo que lamentaba haber hecho p\u00fablica la informaci\u00f3n. \u201cLamento profundamente haber [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-11T16:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/"},"author":{"name":"","@id":""},"headline":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad","datePublished":"2026-02-11T16:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","name":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-11T16:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Medallista ol\u00edmpico dice que est\u00e1 arrepentido de haber revelado en p\u00fablico su infidelidad","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/11\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-11T16:03:52Z","datePublished":"2026-02-11T16:03:52Z","dateModified":"2026-02-11T16:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Medallista ol\\u00edmpico dice que est\\u00e1 arrepentido de haber revelado en p\\u00fablico su infidelidad\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/11\\\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/11\\\/medallista-olimpico-arrepentido-revelado-infidelidad-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-11T16:03:52Z\",\"datePublished\":\"2026-02-11T16:03:52Z\",\"dateModified\":\"2026-02-11T16:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471082,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","url_meta":{"origin":1471107,"position":0},"title":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo","author":"","date":"febrero 10, 2026","format":false,"excerpt":"Bueno, no estoy seguro de si es la primera vez que se celebra en los Juegos Ol\u00edmpicos, pero sin duda ha dado que hablar.El biatleta noruego Sturla Holm Laegreid, tras conseguir el bronce en la prueba individual masculina de 20 km, admiti\u00f3 en la televisi\u00f3n noruega que le hab\u00eda sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471570,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/23\/diez-momentos-destacados-juegos-olimpicos-invierno-orix\/","url_meta":{"origin":1471107,"position":1},"title":"Los 10 momentos m\u00e1s destacados que dejaron los Juegos Ol\u00edmpicos de Invierno de 2026","author":"","date":"febrero 23, 2026","format":false,"excerpt":"Los Juegos Ol\u00edmpicos de Invierno de Milano Cortina dejaron una serie de postales memorables. Ca\u00eddas dolorosas, momentos para la historia y hasta participantes inusuales\u2026 la justa italiana tuvo de todo y para todos los gustos.Aqu\u00ed va un repaso de los momentos m\u00e1s ic\u00f3nicos de Milano-Cortina:La plusmarquista estadounidense del esqu\u00ed femenino\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471100,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/11\/5-cosas-11-de-febrero-orix\/","url_meta":{"origin":1471107,"position":2},"title":"Las 5 cosas que debes saber este 11 de febrero","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Cuba despliega plan para sobrevivir a una de sus peores crisis. Miles de hondure\u00f1os y nicarag\u00fcenses est\u00e1n en riesgo de deportaci\u00f3n tras fallo sobre el TPS. El FBI publica im\u00e1genes de la casa de Nancy Guthrie mientras sigue su b\u00fasqueda. Esto es lo que debes saber para comenzar el d\u00eda.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467261,"url":"https:\/\/noticiasya.com\/hartford\/2025\/10\/10\/putin-nobel-paz-machado-trump-orix\/","url_meta":{"origin":1471107,"position":3},"title":"Putin dice que el Nobel de Paz ha sido otorgado en ocasiones &#171;a personas que no han hecho nada por la paz&#187; y elogia a Trump","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El presidente de Rusia, Vladimir Putin, dijo este viernes que \u201cha habido casos en los que el Comit\u00e9 ha otorgado el Premio Nobel de la Paz a personas que no han hecho nada por la paz\u201d, horas despu\u00e9s de que el Comit\u00e9 Noruego anunciara su decisi\u00f3n de galardonar a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467278,"url":"https:\/\/noticiasya.com\/hartford\/2025\/10\/10\/premio-nobel-paz-latinoamericanos-orix\/","url_meta":{"origin":1471107,"position":4},"title":"Adem\u00e1s de Mar\u00eda Corina Machado, otros seis latinoamericanos han sido galardonados con el Premio Nobel de la Paz","author":"","date":"octubre 10, 2025","format":false,"excerpt":"Mar\u00eda Corina Machado se ha convertido en la s\u00e9ptima persona en Am\u00e9rica Latina en recibir el Premio Nobel de la Paz. La l\u00edder opositora de Venezuela recibi\u00f3 un reconocimiento que en la historia de los premios recibieron en total 112 personas.El Comit\u00e9 Noruego del Nobel afirm\u00f3 que Machado hab\u00eda ayudado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467253,"url":"https:\/\/noticiasya.com\/hartford\/2025\/10\/10\/premio-nobel-paz-maria-corina-machado-lider-opositora-venezolana-trax\/","url_meta":{"origin":1471107,"position":5},"title":"Premio Nobel de la Paz para Mar\u00eda Corina Machado, l\u00edder opositora venezolana","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El Premio Nobel de la Paz 2025 fue otorgado a Mar\u00eda Corina Machado por \u201cpromover los derechos democr\u00e1ticos del pueblo de Venezuela\u201d.El Comit\u00e9 Noruego del Nobel afirm\u00f3 que Mar\u00eda Corina Machado hab\u00eda ayudado a \u201cmantener encendida la llama de la democracia frente a una oscuridad creciente\u201d.Al anunciar el premio en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471107"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471107\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}