{"id":1471143,"date":"2026-02-12T05:04:00","date_gmt":"2026-02-12T13:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/"},"modified":"2026-02-12T05:04:00","modified_gmt":"2026-02-12T13:04:00","slug":"ucranianos-reclutados-espias-rusos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/","title":{"rendered":"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana"},"content":{"rendered":"<p>Poco despu\u00e9s del mediod\u00eda del 19 de julio de 2024, Hrystyna Garkavenko, la hija de 19 a\u00f1os de un sacerdote, lleg\u00f3 a su iglesia en Pokrovsk, al este de Ucrania. Aunque era devota, no estaba all\u00ed para rezar.<\/p>\n<p>Familiarizada con el edificio gracias al cargo que desempe\u00f1aba su padre all\u00ed, la joven subi\u00f3 al segundo piso y entr\u00f3 en una de las habitaciones. All\u00ed, en una ventana protegida por persianas, instal\u00f3 un tel\u00e9fono m\u00f3vil como c\u00e1mara de transmisi\u00f3n en vivo, apuntando hacia una carretera utilizada por las tropas y veh\u00edculos ucranianos que iban y ven\u00edan del frente, m\u00e1s al este. La se\u00f1al se enviaba directamente a la inteligencia rusa.<\/p>\n<p>Esta no fue ni mucho menos la \u00fanica tarea que Garkavenko realiz\u00f3 para la principal agencia de inteligencia rusa, el Servicio Federal de Seguridad (FSB, por sus siglas), seg\u00fan la fiscal\u00eda ucraniana. A lo largo de ese a\u00f1o, intercambi\u00f3 mensajes con un agente del FSB, transmiti\u00e9ndole informaci\u00f3n sobre la ubicaci\u00f3n del personal y el equipo militar ucraniano en Pokrovsk, un centro estrat\u00e9gico.<\/p>\n<p>\u201cSolo quer\u00eda hablar m\u00e1s con esta persona. Y solo porque quer\u00eda hablar con \u00e9l, acept\u00e9 ayudarlo\u201d, declar\u00f3 Garkavenko a CNN en una inusual entrevista telef\u00f3nica desde la prisi\u00f3n, donde cumple una condena de 15 a\u00f1os por traici\u00f3n.<\/p>\n<p>Se neg\u00f3 a revelar a CNN si sent\u00eda algo por el agente. Pero Pavlo Uhrovetsky, jefe de la Fiscal\u00eda Regional de Donetsk, afirm\u00f3 que \u201cadem\u00e1s de su activa postura prorrusa, la joven hab\u00eda desarrollado una relaci\u00f3n m\u00e1s que amistosa con esa persona\u201d.<\/p>\n<p>Garkavenko es una de los miles de ucranianos que se cree que fueron reclutados por el FSB y otras agencias de inteligencia rusas para espiar a su propio pa\u00eds. Seg\u00fan el Servicio de Seguridad de Ucrania (SBU, por sus siglas), se han abierto m\u00e1s de 3.800 investigaciones por traici\u00f3n desde que Rusia lanz\u00f3 su invasi\u00f3n a gran escala en febrero de 2022, y m\u00e1s de 1.200 personas ya han sido declaradas culpables y condenadas. En promedio, los condenados enfrentan entre 12 y 13 a\u00f1os de prisi\u00f3n, aunque algunos son condenados a cadena perpetua.<\/p>\n<p>CNN se ha puesto en contacto con el FSB para solicitar comentarios.<\/p>\n<p>Andrii Yakovliev, abogado defensor y experto en derecho internacional humanitario y penal de la Iniciativa Medi\u00e1tica para los Derechos Humanos, una ONG ucraniana, declar\u00f3 a CNN que Ucrania garantiza las condiciones para un juicio justo y que, en general, los tribunales del pa\u00eds respetan el debido proceso. A\u00f1adi\u00f3 que los fiscales suelen acudir a los tribunales solo si tienen pruebas suficientes y no acusan a nadie de ser blanco o negro para obtener una condena.<\/p>\n<p>\u201cPasar informaci\u00f3n a la inteligencia rusa es la traici\u00f3n m\u00e1s com\u00fan en tiempos de guerra\u201d, dijo a CNN Ivan Kisilevych, jefe del Departamento de la Fiscal\u00eda General.<\/p>\n<p>Seg\u00fan el SBU, la gama de tareas realizadas por encargo del FSB es muy amplia y la geograf\u00eda (en t\u00e9rminos de proximidad a los combates) no importa.<\/p>\n<p>\u201cEn las zonas de primera l\u00ednea, detenemos con mayor frecuencia a agentes que recopilan y transmiten informaci\u00f3n sobre los movimientos o posiciones de las fuerzas ucranianas\u201d, declar\u00f3 el SBU. \u201cEn el oeste y centro de Ucrania, los agentes rusos recopilan y filtran con mayor frecuencia informaci\u00f3n sobre instalaciones militares e infraestructuras cr\u00edticas, e intentan sabotear cerca de centrales t\u00e9rmicas, dependencias policiales y l\u00edneas ferroviarias\u201d.<\/p>\n<p>El asesor del Ministerio de Defensa, Serhiy Beskrestnov, advirti\u00f3 esta semana que agentes rusos buscaban reclutar ucranianos para registrar terminales de internet satelital Starlink que las fuerzas rusas podr\u00edan usar, tras <a href=\"https:\/\/www.cnn.com\/2026\/02\/05\/europe\/starlink-ukraine-russia-blocked-intl\">el bloqueo de sistemas rusos no aprobados<\/a> . Los rusos ofrecen US$ 300 a los ucranianos que est\u00e9n dispuestos a hacerlo, afirm\u00f3.<\/p>\n<p>El perfil de los ucranianos reclutados por Rusia es amplio. Si bien algunos tienen motivaciones ideol\u00f3gicas, este grupo est\u00e1 disminuyendo, seg\u00fan los servicios de inteligencia. Para la mayor\u00eda, el dinero es la principal motivaci\u00f3n.<\/p>\n<p>Seg\u00fan el SBU, los agentes de inteligencia rusos reclutan principalmente a personas desesperadas por dinero, como desempleados o individuos con diversas adicciones: drogas, alcohol o juegos de azar.<\/p>\n<p>\u201cEs importante entender que no estamos hablando de miles de d\u00f3lares\u201d, dijo Kisilevych. \u201cPara la mayor\u00eda, son unos pocos cientos de d\u00f3lares u otros beneficios materiales\u2026 Es dinero f\u00e1cil para los traidores. Simplemente reciben el dinero en sus tarjetas, sin pensar de d\u00f3nde ni de qui\u00e9n viene\u201d.<\/p>\n<p>Andriy, oficial de contrainteligencia del SBU, declar\u00f3 a CNN que los canales de Telegram son actualmente una de las herramientas de reclutamiento m\u00e1s comunes. CNN no utiliza su apellido debido a la naturaleza de su trabajo.<\/p>\n<p>Los rusos publican anuncios ofreciendo dinero f\u00e1cil y r\u00e1pido. Luego, asignan tareas gradualmente. Al principio, son muy rudimentarias: comprar caf\u00e9, tomar una foto del recibo en una cafeter\u00eda. Para ello, se transfieren los fondos a una tarjeta bancaria y el proceso de reclutamiento comienza gradualmente \u2014explic\u00f3\u2014. M\u00e1s adelante, aparecen tareas m\u00e1s complejas: instalar c\u00e1maras a lo largo de las v\u00edas del tren, fotografiar instalaciones militares, etc.<\/p>\n<p>Si llega un momento en que la persona se niega a cooperar, los reclutadores recurren al chantaje, dijo Andriy, amenazando con entregar la correspondencia al SBU. \u201cEn ese momento, la gente no tiene vuelta atr\u00e1s\u201d, explic\u00f3.<\/p>\n<p>Garkavenko afirma que su contacto comenz\u00f3 como un conocido casual v\u00eda Telegram. \u201cAl principio, fue solo una presentaci\u00f3n normal, una conversaci\u00f3n informal. Luego se present\u00f3 como agente de la Federaci\u00f3n Rusa y sugiri\u00f3 cooperaci\u00f3n\u201d, dijo, hablando desde una colonia penal para mujeres condenadas por delitos contra la seguridad nacional y traici\u00f3n.<\/p>\n<p>Garkavenko dijo que en alg\u00fan momento consider\u00f3 renunciar. \u201cTen\u00eda dudas, quise parar en cierto momento, y se lo dije varias veces. Pero me dijeron que todo estar\u00eda bien, que me proteger\u00edan y que no pasar\u00eda nada malo. Le cre\u00ed\u201d.<\/p>\n<p>Aunque el FSB le pag\u00f3 por sus acciones, esa no fue su principal motivaci\u00f3n, dijo a CNN.<\/p>\n<p>El SBU informa casi semanalmente sobre nuevas detenciones de presuntos colaboradores locales, desde ciudadanos comunes hasta personal militar.<\/p>\n<p>La presunta traici\u00f3n que afirma descubrir involucra a una amplia gama de individuos. Entre los ya condenados se encuentran un mec\u00e1nico de f\u00e1brica de 50 a\u00f1os en Kramatorsk, reclutado por el FSB, quien envi\u00f3 coordenadas de personal militar y armamento pesado ucraniano; un exempleado de f\u00e1brica de 40 a\u00f1os en Kramatorsk, quien gui\u00f3 bombas rusas a la regi\u00f3n; un residente de Kyiv de 21 a\u00f1os, quien ayud\u00f3 a coordinar ataques con misiles rusos contra la capital; y un residente de la regi\u00f3n de Chernivtsi de 49 a\u00f1os que trabajaba para un servicio de mensajer\u00eda. Actuando bajo la \u201cexenci\u00f3n\u201d de su trabajo de mensajero, el agente recorri\u00f3 la zona grabando instalaciones militares y de infraestructura cr\u00edtica, seg\u00fan el SBU.<\/p>\n<p>Uhrovetsky, de la Fiscal\u00eda Regional de Donetsk, recuerda lo que calific\u00f3 como el caso \u201cc\u00ednico\u201d de Iryna Landuga, una mujer condenada el a\u00f1o pasado por pasar informaci\u00f3n sobre posiciones militares ucranianas a su hijo, que luch\u00f3 para el ej\u00e9rcito ruso, y recibir una compensaci\u00f3n econ\u00f3mica a cambio.<\/p>\n<p>La o\u00edmos hablando con su hijo despu\u00e9s de darle las coordenadas de las fuerzas ucranianas. Despu\u00e9s, estos lugares fueron bombardeados, y ella misma fue a comprobar que hab\u00eda muertos y heridos. Les dio las gracias y se alegr\u00f3, diciendo: \u201cBien hecho, los quiero\u201d.<\/p>\n<p>Seg\u00fan la sentencia judicial, en agosto de 2023, al regresar de la tienda, Landuga, residente en Kurakhivka, en la regi\u00f3n de Donetsk, vio soldados ucranianos en casa de la madrina de su hijo y en el cuartel de la Unidad Militar de Rescate Minero. Se lo cont\u00f3 a su hijo, tras lo cual la zona fue bombardeada, con al menos una muerte. Una civil de 59 a\u00f1os que viv\u00eda en un edificio cercano muri\u00f3 bajo los escombros, seg\u00fan el documento judicial. La madrina se encontraba fuera de la ciudad en ese momento.<\/p>\n<p>En un audio proporcionado por la fiscal\u00eda a CNN, se escucha a Landuga decir sobre el ataque: \u201cMurieron all\u00ed. Muri\u00f3 una mujer\u2026 Todo est\u00e1 bien, todo est\u00e1 bien. \u00bfAtacaron el cuartel? Bien hecho, te quiero. Buen trabajo. Para la madrina, te beso las manos\u2026 Muy agradecido por el cuartel. Y el resto lo consideraremos da\u00f1os colaterales\u201d.<\/p>\n<p>En octubre de 2025, fue condenada a cadena perpetua, y el tribunal tom\u00f3 nota de su indiferencia ante las consecuencias de sus actos.<\/p>\n<p>Garkavenko recibi\u00f3 una condena de 15 a\u00f1os en junio, tras declararse culpable y expresar arrepentimiento. Uhrovetsky dijo que se declar\u00f3 culpable \u201cporque quiere ser intercambiada\u201d.<\/p>\n<p>En su entrevista con CNN, Garkavenko dijo que aunque nunca ha estado en Rusia, tiene familiares all\u00ed y quiere vivir con ellos.<\/p>\n<p>Kisilevych se\u00f1al\u00f3 que a algunos ucranianos se les promete que, si las cosas salen mal, ser\u00e1n intercambiados por ciudadanos ucranianos retenidos como prisioneros de guerra por Rusia. Para algunos de los detenidos, ir a Rusia es la \u00fanica opci\u00f3n viable, dijo. \u201cPero tengo serias dudas de que all\u00ed les vaya mejor. Dudo que lleguen como h\u00e9roes\u201d.<\/p>\n<p>Mientras espera un posible intercambio, el padre de Garkavenko, el sacerdote, permanece en Ucrania. Ella dijo que \u00e9l se qued\u00f3 impactado al enterarse de lo que hizo, pero no la abandon\u00f3. \u201cMe apoya y dice que todo estar\u00e1 bien. Acept\u00f3 mi decisi\u00f3n de hacer un intercambio\u201d.<\/p>\n<p>Andriy, oficial de contrainteligencia del SBU, afirm\u00f3 que al servicio de inteligencia ruso no le importan realmente quienes son reclutados a distancia. \u201cSimplemente son prescindibles para ellos\u201d.<\/p>\n<p>A\u00f1adi\u00f3 que siempre habr\u00e1 gente intentando robar secretos, y que para los agentes de inteligencia, la b\u00fasqueda de traidores nunca se detiene. \u201cEs un trabajo minucioso que implica un estudio detallado de la vida de un colaborador. A veces llegas al punto en que te das cuenta de que conoces su vida tan bien que pr\u00e1cticamente te conviertes en parte de ella\u201d, dijo.<\/p>\n<p>Garkavenko dijo que tom\u00f3 la decisi\u00f3n consciente de ayudar a Rusia y ahora se arrepiente de lo que hizo. \u201cLastim\u00e9 a mis seres queridos y, en cierta medida, arruin\u00e9 mi propia vida\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poco despu\u00e9s del mediod\u00eda del 19 de julio de 2024, Hrystyna Garkavenko, la hija de 19 a\u00f1os de un sacerdote, lleg\u00f3 a su iglesia en Pokrovsk, al este de Ucrania. Aunque era devota, no estaba all\u00ed para rezar. Familiarizada con el edificio gracias al cargo que desempe\u00f1aba su padre all\u00ed, la joven subi\u00f3 al segundo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471143","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana - Noticias\" \/>\n<meta property=\"og:description\" content=\"Poco despu\u00e9s del mediod\u00eda del 19 de julio de 2024, Hrystyna Garkavenko, la hija de 19 a\u00f1os de un sacerdote, lleg\u00f3 a su iglesia en Pokrovsk, al este de Ucrania. Aunque era devota, no estaba all\u00ed para rezar. Familiarizada con el edificio gracias al cargo que desempe\u00f1aba su padre all\u00ed, la joven subi\u00f3 al segundo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T13:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana\",\"datePublished\":\"2026-02-12T13:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/\"},\"wordCount\":1769,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/\",\"name\":\"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-12T13:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana - Noticias","og_description":"Poco despu\u00e9s del mediod\u00eda del 19 de julio de 2024, Hrystyna Garkavenko, la hija de 19 a\u00f1os de un sacerdote, lleg\u00f3 a su iglesia en Pokrovsk, al este de Ucrania. Aunque era devota, no estaba all\u00ed para rezar. Familiarizada con el edificio gracias al cargo que desempe\u00f1aba su padre all\u00ed, la joven subi\u00f3 al segundo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-12T13:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/"},"author":{"name":"","@id":""},"headline":"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana","datePublished":"2026-02-12T13:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/"},"wordCount":1769,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/","name":"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-12T13:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esta mujer espi\u00f3 para un agente ruso. Ahora cumple 15 a\u00f1os en una colonia penal ucraniana","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/12\/ucranianos-reclutados-espias-rusos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-12T13:04:00Z","datePublished":"2026-02-12T13:04:00Z","dateModified":"2026-02-12T13:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esta mujer espi\\u00f3 para un agente ruso. Ahora cumple 15 a\\u00f1os en una colonia penal ucraniana\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/12\\\/ucranianos-reclutados-espias-rusos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/12\\\/ucranianos-reclutados-espias-rusos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-12T13:04:00Z\",\"datePublished\":\"2026-02-12T13:04:00Z\",\"dateModified\":\"2026-02-12T13:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470228,"url":"https:\/\/noticiasya.com\/hartford\/2026\/01\/19\/delcy-rodriguez-maria-corina-machado-trump-relacion-orix\/","url_meta":{"origin":1471143,"position":0},"title":"Cuatro se\u00f1ales que indican que la relaci\u00f3n de Trump con Delcy Rodr\u00edguez se est\u00e1 afianzando","author":"","date":"enero 19, 2026","format":false,"excerpt":"Dos semanas despu\u00e9s del sorpresivo operativo estadounidense en Caracas que llev\u00f3 a la captura de Nicol\u00e1s Maduro, la confrontaci\u00f3n pol\u00edtica sobre el futuro de Venezuela se est\u00e1 consolidando r\u00e1pidamente en torno a dos l\u00edderes, ambas mujeres, que representan diferentes visiones para su pa\u00eds: la presidenta encargada, Delcy Rodr\u00edguez, que representa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450623,"url":"https:\/\/noticiasya.com\/hartford\/2024\/06\/23\/muere-cuarta-victima-tiroteo-masivo-tienda-comestibles-de-arkansas-trax\/","url_meta":{"origin":1471143,"position":1},"title":"Muere la cuarta v\u00edctima del tiroteo masivo en una tienda de comestibles de Arkansas mientras contin\u00faa la investigaci\u00f3n policial","author":"","date":"junio 23, 2024","format":false,"excerpt":"(CNN) -- Una cuarta v\u00edctima muri\u00f3 este s\u00e1bado por la noche tras un tiroteo en una tienda de comestibles en Fordyce, Arkansas , dijeron las autoridades, mientras la Polic\u00eda continuaba investigando el ataque.Un hombre abri\u00f3 fuego en Mad Butcher en Fordyce este viernes, matando a cuatro personas de edades comprendidas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446756,"url":"https:\/\/noticiasya.com\/hartford\/2024\/03\/10\/meghan-principe-harry-familiares-victimas-masacre-uvalde\/","url_meta":{"origin":1471143,"position":2},"title":"Meghan, la Duquesa de Susex y el pr\u00edncipe Harry visitaron a los familiares de las v\u00edctimas de la masacre de Uvalde","author":"","date":"marzo 10, 2024","format":false,"excerpt":"(CNN) -- El pr\u00edncipe Harry y su esposa Meghan, Duquesa de Sussex, visitaron Uvalde, Texas, este s\u00e1bado y se reunieron con la familia de Irma Garc\u00eda, una querida maestra asesinada en el tiroteo de la Escuela Primaria Robb.Garc\u00eda, quien hab\u00eda trabajado como maestra durante 23 a\u00f1os, fue una de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456778,"url":"https:\/\/noticiasya.com\/hartford\/2024\/12\/19\/zelensky-estupido-putin-duelo-misiles-trax\/","url_meta":{"origin":1471143,"position":3},"title":"Zelensky llama &#171;est\u00fapido&#187; a Putin por desafiarlo en un &#171;duelo&#187; de misiles","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Este jueves, el presidente de Ucrania, Volodymyr Zelensky, emiti\u00f3 una respuesta \u00e1cida a la conferencia de prensa anual del presidente de Rusia, Vladimir Putin, y lanz\u00f3 un insulto al l\u00edder del Kremlin en sus redes sociales.Durante la conferencia de prensa, Putin se jact\u00f3 de la capacidad del Oreshnik, un nuevo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468511,"url":"https:\/\/noticiasya.com\/hartford\/2025\/11\/19\/estadounidense-hekmati-preso-iran-trax\/","url_meta":{"origin":1471143,"position":4},"title":"Un estadounidense viaj\u00f3 a Israel hace 13 a\u00f1os. Ahora fue detenido por eso en Ir\u00e1n","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"A Kamran Hekmati no le preocupaba viajar a Ir\u00e1n a comienzos de este a\u00f1o para lo que se supon\u00eda ser\u00eda un viaje breve.Hekmati, quien es iran\u00ed-estadounidense y jud\u00edo, hab\u00eda viajado all\u00ed numerosas veces con su familia, y nunca fue una persona que se involucrase en pol\u00edtica, dijeron familiares a CNN.Pero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462187,"url":"https:\/\/noticiasya.com\/hartford\/2025\/05\/09\/pentagono-mover-groenlandia-comando-norte-trump-trax\/","url_meta":{"origin":1471143,"position":5},"title":"El Pent\u00e1gono eval\u00faa mover Groenlandia dentro del Comando Norte de EE.UU., generando preocupaci\u00f3n por las ambiciones de Trump","author":"","date":"mayo 9, 2025","format":false,"excerpt":"Los funcionarios de la administraci\u00f3n Trump est\u00e1n sopesando un cambio que trasladar\u00eda la responsabilidad de los intereses de seguridad de EE.UU. en Groenlandia al comando militar que supervisa la defensa del territorio nacional de Estados Unidos, subrayando el enfoque del presidente en el territorio estrat\u00e9gicamente importante que ha dicho repetidamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471143"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471143\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}