{"id":1471155,"date":"2026-02-12T10:03:43","date_gmt":"2026-02-12T18:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/"},"modified":"2026-02-12T10:03:43","modified_gmt":"2026-02-12T18:03:43","slug":"trump-relacion-venezuela-extraordinaria-petroleo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/","title":{"rendered":"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &#171;extraordinaria&#187; y que el ingreso petrolero ayudar\u00e1 a los venezolanos"},"content":{"rendered":"<p>Este jueves, el presidente Donald Trump calific\u00f3 las relaciones entre Estados Unidos y Venezuela como \u201cextraordinarias\u201d, y destac\u00f3 los avances en el sector energ\u00e9tico venezolano un d\u00eda despu\u00e9s de la visita del secretario de Energ\u00eda, Chris Wright, a Caracas.<\/p>\n<p>\u201cEstamos llevando muy bien la relaci\u00f3n con la presidenta Delcy Rodr\u00edguez y sus representantes\u201d, escribi\u00f3 Trump en una publicaci\u00f3n en Truth Social.<\/p>\n<p>\u201cEl petr\u00f3leo est\u00e1 comenzando a fluir, y grandes cantidades de dinero, no vistas en muchos a\u00f1os, pronto beneficiar\u00e1n enormemente al pueblo venezolano\u201d, a\u00f1adi\u00f3 Trump, sugiriendo que la reanudaci\u00f3n de la actividad petrolera podr\u00eda impulsar financieramente la econom\u00eda del pa\u00eds en crisis.<\/p>\n<p>Wright es el funcionario estadounidense de mayor rango que ha visitado Venezuela en casi tres d\u00e9cadas. Trump tambi\u00e9n elogi\u00f3 al secretario de Estado de EE.UU., Marco Rubio.<\/p>\n<p>Adem\u00e1s, el presidente abord\u00f3 los informes sobre el magnate energ\u00e9tico Harry Sargeant III, quien busca liberar las reservas petroleras de Venezuela, ya afirm\u00f3 que \u201cno tiene autoridad, de ninguna manera, forma o modo, para actuar en nombre de los Estados Unidos de Am\u00e9rica\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves, el presidente Donald Trump calific\u00f3 las relaciones entre Estados Unidos y Venezuela como \u201cextraordinarias\u201d, y destac\u00f3 los avances en el sector energ\u00e9tico venezolano un d\u00eda despu\u00e9s de la visita del secretario de Energ\u00eda, Chris Wright, a Caracas. \u201cEstamos llevando muy bien la relaci\u00f3n con la presidenta Delcy Rodr\u00edguez y sus representantes\u201d, escribi\u00f3 Trump [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471155","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &quot;extraordinaria&quot; y que el ingreso petrolero ayudar\u00e1 a los venezolanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &quot;extraordinaria&quot; y que el ingreso petrolero ayudar\u00e1 a los venezolanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Este jueves, el presidente Donald Trump calific\u00f3 las relaciones entre Estados Unidos y Venezuela como \u201cextraordinarias\u201d, y destac\u00f3 los avances en el sector energ\u00e9tico venezolano un d\u00eda despu\u00e9s de la visita del secretario de Energ\u00eda, Chris Wright, a Caracas. \u201cEstamos llevando muy bien la relaci\u00f3n con la presidenta Delcy Rodr\u00edguez y sus representantes\u201d, escribi\u00f3 Trump [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T18:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &#171;extraordinaria&#187; y que el ingreso petrolero ayudar\u00e1 a los venezolanos\",\"datePublished\":\"2026-02-12T18:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/\"},\"wordCount\":231,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/\",\"name\":\"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es \\\"extraordinaria\\\" y que el ingreso petrolero ayudar\u00e1 a los venezolanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-12T18:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &#171;extraordinaria&#187; y que el ingreso petrolero ayudar\u00e1 a los venezolanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es \"extraordinaria\" y que el ingreso petrolero ayudar\u00e1 a los venezolanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es \"extraordinaria\" y que el ingreso petrolero ayudar\u00e1 a los venezolanos - Noticias","og_description":"Este jueves, el presidente Donald Trump calific\u00f3 las relaciones entre Estados Unidos y Venezuela como \u201cextraordinarias\u201d, y destac\u00f3 los avances en el sector energ\u00e9tico venezolano un d\u00eda despu\u00e9s de la visita del secretario de Energ\u00eda, Chris Wright, a Caracas. \u201cEstamos llevando muy bien la relaci\u00f3n con la presidenta Delcy Rodr\u00edguez y sus representantes\u201d, escribi\u00f3 Trump [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-12T18:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/"},"author":{"name":"","@id":""},"headline":"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &#171;extraordinaria&#187; y que el ingreso petrolero ayudar\u00e1 a los venezolanos","datePublished":"2026-02-12T18:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/"},"wordCount":231,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/","name":"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es \"extraordinaria\" y que el ingreso petrolero ayudar\u00e1 a los venezolanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-12T18:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &#171;extraordinaria&#187; y que el ingreso petrolero ayudar\u00e1 a los venezolanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump dice que la relaci\u00f3n entre EE.UU. y Venezuela es &#171;extraordinaria&#187; y que el ingreso petrolero ayudar\u00e1 a los venezolanos","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/12\/trump-relacion-venezuela-extraordinaria-petroleo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-12T18:03:43Z","datePublished":"2026-02-12T18:03:43Z","dateModified":"2026-02-12T18:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump dice que la relaci\\u00f3n entre EE.UU. y Venezuela es &#171;extraordinaria&#187; y que el ingreso petrolero ayudar\\u00e1 a los venezolanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/12\\\/trump-relacion-venezuela-extraordinaria-petroleo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/12\\\/trump-relacion-venezuela-extraordinaria-petroleo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-12T18:03:43Z\",\"datePublished\":\"2026-02-12T18:03:43Z\",\"dateModified\":\"2026-02-12T18:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471234,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/14\/venezuela-toneladas-suministros-medicos-eeuu-trump-no-es-caridad-orix\/","url_meta":{"origin":1471155,"position":0},"title":"Venezuela recibe m\u00e1s de 6 toneladas de suministros m\u00e9dicos de EE.UU. El Gobierno de Trump dice que no es &#171;caridad&#187;","author":"","date":"febrero 14, 2026","format":false,"excerpt":"Venezuela recibi\u00f3 el viernes seis toneladas de suministros m\u00e9dicos desde Estados Unidos, lo cual marca el primer env\u00edo de este tipo en medio de acercamientos recientes entre los gobiernos de Donald Trump y Delcy Rodr\u00edguez tras el derrocamiento del l\u00edder venezolano Nicol\u00e1s Maduro el pasado 3 de enero.El cargamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470489,"url":"https:\/\/noticiasya.com\/hartford\/2026\/01\/26\/lula-da-silva-trump-venezuela-orix\/","url_meta":{"origin":1471155,"position":1},"title":"Lula da Silva le pide a Trump trabajar &#171;para el bienestar del pueblo venezolano&#187;","author":"","date":"enero 26, 2026","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, convers\u00f3 este lunes con el mandatario estadounidense, Donald Trump, a quien le subray\u00f3 la necesidad de trabajar \u201cpara el bienestar del pueblo venezolano\u201d.\u201cIntercambiamos impresiones sobre la situaci\u00f3n de Venezuela. Resalt\u00e9 la importancia de preservar la paz y la estabilidad de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471230,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/14\/maria-corina-machado-eeuu-derrocamiento-maduro-trax\/","url_meta":{"origin":1471155,"position":2},"title":"Mar\u00eda Corina Machado elogia el papel de EE.UU. en el derrocamiento de Maduro","author":"","date":"febrero 14, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado dijo que Estados Unidos arriesg\u00f3 la vida de sus ciudadanos para derrocar la dictadura de Nicol\u00e1s Maduro en Venezuela, por lo cual dedic\u00f3 su Premio Nobel de la Paz al presidente de EE.UU., Donald Trump.En su intervenci\u00f3n este s\u00e1bado en la Conferencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471951,"url":"https:\/\/noticiasya.com\/hartford\/2026\/03\/06\/que-significa-que-venezuela-y-ee-uu-hayan-recompuesto-sus-relaciones-diplomaticas-despues-de-7-anos\/","url_meta":{"origin":1471155,"position":3},"title":"\u00bfQu\u00e9 significa que Venezuela y EE.UU. hayan restablecido sus relaciones diplom\u00e1ticas despu\u00e9s de 7 a\u00f1os?","author":"","date":"marzo 6, 2026","format":false,"excerpt":"El restablecimiento de relaciones diplom\u00e1ticas entre Estados Unidos y Venezuela despu\u00e9s de siete a\u00f1os implica que ambos pa\u00edses vuelven a reconocer formalmente sus canales oficiales de di\u00e1logo y cooperaci\u00f3n, lo que puede incluir el intercambio de representantes diplom\u00e1ticos, la reapertura de embajadas y la coordinaci\u00f3n en asuntos pol\u00edticos, econ\u00f3micos y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458409,"url":"https:\/\/noticiasya.com\/hartford\/2025\/02\/07\/canciller-incautacion-avion-venezolano-robo-orix\/","url_meta":{"origin":1471155,"position":4},"title":"Canciller venezolano dice que la incautaci\u00f3n del segundo avi\u00f3n venezolano en Rep\u00fablica Dominicana no es m\u00e1s que un robo","author":"","date":"febrero 7, 2025","format":false,"excerpt":"El canciller de Venezuela, Yv\u00e1n Gil, calific\u00f3 de \u201crobo descarado\u201d la incautaci\u00f3n en Santo Domingo de un avi\u00f3n de la estatal Petr\u00f3leos de Venezuela (PDVSA) a pedido del Gobierno de Estados Unidos, debido a \u201cviolaciones de las leyes de control de exportaciones y sanciones\u201d del pa\u00eds, argumenta el Departamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473484,"url":"https:\/\/noticiasya.com\/hartford\/2026\/04\/24\/gustavo-petro-visita-delcy-rodriguez-crimen-organizado-frontera-orix\/","url_meta":{"origin":1471155,"position":5},"title":"Tras reunirse en Caracas, Delcy Rodr\u00edguez y Gustavo Petro acuerdan combatir a los grupos criminales en la frontera com\u00fan","author":"","date":"abril 24, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, dio un paso adelante y este viernes se convirti\u00f3 en el primer jefe de Estado en viajar a Venezuela para reunirse con la presidenta encargada, Delcy Rodr\u00edguez, luego de la captura de Nicol\u00e1s Maduro ocurrida el 3 de enero durante un operativo militar de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471155"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471155\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}