{"id":1471187,"date":"2026-02-13T01:03:42","date_gmt":"2026-02-13T09:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/"},"modified":"2026-02-13T01:03:42","modified_gmt":"2026-02-13T09:03:42","slug":"gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/","title":{"rendered":"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna"},"content":{"rendered":"<p>El Departamento de Justicia de Estados Unidos present\u00f3 este jueves una moci\u00f3n que busca desestimar los cargos penales contra dos hombres venezolanos que, seg\u00fan las autoridades, agredieron a un agente federal que luego le dispar\u00f3 a uno de ellos en la pierna en Minneapolis el mes pasado, seg\u00fan documentos judiciales.<\/p>\n<p>La moci\u00f3n para desestimar los cargos penales con perjuicio, presentada en el Tribunal de Distrito de Estados Unidos de Minnesota, cita \u201cpruebas recientemente descubiertas\u201d descritas como \u201cmaterialmente inconsistentes con las acusaciones\u201d en la declaraci\u00f3n jurada.<\/p>\n<p>Julio Sosa-Celis, quien recibi\u00f3 un disparo en la pierna, y su coacusado Alfredo Alejandro Aljorna, fueron acusados \u200b\u200bde complicidad, agresi\u00f3n forzosa, resistencia, oposici\u00f3n, impedimento, intimidaci\u00f3n e interferencia con un agente del orden p\u00fablico federal en relaci\u00f3n con el incidente del 14 de enero.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/01\/18\/us\/ice-agent-shooting-video-minneapolis\">Videos obtenidos por CNN<\/a> de familiares de Sosa-Celis que llamaron desesperadamente al 911 en busca de ayuda parec\u00edan contradecir al menos algunas de las afirmaciones de ICE sobre los sucesos previos al tiroteo.<\/p>\n<p>Uno de ellos muestra una videollamada realizada por la pareja de Sosa-Celis, revisada por CNN, en la que parece decir que el conductor del auto no era Sosa-Celis, sino Aljorna.<\/p>\n<p>La madre de Aljorna cont\u00f3 previamente a CNN que su hijo dijo que \u00e9l era el que estaba siendo perseguido a pie por ICE, y que Sosa-Celis ya estaba dentro de la casa cuando el agente le dispar\u00f3, no afuera, donde ICE asegur\u00f3 que el funcionario descarg\u00f3 el arma.<\/p>\n<p>El Departamento de Seguridad Nacional indic\u00f3 que era Sosa-Celis quien conduc\u00eda un veh\u00edculo que se estrell\u00f3 y quien huy\u00f3 a pie antes de que los agentes forcejearan con \u00e9l en el suelo.<\/p>\n<p>El DHS indic\u00f3 que Sosa-Celis se resisti\u00f3 al arresto y comenz\u00f3 a \u201cagredir violentamente\u201d a uno de sus funcionarios mientras otros federales realizaban una parada de tr\u00e1fico selectiva.<\/p>\n<p>Durante el forcejeo, dos personas m\u00e1s salieron de un apartamento cercano y atacaron al oficial con una pala de nieve y un palo de escoba. El agente, seg\u00fan el DHS, dispar\u00f3 entonces un \u201ctiro defensivo\u201d que impact\u00f3 a Sosa-Celis en la pierna.<\/p>\n<p>Frederick J. Goetz, abogado de Sosa-Celis, declar\u00f3 a CNN que estaba encantado con la noticia y a\u00f1adi\u00f3: \u201cFelicito a la Fiscal\u00eda de Estados Unidos para el Distrito de Minnesota por actuar correctamente. Esto demuestra la continua profesionalidad e integridad de los abogados de esa oficina\u201d.<\/p>\n<p>CNN se ha comunicado con el DHS y el DOJ, as\u00ed como con un abogado de Aljorna, para solicitar comentarios sobre la moci\u00f3n.<\/p>\n<p><em>Diego Mendoza, Caroll Alvarado y Alaa Elassar de CNN contribuyeron a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Justicia de Estados Unidos present\u00f3 este jueves una moci\u00f3n que busca desestimar los cargos penales contra dos hombres venezolanos que, seg\u00fan las autoridades, agredieron a un agente federal que luego le dispar\u00f3 a uno de ellos en la pierna en Minneapolis el mes pasado, seg\u00fan documentos judiciales. La moci\u00f3n para desestimar los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471187","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Justicia de Estados Unidos present\u00f3 este jueves una moci\u00f3n que busca desestimar los cargos penales contra dos hombres venezolanos que, seg\u00fan las autoridades, agredieron a un agente federal que luego le dispar\u00f3 a uno de ellos en la pierna en Minneapolis el mes pasado, seg\u00fan documentos judiciales. La moci\u00f3n para desestimar los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T09:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna\",\"datePublished\":\"2026-02-13T09:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/\"},\"wordCount\":479,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/\",\"name\":\"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-13T09:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna - Noticias","og_description":"El Departamento de Justicia de Estados Unidos present\u00f3 este jueves una moci\u00f3n que busca desestimar los cargos penales contra dos hombres venezolanos que, seg\u00fan las autoridades, agredieron a un agente federal que luego le dispar\u00f3 a uno de ellos en la pierna en Minneapolis el mes pasado, seg\u00fan documentos judiciales. La moci\u00f3n para desestimar los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-13T09:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna","datePublished":"2026-02-13T09:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/"},"wordCount":479,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/","name":"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-13T09:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\u00f3 un disparo de un agente federal en la pierna","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/13\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-13T09:03:42Z","datePublished":"2026-02-13T09:03:42Z","dateModified":"2026-02-13T09:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de EE.UU. planea retirar los cargos contra un venezolano que recibi\\u00f3 un disparo de un agente federal en la pierna\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/13\\\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/13\\\/gobierno-ee-uu-retirar-cargos-venezolano-recibio-disparo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-13T09:03:42Z\",\"datePublished\":\"2026-02-13T09:03:42Z\",\"dateModified\":\"2026-02-13T09:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468545,"url":"https:\/\/noticiasya.com\/hartford\/2025\/11\/20\/fiscales-desestimar-cargos-mujer-chicago-baleada-trax\/","url_meta":{"origin":1471187,"position":0},"title":"Fiscales solicitan desestimar cargos contra mujer de Chicago baleada tras ser acusada de embestir un veh\u00edculo policial","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"En un giro inesperado del Gobierno estadounidense, la Fiscal\u00eda present\u00f3 este jueves una moci\u00f3n para desestimar los cargos federales contra una mujer que recibi\u00f3 un disparo de parte de un agente de la Oficina de Aduanas y Protecci\u00f3n Fronteriza en Chicago tras supuestamente chocar contra su auto, seg\u00fan muestran documentos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471249,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/15\/hombre-baleado-ice-minneapolis-confesion-trax\/","url_meta":{"origin":1471187,"position":1},"title":"Acusan de agresi\u00f3n a un hombre baleado por un agente de ICE en Minneapolis. Una sorprendente confesi\u00f3n puso fin al caso","author":"","date":"febrero 15, 2026","format":false,"excerpt":"Alfredo Alejandro Aljorna estaba trabajando en Minneapolis una noche de mi\u00e9rcoles del mes pasado, haciendo entregas como conductor de DoorDash, cuando se dio cuenta de que estaba siendo seguido por agentes de ICE, seg\u00fan su abogado.Condujo hasta su casa y fue derribado por un agente, pero logr\u00f3 zafarse y corri\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472617,"url":"https:\/\/noticiasya.com\/hartford\/2026\/03\/27\/jill-biden-seguridad-disparo-accidental-trax\/","url_meta":{"origin":1471187,"position":2},"title":"Un agente del Servicio Secreto asignado a Jill Biden se dispar\u00f3 accidentalmente en la pierna, dice un funcionario","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Un agente especial del Servicio Secreto de Estados Unidos asignado al equipo de seguridad de la ex primera dama Jill Biden se dispar\u00f3 accidentalmente en la pierna en la ma\u00f1ana de este viernes en el Aeropuerto Internacional de Filadelfia, dijo un funcionario de la agencia.\u201cEste viernes por la ma\u00f1ana, poco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471866,"url":"https:\/\/noticiasya.com\/hartford\/2026\/03\/04\/cilia-flores-nicolas-maduro-venezuela-desestimar-cargos-eeuu-orix\/","url_meta":{"origin":1471187,"position":3},"title":"Cilia Flores, esposa de Nicol\u00e1s Maduro, pide unirse a solicitud para desestimar cargos de narcoterrorismo en EE.UU.","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La esposa del derrocado presidente de Venezuela, Cilia Flores de Maduro, pidi\u00f3 a un juez federal en Nueva York que le permita sumarse a la ofensiva legal de Nicol\u00e1s Maduro para desestimar la acusaci\u00f3n penal que ambos enfrentan en Estados Unidos.En documentos presentados ante la corte este martes, los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468574,"url":"https:\/\/noticiasya.com\/hartford\/2025\/11\/21\/marimar-martinez-patrulla-fronteriza-trax\/","url_meta":{"origin":1471187,"position":4},"title":"Ataque a Marimar Mart\u00ednez: as\u00ed se desmoron\u00f3 la defensa del agente de la Patrulla Fronteriza por parte del Gobierno","author":"","date":"noviembre 21, 2025","format":false,"excerpt":"El jueves, Marimar Mart\u00ednez luc\u00eda una amplia sonrisa mientras agradec\u00eda a sus abogados a la salida de un tribunal de Illinois y declar\u00f3 a los reporteros: \u201cMe siento bendecida. Estoy feliz\u201d.\u201cHa sido dif\u00edcil\u201d, dijo. \u201cNo pod\u00eda dormir, pero ahora voy a dormir\u201d.Una jueza, tras una solicitud extraordinaria de la fiscal\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448239,"url":"https:\/\/noticiasya.com\/hartford\/2024\/04\/18\/muerte-valentina-orellana-peralta-policia-no-enfrentara-cargos-penales-trax\/","url_meta":{"origin":1471187,"position":5},"title":"Agente de Polic\u00eda de Los \u00c1ngeles no enfrentar\u00e1 a cargos penales por la muerte de una joven de 14 a\u00f1os en una tienda durante un enfrentamiento policial con un sospechoso","author":"","date":"abril 18, 2024","format":false,"excerpt":"(CNN) -- Un agente del Departamento de Polic\u00eda de Los \u00c1ngeles no enfrentar\u00e1 a cargos penales por el tiroteo mortal en 2021 de una adolescente de 14 a\u00f1os que muri\u00f3 en el interior de una tienda por departamentos cuando la Polic\u00eda dispar\u00f3 contra un hombre sospechoso de atacar a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471187"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471187\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}