{"id":1471200,"date":"2026-02-13T08:03:41","date_gmt":"2026-02-13T16:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/"},"modified":"2026-02-13T08:03:41","modified_gmt":"2026-02-13T16:03:41","slug":"inflacion-anual-enero-minimo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/","title":{"rendered":"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses"},"content":{"rendered":"<p>Un informe econ\u00f3mico en EE.UU. publicado el viernes 13 pareci\u00f3 ofrecer una buena noticia: la inflaci\u00f3n anual se desaceler\u00f3 significativamente.<\/p>\n<p>Sin embargo, los detalles del \u00faltimo \u00cdndice de Precios al Consumidor presentaron un panorama m\u00e1s desalentador: algunas presiones inflacionarias no solo persisten, sino que se est\u00e1n acelerando.<\/p>\n<p>Los precios al consumidor subieron un 2,4% en enero con respecto al a\u00f1o anterior, marcando su m\u00ednimo en ocho meses y una marcada desaceleraci\u00f3n respecto a la tasa del <a href=\"https:\/\/www.cnn.com\/2026\/01\/13\/economy\/us-cpi-consumer-prices-inflation-december\">2,7% registrada en diciembre<\/a>, seg\u00fan el informe del IPC de la Oficina de Estad\u00edsticas Laborales publicado el viernes.<\/p>\n<p>Mensualmente, los precios subieron un 0,2%, un ritmo m\u00e1s lento que el de diciembre, impulsado por la ca\u00edda de los precios de la gasolina, la continuaci\u00f3n de una desaceleraci\u00f3n de a\u00f1os en los costos relacionados con la vivienda y un aumento m\u00e1s moderado en los precios de los alimentos.<\/p>\n<p>La lectura mensual del viernes fue mejor de lo previsto, ya que los economistas hab\u00edan pronosticado un aumento del 0,3%.<\/p>\n<p>Los economistas esperaban que la tasa anual se redujera al 2,5%. Pero la inflaci\u00f3n se desaceler\u00f3 a\u00fan m\u00e1s, al 2,4%, impulsada por precios m\u00e1s favorables en los supermercados. Las matem\u00e1ticas tambi\u00e9n influyeron: dado que los precios se dispararon tanto en enero de 2025, este enero se ve\u00eda a\u00fan mejor en comparaci\u00f3n.<\/p>\n<p>El IPC subyacente, una medici\u00f3n muy vigilada que excluye los precios vol\u00e1tiles de los alimentos y la energ\u00eda, tambi\u00e9n vio una desaceleraci\u00f3n en su tasa anual de inflaci\u00f3n.<\/p>\n<p>El IPC subyacente se desaceler\u00f3 al 2,5%, su tasa m\u00e1s baja desde marzo de 2021, justo antes del pico inflacionario de la pandemia.<\/p>\n<p>Pero la trayectoria tom\u00f3 una direcci\u00f3n diferente: el IPC subyacente se aceler\u00f3 hasta un m\u00e1ximo de cinco meses del 0,3% desde el 0,2% de diciembre.<\/p>\n<p>\u201cSi bien una inflaci\u00f3n general moderada es alentadora, ser\u00eda prematuro declarar la victoria sobre la inflaci\u00f3n\u201d, escribi\u00f3 Joe Brusuelas, economista jefe de RSM US, en un correo electr\u00f3nico a CNN, \u201ccomo se puede observar claramente por el brusco cambio de a\u00f1o en los precios y un aumento sostenido de los bienes sensibles a los aranceles\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un informe econ\u00f3mico en EE.UU. publicado el viernes 13 pareci\u00f3 ofrecer una buena noticia: la inflaci\u00f3n anual se desaceler\u00f3 significativamente. Sin embargo, los detalles del \u00faltimo \u00cdndice de Precios al Consumidor presentaron un panorama m\u00e1s desalentador: algunas presiones inflacionarias no solo persisten, sino que se est\u00e1n acelerando. Los precios al consumidor subieron un 2,4% en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471200","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un informe econ\u00f3mico en EE.UU. publicado el viernes 13 pareci\u00f3 ofrecer una buena noticia: la inflaci\u00f3n anual se desaceler\u00f3 significativamente. Sin embargo, los detalles del \u00faltimo \u00cdndice de Precios al Consumidor presentaron un panorama m\u00e1s desalentador: algunas presiones inflacionarias no solo persisten, sino que se est\u00e1n acelerando. Los precios al consumidor subieron un 2,4% en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T16:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses\",\"datePublished\":\"2026-02-13T16:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/\",\"name\":\"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-13T16:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses - Noticias","og_description":"Un informe econ\u00f3mico en EE.UU. publicado el viernes 13 pareci\u00f3 ofrecer una buena noticia: la inflaci\u00f3n anual se desaceler\u00f3 significativamente. Sin embargo, los detalles del \u00faltimo \u00cdndice de Precios al Consumidor presentaron un panorama m\u00e1s desalentador: algunas presiones inflacionarias no solo persisten, sino que se est\u00e1n acelerando. Los precios al consumidor subieron un 2,4% en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-13T16:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/"},"author":{"name":"","@id":""},"headline":"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses","datePublished":"2026-02-13T16:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/","name":"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-13T16:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La inflaci\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\u00ednimo en ocho meses","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/13\/inflacion-anual-enero-minimo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-13T16:03:41Z","datePublished":"2026-02-13T16:03:41Z","dateModified":"2026-02-13T16:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La inflaci\\u00f3n anual en EE.UU. fue de 2,4% en enero, su m\\u00ednimo en ocho meses\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/13\\\/inflacion-anual-enero-minimo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/13\\\/inflacion-anual-enero-minimo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-13T16:03:41Z\",\"datePublished\":\"2026-02-13T16:03:41Z\",\"dateModified\":\"2026-02-13T16:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459819,"url":"https:\/\/noticiasya.com\/hartford\/2025\/03\/12\/inflacion-ee-uu-febrero-aranceles-trax\/","url_meta":{"origin":1471200,"position":0},"title":"La inflaci\u00f3n en EE.UU. se desaceler\u00f3 en febrero, pero los aranceles y la guerra comercial de Trump acechan","author":"","date":"marzo 12, 2025","format":false,"excerpt":"La inflaci\u00f3n en EE.UU. se desaceler\u00f3 m\u00e1s de lo previsto en febrero y se enfri\u00f3 por primera vez en cuatro meses. Sin embargo, este avance podr\u00eda ser ef\u00edmero, ya que el presidente Donald Trump intensifica su guerra comercial, que amenaza con aumentar los precios para los estadounidenses.El \u00cdndice de Precios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461030,"url":"https:\/\/noticiasya.com\/hartford\/2025\/04\/10\/inflacion-eeuu-marzo-trax\/","url_meta":{"origin":1471200,"position":1},"title":"La inflaci\u00f3n de EE.UU. se desacelera en marzo a su m\u00ednimo en seis meses, pero los aranceles aumentan la presi\u00f3n","author":"","date":"abril 10, 2025","format":false,"excerpt":"La inflaci\u00f3n se desaceler\u00f3 fuertemente en marzo, seg\u00fan mostraron nuevos datos este jueves, lo que en cualquier otro momento avivar\u00eda el optimismo de que el costo de la vida de los estadounidenses ya no est\u00e1 en alza.Sin embargo, la \u00faltima lectura del \u00cdndice de Precios al Consumidor (IPC) \u2014que mostr\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463005,"url":"https:\/\/noticiasya.com\/hartford\/2025\/05\/30\/estadounidenses-redujeron-gastos-aranceles-trax\/","url_meta":{"origin":1471200,"position":2},"title":"Los estadounidenses redujeron sus gastos en abril ante la implementaci\u00f3n de los aranceles","author":"","date":"mayo 30, 2025","format":false,"excerpt":"Los consumidores estadounidenses moderaron sus gastos en abril tras una ola de compras impulsada por los aranceles el mes anterior, seg\u00fan nuevos datos publicados este viernes, que tambi\u00e9n mostraron una desaceleraci\u00f3n de la inflaci\u00f3n.El informe del viernes del Departamento de Comercio mostr\u00f3 que el gasto del consumidor aument\u00f3 un 0,2\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465424,"url":"https:\/\/noticiasya.com\/hartford\/2025\/08\/12\/inflacion-mantiene-estable-aranceles-trump-impulsando-precios-trax\/","url_meta":{"origin":1471200,"position":3},"title":"La inflaci\u00f3n se mantiene estable, pero los aranceles de Trump est\u00e1n impulsando algunos precios","author":"","date":"agosto 12, 2025","format":false,"excerpt":"La ca\u00edda de los precios de la gasolina ayud\u00f3 a mantener la inflaci\u00f3n general moderada en julio; sin embargo, una gama m\u00e1s amplia de productos se encareci\u00f3 el mes pasado, lo que muestra que los extensos aranceles del presidente Donald Trump se est\u00e1n trasladando a los consumidores.Los precios subieron un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472997,"url":"https:\/\/noticiasya.com\/hartford\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","url_meta":{"origin":1471200,"position":4},"title":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal","author":"","date":"abril 9, 2026","format":false,"excerpt":"Los estadounidenses siguieron gastando en febrero incluso cuando los precios aumentaban, y se espera que la guerra con Ir\u00e1n impulse a\u00fan m\u00e1s los costos, seg\u00fan datos publicados este jueves.El gasto del consumidor aument\u00f3 un 0,5 % en febrero, frente a un incremento del 0,3 % en enero, seg\u00fan un informe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464569,"url":"https:\/\/noticiasya.com\/hartford\/2025\/07\/16\/inflacion-mayorista-sin-cambios-aranceles-trump-trax\/","url_meta":{"origin":1471200,"position":5},"title":"La inflaci\u00f3n mayorista en EE.UU. se mantuvo sin cambios el mes pasado a pesar de la implementaci\u00f3n de aranceles","author":"","date":"julio 16, 2025","format":false,"excerpt":"La inflaci\u00f3n mayorista en Estados Unidos fue moderada en junio, a pesar de las expectativas de un aumento en medio de la implementaci\u00f3n de aranceles.El \u00edndice de precios al productor (IPP), que mide el cambio promedio en los precios pagados a los productores, se mantuvo sin cambios respecto de mayo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471200"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471200\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}