{"id":1471615,"date":"2026-02-24T18:03:50","date_gmt":"2026-02-25T02:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/"},"modified":"2026-02-24T18:03:50","modified_gmt":"2026-02-25T02:03:50","slug":"madres-buscadoras-busqueda-nancy-guthrie-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/","title":{"rendered":"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie"},"content":{"rendered":"<p>Un grupo de madres mexicanas con a\u00f1os de experiencia buscando personas desaparecidas en el estado de Sonora, M\u00e9xico, ha llegado a Arizona para ayudar en la b\u00fasqueda de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/18\/eeuu\/acontecimientos-clave-busqueda-nancy-guthrie-trax\">Nancy Guthrie<\/a>.<\/p>\n<p>En un primer momento, las Madres Buscadoras de Sonora solicitaron un permiso para realizar una b\u00fasqueda de campo en el desierto de Arizona. Esperaban comenzar el martes, pero el alguacil local neg\u00f3 la solicitud argumentando que podr\u00eda interferir con la investigaci\u00f3n oficial.<\/p>\n<p>Sin embargo, las Madres \u2013una red nacional compuesta por voluntarias, madres y esposas\u2013 no se han dejado intimidar. Algunas viajaron a Arizona para distribuir volantes con la imagen de Guthrie, mientras que otras se quedaron en M\u00e9xico para buscar en la ciudad fronteriza de Nogales.<\/p>\n<p>La presencia del grupo en Arizona se da mientras la b\u00fasqueda de Guthrie \u2013la madre de 84 a\u00f1os de la presentadora del programa \u201cToday\u201d, Savannah Guthrie\u2013 entra en su cuarta semana. Guthrie fue vista por \u00faltima vez el 31 de enero antes de ser aparentemente secuestrada de su casa en Catalina Foothills, Arizona, a las afueras de Tucson, a unos 95 kil\u00f3metros de la frontera con M\u00e9xico.<\/p>\n<p>El martes, Savannah Guthrie anunci\u00f3 en un video en Instagram que la familia ofrece <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/24\/eeuu\/sospechoso-puerta-nancy-guthrie-desaparicion-fuente-trax\">hasta US$ 1 mill\u00f3n<\/a> por informaci\u00f3n que conduzca a la recuperaci\u00f3n de su madre. El video fue la primera declaraci\u00f3n de la familia Guthrie en m\u00e1s de una semana.<\/p>\n<p>Aunque el caso sigue atrayendo una atenci\u00f3n significativa, las actualizaciones de la investigaci\u00f3n por parte de las autoridades han disminuido.<\/p>\n<p>\u201cEstamos aqu\u00ed para ayudar en todo lo que podamos\u201d, dijo la l\u00edder de la organizaci\u00f3n, Cecilia Flores, a CNN. \u201cHaremos todo lo que est\u00e9 en nuestras manos para ayudar a esta familia. Nancy es una madre que merece reunirse con su familia\u201d.<\/p>\n<p>El grupo dice que un amigo de la familia Guthrie les pidi\u00f3 ayuda. Sin embargo, su presencia no ha sido bienvenida por algunos lugare\u00f1os, especialmente despu\u00e9s de que algunos de ellos realizaran una b\u00fasqueda limitada en el lecho de un arroyo cerca de la casa de Guthrie.<\/p>\n<p>\u201cLos vecinos salieron grit\u00e1ndonos y dici\u00e9ndonos que nos fu\u00e9ramos, que era propiedad privada\u201d, dijo Lupita Tello, una de las Madres.<\/p>\n<p>\u201cQueremos explorar el \u00e1rea circundante, las salidas, todo, incluso las salidas principales de las calles principales\u201d, dijo, pero agreg\u00f3 que no han podido hacer una \u201cb\u00fasqueda adecuada debido a las regulaciones locales\u201d.<\/p>\n<p>\u201cRespeto las leyes y las reglas, pero no s\u00e9 d\u00f3nde podr\u00edamos buscar sin tener problemas con la gente, porque la gente simplemente no coopera\u201d, agreg\u00f3 Tello.<\/p>\n<p>Al ser consultado sobre las Madres, el Departamento del Sheriff del Condado de Pima dijo a CNN: \u201cagradecemos su preocupaci\u00f3n\u2026 y todos queremos encontrar a Nancy, pero este trabajo es mejor dejarlo en manos de profesionales\u201d.<\/p>\n<p>\u201cTenemos oportunidades de voluntariado si desean involucrarse con el departamento\u201d, agreg\u00f3. \u201cSe aplican las leyes de propiedad privada. Depende de cada propietario dar permiso para que alguien est\u00e9 en su propiedad\u201d.<\/p>\n<p>Flores fund\u00f3 Madres Buscadoras de Sonora despu\u00e9s de que sus <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/07\/13\/ceci-flores-madre-buscadora-desaparecidos-mexico-orix\">tres hijos desaparecieran<\/a> en 2015 y 2019. Se cree que los tres fueron secuestrados por grupos del crimen organizado, que han generado una crisis creciente en M\u00e9xico.<\/p>\n<p>Desde su fundaci\u00f3n en 2019, el grupo se ha convertido en una red nacional que ha ayudado a localizar a m\u00e1s de 5.000 personas en todo el pa\u00eds, vivas y muertas.<\/p>\n<p>El grupo tiene amplia experiencia realizando b\u00fasquedas de campo en zonas remotas, donde los c\u00e1rteles de la droga suelen deshacerse de sus v\u00edctimas, aunque Flores enfatiza que muchas b\u00fasquedas finalmente no resultan exitosas, lo que deja una dolorosa incertidumbre en las familias, como ella misma ha experimrntado.<\/p>\n<p>Flores dijo que uno de sus hijos finalmente fue devuelto por sus secuestradores, y todav\u00eda mantiene la esperanza de encontrar a sus otros dos hijos desaparecidos.<\/p>\n<p>Dijo a CNN que el dolor y la incertidumbre suelen ser lo que mantiene a las buscadoras en marcha, a pesar del impacto en su salud.<\/p>\n<p>\u201cCada d\u00eda, la esperanza se desvanece poco a poco\u201d, dijo Flores. \u201cEl cuerpo se cansa. Y la verdad es que esta desesperaci\u00f3n es tan grande que nos estamos enfermando d\u00eda tras d\u00eda\u201d. Mientras el grupo de Flores tambi\u00e9n busca se\u00f1ales por si Guthrie fue llevada a M\u00e9xico, las autoridades mexicanas han rechazado esa posibilidad.<\/p>\n<p>\u201cEl FBI nos inform\u00f3 que actualmente no tienen pistas que sugieran que esta mujer podr\u00eda estar en M\u00e9xico\u201d, dijo Carlos Flores, comisionado general de la Agencia de Investigaci\u00f3n Criminal del Estado de Sonora, a los reporteros el 19 de febrero.<\/p>\n<p>El fiscal general de Sonora, Gustavo R\u00f3mulo Salas, agreg\u00f3 que no ha recibido ninguna solicitud del FBI para buscarla en territorio mexicano.<\/p>\n<p>Funcionarios de ambos lados de la frontera entre Estados Unidos y M\u00e9xico ya hab\u00edan recibido instrucciones de estar atentos a pistas que pudieran ayudar en el caso como parte de los procedimientos est\u00e1ndar de investigaci\u00f3n, seg\u00fan un funcionario policial familiarizado con el asunto. Los investigadores informaron a los agentes de la Patrulla Fronteriza de Estados Unidos y a las autoridades policiales mexicanas, dijo el funcionario.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de madres mexicanas con a\u00f1os de experiencia buscando personas desaparecidas en el estado de Sonora, M\u00e9xico, ha llegado a Arizona para ayudar en la b\u00fasqueda de Nancy Guthrie. En un primer momento, las Madres Buscadoras de Sonora solicitaron un permiso para realizar una b\u00fasqueda de campo en el desierto de Arizona. Esperaban comenzar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471615","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un grupo de madres mexicanas con a\u00f1os de experiencia buscando personas desaparecidas en el estado de Sonora, M\u00e9xico, ha llegado a Arizona para ayudar en la b\u00fasqueda de Nancy Guthrie. En un primer momento, las Madres Buscadoras de Sonora solicitaron un permiso para realizar una b\u00fasqueda de campo en el desierto de Arizona. Esperaban comenzar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T02:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie\",\"datePublished\":\"2026-02-25T02:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/\"},\"wordCount\":908,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/\",\"name\":\"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-25T02:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie - Noticias","og_description":"Un grupo de madres mexicanas con a\u00f1os de experiencia buscando personas desaparecidas en el estado de Sonora, M\u00e9xico, ha llegado a Arizona para ayudar en la b\u00fasqueda de Nancy Guthrie. En un primer momento, las Madres Buscadoras de Sonora solicitaron un permiso para realizar una b\u00fasqueda de campo en el desierto de Arizona. Esperaban comenzar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-25T02:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/"},"author":{"name":"","@id":""},"headline":"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie","datePublished":"2026-02-25T02:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/"},"wordCount":908,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/","name":"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-25T02:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las Madres Buscadoras de Sonora, M\u00e9xico, se unen a la b\u00fasqueda de Nancy Guthrie","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/24\/madres-buscadoras-busqueda-nancy-guthrie-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-25T02:03:50Z","datePublished":"2026-02-25T02:03:50Z","dateModified":"2026-02-25T02:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las Madres Buscadoras de Sonora, M\\u00e9xico, se unen a la b\\u00fasqueda de Nancy Guthrie\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/24\\\/madres-buscadoras-busqueda-nancy-guthrie-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/24\\\/madres-buscadoras-busqueda-nancy-guthrie-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-25T02:03:50Z\",\"datePublished\":\"2026-02-25T02:03:50Z\",\"dateModified\":\"2026-02-25T02:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450466,"url":"https:\/\/noticiasya.com\/hartford\/2024\/06\/18\/reportan-aparicion-ceci-flores-presidenta-colectivo-madres-buscadoras-sonora-orix\/","url_meta":{"origin":1471615,"position":0},"title":"Reportan aparici\u00f3n de Ceci Flores, presidenta del colectivo Madres buscadoras de Sonora","author":"","date":"junio 18, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) - -\u00a0 La Comisi\u00f3n Nacional de B\u00fasqueda de M\u00e9xico inform\u00f3 este lunes a trav\u00e9s de un comunicado la aparici\u00f3n de la activista Cecilia Flores Armenta, quien se encontraba desaparecida desde este domingo.Las autoridades dijeron que Flores fue hallada en su domicilio con un cuadro medico delicado y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448758,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/01\/fiscalia-ciudad-de-mexico-investiga-posible-crematorio-clandestino-orix\/","url_meta":{"origin":1471615,"position":1},"title":"La Fiscal\u00eda de la Ciudad de M\u00e9xico investiga hallazgo de posible &#171;crematorio clandestino&#187; en la capital del pa\u00eds","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico inform\u00f3 este mi\u00e9rcoles que abri\u00f3 una investigaci\u00f3n por un posible crematorio clandestino encontrado en la capital del pa\u00eds.En un video publicado por la instituci\u00f3n, el fiscal general Ulises Lara L\u00f3pez explic\u00f3 que se registr\u00f3 el \u201cposible hallazgo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448757,"url":"https:\/\/noticiasya.com\/hartford\/2024\/05\/01\/restos-oseos-presunto-crematorio-ciudad-de-mexico-no-humanos-fiscalia-orix\/","url_meta":{"origin":1471615,"position":2},"title":"Restos \u00f3seos hallados en un presunto crematorio de la capital mexicana no son humanos, dice la Fiscal\u00eda","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Los restos \u00f3seos encontrados en el lugar se\u00f1alado por activistas buscadoras de familiares desaparecidos en M\u00e9xico como presunto crematorio clandestino son de perro y no de seres humanos, inform\u00f3 la Fiscal\u00eda capitalina.El encargado de despacho de la fiscal\u00eda, Ulises Lara L\u00f3pez, explic\u00f3 en un mensaje ofrecido en conjunto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472537,"url":"https:\/\/noticiasya.com\/hartford\/2026\/03\/25\/vamos-casa-hijo-madre-buscadora-ceci-flores-restos-hijo-desaparecido-2019-orix\/","url_meta":{"origin":1471615,"position":3},"title":"&#171;\u00a1Vamos a casa, hijo!&#187;: la madre buscadora Ceci Flores dice que encontr\u00f3 restos de su hijo desaparecido en 2019 en M\u00e9xico","author":"","date":"marzo 25, 2026","format":false,"excerpt":"\u201c\u00a1Vamos a casa, hijo\u201d. Fue con estas palabras que Ceci Flores, fundadora del Colectivo Madres Buscadoras de Sonora, anunci\u00f3 el martes el hallazgo de restos que, seg\u00fan afirma, corresponden a su hijo Marco Antonio Sauceda Rocha, quien fue v\u00edctima de desaparici\u00f3n forzada en 2019, cuando un grupo armado se lo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471207,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/13\/busqueda-personas-desaparecidas-tarea-alto-riesgo-orix\/","url_meta":{"origin":1471615,"position":4},"title":"En M\u00e9xico, las desapariciones ocurren a diario. Buscar a esas personas es una tarea de alto riesgo y de tiempo completo","author":"","date":"febrero 13, 2026","format":false,"excerpt":"En M\u00e9xico, la desaparici\u00f3n de una persona, cualquiera sea su condici\u00f3n, tiene un pron\u00f3stico fatal en la mayor\u00eda de las ocasiones. El asunto es que esto sucede cotidianamente. Es lo que ocurri\u00f3 hace unos d\u00edas con 10 mineros desaparecidos en la sierra del estado de Sinaloa; su ausencia fue denunciada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471375,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/18\/acontecimientos-clave-busqueda-nancy-guthrie-trax\/","url_meta":{"origin":1471615,"position":5},"title":"Estos son los acontecimientos clave en la b\u00fasqueda de Nancy Guthrie, que dura ya varias semanas","author":"","date":"febrero 18, 2026","format":false,"excerpt":"La b\u00fasqueda de Nancy Guthrie, desaparecida de 84 a\u00f1os y madre de la presentadora del programa \u201cToday\u201d, Savannah Guthrie, se ha extendido a una tercera y angustiosa semana, con una creciente presi\u00f3n sobre los investigadores y una familia lidiando con la incertidumbre.Nancy Guthrie fue vista por \u00faltima vez el 31\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471615"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471615\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}