{"id":1471620,"date":"2026-02-25T00:03:48","date_gmt":"2026-02-25T08:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/"},"modified":"2026-02-25T00:03:48","modified_gmt":"2026-02-25T08:03:48","slug":"cnn-verifica-datos-trump-discurso-estado-union-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/hartford\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/","title":{"rendered":"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n"},"content":{"rendered":"<p>El presidente Donald Trump realiz\u00f3 una serie de afirmaciones falsas en su discurso sobre el <a href=\"https:\/\/cnnespanol.cnn.com\/eeuu\/live-news\/discurso-trump-estado-union-en-vivo-aranceles-inmigracion-orix\"><strong>Estado de la Uni\u00f3n<\/strong><\/a> durnate la noche de este martes.<\/p>\n<p>Aqu\u00ed hemos compilado una verificaci\u00f3n de datos de algunas de las declaraciones que el presidente Trump realiz\u00f3:<\/p>\n<p>Trump repiti\u00f3 su habitual discurso con la afirmaci\u00f3n falsa de que ha asegurado US$ 18 billones en inversiones en EE.UU. desde que regres\u00f3 al cargo: \u201cEn 12 meses, asegur\u00e9 compromisos por m\u00e1s de US$ 18 billones que llegan de todas partes del mundo.\u201d<\/p>\n<p>La cifra de\u202fUS$ 18 billones es ficticia. Hasta la noche del discurso de Trump, el <a href=\"https:\/\/www.whitehouse.gov\/investments\/\">propio\u202fsitio web de la Casa Blanca<\/a>\u202fdec\u00eda que la cifra de \u201canuncios de inversiones importantes\u201d durante este per\u00edodo de Trump era de \u201cUS$ 9.7 billones\u201d\u202fy eso incluso es una gran exageraci\u00f3n.<\/p>\n<p>Una\u202f<a href=\"https:\/\/www.cnn.com\/2025\/10\/11\/politics\/fact-check-trump-17-trillion-investment\">revisi\u00f3n detallada realizada por CNN\u202fen octubre<\/a> encontr\u00f3 que la Casa Blanca estaba contando billones de d\u00f3lares en promesas de inversi\u00f3n vagas, propuestas que trataban de \u201ccomercio bilateral\u201d o \u201cintercambio econ\u00f3mico\u201d m\u00e1s que de inversi\u00f3n en EE.UU., y declaraciones sin concretar que ni siquiera llegaban al nivel de compromiso.<\/p>\n<p>Trump afirm\u00f3 que los precios de la gasolina \u201cahora est\u00e1n por debajo de US$ 2,30 el gal\u00f3n en la mayor\u00eda de los estados, y en algunos lugares, US$ 1,99 el gal\u00f3n.\u201d Pero ning\u00fan estado ten\u00eda el martes un precio promedio de gasolina por debajo de US$ 2,37 por gal\u00f3n, <a href=\"https:\/\/gasprices.aaa.com\/state-gas-price-averages\/\">seg\u00fan la AAA<\/a>.<\/p>\n<p>Solo dos estados ten\u00edan un promedio por debajo de US$ 2,50 por gal\u00f3n.<\/p>\n<p>Y aunque hay algunas estaciones de servicio individuales que venden gasolina por debajo de US$ 2 por gal\u00f3n, son escasas.<\/p>\n<p>Patrick De Haan, director de an\u00e1lisis de petr\u00f3leo de la firma GasBuddy, declar\u00f3 durante el discurso que la firma encontr\u00f3 solo cuatro estaciones en todo el pa\u00eds con precios inferiores a US$ 2 (aparte de descuentos especiales) de unas 150.000 que la firma rastrea, es decir, aproximadamente el 0,00003 % del total.<\/p>\n<p>Trump podr\u00eda decir con justicia que los precios de la gasolina han ca\u00eddo durante esta presidencia. Han disminuido de un promedio nacional de US$ 3,12 por gal\u00f3n en su d\u00eda de inauguraci\u00f3n en enero de 2025, seg\u00fan la AAA, a un promedio nacional de <a href=\"https:\/\/gasprices.aaa.com\/\">US$ 2,95 por gal\u00f3n este martes<\/a>.<\/p>\n<p>Adem\u00e1s, Trump afirm\u00f3: \u201cY cuando visit\u00e9 el gran estado de Iowa hace solo unas semanas, incluso vi gasolina a US$ 1,85 el gal\u00f3n.\u201d No sabemos qu\u00e9 vio Trump, pero el precio promedio de un gal\u00f3n de gasolina regular en Iowa el d\u00eda del <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-speech-economy-energy-clive-iowa-january-27-2026\/\">discurso del 27 de enero era de US$ 2,57<\/a>, seg\u00fan los datos publicados ese d\u00eda por la AAA.<\/p>\n<p>Patrick De Haan, director de an\u00e1lisis de petr\u00f3leo de GasBuddy, manifest\u00f3 a CNN en ese momento que GasBuddy encontr\u00f3 solo cuatro estaciones en el estado vendiendo a US$ 1,97 el gal\u00f3n (aparte de descuentos especiales) de un total de 2.036 que la firma rastrea, es decir, el 0,19 % del total.<\/p>\n<p>Trump fue corregido sobre este tema por un asistente al discurso en Iowa al que se refer\u00eda. Cuando\u202f<a href=\"https:\/\/www.youtube.com\/watch?t=1847&#038;v=AD8HxPr23sM\">habl\u00f3\u202fde la gasolina en Iowa<\/a> a US$ 1,95 o US$ 1,85 por gal\u00f3n, alguien en la multitud grit\u00f3: \u201cNo, US$ 2,63\u201d, seg\u00fan el reportero de CNN Steve Contorno, que estaba en el lugar.<\/p>\n<p>Contorno vio que la estaci\u00f3n de servicio justo fuera del lugar donde habl\u00f3 Trump vend\u00eda a US$ 2,69 por gal\u00f3n.<\/p>\n<p>Trump afirm\u00f3 falsamente que cuando dio su discurso anterior al Congreso a principios del a\u00f1o pasado, \u00e9l hab\u00eda \u201cacabado de heredar \u2026 inflaci\u00f3n en niveles r\u00e9cord.\u201d A\u00f1adi\u00f3 un poco m\u00e1s tarde que Biden y sus aliados en el Congreso \u201cnos dieron la peor inflaci\u00f3n en la historia de nuestro pa\u00eds.\u201d<\/p>\n<p>Trump no hered\u00f3 la peor inflaci\u00f3n en la historia de EE.UU., y Biden nunca tuvo la peor inflaci\u00f3n en la historia de EE.UU.<\/p>\n<p>La tasa de inflaci\u00f3n interanual en el \u00faltimo mes completo de Biden en el cargo, diciembre de 2024, fue del <a href=\"https:\/\/www.cnn.com\/2025\/01\/15\/economy\/us-cpi-consumer-price-index-december\">2,9 %<\/a>, y la tasa en el mes en que Trump asumi\u00f3 el cargo a mitad de mes, enero de 2025, fue del <a href=\"https:\/\/www.cnn.com\/2025\/02\/12\/business\/us-cpi-consumer-inflation-january\">3,0 %<\/a>.<\/p>\n<p>La tasa m\u00e1s reciente, para enero de 2026, es del 2,4 %.<\/p>\n<p>La tasa s\u00ed alcanz\u00f3 un m\u00e1ximo de 40 a\u00f1os, <a href=\"https:\/\/www.cnn.com\/2022\/07\/13\/economy\/cpi-inflation-june\" rel=\"noopener noreferrer\" target=\"_blank\">9,1 %<\/a>, en junio de 2022, pero eso estuvo muy lejos <a href=\"https:\/\/www.bls.gov\/opub\/mlr\/2014\/article\/one-hundred-years-of-price-change-the-consumer-price-index-and-the-american-inflation-experience.htm\" rel=\"noopener noreferrer\" target=\"_blank\">del m\u00e1ximo hist\u00f3rico de 23,7 %<\/a>, que se estableci\u00f3 en 1920. De todas formas, la tasa luego cay\u00f3 dr\u00e1sticamente durante los \u00faltimos dos a\u00f1os y medio del mandato de Biden.<\/p>\n<p>Trump afirm\u00f3 que hered\u00f3 una \u201ceconom\u00eda estancada\u201d de la administraci\u00f3n Biden y que ahora est\u00e1 \u201crugiendo como nunca antes.\u201d<\/p>\n<p>Aunque no hay una definici\u00f3n firme de \u201cestancada\u201d o \u201crugiendo,\u201d los hechos no corroboran la sugerencia de que haya presidido un enorme auge econ\u00f3mico desde que regres\u00f3 al cargo en enero de 2025.<\/p>\n<p>La econom\u00eda de EE.UU. <a href=\"https:\/\/www.cnn.com\/2026\/02\/20\/economy\/us-gdp-economy-q4\">creci\u00f3 un 2,2 % en 2025<\/a>, lo cual fue menor que en cualquier a\u00f1o de la presidencia de Biden. Se registr\u00f3 un crecimiento del <a href=\"https:\/\/www.bea.gov\/news\/2026\/gdp-advance-estimate-4th-quarter-and-year-2025\">2,8 % en 2024<\/a>. (El cierre del Gobierno en el oto\u00f1o de 2025 probablemente redujo el crecimiento a finales de 2025.) Mientras tanto, <a href=\"https:\/\/fred.stlouisfed.org\/series\/UNRATE\">la tasa de desempleo aument\u00f3 del 4,0 %<\/a> en enero de 2025 al 4,3 % en enero de 2026.<\/p>\n<p>La tasa de inflaci\u00f3n interanual del \u00cdndice de Precios al Consumidor s\u00ed baj\u00f3 del 3,0 % en enero de 2025 al <a href=\"https:\/\/www.cnn.com\/2026\/02\/13\/economy\/us-inflation-cpi-consumer-prices-january\">2,4 % en enero de 2026<\/a>, y Trump ciertamente tiene otros datos positivos que citar.<\/p>\n<p>Pero su relato sobre haber llevado la econom\u00eda de estar muerta a estar en auge simplemente no est\u00e1 respaldado por los datos generales.<\/p>\n<p>Trump volvi\u00f3 a afirmar que la amplia agenda de pol\u00edtica interna que promulg\u00f3 el verano pasado inclu\u00eda los mayores recortes de impuestos en la historia de Estados Unidos. Pero no es as\u00ed.<\/p>\n<p>El llamado \u201cproyecto de ley grande y hermoso\u201d introdujo numerosos cambios permanentes y temporales en el c\u00f3digo tributario, incluyendo la eliminaci\u00f3n de impuestos sobre las propinas y las horas extras, la concesi\u00f3n de desgravaciones fiscales adicionales a las personas mayores y a los padres de ni\u00f1os peque\u00f1os, y la autorizaci\u00f3n para que las empresas deduzcan ciertas inversiones con mayor rapidez.<\/p>\n<p>Los recortes de impuestos ascienden a US$ 4,8 billones, o el 1,3 % del producto interior bruto (PIB) del pa\u00eds, a lo largo de una d\u00e9cada, seg\u00fan el \u00faltimo an\u00e1lisis de la Oficina de Presupuesto del Congreso, publicado a principios de este mes.<\/p>\n<p>Sin embargo, el proyecto de ley no es el mayor recorte de impuestos de la historia, dijeron los expertos.<\/p>\n<p>Ocupa el s\u00e9ptimo lugar en t\u00e9rminos de participaci\u00f3n en el PIB desde 1918, seg\u00fan Chris Towner, director de pol\u00edticas del Comit\u00e9 para un Presupuesto Federal Responsable, un grupo de vigilancia no partidista.<\/p>\n<p>El m\u00e1s grande fue el paquete fiscal de 1981 del expresidente Ronald Reagan, <a href=\"https:\/\/www.crfb.org\/blogs\/president-trumps-tax-cut-largest-history-yet\">que cost\u00f3 el 2,9 % del PIB en cuatro a\u00f1os<\/a>. (Observar los cambios en los ingresos como una proporci\u00f3n del PIB es una forma com\u00fan de evaluar la magnitud de los recortes de impuestos porque muestra los cambios en relaci\u00f3n con el tama\u00f1o de la econom\u00eda. Permite comparaciones a lo largo del tiempo a pesar de los cambios en la inflaci\u00f3n y la poblaci\u00f3n, por ejemplo).<\/p>\n<p>De manera similar, la Tax Foundation, un grupo de expertos de tendencia derechista, <a href=\"https:\/\/taxfoundation.org\/blog\/obbba-largest-tax-cut-in-american-history\/\" rel=\"noopener noreferrer\" target=\"_blank\">descubri\u00f3<\/a> que el proyecto de ley es el sexto mayor recorte de impuestos desde 1940, en t\u00e9rminos de participaci\u00f3n en el PIB.<\/p>\n<p>Al criticar las pol\u00edticas fronterizas del gobierno de Biden, Trump reiter\u00f3 su habitual afirmaci\u00f3n de que el Gobierno de Biden permiti\u00f3 la entrada de 11.888 asesinos a Estados Unidos como inmigrantes: \u201cEran asesinos, 11.888 asesinos. Entraron a nuestro pa\u00eds\u201d.<\/p>\n<p>Trump estaba describiendo incorrectamente los datos federales.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2024\/09\/29\/politics\/fact-check-trump-harris-immigrants-homicide\/index.html\">El Departamento de Seguridad Nacional y expertos independientes han se\u00f1alado<\/a> que la cifra a la que parece referirse Trump cuando usa el n\u00famero \u201c11.888\u201d se refiere a no ciudadanos que ingresaron a EE.UU. no solo bajo Biden, sino a lo largo de varias d\u00e9cadas, incluso <em>durante la primera administraci\u00f3n de Trump<\/em>.<\/p>\n<p>Estos inmigrantes fueron condenados por homicidio en alg\u00fan momento, generalmente en EE.UU. despu\u00e9s de su llegada, y todav\u00eda se encuentran en el pa\u00eds.<\/p>\n<p>Estas personas figuran en el \u201cregistro de no detenidos\u201d del Servicio de Inmigraci\u00f3n y Control de Aduanas, que incluye a indocumentados que actualmente cumplen sus condenas de prisi\u00f3n, no que andan libres como Trump tambi\u00e9n ha afirmado.<\/p>\n<p>Puede leer m\u00e1s <a href=\"https:\/\/www.cnn.com\/2024\/09\/29\/politics\/fact-check-trump-harris-immigrants-homicide\/index.html\">aqu\u00ed<\/a>.<\/p>\n<p>Trump repiti\u00f3 su habitual afirmaci\u00f3n falsa de que los aranceles son \u201cpagados por pa\u00edses extranjeros\u201d.<\/p>\n<p>De hecho, los pagos de grav\u00e1menes los realizan los importadores en Estados Unidos, no otras naciones, y estos importadores suelen trasladar parte de sus costos a los consumidores.<\/p>\n<p>Si bien los exportadores extranjeros a veces bajan sus precios para intentar mantener la competitividad de sus productos, <a href=\"https:\/\/www.cfr.org\/articles\/who-pays-trumps-tariffs\" rel=\"noopener noreferrer\" target=\"_blank\">diversos <\/a><a href=\"https:\/\/www.kielinstitut.de\/publications\/news\/americas-own-goal-americans-pay-almost-entirely-for-trumps-tariffs\/\" rel=\"noopener noreferrer\" target=\"_blank\">an\u00e1lisis <\/a><a href=\"https:\/\/www.cnn.com\/2026\/02\/12\/business\/trump-tariffs-consumers-nightcap\" rel=\"noopener noreferrer\" target=\"_blank\">han revelado<\/a> que la gran mayor\u00eda de los costos de los aranceles que Trump ha impuesto este mandato est\u00e1n siendo cubiertos por una combinaci\u00f3n de empresas y consumidores estadounidenses.<\/p>\n<p>En un an\u00e1lisis publicado en febrero, los funcionarios del Banco de la Reserva Federal de Nueva York <a href=\"https:\/\/libertystreeteconomics.newyorkfed.org\/2026\/02\/who-is-paying-for-the-2025-u-s-tariffs\/\">escribieron<\/a>: \u201cEncontramos que casi el 90 por ciento de la carga econ\u00f3mica de los aranceles recay\u00f3 en las empresas y los consumidores estadounidenses\u201d.<\/p>\n<p>La Oficina de Presupuesto del Congreso, un organismo federal no partidista, escribi\u00f3 en un <a href=\"https:\/\/www.cbo.gov\/publication\/62105\" rel=\"noopener noreferrer\" target=\"_blank\">informe<\/a> de febrero que \u201cel efecto neto de los aranceles es aumentar los precios al consumidor en Estados Unidos en la parte completa del costo de los aranceles soportados a nivel nacional (95 por ciento)\u201d, a partir de una combinaci\u00f3n de aumentos de precios por parte de las empresas estadounidenses que importan productos arancelados y aumentos de precios por parte de las empresas estadounidenses que enfrentan menos competencia extranjera debido a los aranceles.<\/p>\n<p>Trump reiter\u00f3 su afirmaci\u00f3n de que los residentes somal\u00edes de Minnesota han cometido un fraude de US$ 19.000 millones: \u201cNo ha habido un ejemplo m\u00e1s impactante que el de Minnesota, donde miembros de la comunidad somal\u00ed han desfalcado aproximadamente US$ 19.000 millones del contribuyente estadounidense. Tenemos toda la informaci\u00f3n, y en realidad, la cifra es mucho mayor\u201d.<\/p>\n<p>Es posible que se pruebe que la cifra de \u201cUS$ 19.000 millones\u201d es cierta, pero hasta la fecha no se ha demostrado nada cercano a esa cifra.<\/p>\n<p>En diciembre, un fiscal federal, Joseph Thompson, afirm\u00f3 que \u201cla mitad o m\u00e1s\u201d de US$ 18.000 millones en fondos federales facturados por <a href=\"https:\/\/mn.gov\/governor\/newsroom\/press-releases\/?id=1055-711001\">14 servicios de Medicaid en Minnesota<\/a> considerados de alto riesgo de fraude \u2013y ahora bajo una auditor\u00eda de terceros ordenada por el gobernador Tim Walz\u2013 podr\u00edan ser fraudulentos.<\/p>\n<p>Pero US$ 9.000 millones no son US$ 19.000 millones, Thompson no dijo que todo el posible fraude fue cometido por residentes somal\u00edes y la administraci\u00f3n de Walz <a href=\"https:\/\/www.kare11.com\/article\/news\/politics\/i-am-the-one-that-will-fix-it-gov-tim-walz-addresses-fraud-in-minnesota\/89-5ca32eb0-9207-4ca2-b896-acaaa293bc81\">cuestion\u00f3<\/a> la afirmaci\u00f3n de Thompson.<\/p>\n<p>Un funcionario de la administraci\u00f3n de Walz declar\u00f3 en diciembre que ten\u00edan \u201cpruebas de decenas de millones de d\u00f3lares en fraude hasta el momento\u201d, no de US$ 9.000 millones.<\/p>\n<p>El propio Walz declar\u00f3: \u201cDeber\u00edan estar igualmente indignados por US$ 1 o la cifra que sea, pero la est\u00e1n usando sin pruebas\u201d.<\/p>\n<p>Y Thompson, quien <a href=\"https:\/\/www.cnn.com\/2026\/02\/10\/media\/don-lemon-minnesota-joseph-thompson-renee-good-ice\">renunci\u00f3 en enero<\/a> en medio de tensiones con la administraci\u00f3n Trump por su gesti\u00f3n del caso de un agente de ICE que dispar\u00f3 fatalmente a Ren\u00e9e Good, <a href=\"https:\/\/www.cbsnews.com\/minnesota\/news\/billions-paid-out-by-medicaid-in-minnesota-may-be-fraudulent-us-attorney\/\">dej\u00f3 claro<\/a> en ese momento que el comentario de \u201cla mitad o m\u00e1s\u201d era una estimaci\u00f3n preliminar, no una cifra definitiva.<\/p>\n<p>Trump hizo una serie de afirmaciones falsas sobre las elecciones estadounidenses mientras ped\u00eda al Congreso aprobar un proyecto de ley que exigiera la identificaci\u00f3n del votante y una prueba de ciudadan\u00eda al registrarse para votar.<\/p>\n<p>Trump afirm\u00f3 falsamente: \u201cEl fraude es rampante en nuestras elecciones. Es rampante\u201d.<\/p>\n<p>Simplemente no es as\u00ed. Toda la evidencia sugiere que el fraude representa un porcentaje min\u00fasculo de los votos emitidos.<\/p>\n<p>Trump se refiri\u00f3 a \u201cvotos por correo fraudulentos\u201d. La incidencia del fraude tambi\u00e9n es m\u00ednima con los votos por correo, aunque los expertos afirman que es ligeramente mayor que con el voto en persona, y no hay base para describir este m\u00e9todo categ\u00f3ricamente como \u201cfraudulento\u201d.<\/p>\n<p>Trump manifest\u00f3: \u201cHan hecho trampa, y su pol\u00edtica es tan mala que la \u00fanica manera de que salgan elegidos es haciendo trampa\u201d. Eso es mentira, ya que los dem\u00f3cratas, al igual que los republicanos, son elegidos constantemente en elecciones libres y justas en Estados Unidos.<\/p>\n<p>Trump repiti\u00f3 su habitual afirmaci\u00f3n de que hoy en d\u00eda hay m\u00e1s gente trabajando en Estados Unidos que nunca.<\/p>\n<p>Es cierto, pero la afirmaci\u00f3n requiere contexto: el n\u00famero de personas que trabajan <a href=\"https:\/\/fred.stlouisfed.org\/series\/CE16OV\">tiende a aumentar con el tiempo<\/a> porque la poblaci\u00f3n estadounidense tiende a crecer con el tiempo.<\/p>\n<p>Los economistas afirman que existen indicadores mucho m\u00e1s precisos de la salud del mercado laboral.<\/p>\n<p>La <a href=\"https:\/\/fred.stlouisfed.org\/series\/EMRATIO\">tasa de empleo-poblaci\u00f3n<\/a>, que mide el porcentaje de la poblaci\u00f3n que est\u00e1 empleada, ha bajado ligeramente en lo que va de mandato presidencial, pasando del 60,1 % en enero de 2025, mes en que Trump volvi\u00f3 al cargo, al 59,8 % en enero de 2026.<\/p>\n<p>La <a href=\"https:\/\/fred.stlouisfed.org\/series\/UNRATE\">tasa de desempleo<\/a>, que mide el desempleo como porcentaje de la fuerza laboral, ha aumentado, pasando del 4,0 % en enero de 2025 al 4,3 % en enero de 2026 y alcanz\u00f3 un m\u00e1ximo de cuatro a\u00f1os del 4,5 % en noviembre antes de disminuir.<\/p>\n<p>La <a href=\"https:\/\/fred.stlouisfed.org\/series\/CIVPART\">tasa de participaci\u00f3n en la fuerza laboral<\/a>, que mide el porcentaje de la poblaci\u00f3n que est\u00e1 empleada o buscando trabajo activamente, se ha mantenido pr\u00e1cticamente sin cambios, bajando del 62,6 % en enero de 2025 al 62,5 % en enero de 2026.<\/p>\n<p>Trump repiti\u00f3 una afirmaci\u00f3n falsa y familiar sobre su papel en asuntos exteriores: \u201cEn mis primeros 10 meses, termin\u00e9 ocho guerras\u201d. Si bien Trump ha contribuido a la resoluci\u00f3n de algunos conflictos (al menos temporalmente), la cifra de \u201cocho\u201d es una <a href=\"https:\/\/www.cnn.com\/2025\/09\/24\/world\/seven-unendable-wars-trump-intl\">clara exageraci\u00f3n<\/a>.<\/p>\n<p>Trump <a href=\"https:\/\/www.cnn.com\/2025\/09\/23\/politics\/fact-check-un-speech-claims-trump\">explic\u00f3<\/a> durante su discurso que su lista de supuestas guerras resueltas incluye una guerra entre Egipto y Etiop\u00eda, pero que en realidad no fue. Se trata de una larga disputa diplom\u00e1tica sobre un <a href=\"https:\/\/www.cnn.com\/2025\/09\/09\/africa\/ethiopia-launches-massive-hydropower-dam-intl\">importante proyecto de presa et\u00edope<\/a> en un afluente del r\u00edo Nilo.<\/p>\n<p>La lista de Trump tambi\u00e9n inclu\u00eda <a href=\"https:\/\/www.bbc.com\/news\/articles\/c5y3599gx4qo\">otra supuesta guerra que no ocurri\u00f3<\/a> durante su presidencia, entre Serbia y Kosovo. (En ocasiones ha afirmado <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-remarks-foreign-ministers-democratic-republic-congo-rwanda-june-27-2025\/#50\">haber<\/a> evitado el estallido de una nueva guerra entre ambas entidades, ofreciendo pocos detalles sobre a qu\u00e9 se refer\u00eda, pero eso es diferente a resolver una guerra real).<\/p>\n<p>Su lista tambi\u00e9n inclu\u00eda una guerra que involucraba a la Rep\u00fablica Democr\u00e1tica del Congo y Ruanda, pero ese conflicto <a href=\"https:\/\/www.criticalthreats.org\/briefs\/congo-war-security-review\/february-20-2026\">ha continuado<\/a> a pesar de un acuerdo de paz negociado por la administraci\u00f3n Trump en 2025, que nunca fue firmado por la principal coalici\u00f3n rebelde que libra el conflicto.<\/p>\n<p>La lista de Trump tambi\u00e9n incluy\u00f3 un conflicto armado entre Tailandia y Camboya, donde los combates <a href=\"https:\/\/www.cnn.com\/2025\/12\/13\/asia\/thailand-cambodia-fighting-donald-trump-ceasefire-hnk-intl\">estallaron temporalmente nuevamente<\/a> \u202fen diciembre a pesar de un acuerdo de paz negociado por la administraci\u00f3n Trump\u202f <a href=\"https:\/\/www.cnn.com\/2025\/11\/10\/asia\/thailand-suspends-peace-accord-cambodia-intl-hnk\">a principios de 2025<\/a> .<\/p>\n<p>Se puede debatir la importancia del papel de Trump en la finalizaci\u00f3n de los dem\u00e1s conflictos de su lista, o cuestionar con raz\u00f3n si algunos realmente han terminado; por ejemplo, las matanzas <a href=\"https:\/\/www.cnn.com\/2026\/01\/31\/middleeast\/gaza-death-toll-ceasefire-intl\">continuaron<\/a> en Gaza tras el acuerdo de alto el fuego de octubre entre Israel y Hamas.<\/p>\n<p>Trump manifest\u00f3 en su discurso: \u201cLa guerra en Gaza, que contin\u00faa a un nivel muy bajo; ya casi est\u00e1\u201d. En cualquier caso, la cifra de \u201cocho\u201d de Trump es obviamente demasiado elevada.<\/p>\n<p>Trump volvi\u00f3 a afirmar falsamente que elimin\u00f3 los impuestos a la Seguridad Social, una de sus principales promesas de campa\u00f1a para 2024.<\/p>\n<p>\u201cCon el gran y hermoso proyecto de ley, no creamos impuestos sobre las propinas, ni impuestos sobre las horas extras, ni impuestos sobre la Seguridad Social\u201d, declar\u00f3 durante su discurso sobre el Estado de la Uni\u00f3n el martes.<\/p>\n<p>El enorme paquete de medidas de pol\u00edtica interna que Trump firm\u00f3 el verano pasado cre\u00f3 una deducci\u00f3n fiscal adicional temporal de US$ 6.000 anuales para las personas mayores de 65 a\u00f1os (con una deducci\u00f3n menor para quienes ganan US$ 75.000 anuales o m\u00e1s).<\/p>\n<p>Sin embargo, como la propia Casa Blanca ha <a href=\"https:\/\/www.cnn.com\/2025\/06\/28\/politics\/fact-check-trump-big-beautiful-bill\">reconocido<\/a> impl\u00edcitamente, millones de beneficiarios de la Seguridad Social mayores de 65 a\u00f1os seguir\u00e1n pagando impuestos sobre sus prestaciones, y esa nueva deducci\u00f3n, que vence en 2028, no se aplica a los <a href=\"https:\/\/www.ssa.gov\/benefits\/retirement\/planner\/agereduction.html\">beneficiarios de la Seguridad Social menores de 65 a\u00f1os<\/a>.<\/p>\n<p>Trump afirm\u00f3 sin fundamento que eliminar el fraude en los programas federales equilibrar\u00eda el presupuesto federal: \u201cSi logramos encontrar suficiente fraude, tendremos un presupuesto equilibrado de la noche a la ma\u00f1ana. Se acabar\u00e1 muy r\u00e1pido\u201d.<\/p>\n<p>El d\u00e9ficit presupuestario anual excede con creces la cantidad estimada de dinero que el Gobierno federal pierde por fraude cada a\u00f1o.<\/p>\n<p><a href=\"https:\/\/www.gao.gov\/products\/gao-24-105833\">Una estimaci\u00f3n<\/a> pionera, publicada en 2024 por la Oficina de Responsabilidad Gubernamental (GAO), revel\u00f3 que anualmente se pierden entre US$ 233.000 y US$ 521.000 millones por fraude.<\/p>\n<p>Sin embargo, el d\u00e9ficit presupuestario federal se situ\u00f3 en <a href=\"https:\/\/fiscal.treasury.gov\/files\/reports-statements\/mts\/mts0925.pdf\">poco menos de US$ 1,8 billones de<\/a> en el \u00faltimo ejercicio fiscal, que finaliz\u00f3 en septiembre, seg\u00fan el Departamento del Tesoro, m\u00e1s del triple del total estimado de fraude m\u00e1s alto.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump realiz\u00f3 una serie de afirmaciones falsas en su discurso sobre el Estado de la Uni\u00f3n durnate la noche de este martes. Aqu\u00ed hemos compilado una verificaci\u00f3n de datos de algunas de las declaraciones que el presidente Trump realiz\u00f3: Trump repiti\u00f3 su habitual discurso con la afirmaci\u00f3n falsa de que ha asegurado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471620","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump realiz\u00f3 una serie de afirmaciones falsas en su discurso sobre el Estado de la Uni\u00f3n durnate la noche de este martes. Aqu\u00ed hemos compilado una verificaci\u00f3n de datos de algunas de las declaraciones que el presidente Trump realiz\u00f3: Trump repiti\u00f3 su habitual discurso con la afirmaci\u00f3n falsa de que ha asegurado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T08:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n\",\"datePublished\":\"2026-02-25T08:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/\"},\"wordCount\":2931,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/\",\"name\":\"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-25T08:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/","og_locale":"es_ES","og_type":"article","og_title":"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n - Noticias","og_description":"El presidente Donald Trump realiz\u00f3 una serie de afirmaciones falsas en su discurso sobre el Estado de la Uni\u00f3n durnate la noche de este martes. Aqu\u00ed hemos compilado una verificaci\u00f3n de datos de algunas de las declaraciones que el presidente Trump realiz\u00f3: Trump repiti\u00f3 su habitual discurso con la afirmaci\u00f3n falsa de que ha asegurado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-25T08:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/"},"author":{"name":"","@id":""},"headline":"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n","datePublished":"2026-02-25T08:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/"},"wordCount":2931,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/","name":"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-25T08:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\u00f3n","url":"http:\/\/noticiasya.com\/hartford\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/hartford\/2026\/02\/25\/cnn-verifica-datos-trump-discurso-estado-union-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-25T08:03:48Z","datePublished":"2026-02-25T08:03:48Z","dateModified":"2026-02-25T08:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"CNN Verifica: Trump emite afirmaciones falsas durante el discurso sobre el Estado de la Uni\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/25\\\/cnn-verifica-datos-trump-discurso-estado-union-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/hartford\\\/2026\\\/02\\\/25\\\/cnn-verifica-datos-trump-discurso-estado-union-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-25T08:03:48Z\",\"datePublished\":\"2026-02-25T08:03:48Z\",\"dateModified\":\"2026-02-25T08:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469390,"url":"https:\/\/noticiasya.com\/hartford\/2025\/12\/18\/verifica-trump-falsas-discurso-trax\/","url_meta":{"origin":1471620,"position":0},"title":"CNN verifica: Trump repite numerosas afirmaciones falsas en esperado mensaje a la naci\u00f3n","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, hizo una serie de afirmaciones falsas durante su discurso en horario de m\u00e1xima audiencia desde la Casa Blanca, el mi\u00e9rcoles por la noche, la mayor\u00eda de las cuales ya han sido desmentidas. Aqu\u00ed hay una verificaci\u00f3n de datos.Inflaci\u00f3n bajo el Gobierno de Trump: Casi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471618,"url":"https:\/\/noticiasya.com\/hartford\/2026\/02\/24\/conclusiones-discurso-estado-de-la-union-trump-trax\/","url_meta":{"origin":1471620,"position":1},"title":"Conclusiones del discurso sobre el Estado de la Uni\u00f3n de Donald Trump","author":"","date":"febrero 24, 2026","format":false,"excerpt":"El presidente Donald Trump pronunci\u00f3 el primer discurso sobre el Estado de la Uni\u00f3n de su segundo mandato la noche del martes en el Capitolio de Estados Unidos.El discurso llega poco despu\u00e9s de que la Corte Suprema anulara sus aranceles globales emblem\u00e1ticos, mientras considera una segunda ronda de posibles ataques\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469601,"url":"https:\/\/noticiasya.com\/hartford\/2025\/12\/27\/analisis-principales-mentiras-donald-trump-2025-trax\/","url_meta":{"origin":1471620,"position":2},"title":"Las 25 principales mentiras de Donald Trump en 2025","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"Fue dif\u00edcil elegir solo 25. Pero result\u00f3 m\u00e1s f\u00e1cil de lo que sol\u00eda ser.Al igual que su primer mandato, el primer a\u00f1o del presidente Donald Trump en su regreso a la Casa Blanca fue un desfile incesante de mentiras. Sin embargo, la cantidad de afirmaciones falsas de Trump en 2025\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466762,"url":"https:\/\/noticiasya.com\/hartford\/2025\/09\/23\/cnn-verifica-trump-discurso-onu-afirmaciones-falsas-trax\/","url_meta":{"origin":1471620,"position":3},"title":"CNN verifica: Trump pronuncia discurso en ONU lleno de afirmaciones falsas sobre el clima, la inflaci\u00f3n, inmigraci\u00f3n y la paz","author":"","date":"septiembre 23, 2025","format":false,"excerpt":"El discurso del presidente Donald Trump ante la Asamblea General de las Naciones Unidas este martes estuvo lleno de numerosas afirmaciones falsas, muchas de las cuales ya fueron desmentidas anteriormente.Trump fue inexacto sobre una amplia variedad de temas, incluyendo la inflaci\u00f3n en EE.UU., las pol\u00edticas clim\u00e1ticas tanto en el pa\u00eds\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468004,"url":"https:\/\/noticiasya.com\/hartford\/2025\/11\/03\/afirmaciones-falsas-trump-60-minutes-trax\/","url_meta":{"origin":1471620,"position":4},"title":"CNN verifica: 18 afirmaciones falsas que Trump hizo en su entrevista con &#171;60 Minutes&#187;","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump llen\u00f3 su m\u00e1s reciente entrevista en \u201c60 Minutes\u201d con una amplia variedad de afirmaciones falsas, la gran mayor\u00eda de ellas previamente desmentidas. Contamos al menos 18 declaraciones imprecisas.Trump repiti\u00f3 su habitual mentira de que las elecciones libres y justas de 2020 le fueron robadas.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469231,"url":"https:\/\/noticiasya.com\/hartford\/2025\/12\/12\/trump-conomia-grande-problema-analisis-trax\/","url_meta":{"origin":1471620,"position":5},"title":"Trump dice que est\u00e1 haciendo que la econom\u00eda de EE.UU. vuelva a ser grande, pero est\u00e1 abordando el problema equivocado","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Para muchas personas, la econom\u00eda es una ecuaci\u00f3n simple: ingresos menos gastos. Cuando parece que nuestros ingresos crecen m\u00e1s r\u00e1pido que los precios, la econom\u00eda est\u00e1 en buena forma. Cuando no, est\u00e1 mal.El presidente Donald Trump parece estar haciendo un c\u00e1lculo diferente.En lugar de enfocarse en el costo de vida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/hartford\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/comments?post=1471620"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/posts\/1471620\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/media?parent=1471620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/categories?post=1471620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/hartford\/wp-json\/wp\/v2\/tags?post=1471620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}