{"id":1450907,"date":"2024-07-05T14:03:55","date_gmt":"2024-07-05T21:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/"},"modified":"2024-07-05T14:03:55","modified_gmt":"2024-07-05T21:03:55","slug":"agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/","title":{"rendered":"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Las autoridades judiciales han registrado m\u00e1s de 50 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral francesa, dijo este viernes el ministro del Interior del pa\u00eds, G\u00e9rald Darmanin.<\/p>\n<p>&#171;Esta campa\u00f1a es corta, menos de tres semanas, y sin embargo hemos contado 51 candidatos, diputados o activistas que han sido agredidos f\u00edsicamente. Sin contar las agresiones verbales&#187;, dijo Darmanin a BFMTV, afiliada de CNN.<\/p>\n<p>Los ataques han variado desde menos graves hasta &#171;extremadamente graves&#187;, dijo Darmanin, a\u00f1adiendo que algunos candidatos han sido hospitalizados por sus heridas.<\/p>\n<p>Aumentan los temores de violencia electoral en Francia despu\u00e9s de que un portavoz del gobierno fuera atacado durante la campa\u00f1a<\/p>\n<p>Una treintena de personas han sido interrogadas en relaci\u00f3n con los ataques, a\u00f1adi\u00f3 Darmanin.<\/p>\n<p>Un hombre pasa junto a carteles electorales en medio de la campa\u00f1a pol\u00edtica en Villiers-sur-Marne el 5 de julio de 2024. (Foto de EMMANUEL DUNAND\/AFP v\u00eda Getty Images)<\/p>\n<p>Francia ha estado lidiando con altas tensiones en el per\u00edodo previo a las elecciones de alto riesgo de este domingo. Se han desplegado 30.000 polic\u00edas adicionales para garantizar que ni la extrema izquierda ni la extrema derecha logren &#171;crear&#187; desorden, dijo Darmanin a principios de esta semana.<\/p>\n<p>La amenaza terrorista en el pa\u00eds &#171;sigue siendo extremadamente fuerte&#187;, advirti\u00f3 el ministro, a\u00f1adiendo que recientemente se han producido varias detenciones en dos lugares distintos.<\/p>\n<p>Aunque los dos incidentes &#171;podr\u00edan calificarse como terroristas&#187;, deben ser clasificados formalmente como tales por el fiscal nacional antiterrorista, a\u00f1adi\u00f3 Darmanin.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Las autoridades judiciales han registrado m\u00e1s de 50 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral francesa, dijo este viernes el ministro del Interior del pa\u00eds, G\u00e9rald Darmanin. &#171;Esta campa\u00f1a es corta, menos de tres semanas, y sin embargo hemos contado 51 candidatos, diputados o activistas que han sido agredidos f\u00edsicamente. Sin [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450907","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Las autoridades judiciales han registrado m\u00e1s de 50 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral francesa, dijo este viernes el ministro del Interior del pa\u00eds, G\u00e9rald Darmanin. &#171;Esta campa\u00f1a es corta, menos de tres semanas, y sin embargo hemos contado 51 candidatos, diputados o activistas que han sido agredidos f\u00edsicamente. Sin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-05T21:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia\",\"datePublished\":\"2024-07-05T21:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/\"},\"wordCount\":294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/\",\"name\":\"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-05T21:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia - Noticias","og_description":"(CNN) &#8212;\u00a0Las autoridades judiciales han registrado m\u00e1s de 50 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral francesa, dijo este viernes el ministro del Interior del pa\u00eds, G\u00e9rald Darmanin. &#171;Esta campa\u00f1a es corta, menos de tres semanas, y sin embargo hemos contado 51 candidatos, diputados o activistas que han sido agredidos f\u00edsicamente. Sin [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-05T21:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/"},"author":{"name":"","@id":""},"headline":"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia","datePublished":"2024-07-05T21:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/"},"wordCount":294,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/","name":"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-05T21:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las autoridades registran 51 agresiones f\u00edsicas a candidatos y militantes durante la campa\u00f1a electoral en Francia","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/05\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-05T21:03:55Z","datePublished":"2024-07-05T21:03:55Z","dateModified":"2024-07-05T21:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las autoridades registran 51 agresiones f\\u00edsicas a candidatos y militantes durante la campa\\u00f1a electoral en Francia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/05\\\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/05\\\/agresiones-fisicas-candidatos-militantes-campana-electoral-francia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-05T21:03:55Z\",\"datePublished\":\"2024-07-05T21:03:55Z\",\"dateModified\":\"2024-07-05T21:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450880,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/04\/temores-violencia-electoral-francia-ataques-trax\/","url_meta":{"origin":1450907,"position":0},"title":"Aumentan los temores de violencia electoral en Francia despu\u00e9s de que un portavoz del gobierno fuera atacado durante la campa\u00f1a","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN) -- En Francia aumentan las preocupaciones por la violencia pol\u00edtica antes de las elecciones parlamentarias despu\u00e9s de que una serie de legisladores fueran atacados durante la campa\u00f1a electoral esta semana.La portavoz del Gobierno franc\u00e9s, Prisca Thevenot, y su equipo fueron atacados mientras hac\u00edan campa\u00f1a este mi\u00e9rcoles por la noche.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448015,"url":"https:\/\/noticiasya.com\/kansas\/2024\/04\/12\/elecciones-mexico-asesinatos-democracia-trax\/","url_meta":{"origin":1450907,"position":1},"title":"En las elecciones generales de M\u00e9xico, una ola de asesinatos ha puesto a la propia democracia en el punto de mira","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN) -- Jes\u00fas Corona Dami\u00e1n, candidato a la alcald\u00eda de Cuautla, M\u00e9xico, se encontraba una noche del mes pasado en un autom\u00f3vil cerca de su casa cuando dos hombres en motocicleta pasaron a toda velocidad y abrieron fuego.El d\u00eda anterior, una banda local le hab\u00eda enviado una amenaza, as\u00ed que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473126,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/14\/amenazas-candidatos-presidenciales-elecciones-orix\/","url_meta":{"origin":1450907,"position":2},"title":"Amenazas contra candidatos presidenciales en Colombia encienden alarmas cuando falta poco m\u00e1s de un mes para las elecciones","author":"","date":"abril 14, 2026","format":false,"excerpt":"En la antesala de las elecciones presidenciales en Colombia, las amenazas ensombrecen el proceso. Este domingo, el expresidente de Colombia \u00c1lvaro Uribe, l\u00edder del partido opositor de derecha Centro Democr\u00e1tico, public\u00f3 en sus redes sociales la fotograf\u00eda de una corona funeraria y un falso obituario con la frase \u201cPaloma Valencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449663,"url":"https:\/\/noticiasya.com\/kansas\/2024\/05\/22\/presidente-de-francia-emmanuel-macron-se-dirige-nueva-caledonia-golpeada-por-la-violencia-trax\/","url_meta":{"origin":1450907,"position":3},"title":"El presidente de Francia, Emmanuel Macron, se dirige a una Nueva Caledonia golpeada por la violencia","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) -- El presidente de Francia, Emmanuel Macron, est\u00e1 de camino a Nueva Caledonia, dijo un funcionario del gobierno, despu\u00e9s de una semana de disturbios mortales en el archipi\u00e9lago del Pac\u00edfico.Macron saldr\u00eda de Par\u00eds este\u00a0 martes por la noche y \"establecer\u00e1 una misi\u00f3n\" en territorio franc\u00e9s, dijo en rueda de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450929,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/07\/se-abren-urnas-para-segunda-vuelta-de-las-elecciones-parlamentarias-francia-trax\/","url_meta":{"origin":1450907,"position":4},"title":"Los votantes franceses acuden a las urnas para la crucial segunda vuelta de las elecciones parlamentarias anticipadas","author":"","date":"julio 7, 2024","format":false,"excerpt":"(CNN) -- Los votantes se dirigen a las urnas en toda Francia para votar en la segunda vuelta de una elecci\u00f3n anticipada convocada por el presidente Emmanuel Macron , quien corre el riesgo de perder franjas de sus aliados centristas en el parlamento y verse obligado a pasar los tres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447030,"url":"https:\/\/noticiasya.com\/kansas\/2024\/03\/16\/cada-dia-mexico-politico-sufre-agresion-orix\/","url_meta":{"origin":1450907,"position":5},"title":"Cada d\u00eda una persona vinculada al \u00e1mbito pol\u00edtico sufre una agresi\u00f3n en M\u00e9xico, seg\u00fan una consultora","author":"","date":"marzo 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 En los primeros seis meses del proceso electoral en M\u00e9xico, se ha registrado en promedio una agresi\u00f3n diaria a personas vinculadas con el \u00e1mbito pol\u00edtico, indica el reporte m\u00e1s reciente de violencia pol\u00edtica elaborado por Integralia, una consultora en asuntos p\u00fablicos.De septiembre del a\u00f1o pasado \u2014fecha en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1450907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1450907"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1450907\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1450907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1450907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1450907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}