{"id":1450982,"date":"2024-07-09T10:03:47","date_gmt":"2024-07-09T17:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/"},"modified":"2024-07-09T10:03:47","modified_gmt":"2024-07-09T17:03:47","slug":"por-que-mbappe-mascara-eurocopa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/","title":{"rendered":"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa?"},"content":{"rendered":"<p>(CNN) &#8212; \u00bfEs Batman? \u00bfEs Superman? No, es nada menos que Kylian Mbapp\u00e9, la joven figura de la Selecci\u00f3n francesa. Y no, no forma parte de una rutina de celebraci\u00f3n o de alguna especie de ritual.<\/p>\n<p>El futbolista franc\u00e9s utilizaba la m\u00e1scara, que cubre sus ojos y su nariz, como medida de protecci\u00f3n. Es que el capit\u00e1n de la selecci\u00f3n de Francia se rompi\u00f3 la nariz durante la primera victoria del equipo en la Eurocopa 2024 contra Austria.<\/p>\n<p>Mbapp\u00e9 en X, antes Twitter, despu\u00e9s de su lesi\u00f3n.<\/p>\n<p>Tras el incidente, ocurrido en el minuto 86 del partido, Mbapp\u00e9 particip\u00f3 de un entrenamiento sin contacto con apenas tiritas en la nariz. Sin embargo, un d\u00eda despu\u00e9s el n\u00famero 10 us\u00f3 una m\u00e1scara hecha a medida que ten\u00eda estampadas sus iniciales y que ten\u00eda los colores de la bandera francesa.<\/p>\n<p>En los entrenamientos posteriores, Mbapp\u00e9 uso en cambio una m\u00e1scara de color negro, ya que las reglas de la UEFA estipulan que &#171;el equipo m\u00e9dico usado en el campo de juego debe ser de un solo color y estar libre de identificaci\u00f3n del equipo y del fabricante&#187;.<\/p>\n<p>El jugador franc\u00e9s continu\u00f3 usando la m\u00e1scara en los duelos ante Polonia, B\u00e9lgica y Portugal.<\/p>\n<p>Kylian Mbapp\u00e9 hace un calentamiento con la pelota justo antes del partido contra Pa\u00edses Bajos, durante la Eurocopa 2024, en el Estadio de Leipzig. (Clive Mason\/Getty Images)<\/p>\n<p>Las m\u00e1scaras son habituales en el juego<\/p>\n<p>Este tipo de m\u00e1scaras han sido habituales durante los \u00faltimos a\u00f1os, y tienen el objetivo de proteger a los jugadores que se recuperan de lesiones faciales.<\/p>\n<p>En los \u00faltimos a\u00f1os, hemos visto a algunas estrellas del f\u00fatbol mundial como Son Heung-min, Antonio R\u00fcdiger, Harry Kane, Robert Lewandowski, Victor Osimhen \u00a0Jasko Gvardiol, y Sergio Ramos, llevar m\u00e1scaras en el campo de los torneos importantes, incluida la Copa del Mundo de Qatar 2022.<\/p>\n<p>&#8212; Con informaci\u00f3n de Ben Morse, de CNN. Alasdair Howorth y Adrienne Vogt de CNN contribuyeron con este reportaje.<\/p>\n<p>Nota del editor: este art\u00edculo fue publicado originalmente el 5 de diciembre de 2022 y republicado el 9 de julio de 2024.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; \u00bfEs Batman? \u00bfEs Superman? No, es nada menos que Kylian Mbapp\u00e9, la joven figura de la Selecci\u00f3n francesa. Y no, no forma parte de una rutina de celebraci\u00f3n o de alguna especie de ritual. El futbolista franc\u00e9s utilizaba la m\u00e1scara, que cubre sus ojos y su nariz, como medida de protecci\u00f3n. Es que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450982","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; \u00bfEs Batman? \u00bfEs Superman? No, es nada menos que Kylian Mbapp\u00e9, la joven figura de la Selecci\u00f3n francesa. Y no, no forma parte de una rutina de celebraci\u00f3n o de alguna especie de ritual. El futbolista franc\u00e9s utilizaba la m\u00e1scara, que cubre sus ojos y su nariz, como medida de protecci\u00f3n. Es que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T17:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa?\",\"datePublished\":\"2024-07-09T17:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/\",\"name\":\"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-09T17:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa? - Noticias","og_description":"(CNN) &#8212; \u00bfEs Batman? \u00bfEs Superman? No, es nada menos que Kylian Mbapp\u00e9, la joven figura de la Selecci\u00f3n francesa. Y no, no forma parte de una rutina de celebraci\u00f3n o de alguna especie de ritual. El futbolista franc\u00e9s utilizaba la m\u00e1scara, que cubre sus ojos y su nariz, como medida de protecci\u00f3n. Es que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-09T17:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa?","datePublished":"2024-07-09T17:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/","name":"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-09T17:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 Mbapp\u00e9 juega con una m\u00e1scara en los partidos de la Eurocopa?","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/09\/por-que-mbappe-mascara-eurocopa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-09T17:03:47Z","datePublished":"2024-07-09T17:03:47Z","dateModified":"2024-07-09T17:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 Mbapp\\u00e9 juega con una m\\u00e1scara en los partidos de la Eurocopa?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/09\\\/por-que-mbappe-mascara-eurocopa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/09\\\/por-que-mbappe-mascara-eurocopa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-09T17:03:47Z\",\"datePublished\":\"2024-07-09T17:03:47Z\",\"dateModified\":\"2024-07-09T17:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450561,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/20\/mbappe-mascara-tricolor-romperse-nariz-eurocopa-trax\/","url_meta":{"origin":1450982,"position":0},"title":"Kylian Mbapp\u00e9 usa una m\u00e1scara tricolor en entrenamiento tras romperse la nariz en la Eurocopa 2024","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN) -- El astro del f\u00fatbol Kylian Mbapp\u00e9 fue fotografiado con una m\u00e1scara tricolor de inspiraci\u00f3n francesa durante una sesi\u00f3n de entrenamiento este jueves, luego de que el capit\u00e1n de la selecci\u00f3n de Francia se rompiera la nariz durante la primera victoria del equipo en la Eurocopa 2024 contra Austria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450888,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/04\/mbappe-primera-vuelta-elecciones-francia-derecha-trax\/","url_meta":{"origin":1450982,"position":1},"title":"Kylian Mbapp\u00e9 califica de &#171;catastr\u00f3fica&#187; la primera vuelta de las elecciones en Francia tras el giro del pa\u00eds hacia la extrema derecha","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN) -- La estrella del f\u00fatbol Kylian Mbapp\u00e9 calific\u00f3 de \"catastr\u00f3fica\" la primera vuelta de las elecciones de Francia despu\u00e9s de que los resultados del domingo pasado vieran al pa\u00eds tambalearse hacia la extrema derecha ya que el partido antiinmigraci\u00f3n Agrupaci\u00f3n Nacional (RN) lider\u00f3 el primer lugar.El capit\u00e1n de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450800,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/29\/italia-eliminada-eurocopa-2024-suiza-octavos-de-final-trax\/","url_meta":{"origin":1450982,"position":2},"title":"Italia, \u00faltima campeona, fue eliminada de la Eurocopa 2024 por Suiza en octavos de final","author":"","date":"junio 29, 2024","format":false,"excerpt":"(CNN) -- La vigente campeona Italia fue eliminada de la Eurocopa 2024 en octavos de final, despu\u00e9s de que Suiza diera una impactante sorpresa para ganar 2-0 este s\u00e1bado.Los goles de Remo Freuler y Ruben Vargas antes y despu\u00e9s del descanso fueron suficientes para que el equipo de Murat Yakin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449962,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/03\/kyilian-mbappe-real-madrid-equipos-titulos-records-cifras-orix\/","url_meta":{"origin":1450982,"position":3},"title":"La carrera de Kylian Mbapp\u00e9: equipos, t\u00edtulos ganados, r\u00e9cords y cifras","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --Kylian Mbapp\u00e9 llega finalmente al Real Madrid despu\u00e9s de a\u00f1os de especulaciones y en un momento en el club refuerza su poder\u00edo con una nueva Champions League en sus vitrinas. La mayor estrella de Francia \u2014uno de los mejores del mundo\u2014, protagonista del Mundial de 2018 que levant\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450796,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/29\/eurocopa-2024-austria-gran-sorpresa-torneo-trax\/","url_meta":{"origin":1450982,"position":4},"title":"Eurocopa 2024: Por qu\u00e9 Austria es la gran sorpresa del torneo","author":"","date":"junio 29, 2024","format":false,"excerpt":"(CNN) -- No es raro ver a ciertos equipos emerger como sorpresas en torneos internacionales, pero pocos podr\u00edan haber anticipado que Austria ser\u00eda la atracci\u00f3n de la Eurocopa 2024.Situada en el Grupo D junto a rivales complicados, parec\u00eda que a Austria le iba a costar llegar a octavos de final.Polonia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450608,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/22\/arda-guler-messi-turco-eurocopa-futbol\/","url_meta":{"origin":1450982,"position":5},"title":"Qui\u00e9n es Arda G\u00fcler, &#171;el Messi turco&#187; de 19 a\u00f1os que ilumin\u00f3 la Eurocopa","author":"","date":"junio 22, 2024","format":false,"excerpt":"(CNN) -- Cuando Arda G\u00fcler marc\u00f3 un golazo en la victoria por 3-1 de Turqu\u00eda contra Georgia esta semana (un disparo lejano que se col\u00f3 por la escuadra), se consolid\u00f3 como uno de los mejores futbolistas j\u00f3venes del mundo.G\u00fcler solo tiene 19 a\u00f1os, pero su talento ya le ha valido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1450982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1450982"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1450982\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1450982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1450982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1450982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}