{"id":1450991,"date":"2024-07-09T14:03:39","date_gmt":"2024-07-09T21:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/"},"modified":"2024-07-09T14:03:39","modified_gmt":"2024-07-09T21:03:39","slug":"inmigrantes-familias-aeropuerto-boston-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/","title":{"rendered":"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston"},"content":{"rendered":"<p>(CNN) &#8212; Las familias de inmigrantes que han pasado la noche en el aeropuerto de Boston podr\u00edan encontrarse pronto en un lugar inesperado: una antigua prisi\u00f3n estatal.<\/p>\n<p>Hoy entra en vigor una nueva pol\u00edtica de Massachusetts que proh\u00edbe pasar la noche en el Aeropuerto Internacional Logan.<\/p>\n<p>Algunas familias elegibles en lista de espera ser\u00e1n llevadas a nuevos refugios, dijeron las autoridades, incluida una antigua prisi\u00f3n en Norfolk, Massachusetts, que recientemente se convirti\u00f3 en un refugio de emergencia.<\/p>\n<p>La medida se produce cuando los funcionarios estatales dicen que se han quedado sin espacio para refugios.<\/p>\n<p>\u201cNunca pensamos que Logan fuera un lugar apropiado para que la gente pasara la noche\u201d, dijo la gobernadora Maura Healey a WBZ, afiliada de CNN, despu\u00e9s de anunciar la medida.<\/p>\n<p>Controversia por convertir una antigua prisi\u00f3n en un refugio<\/p>\n<p>Durante meses, los funcionarios de Massachusetts han advertido que estaban abrumados por la cantidad de inmigrantes que llegaban.<\/p>\n<p>Healey indic\u00f3 el a\u00f1o pasado que el sistema de refugios de emergencia para familias del estado alcanz\u00f3 su capacidad con 7.500 familias.<\/p>\n<p>En un momento del a\u00f1o pasado, el vicegobernador del estado pidi\u00f3 a los residentes que consideraran alojar a los inmigrantes en sus hogares debido a la falta de espacio para albergar. Y recientemente una delegaci\u00f3n del estado viaj\u00f3 a la frontera sur de Estados Unidos para difundir \u201cque Massachusetts se qued\u00f3 sin espacio para albergar refugio\u201d, dijeron las autoridades.<\/p>\n<p>En mayo, los funcionarios anunciaron que el Centro Correccional Bay State en Norfolk, que cerr\u00f3 en 2015, se estaba convirtiendo en un refugio de emergencia que podr\u00eda albergar a 140 familias.<\/p>\n<p>El controvertido anuncio desat\u00f3 protestas frente a las instalaciones a unos 64 kil\u00f3metros al suroeste de Boston, inform\u00f3 WBZ.<\/p>\n<p>Las im\u00e1genes de la filial de CNN mostraron a los manifestantes agitando carteles que dec\u00edan: \u201cSin ni\u00f1os en las c\u00e1rceles\u201d y \u201c\u00a1El refugio-prisi\u00f3n de Norfolk no es seguro para nadie!\u201d.<\/p>\n<p>Y en una acalorada reuni\u00f3n comunitaria el mes pasado, las tensiones estallaron cuando los residentes de Norfolk expresaron su preocupaci\u00f3n por posibles impactos en las escuelas, los servicios m\u00e9dicos y la seguridad p\u00fablica, seg\u00fan WBZ.<\/p>\n<p>La polic\u00eda y los trabajadores sociales escoltaron a las familias hasta la salida<\/p>\n<p>Los inmigrantes llevan meses durmiendo en un rinc\u00f3n de la terminal de llegadas internacionales del aeropuerto de Boston. Im\u00e1genes de afiliados de CNN mostraron a personas alineando sacos de dormir, mantas y almohadas en filas a lo largo de las paredes de la terminal.<\/p>\n<p>Esta fotograf\u00eda de archivo de enero muestra a familias de inmigrantes utilizando la Terminal E del Aeropuerto Internacional Logan de Boston como refugio. Cr\u00e9dito: Jos\u00e9 Prezioso\/AFP\/Getty Images<\/p>\n<p>En un momento, cientos de familias inmigrantes se alojaban all\u00ed, inform\u00f3 WCVB, afiliada de CNN. El 25 de junio, las autoridades dijeron que 288 personas hab\u00edan dormido all\u00ed durante la noche. El martes por la ma\u00f1ana s\u00f3lo quedaban unas pocas familias.<\/p>\n<p>Despu\u00e9s del amanecer, WBZ inform\u00f3 que la polic\u00eda estatal, los trabajadores sociales y el personal del aeropuerto llevaron a esos inmigrantes a taxis, que los llevaron a los centros de bienvenida en Allston y Quincy.<\/p>\n<p>&#171;Esto es lo mejor para las familias, los viajeros y el personal de Logan, ya que el aeropuerto no es un lugar apropiado para que las personas busquen refugio&#187;, dijo el director estatal de Asistencia de Emergencia, Scott Rice, en un comunicado de prensa el mes pasado. &#171;Seguiremos ampliando el mensaje de que Massachusetts se qued\u00f3 sin espacio para refugios y que, si las familias viajan a Massachusetts, deben estar preparados con un plan de vivienda que no incluya el Aeropuerto Logan ni nuestros refugios de Asistencia de Emergencia&#187;.<\/p>\n<p>Braden Walker de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Las familias de inmigrantes que han pasado la noche en el aeropuerto de Boston podr\u00edan encontrarse pronto en un lugar inesperado: una antigua prisi\u00f3n estatal. Hoy entra en vigor una nueva pol\u00edtica de Massachusetts que proh\u00edbe pasar la noche en el Aeropuerto Internacional Logan. Algunas familias elegibles en lista de espera ser\u00e1n llevadas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450991","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Las familias de inmigrantes que han pasado la noche en el aeropuerto de Boston podr\u00edan encontrarse pronto en un lugar inesperado: una antigua prisi\u00f3n estatal. Hoy entra en vigor una nueva pol\u00edtica de Massachusetts que proh\u00edbe pasar la noche en el Aeropuerto Internacional Logan. Algunas familias elegibles en lista de espera ser\u00e1n llevadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T21:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston\",\"datePublished\":\"2024-07-09T21:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/\"},\"wordCount\":661,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/\",\"name\":\"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-09T21:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston - Noticias","og_description":"(CNN) &#8212; Las familias de inmigrantes que han pasado la noche en el aeropuerto de Boston podr\u00edan encontrarse pronto en un lugar inesperado: una antigua prisi\u00f3n estatal. Hoy entra en vigor una nueva pol\u00edtica de Massachusetts que proh\u00edbe pasar la noche en el Aeropuerto Internacional Logan. Algunas familias elegibles en lista de espera ser\u00e1n llevadas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-09T21:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/"},"author":{"name":"","@id":""},"headline":"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston","datePublished":"2024-07-09T21:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/"},"wordCount":661,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/","name":"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-09T21:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/09\/inmigrantes-familias-aeropuerto-boston-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-09T21:03:39Z","datePublished":"2024-07-09T21:03:39Z","dateModified":"2024-07-09T21:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las familias inmigrantes ahora tienen prohibido dormir en el aeropuerto de Boston\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/09\\\/inmigrantes-familias-aeropuerto-boston-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/09\\\/inmigrantes-familias-aeropuerto-boston-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-09T21:03:39Z\",\"datePublished\":\"2024-07-09T21:03:39Z\",\"dateModified\":\"2024-07-09T21:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442428,"url":"https:\/\/noticiasya.com\/kansas\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","url_meta":{"origin":1450991,"position":0},"title":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago","author":"","date":"diciembre 21, 2023","format":false,"excerpt":"(CNN) -- El gobernador de Texas, Greg Abbott, est\u00e1 subiendo la apuesta en sus esfuerzos por transportar inmigrantes a ciudades santuario, llev\u00e1ndolos en avi\u00f3n a Chicago, dijo a CNN el secretario de prensa del gobernador, Andrew Mahaleris.\"Hasta que el presidente Biden d\u00e9 un paso al frente y haga su trabajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445143,"url":"https:\/\/noticiasya.com\/kansas\/2024\/02\/09\/un-profugo-al-que-buscaban-por-el-crimen-de-una-enfermera-en-boston-fue-capturado-en-kenia-acaba-de-escapar-otra-vez\/","url_meta":{"origin":1450991,"position":1},"title":"Un pr\u00f3fugo al que buscaban por el crimen de una enfermera en Boston fue capturado en Kenia. Acaba de escapar otra vez","author":"","date":"febrero 9, 2024","format":false,"excerpt":"(CNN) -- Un hombre acusado de matar a su novia en Boston y luego huir a Kenia se fug\u00f3 de una c\u00e1rcel de Nairobi, donde esperaba la extradici\u00f3n despu\u00e9s de que lo arrestaran la semana pasada.Kevin Kangethe, de 42 a\u00f1os, estaba detenido sin derecho a fianza luego de que las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445144,"url":"https:\/\/noticiasya.com\/kansas\/2024\/02\/09\/un-profugo-al-que-buscaban-por-el-crimen-de-una-enfermera-en-boston-fue-capturado-en-kenia-acaba-de-escapar-otra-vez-2\/","url_meta":{"origin":1450991,"position":2},"title":"Un pr\u00f3fugo al que buscaban por el crimen de una enfermera en Boston fue capturado en Kenia. Acaba de escapar otra vez","author":"","date":"febrero 9, 2024","format":false,"excerpt":"(CNN) -- Un hombre acusado de matar a su novia en Boston y luego huir a Kenia se fug\u00f3 de una c\u00e1rcel de Nairobi, donde esperaba la extradici\u00f3n despu\u00e9s de que lo arrestaran la semana pasada.Kevin Kangethe, de 42 a\u00f1os, estaba detenido sin derecho a fianza luego de que las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457338,"url":"https:\/\/noticiasya.com\/kansas\/2025\/01\/08\/pasajero-jetblue-abrio-salida-emergencia-avion-trax\/","url_meta":{"origin":1450991,"position":3},"title":"La Polic\u00eda arresta a un pasajero de JetBlue que abri\u00f3 la salida de emergencia, lo que genera preocupaciones de seguridad","author":"","date":"enero 8, 2025","format":false,"excerpt":"La Polic\u00eda Estatal de Massachusetts fue llamada al Aeropuerto Internacional Logan de Boston este martes por la noche despu\u00e9s de que un pasajero de JetBlue abri\u00f3 la puerta de un avi\u00f3n, desplegando el tobog\u00e1n de emergencia, dijeron la Polic\u00eda y la aerol\u00ednea a CNN.Alrededor de las 7:30 p.m. hora local,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456974,"url":"https:\/\/noticiasya.com\/kansas\/2024\/12\/26\/disputa-familia-aeropuerto-phoenix\/","url_meta":{"origin":1450991,"position":4},"title":"Aparente disputa familiar termina con tres heridos de bala y un apu\u00f1alado en aeropuerto de Phoenix, dicen autoridades","author":"","date":"diciembre 26, 2024","format":false,"excerpt":"Tres personas resultaron heridas de bala y otra fue apu\u00f1alada en el aeropuerto internacional Sky Harbor de Phoenix, Arizona, durante una disputa familiar en una de las terminales la noche de Navidad, inform\u00f3 la polic\u00eda.El incidente se produjo en un restaurante de la Terminal 4, fuera del per\u00edmetro de seguridad,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472462,"url":"https:\/\/noticiasya.com\/kansas\/2026\/03\/23\/que-paso-avion-air-canada-laguardia-trax\/","url_meta":{"origin":1450991,"position":5},"title":"\u00bfQu\u00e9 pas\u00f3 con el avi\u00f3n de Air Canada y c\u00f3mo se estrell\u00f3 en el aeropuerto de LaGuardia con un cami\u00f3n?","author":"","date":"marzo 23, 2026","format":false,"excerpt":"El aeropuerto LaGuardia de Nueva York permanece cerrado tras la colisi\u00f3n de un avi\u00f3n de Air Canada con un cami\u00f3n de bomberos durante el aterrizaje el domingo por la noche. El piloto y el copiloto fallecieron, y dos personas que viajaban en el cami\u00f3n resultaron heridas, seg\u00fan inform\u00f3 un agente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1450991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1450991"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1450991\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1450991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1450991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1450991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}