{"id":1451016,"date":"2024-07-10T16:03:45","date_gmt":"2024-07-10T23:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/"},"modified":"2024-07-10T16:03:45","modified_gmt":"2024-07-10T23:03:45","slug":"agua-restaurantes-europeos-debate-redes-sociales-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/","title":{"rendered":"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales"},"content":{"rendered":"<p>(CNN) &#8212; La estadounidense Helene Sula recuerda v\u00edvidamente la primera vez que descubri\u00f3 que el agua del grifo era algo diferente para los europeos.<\/p>\n<p>Sula, de Texas, estaba en un restaurante en Alemania. Cuando el mesero le pregunt\u00f3 qu\u00e9 quer\u00eda beber, ella pidi\u00f3 agua.<br \/>\n&#171;Se burlaron de m\u00ed y me dijeron: &#8216;Puedes pedir agua. Pero, \u00bfpor qu\u00e9 lo har\u00edas?&#187;, recuerda Sula.<\/p>\n<p>Recuerda que mir\u00f3 a su alrededor y se dio cuenta de que todo el mundo en el restaurante estaba disfrutando de copas de vino y pintas de cerveza, pero no de agua.<\/p>\n<p>Sula repiti\u00f3 su pedido de agua y el camarero objet\u00f3. Pero, cuando lleg\u00f3 el agua, no era el vaso gigante de agua del grifo, lleno de hielo, que Sula esperaba.<\/p>\n<p>En cambio, le sirvieron una botella de un litro de agua con gas, acompa\u00f1ada de un vaso diminuto y un precio de 2 euros.<br \/>\nSula no lo pod\u00eda creer.<\/p>\n<p>&#171;En EE.UU., te sientas a la mesa y te dan un vaso enorme de agua con hielo, sin preguntarte nada. No importa si est\u00e1s en un restaurante de lujo o en uno informal, te van a dar un enorme vaso de agua de cortes\u00eda&#187;, explica Sula a CNN Travel.<\/p>\n<p>Un d\u00f3lar m\u00e1s d\u00e9bil, precios por las nubes y cifras &#171;r\u00e9cord&#187; de visitantes: suerte en Europa este verano boreal<\/p>\n<p>Unos a\u00f1os m\u00e1s tarde, cuando Sula y su marido se mudaron a Alemania, la pareja observ\u00f3 otra diferencia cultural relacionada con el agua.<\/p>\n<p>Siempre que sal\u00edan de excursi\u00f3n, en bicicleta o a pasear por la ciudad, Sula y su marido llevaban grandes botellas de agua, a veces incluso CamelBaks, una especie de mochila de agua (&#171;Para poder beber agua en cualquier momento posible&#187;, explica Sula).<\/p>\n<p>Mientras tanto, sus amigos europeos sol\u00edan prescindir por completo del agua y aguantaban hasta que se iban a un bar por la noche, e incluso entonces sol\u00edan optar por el vino. Sula no daba cr\u00e9dito.<\/p>\n<p>&#171;Pens\u00e9 que tal vez los europeos no se deshidrataban tanto como nosotros&#187;, dice Sula, todav\u00eda perpleja despu\u00e9s de varios a\u00f1os viviendo en Europa.<\/p>\n<p>\u00bfQu\u00e9 bebida es la mejor para hidratarse? Pista: no es agua<\/p>\n<p>Comprender los h\u00e1bitos europeos<\/p>\n<p>La estadounidense Helene Sula, en la foto, siempre lleva grandes botellas de agua en sus viajes. Se qued\u00f3 sorprendida cuando se dio cuenta de que sus amigos europeos ten\u00edan h\u00e1bitos muy diferentes a la hora de beber agua. Cr\u00e9dito: Helene Sula<\/p>\n<p>Si est\u00e1s pensando: &#171;Espera, esto es s\u00f3lo la opini\u00f3n de una persona y es una generalizaci\u00f3n bastante amplia&#187;, estar\u00edas en lo cierto. Al fin y al cabo, en Europa hay muchos pa\u00edses diferentes, cada uno con su propia cultura, h\u00e1bitos alimenticios, tradiciones y h\u00e1bitos de consumo de agua.<\/p>\n<p>Y, por supuesto, Estados Unidos tampoco es un monolito cultural. Claro que algunos estadounidenses se enorgullecen de sus enormes tarros Stanley y emprenden retos diarios relacionados con el agua, pero otros siempre optar\u00edan por los refrescos si les dieran a elegir.<\/p>\n<p>Y aunque muchos son conscientes del impacto ambiental de las botellas de pl\u00e1stico, otros evitan el agua de la llave y mantienen la nevera llena de agua embotellada.<\/p>\n<p>Sin embargo, Sula no est\u00e1 sola en sus observaciones. Los viajeros estadounidenses que comparten sus opiniones sobre el consumo (o la falta de consumo) de agua del grifo en Europa se han convertido en una tendencia en las redes sociales en los \u00faltimos a\u00f1os.<\/p>\n<p>Por ejemplo, la usuaria de TikTok br3nnak3ough, que en verano de 2023 subi\u00f3 un video en el que aparec\u00edan sus amigos bebiendo grandes botellas de agua: &#171;Nosotros en el momento en que podemos encontrar agua porque los europeos no creen en el agua&#187;.<\/p>\n<p>Este video lleva 10,9 millones de visitas y 13.800 comentarios, tanto de estadounidenses que est\u00e1n de acuerdo (&#171;Estaba tan deshidratada cuando fui lol, el calor + la falta de ac y agua\/hielo me estaba muriendo&#8230;&#187;) como de europeos que discrepan rotundamente (&#171;\u00bfDe qu\u00e9 est\u00e1s hablando?&#187;).<\/p>\n<p>&#171;El sue\u00f1o americano es salir de Estados Unidos&#187;: TikTokers estadounidenses revelan c\u00f3mo es la vida en el extranjero<\/p>\n<p>Por su parte, Rob Murgatroyd, un estadounidense residente en Italia, subi\u00f3 recientemente un TikTok en el que comentaba que la diferencia entre el consumo de agua en Estados Unidos y en Italia lo &#171;dej\u00f3 alucinado&#187; desde que se mud\u00f3 a Florencia.<\/p>\n<p>&#171;De donde yo vengo, estamos pr\u00e1cticamente programados para beber agua sin parar, como si fuera nuestro trabajo principal, mientras que aqu\u00ed en Italia, ver a alguien con una botella de agua es como encontrar una aguja en un pajar&#187;, seg\u00fan el texto que acompa\u00f1a el video de Murgatroyd.<\/p>\n<p>@br3nnak3ough<br \/>\n \u266c Yeahhhh slurpyyyy &#8211; AAA<\/p>\n<p>Hay TikToks que se asombran del tama\u00f1o de los vasos de agua europeos, Reels de Instagram que narran la b\u00fasqueda, a menudo infructuosa, de una jarra de agua del grifo en un bar europeo y posts en X que se lamentan de tener que pagar por el agua embotellada en los restaurantes.<\/p>\n<p>Sula, que relata su vida en el extranjero en el blog Helene in Between, ha intervenido un par de veces en el gran debate europeo sobre el agua del grifo, incluso a finales del a\u00f1o pasado:<\/p>\n<p>&#171;El agua del grifo no es gratis en los restaurantes (europeos)&#187;, afirmaba Sula en un video de TikTok en noviembre de 2023. &#171;Y si te la dan, viene en un vaso diminuto&#187;.<\/p>\n<p>Muchos comentarios fueron despectivos: &#171;Es gratis. Te conocen de sobra&#187;, dec\u00eda uno.<\/p>\n<p>Otros coincidieron con la experiencia de Sula y a\u00f1adieron que, aunque suele haber agua del grifo, el agua mineral embotellada o el agua filtrada embotellada son m\u00e1s habituales en muchos pa\u00edses europeos.<\/p>\n<p>&#171;Creo que es una conversaci\u00f3n muy interesante&#187;, dice Sula. &#171;El mundo puede parecer muy peque\u00f1o a veces, porque todos estamos en l\u00ednea y es una sociedad tan global ahora &#8230; as\u00ed que creo que es interesante tener estas conversaciones, hablar de las diferencias&#187;.<\/p>\n<p>Los pasos a seguir para revertir la escasez de agua potable en el mundo<\/p>\n<p>Opini\u00f3n de un experto<\/p>\n<p>Algunos europeos prefieren el agua con gas cuando comen en restaurantes. Cr\u00e9dito: Marco Bertorello\/AFP\/Getty Images<\/p>\n<p>Para tener una idea de lo que realmente est\u00e1 pasando m\u00e1s all\u00e1 de las pruebas anecd\u00f3ticas, CNN Travel llam\u00f3 a Stavros A. Kavouras, profesor de Nutrici\u00f3n de la Universidad Estatal de Arizona. Kavouras es director del Laboratorio de Ciencias de la Hidrataci\u00f3n de la universidad, que se centra en el impacto de la hidrataci\u00f3n en la salud y el rendimiento.<\/p>\n<p>Kavouras es tambi\u00e9n un griego que lleva 20 a\u00f1os viviendo en Estados Unidos, por lo que est\u00e1 bien preparado para comentar sobre los choques culturales transatl\u00e1nticos.<\/p>\n<p>En primer lugar, Kavouras subraya la mir\u00edada de diferencias entre los pa\u00edses que componen el continente europeo. Destaca, por ejemplo, el contraste entre &#171;los alimentos del norte de Europa frente a la cocina francesa, italiana, griega y las preferencias diet\u00e9ticas&#187;.<\/p>\n<p>&#171;No me gustan las generalizaciones&#187;, dice Kavouras, quien afirma que aunque es tentador establecer una dicotom\u00eda Europa frente a Estados Unidos, no suele sostenerse.<\/p>\n<p>Kavouras se\u00f1ala tambi\u00e9n que los estadounidenses que visitan Europa (y publican sobre ello en Internet) no representan a la mayor\u00eda de la poblaci\u00f3n de Estados Unidos.<\/p>\n<p>&#171;No es el estadounidense medio&#187;, dice Kavouras. &#171;La poblaci\u00f3n que viene a Europa es m\u00e1s educada, m\u00e1s rica, de mayor nivel socioecon\u00f3mico&#8230;&#187;. Esto es relevante, afirma Kavouras, porque hay datos que sugieren que los estadounidenses de menor estatus socioecon\u00f3mico beben menos agua.<\/p>\n<p>Pero tras establecer estos par\u00e1metros y salvedades, Kavouras est\u00e1 de acuerdo en que existen algunas diferencias potenciales entre EE.UU. y Europa en lo que se refiere a &#171;lo que bebe la gente, lo que le gusta y cu\u00e1n hidratada est\u00e1&#187;.<\/p>\n<p>&#171;Por ejemplo, si vas a Alemania y pides agua, te dan agua con gas. \u00c9sa es la norma&#187;, dice Kavouras. &#171;As\u00ed que si sirvieras agua del grifo en Alemania, a todos los seres humanos, la gente dir\u00eda: &#8216;Oh, yo no bebo esta agua&#8217;. As\u00ed que, \u00bfpor qu\u00e9 lo har\u00edas?&#187;.<\/p>\n<p>Aunque el agua corriente suele estar disponible en la mayor\u00eda de los pa\u00edses europeos, a menudo no se sirve como un servicio normal. Stavros A. Kavouras, profesor de Nutrici\u00f3n de la Universidad Estatal de Arizona, sugiere que si as\u00ed fuera, algunos europeos seguir\u00edan evit\u00e1ndola en favor del agua embotellada. Cr\u00e9dito: Nathan Laine\/Bloomberg\/Getty Images<\/p>\n<p>Kavouras tambi\u00e9n se\u00f1ala que pagar unos euros m\u00e1s por una botella de agua de un litro en la cena es m\u00e1s aceptado en Europa que en Estados Unidos. Aunque a los estadounidenses les escandalice, es algo que muchos europeos no dudar\u00edan en hacer, dice Kavouras.<\/p>\n<p>El experto sugiere que los estadounidenses perturbados por el costo extra podr\u00edan verlo como &#171;el equivalente de la propina estadounidense que hay que pagar garantizada del 17 al 25% hoy en d\u00eda en Estados Unidos&#187;. (La cultura de la propina en Europa es bastante diferente, y suele implicar porcentajes mucho menores).<\/p>\n<p>\u00bfTu &#171;botella de agua de apoyo emocional&#187; est\u00e1 provocando sobrehidrataci\u00f3n?<\/p>\n<p>En cuanto a si los europeos est\u00e1n en general m\u00e1s deshidratados que los estadounidenses, Kavouras dice que es interesante que haya una diferencia entre las directrices diet\u00e9ticas para la ingesta de agua en Estados Unidos y Europa.<\/p>\n<p>&#171;En Estados Unidos, las directrices son de 2,7 litros para las mujeres y de 3,7 litros al d\u00eda para los hombres. Y en Europa, las cifras equivalentes son 2,0 y 2,5&#187;, afirma. &#171;As\u00ed que estas son las directrices -no significa que esto sea lo que bebe la gente-, pero es lo que se recomienda&#187;.<\/p>\n<p>Y en cuanto a los TikTokers estadounidenses que bromean sobre el agua del grifo servida en diminutos &#171;vasos de shot&#187; en Europa, Kavouras sugiere que esto podr\u00eda ser parte de una diferencia m\u00e1s general entre Estados Unidos y el resto del mundo.<\/p>\n<p>&#171;Ya conoces el estereotipo: en Estados Unidos todo es m\u00e1s grande: los coches, las casas, todo es m\u00e1s grande, las raciones en los restaurantes&#8230; etc\u00e9tera. Creo que puede ser un poco eso&#187;, dice Kavouras, y a\u00f1ade que lo mismo ocurre con &#171;los contenedores de agua que llevan los estadounidenses&#187;.<\/p>\n<p>A Kavouras siempre le hace gracia ver a sus compa\u00f1eros llegar al trabajo con &#171;un barrilito de agua, como si no hubiera agua en el edificio&#187;.<\/p>\n<p>Mantenerse hidratado se relaciona con un menor riesgo de enfermedad, de envejecimiento m\u00e1s r\u00e1pido y de muerte prematura, seg\u00fan estudio<\/p>\n<p>En opini\u00f3n de Kavouras, los contenedores gigantes de agua son &#171;innecesarios&#187;. Dicho esto, Kavouras aconseja que todo el mundo encuentre la forma de asegurarse una buena hidrataci\u00f3n a lo largo del d\u00eda, tanto si trabaja en una oficina estadounidense como si pasea por una ciudad europea.<\/p>\n<p>&#171;El agua es un componente esencial de toda dieta sana. Por eso, hidratarse adecuadamente es muy importante, sobre todo en verano&#187;, afirma.<\/p>\n<p>Consejos para los estadounidenses<\/p>\n<p>Muchas ciudades europeas tienen fuentes de agua gratuitas en las que se puede rellenar una botella, como la Fontana della Barcaccia, en la Piazzia di Spagna, en el centro de Roma. Cr\u00e9dito: Alberto Pizzoli\/AFP\/Getty Images<\/p>\n<p>Si eres un turista estadounidense que viaja a Europa este verano y te preocupa la situaci\u00f3n del agua, Kavouras te aconseja, en primer lugar, que te tomes todas las publicaciones virales en las redes sociales con cautela.<\/p>\n<p>Merece la pena informarse sobre el destino concreto al que te diriges y averiguar cu\u00e1l es la norma all\u00ed, en lugar de dar por hecho que todos los pa\u00edses de Europa son iguales. Familiar\u00edzate con las palabras que se utilizan en el idioma de tu destino para designar el agua con gas, sin gas y del grifo, para asegurarte de pedir la que prefieras.<\/p>\n<p>Y si no quieres beber agua embotellada en los restaurantes, Kavouras sugiere que te mantengas hidratado abasteci\u00e9ndote en el supermercado: &#171;El agua embotellada no es tan cara si planificas un poco y compras el agua en el supermercado, en comparaci\u00f3n con comprarla siempre en los restaurantes&#187;.<\/p>\n<p>\u00bfY el \u00faltimo consejo de Kavouras? Mete en la maleta una botella de agua reutilizable y ll\u00e9vala contigo durante todas las vacaciones, no s\u00f3lo los d\u00edas de ruta.<\/p>\n<p>&#171;En la mayor\u00eda de las ciudades europeas, el agua del grifo es potable, segura y se puede beber&#187;, afirma Kavouras.<\/p>\n<p>Muchas ciudades europeas tienen fuentes por toda la ciudad donde la gente puede parar e hidratarse. Los hoteles, caf\u00e9s y restaurantes suelen llenarte la botella si lo pides.<\/p>\n<p>&#171;Lleva una botella de agua vac\u00eda, en realidad no hace falta que sea de un gal\u00f3n&#187;, dice Kavouras. &#171;Simplemente lleva una botella de agua de tama\u00f1o normal para poder rellenarla siempre que tengas ocasi\u00f3n&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La estadounidense Helene Sula recuerda v\u00edvidamente la primera vez que descubri\u00f3 que el agua del grifo era algo diferente para los europeos. Sula, de Texas, estaba en un restaurante en Alemania. Cuando el mesero le pregunt\u00f3 qu\u00e9 quer\u00eda beber, ella pidi\u00f3 agua. &#171;Se burlaron de m\u00ed y me dijeron: &#8216;Puedes pedir agua. Pero, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451016","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La estadounidense Helene Sula recuerda v\u00edvidamente la primera vez que descubri\u00f3 que el agua del grifo era algo diferente para los europeos. Sula, de Texas, estaba en un restaurante en Alemania. Cuando el mesero le pregunt\u00f3 qu\u00e9 quer\u00eda beber, ella pidi\u00f3 agua. &#171;Se burlaron de m\u00ed y me dijeron: &#8216;Puedes pedir agua. Pero, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T23:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales\",\"datePublished\":\"2024-07-10T23:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/\"},\"wordCount\":2221,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/\",\"name\":\"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-10T23:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/","og_locale":"es_ES","og_type":"article","og_title":"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales - Noticias","og_description":"(CNN) &#8212; La estadounidense Helene Sula recuerda v\u00edvidamente la primera vez que descubri\u00f3 que el agua del grifo era algo diferente para los europeos. Sula, de Texas, estaba en un restaurante en Alemania. Cuando el mesero le pregunt\u00f3 qu\u00e9 quer\u00eda beber, ella pidi\u00f3 agua. &#171;Se burlaron de m\u00ed y me dijeron: &#8216;Puedes pedir agua. Pero, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-10T23:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/"},"author":{"name":"","@id":""},"headline":"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales","datePublished":"2024-07-10T23:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/"},"wordCount":2221,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/","name":"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-10T23:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"No es com\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\u00f3 un debate en redes sociales","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/10\/agua-restaurantes-europeos-debate-redes-sociales-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-10T23:03:45Z","datePublished":"2024-07-10T23:03:45Z","dateModified":"2024-07-10T23:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"No es com\\u00fan pedir un vaso de agua en restaurantes europeos y eso desat\\u00f3 un debate en redes sociales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/10\\\/agua-restaurantes-europeos-debate-redes-sociales-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/10\\\/agua-restaurantes-europeos-debate-redes-sociales-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-10T23:03:45Z\",\"datePublished\":\"2024-07-10T23:03:45Z\",\"dateModified\":\"2024-07-10T23:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473431,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/23\/toxina-peligrosa-agua-grifo-eeuu-trax\/","url_meta":{"origin":1451016,"position":0},"title":"Uno de cada cinco estadounidenses podr\u00eda tener una toxina peligrosa en el agua del grifo","author":"","date":"abril 23, 2026","format":false,"excerpt":"M\u00e1s de 62 millones de estadounidenses \u2014aproximadamente uno de cada cinco\u2014 podr\u00edan estar expuestos a niveles potencialmente peligrosos de nitratos en el agua del grifo, seg\u00fan un nuevo informe.Los nitratos \u2014compuestos de nitr\u00f3geno y ox\u00edgeno que se encuentran de forma natural en el aire, el agua, el suelo y las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457248,"url":"https:\/\/noticiasya.com\/kansas\/2025\/01\/05\/hidratacion-pequena-accion-anadir-anios-vida-expertos-trax\/","url_meta":{"origin":1451016,"position":1},"title":"Comienza m\u00e1s saludable el 2025 con esta peque\u00f1a acci\u00f3n que puede a\u00f1adir a\u00f1os a tu vida, seg\u00fan expertos","author":"","date":"enero 5, 2025","format":false,"excerpt":"\u00bfEn qu\u00e9 te est\u00e1s centrando este nuevo a\u00f1o para mejorar tu salud? El ejercicio regular, por supuesto, es un \u00e9xito probado, al igual que comer alimentos vegetales. Dormir m\u00e1s y mejor, reducir el estr\u00e9s, limitar el consumo de alcohol y relacionarse con otras personas de forma significativa tambi\u00e9n son medidas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445894,"url":"https:\/\/noticiasya.com\/kansas\/2024\/02\/21\/botella-agua-apoyo-emocional-esta-provocando-sobrehidratacion-trax\/","url_meta":{"origin":1451016,"position":2},"title":"\u00bfTu &#8216;botella de agua de apoyo emocional&#8217; est\u00e1 provocando sobrehidrataci\u00f3n?","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) --\u00a0 Ya sea el \u00faltimo y preciado vaso Stanley o esa botella de pl\u00e1stico con pico de hace 10 a\u00f1os sin la que no vas a ninguna parte, las \u201cbotellas de agua de apoyo emocional\u201d parecen estar pegadas a nuestros costados y no ir a ninguna parte.El t\u00e9rmino para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459630,"url":"https:\/\/noticiasya.com\/kansas\/2025\/03\/07\/trump-doge-liberar-agua-california-trax\/","url_meta":{"origin":1451016,"position":3},"title":"Dentro del ca\u00f3tico esfuerzo de Trump y DOGE por liberar miles de millones de litros de agua de California","author":"","date":"marzo 7, 2025","format":false,"excerpt":"Representantes del Departamento de Eficiencia Gubernamental (DOGE, por sus siglas en ingl\u00e9s) presionaron repetidamente al director de una agencia de gesti\u00f3n del agua de Estados Unidos para que abriera un importante sistema de bombeo de California a finales de enero, con la intenci\u00f3n de liberar una enorme cantidad de agua\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466759,"url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/23\/lugares-sequias-dia-cero-trax\/","url_meta":{"origin":1451016,"position":4},"title":"Qu\u00e9 lugares se podr\u00edan enfrentar a &#171;sequ\u00edas de d\u00eda cero&#187; en esta d\u00e9cada","author":"","date":"septiembre 23, 2025","format":false,"excerpt":"Se prev\u00e9 que muchas partes del mundo sufran \u201csequ\u00edas de d\u00eda cero\u201d, per\u00edodos de escasez de agua extrema y sin precedentes, que podr\u00edan ocurrir tan pronto como esta d\u00e9cada en ciertos puntos cr\u00edticos, incluyendo partes de Norteam\u00e9rica, el Mediterr\u00e1neo y el sur de \u00c1frica, seg\u00fan un nuevo estudio.Es bien sabido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460924,"url":"https:\/\/noticiasya.com\/kansas\/2025\/04\/07\/tormentas-inundaciones-estados-unidos-trax\/","url_meta":{"origin":1451016,"position":5},"title":"Tormentas mortales dan paso a la crecida de r\u00edos en el centro de EE.UU. devastado por inundaciones; el peligro continua","author":"","date":"abril 7, 2025","format":false,"excerpt":"La lluvia mortal e implacable en el sur y el medio oeste finalmente est\u00e1 disminuyendo este lunes, pero el peligro para muchas comunidades est\u00e1 aumentando. Basta con observar la r\u00e1pida crecida de los r\u00edos para ver lo que se avecina.\u201cEn mis 52 a\u00f1os de vida, esto es lo peor que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1451016"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451016\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1451016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1451016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1451016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}