{"id":1451017,"date":"2024-07-10T16:03:45","date_gmt":"2024-07-10T23:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/"},"modified":"2024-07-10T16:03:45","modified_gmt":"2024-07-10T23:03:45","slug":"patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","title":{"rendered":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Agentes migratorios de Estados Unidos y bomberos de Sunland Park, Nuevo M\u00e9xico, asistieron y pusieron a salvo a un grupo de 54 migrantes que cruzaban el R\u00edo Bravo, inform\u00f3 este mi\u00e9rcoles la Oficina de Aduanas y Patrulla Fronteriza (CBP por sus siglas en ingl\u00e9s).<\/p>\n<p>Mueren dos militares y un agente de la Patrulla Fronteriza al estrellarse un helic\u00f3ptero militar estadounidense cerca de la frontera sur<\/p>\n<p>Los migrantes, seg\u00fan un comunicado enviado a CNN por un vocero de la CBP, fueron &#171;rescatados&#187; en una zona con nivel de inundaci\u00f3n del R\u00edo Bravo. Posteriormente, las autoridades los llevaron a la estaci\u00f3n de Santa Teresa para su revisi\u00f3n m\u00e9dica y ser procesados bajo el T\u00edtulo 8 migratorio.<\/p>\n<p>Seg\u00fan la informaci\u00f3n, la oficina de la CBP de El Paso Sector (que abarca al estado de Nuevo M\u00e9xico y los condados de El Paso y Hudspeth en Texas) ha realizado 743 &#171;rescates humanitarios&#187; en lo que va del a\u00f1o fiscal, iniciado en octubre.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Agentes migratorios de Estados Unidos y bomberos de Sunland Park, Nuevo M\u00e9xico, asistieron y pusieron a salvo a un grupo de 54 migrantes que cruzaban el R\u00edo Bravo, inform\u00f3 este mi\u00e9rcoles la Oficina de Aduanas y Patrulla Fronteriza (CBP por sus siglas en ingl\u00e9s). Mueren dos militares y un agente de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451017","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Agentes migratorios de Estados Unidos y bomberos de Sunland Park, Nuevo M\u00e9xico, asistieron y pusieron a salvo a un grupo de 54 migrantes que cruzaban el R\u00edo Bravo, inform\u00f3 este mi\u00e9rcoles la Oficina de Aduanas y Patrulla Fronteriza (CBP por sus siglas en ingl\u00e9s). Mueren dos militares y un agente de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T23:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande\",\"datePublished\":\"2024-07-10T23:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/\"},\"wordCount\":202,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/\",\"name\":\"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-10T23:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Agentes migratorios de Estados Unidos y bomberos de Sunland Park, Nuevo M\u00e9xico, asistieron y pusieron a salvo a un grupo de 54 migrantes que cruzaban el R\u00edo Bravo, inform\u00f3 este mi\u00e9rcoles la Oficina de Aduanas y Patrulla Fronteriza (CBP por sus siglas en ingl\u00e9s). Mueren dos militares y un agente de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-10T23:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/"},"author":{"name":"","@id":""},"headline":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande","datePublished":"2024-07-10T23:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/"},"wordCount":202,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","name":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-10T23:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-10T23:03:45Z","datePublished":"2024-07-10T23:03:45Z","dateModified":"2024-07-10T23:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\\u00edo Grande\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/10\\\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/10\\\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-10T23:03:45Z\",\"datePublished\":\"2024-07-10T23:03:45Z\",\"dateModified\":\"2024-07-10T23:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443659,"url":"https:\/\/noticiasya.com\/kansas\/2024\/01\/13\/tres-migrantes-se-ahogaron-en-eagle-pass-dias-despues-de-que-texas-impidiera-el-paso-a-la-patrulla-fronteriza-asegura-un-congresista\/","url_meta":{"origin":1451017,"position":0},"title":"Tres migrantes se ahogaron en Eagle Pass d\u00edas despu\u00e9s de que Texas impidiera el paso a la Patrulla Fronteriza, asegura un congresista","author":"","date":"enero 13, 2024","format":false,"excerpt":"(CNN) -- Tres migrantes, una mujer adulta y dos ni\u00f1os, se ahogaron en el r\u00edo Grande en Eagle Pass este s\u00e1bado, pocos d\u00edas despu\u00e9s de que las autoridades de Texas impidieran el paso a la Patrulla Fronteriza hacia la frontera entre Estados Unidos y M\u00e9xico, seg\u00fan una publicaci\u00f3n en X\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459996,"url":"https:\/\/noticiasya.com\/kansas\/2025\/03\/16\/canciller-guatemala-frontera-estados-unidos-mexico-orix\/","url_meta":{"origin":1451017,"position":1},"title":"Canciller de Guatemala recorre frontera entre Estados Unidos y M\u00e9xico con autoridades estadounidenses","author":"","date":"marzo 16, 2025","format":false,"excerpt":"La Canciller\u00eda de Guatemala inform\u00f3 este domingo que el ministro de Relaciones Exteriores guatemalteco, Carlos Ramiro Mart\u00ednez, se reuni\u00f3 con autoridades del Centro de Informaci\u00f3n de Aduanas y Protecci\u00f3n Fronteriza (CBP, por sus siglas en ingl\u00e9s) en Eagle Pass, Texas, en la frontera entre M\u00e9xico y Estados Unidos.\u201cEn el marco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456323,"url":"https:\/\/noticiasya.com\/kansas\/2024\/12\/06\/trump-candidatos-ice-cbp-inmigracion-trump-trax\/","url_meta":{"origin":1451017,"position":2},"title":"Trump anuncia a sus elegidos para el ICE y la CBP, dos cargos clave en materia de inmigraci\u00f3n","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"El presidente electo de Estados Unidos, Donald Trump, anunci\u00f3 a sus candidatos para dirigir la Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP) y el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE), dos organismos clave en la pol\u00edtica de inmigraci\u00f3n, a medida que completa el equipo que se encargar\u00e1 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443670,"url":"https:\/\/noticiasya.com\/kansas\/2024\/01\/14\/una-mujer-y-dos-ninos-se-ahogaron-en-el-rio-grande-gobierno-de-texas-habria-impedido-otorgarles-asistencia-confirma-seguridad-nacional\/","url_meta":{"origin":1451017,"position":3},"title":"Una mujer y dos ni\u00f1os se ahogaron en el r\u00edo Grande; Gobierno de Texas habr\u00eda impedido otorgarles asistencia, confirma Seguridad Nacional","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN) -- El Departamento de Seguridad Nacional confirm\u00f3 el s\u00e1bado que una mujer y sus dos hijos se ahogaron en el r\u00edo Grande el viernes por la noche mientras intentaban cruzar a Estados Unidos. Los migrantes murieron en el \u00e1rea de Shelby Park en Eagle Pass, donde el Gobierno de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443073,"url":"https:\/\/noticiasya.com\/kansas\/2024\/01\/02\/el-gobierno-de-joe-biden-pide-a-la-corte-suprema-que-permita-a-la-patrulla-fronteriza-retirar-el-alambre-de-puas-en-la-frontera-entre-ee-uu-y-mexico\/","url_meta":{"origin":1451017,"position":4},"title":"El Gobierno de Joe Biden pide a la Corte Suprema que permita a la Patrulla Fronteriza retirar el alambre de p\u00faas en la frontera entre EE.UU. y M\u00e9xico","author":"","date":"enero 2, 2024","format":false,"excerpt":"(CNN) -- El Gobierno de Biden pidi\u00f3 a la Corte Suprema que permitiera a la Patrulla Fronteriza de Estados Unidos retirar el alambre de p\u00faas en la frontera entre M\u00e9xico y EE.UU., una nueva escalada en la disputa entre el presidente de EE.UU., Joe Biden, y el gobernador republicano de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443077,"url":"https:\/\/noticiasya.com\/kansas\/2024\/01\/03\/el-gobierno-de-joe-biden-pide-a-la-corte-suprema-que-permita-a-la-patrulla-fronteriza-retirar-el-alambre-de-puas-en-la-frontera-entre-ee-uu-y-mexico-2\/","url_meta":{"origin":1451017,"position":5},"title":"El Gobierno de Joe Biden pide a la Corte Suprema que permita a la Patrulla Fronteriza retirar el alambre de p\u00faas en la frontera entre EE.UU. y M\u00e9xico","author":"","date":"enero 3, 2024","format":false,"excerpt":"(CNN) -- El Gobierno de Biden pidi\u00f3 a la Corte Suprema que permitiera a la Patrulla Fronteriza de Estados Unidos retirar el alambre de p\u00faas en la frontera entre M\u00e9xico y EE.UU., una nueva escalada en la disputa entre el presidente de EE.UU., Joe Biden, y el gobernador republicano de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1451017"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451017\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1451017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1451017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1451017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}