{"id":1451024,"date":"2024-07-10T20:03:44","date_gmt":"2024-07-11T03:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/"},"modified":"2024-07-10T20:03:44","modified_gmt":"2024-07-11T03:03:44","slug":"evo-morales-aristegui-entrevista-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","title":{"rendered":"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\u00fa\u00f1iga"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Evo Morales, expresidente de Bolivia y l\u00edder del oficialista Movimiento al Socialismo (MAS), dijo que el levantamiento de militares en Bolivia el 26 de junio fue un &#171;show bien montado entre el presidente Lucho Arce con el comandante de entonces Juan Z\u00fa\u00f1iga&#187;. En entrevista con Carmen Aristegui en CNN, el exmandatario dijo que el hecho fue un &#171;golpe a la econom\u00eda&#187; porque hizo crecer las especulaciones y que el d\u00f3lar paralelo se dispar\u00f3.<\/p>\n<p>&#171;\u00bfGolpe, autogolpe? S\u00ed, es un hecho bien mentado, me imagino entre el presidente y el comandante, porque el comandante era su amigo, su compa\u00f1ero de mucha confianza&#187;, dijo Morales a Carmen Aristegui.<\/p>\n<p>El expresidente Morales ha acusado anteriormente \u2014sin ofrecer pruebas\u2014 al presidente Luis Arce de montar un autogolpe. El Gobierno del presidente Luis Arce lo ha catalogado como un intento de golpe de Estado.<\/p>\n<p>Luis Arce desmiente acusaciones de autogolpe de Estado<\/p>\n<p>El levantamiento \u2014que se prolong\u00f3 durante unas horas, gener\u00f3 incertidumbre entre la poblaci\u00f3n y fue condenado por la comunidad internacional\u2014 se produjo bajo el liderazgo del general Juan Jos\u00e9 Z\u00fa\u00f1iga, ya destituido como jefe del Ej\u00e9rcito, detenido e imputado por los delitos de terrorismo y alzamiento armado.<\/p>\n<p>El presidente Arce rechaz\u00f3 los se\u00f1alamientos de Z\u00fa\u00f1iga en el sentido de que lo ocurrido pudo haber sido un autogolpe. Z\u00fa\u00f1iga incluso afirm\u00f3 que fue Arce quien le orden\u00f3 actuar y que lo hizo para subir sus niveles de popularidad, algo que el mandatario niega.<\/p>\n<p>\u201cNosotros no har\u00edamos ning\u00fan show para elevar la popularidad, nosotros sabemos la aceptaci\u00f3n que tenemos en la poblaci\u00f3n y los retos que tenemos ah\u00ed al frente, que los estamos superando gradualmente\u201d, dijo Arce.<\/p>\n<p>&#171;Medios internacionales resaltan que el fallido golpe solo ha logrado que Bolivia parezca m\u00e1s inestable para las inversiones. Esto s\u00ed, realmente ha sido un golpe a la econom\u00eda&#187;, dijo Morales en la entrevista, y pidi\u00f3 que haya una investigaci\u00f3n transparente para aclarar qu\u00e9 ocurri\u00f3 el 26 de junio.<\/p>\n<p>Evo Morales dijo que que hay cosas \u201csospechosas\u201d sobre el intento de golpe de Estado.<\/p>\n<p>El se\u00f1alamiento de Evo Morales<\/p>\n<p>&#171;Lucho falt\u00f3 el respeto a la verdad, nos enga\u00f1\u00f3, minti\u00f3. No s\u00f3lo al pueblo boliviano sino al mundo entero&#187;, dijo Evo Morales en una entrevista en l\u00ednea en la Radio Kawsachun Coca el 30 de junio.<\/p>\n<p>Morales indic\u00f3 que ha recibido informaci\u00f3n de una fuente militar de que la operaci\u00f3n del mi\u00e9rcoles estaba planificada y dijo que esos detalles lo estaban &#171;convenciendo de que es un autogolpe&#187;.<\/p>\n<p>Dictan prisi\u00f3n preventiva al general Juan Jos\u00e9 Z\u00fa\u00f1iga por intento de golpe de Estado en Bolivia<\/p>\n<p>Estas declaraciones contrastan con lo dicho d\u00edas antes en la red social X, cuando Morales denunci\u00f3 la operaci\u00f3n en la que unidades militares con veh\u00edculos blindados llegaron a la sede del Ejecutivo y hasta convoc\u00f3 a movilizaciones nacionales para &#171;defender la democracia&#187;.<\/p>\n<p>Morales luego public\u00f3 de nuevo en la red social y dijo que era &#171;lamentable que se use un tema tan sensible como la denuncia de un golpe&#187;.<\/p>\n<p>&#171;Frente a esa realidad, debo pedir disculpas a la comunidad internacional por la alarma generada y agradecer por su solidaridad con nuestro pa\u00eds. Es importante que una investigaci\u00f3n completa e independiente demuestre la verdad de este hecho&#187;, agreg\u00f3 Morales.<\/p>\n<p>Arce dijo antes en conferencia de prensa que mientras se llevaba a cabo el intento de golpe de Estado, \u00e9l le llam\u00f3 directamente a Morales para advertirle sobre lo que ocurr\u00eda.<\/p>\n<p>\u00bfTen\u00eda el Gobierno boliviano conocimiento previo del intento de golpe de Estado? Habla la ministra de la Presidencia<\/p>\n<p>Las diferencias de Luis Arce y Evo Morales<\/p>\n<p>Morales y Arce han aceptado p\u00fablicamente que tienen diferencias, en especial luego de que el expresidente externara su intenci\u00f3n de competir en las pr\u00f3ximas elecciones presidenciales y que se agudizaron luego de que el Tribunal Supremo Electoral (TSE) anul\u00f3 el congreso del MAS que se celebr\u00f3 en octubre de 2023 y al que asistieron las corrientes del partido que apoyan a Morales, que lo ratificaron como dirigente y lo eligieron candidato \u00fanico presidencial para 2025. La decisi\u00f3n del TSE invalid\u00f3 la candidatura de Morales.<\/p>\n<p>Con informaci\u00f3n de Marlon Sorto, Cristopher Ulloa, Abel Alvarado y Mauricio Torres<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Evo Morales, expresidente de Bolivia y l\u00edder del oficialista Movimiento al Socialismo (MAS), dijo que el levantamiento de militares en Bolivia el 26 de junio fue un &#171;show bien montado entre el presidente Lucho Arce con el comandante de entonces Juan Z\u00fa\u00f1iga&#187;. En entrevista con Carmen Aristegui en CNN, el exmandatario dijo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451024","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Evo Morales: Intento de golpe de Estado fue un &quot;show bien montado&quot; entre Arce y Z\u00fa\u00f1iga - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evo Morales: Intento de golpe de Estado fue un &quot;show bien montado&quot; entre Arce y Z\u00fa\u00f1iga - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Evo Morales, expresidente de Bolivia y l\u00edder del oficialista Movimiento al Socialismo (MAS), dijo que el levantamiento de militares en Bolivia el 26 de junio fue un &#171;show bien montado entre el presidente Lucho Arce con el comandante de entonces Juan Z\u00fa\u00f1iga&#187;. En entrevista con Carmen Aristegui en CNN, el exmandatario dijo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T03:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\u00fa\u00f1iga\",\"datePublished\":\"2024-07-11T03:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/\"},\"wordCount\":753,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/\",\"name\":\"Evo Morales: Intento de golpe de Estado fue un \\\"show bien montado\\\" entre Arce y Z\u00fa\u00f1iga - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-11T03:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\u00fa\u00f1iga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evo Morales: Intento de golpe de Estado fue un \"show bien montado\" entre Arce y Z\u00fa\u00f1iga - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Evo Morales: Intento de golpe de Estado fue un \"show bien montado\" entre Arce y Z\u00fa\u00f1iga - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Evo Morales, expresidente de Bolivia y l\u00edder del oficialista Movimiento al Socialismo (MAS), dijo que el levantamiento de militares en Bolivia el 26 de junio fue un &#171;show bien montado entre el presidente Lucho Arce con el comandante de entonces Juan Z\u00fa\u00f1iga&#187;. En entrevista con Carmen Aristegui en CNN, el exmandatario dijo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-11T03:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/"},"author":{"name":"","@id":""},"headline":"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\u00fa\u00f1iga","datePublished":"2024-07-11T03:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/"},"wordCount":753,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","name":"Evo Morales: Intento de golpe de Estado fue un \"show bien montado\" entre Arce y Z\u00fa\u00f1iga - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-11T03:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\u00fa\u00f1iga"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\u00fa\u00f1iga","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-11T03:03:44Z","datePublished":"2024-07-11T03:03:44Z","dateModified":"2024-07-11T03:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\\u00fa\\u00f1iga\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/10\\\/evo-morales-aristegui-entrevista-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/10\\\/evo-morales-aristegui-entrevista-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-11T03:03:44Z\",\"datePublished\":\"2024-07-11T03:03:44Z\",\"dateModified\":\"2024-07-11T03:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450759,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/27\/arche-rechaza-acusaciones-supuesto-autogolpe-estado-bolivia-orix\/","url_meta":{"origin":1451024,"position":0},"title":"Arce rechaza acusaciones sobre supuesto autogolpe de Estado en Bolivia","author":"","date":"junio 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un d\u00eda despu\u00e9s del intento de golpe de Estado en Bolivia, el presidente Luis Arce rechaz\u00f3 las acusaciones del general detenido por encabezar estos hechos, Juan Jos\u00e9 Z\u00fa\u00f1iga, quien la noche del mi\u00e9rcoles dijo que fue el mandatario quien le orden\u00f3 ejecutar un autogolpe que le ayudara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450832,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/01\/gobierno-bolivia-convoca-embajador-argentina-declaraciones-milei-intento-golpe-estado-orix\/","url_meta":{"origin":1451024,"position":1},"title":"El Gobierno de Bolivia convoca a su embajador en Argentina tras declaraciones de Milei sobre intento de golpe de Estado","author":"","date":"julio 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno de Bolivia convoc\u00f3 este lunes a consulta a su embajador en Argentina, Ramiro Tapia, ante las declaraciones de la Oficina del presidente Javier Milei que se\u00f1al\u00f3 como \u201cfalsa\u201d la denuncia de golpe de Estado del 26 de junio.La ministra de la Presidencia de Bolivia, Maria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451023,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/10\/alcalde-la-paz-herido-manifestacion-evo-morales-orix\/","url_meta":{"origin":1451024,"position":2},"title":"Alcalde de La Paz resulta herido durante manifestaci\u00f3n de simpatizantes de Evo Morales","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El alcalde de La Paz, Iv\u00e1n Arias, result\u00f3 herido durante una manifestaci\u00f3n de simpatizantes del expresidente boliviano Evo Morales que acudieron al exterior del Tribunal Supremo Electoral (TSE), donde este mi\u00e9rcoles se realiza el \u201cEncuentro multipartidario e interinstitucional por la democracia\u201d, de acuerdo con la agencia estatal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452077,"url":"https:\/\/noticiasya.com\/kansas\/2024\/08\/22\/luis-arce-referendo-reeleccion-bolivia-evo-morales-orix\/","url_meta":{"origin":1451024,"position":3},"title":"Luis Arce propone un referendo sobre la reelecci\u00f3n presidencial en Bolivia y Evo Morales lo acusa de querer frenar sus aspiraciones","author":"","date":"agosto 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Bolivia, Luis Arce, propuso formalmente realizar un referendo en el que se pregunte a la ciudadan\u00eda si estar\u00eda de acuerdo o no en ampliar la reelecci\u00f3n presidencial. El planteamiento fue rechazado por el expresidente Evo Morales \u2014compa\u00f1ero de partido de Arce, aunque ambos mantienen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450732,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/26\/bolivia-fallido-golpe-estado-soldados-armados-tension-defensa-democracia-trax\/","url_meta":{"origin":1451024,"position":4},"title":"Soldados armados, tensi\u00f3n en las calles y el llamado a la defensa de la democracia: as\u00ed se vivi\u00f3 el fracasado intento de golpe de Estado en Bolivia","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN) -- El presidente de Bolivia, Luis Arce, hizo frente este mi\u00e9rcoles a un intento de golpe de Estado de corta duraci\u00f3n, tras llamar a la ciudadan\u00eda a \"organizarse y movilizarse\" en defensa de la democracia, mientras soldados y veh\u00edculos militares blindados rodeaban edificios gubernamentales en La Paz.\"No podemos permitir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1454948,"url":"https:\/\/noticiasya.com\/kansas\/2024\/10\/04\/evo-morales-acusa-luis-arce-de-promover-proceso-penales-orix\/","url_meta":{"origin":1451024,"position":5},"title":"Evo Morales acusa a Luis Arce de promover procesos penales en su contra \u201ccon cualquier calumnia\u201d","author":"","date":"octubre 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El expresidente de Bolivia Evo Morales acus\u00f3 este viernes al presidente Luis Arce de promover procesos penales en su contra con el fin \u2014seg\u00fan dijo\u2014 de inhabilitarlo para impedir que compita en las elecciones presidenciales de 2025.Morales hizo estas declaraciones durante una rueda de prensa en Cochabamba, dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1451024"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451024\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1451024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1451024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1451024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}