{"id":1451060,"date":"2024-07-11T19:03:46","date_gmt":"2024-07-12T02:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/"},"modified":"2024-07-11T19:03:46","modified_gmt":"2024-07-12T02:03:46","slug":"onu-petro-plazo-colombia-acuerdos-paz-farc-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/","title":{"rendered":"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, dijo este jueves ante el Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) que su pa\u00eds se ha esforzado por implementar los acuerdos de paz con la desmovilizada guerrilla de las Fuerzas Armadas Revolucionarias de Colombia (FARC), y plante\u00f3 extender siete a\u00f1os el plazo para cumplirlos ante diversas dificultades.<\/p>\n<p>Los acuerdos se firmaron en 2016, durante el mandato del entonces presidente Juan Manuel Santos, cuando se fij\u00f3 un plazo de 15 a\u00f1os para su cumplimiento. Petro, cuya gesti\u00f3n empez\u00f3 en agosto de 2022, argumenta que la aprobaci\u00f3n de normas necesarias para la implementaci\u00f3n fue lenta, lo que a su vez ha retrasado todo el proceso de pacificaci\u00f3n.<\/p>\n<p>Para ello, dijo este jueves ante el Consejo de Seguridad, plantear\u00e1 en Colombia un mecanismo para agilizar las legislaciones pendientes, en particular para temas como la reforma rural, la integraci\u00f3n territorial y el sistema de verdad y justicia.<\/p>\n<p>\u201cVoy a proponerle al Congreso de Colombia y a las cortes y a la sociedad, indudablemente, repetir un fast track. Le llamaron as\u00ed en ingl\u00e9s en Colombia a un m\u00e9todo m\u00e1s r\u00e1pido para aprobar leyes en el Congreso de la Rep\u00fablica. Ya se hizo, pero los proyectos de aquella \u00e9poca, gobierno Santos, tuvieron que ver con las fases iniciales del acuerdo de paz con las FARC, y ahora tenemos que presentar los cambios de normas que permitan los productos del acuerdo de paz\u201d, expuso.<\/p>\n<p>Santos se\u00f1ala ante la ONU que el acuerdo de paz con las FARC no incluye convocatoria a una Asamblea Constituyente, como sostiene el Gobierno de Petro<\/p>\n<p>\u201cEstas son medidas de ley, no est\u00e1n determinadas por el presidente, tampoco por las FARC. Tienen que ser medidas del Estado, para ser aprobadas tendr\u00edan que ser parte de un pacto nacional, que es lo que no se ha podido producir desde el 2016. En un procedimiento fast track nos llevar\u00eda a reducir los plazos de tiempo para cumplir con efectividad el acuerdo de paz firmado. Lo vamos a presentar, pues, a la sociedad colombiana, pero quisi\u00e9ramos dejarla aqu\u00ed refrendada ante ustedes\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Petro acudi\u00f3 ante el Consejo de Seguridad para dar un informe sobre los avances en los acuerdos con las FARC. Durante su intervenci\u00f3n, tambi\u00e9n dijo que Colombia tiene dificultades financieras para cumplir lo acordado \u2014para lo cual pidi\u00f3 apoyo de la comunidad internacional.<\/p>\n<p>Se\u00f1al\u00f3 que, igual que en 2016 se cre\u00f3 una Misi\u00f3n de Verificaci\u00f3n de la ONU para revisar el estatus de lo pactado, ser\u00eda \u00fatil para su pa\u00eds que se creara una instancia adicional espec\u00edficamente para acompa\u00f1ar las investigaciones por los presuntos homicidios de exguerrilleros, una situaci\u00f3n que \u2014expuso\u2014 obstaculiza la pacificaci\u00f3n.<\/p>\n<p>\u201cYo les voy a solicitar, como jefe del Estado, que se configure una misi\u00f3n internacional complementaria de apoyo a la investigaci\u00f3n judicial del grupo especial de investigaciones de la Fiscal\u00eda, para establecer los autores intelectuales y materiales del asesinato sistem\u00e1tico de combatientes, excombatientes que han firmado paz, y para detener el surgimiento de grupos neoparamilitares\u201d, se\u00f1al\u00f3 el mandatario.<\/p>\n<p>Los miembros del Consejo de Seguridad dijeron que Colombia ha hecho esfuerzos por implementar los acuerdos, pero advirtieron que el camino a la pacificaci\u00f3n a\u00fan es largo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, dijo este jueves ante el Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) que su pa\u00eds se ha esforzado por implementar los acuerdos de paz con la desmovilizada guerrilla de las Fuerzas Armadas Revolucionarias de Colombia (FARC), y plante\u00f3 extender siete a\u00f1os el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451060","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, dijo este jueves ante el Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) que su pa\u00eds se ha esforzado por implementar los acuerdos de paz con la desmovilizada guerrilla de las Fuerzas Armadas Revolucionarias de Colombia (FARC), y plante\u00f3 extender siete a\u00f1os el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T02:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC\",\"datePublished\":\"2024-07-12T02:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/\",\"name\":\"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-12T02:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, dijo este jueves ante el Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) que su pa\u00eds se ha esforzado por implementar los acuerdos de paz con la desmovilizada guerrilla de las Fuerzas Armadas Revolucionarias de Colombia (FARC), y plante\u00f3 extender siete a\u00f1os el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-12T02:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/"},"author":{"name":"","@id":""},"headline":"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC","datePublished":"2024-07-12T02:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/","name":"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-12T02:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ante la ONU, Petro plantea ampliar 7 a\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/11\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-12T02:03:46Z","datePublished":"2024-07-12T02:03:46Z","dateModified":"2024-07-12T02:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ante la ONU, Petro plantea ampliar 7 a\\u00f1os el plazo para que Colombia cumpla los acuerdos de paz con las FARC\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/11\\\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/11\\\/onu-petro-plazo-colombia-acuerdos-paz-farc-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-12T02:03:46Z\",\"datePublished\":\"2024-07-12T02:03:46Z\",\"dateModified\":\"2024-07-12T02:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450995,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/09\/petro-onu-plazo-acuerdos-paz-guerrilla-farc-orix\/","url_meta":{"origin":1451060,"position":0},"title":"Petro pedir\u00e1 ante la ONU ampliar el plazo para cumplir los acuerdos de paz con la desmovilizada guerrilla de las FARC","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Colombia, Gustavo Petro, rendir\u00e1 este jueves un informe ante el Consejo de Seguridad de Naciones Unidas, donde expondr\u00e1 las dificultades que han tenido en la implementaci\u00f3n del acuerdo de paz firmado en 2016 entre el gobierno del entonces presidente Juan Manuel Santos y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450117,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/06\/petro-onu-asamblea-constituyente-colombia-orix\/","url_meta":{"origin":1451060,"position":1},"title":"El presidente Petro niega que llevar\u00e1 a la ONU el tema de una convocatoria a una Asamblea Constituyente en Colombia","author":"","date":"junio 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En medio de la controversia pol\u00edtica en Colombia por la posibilidad de una convocatoria a una Asamblea Constituyente por parte del Gobierno de Gustavo Petro \u2014esto por la interpretaci\u00f3n de un p\u00e1rrafo del acuerdo de paz firmado con las FARC en 2016\u2014, el mandatario neg\u00f3 este jueves\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450024,"url":"https:\/\/noticiasya.com\/kansas\/2024\/06\/04\/santos-onu-acuerdo-paz-colombia-constituyente-orix\/","url_meta":{"origin":1451060,"position":2},"title":"Santos se\u00f1ala ante la ONU que el acuerdo de paz con las FARC no incluye convocatoria a una Asamblea Constituyente, como sostiene el Gobierno de Petro","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El expresidente de Colombia y Premio Nobel de la Paz 2016, Juan Manuel Santos, se\u00f1al\u00f3 en una carta enviada al secretario general de las Naciones Unidas, Ant\u00f3nio Guterres, que el acuerdo de paz firmado en 2016 con la antigua guerrilla de las FARC no prev\u00e9 en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452843,"url":"https:\/\/noticiasya.com\/kansas\/2024\/09\/19\/analisis-politica-paz-petro-violencia-colombia-orix\/","url_meta":{"origin":1451060,"position":3},"title":"AN\u00c1LISIS | La encrucijada que enfrenta la llamada pol\u00edtica de \u201cpaz total\u201d de Petro en medio de una ola de violencia en Colombia","author":"","date":"septiembre 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 En medio de procesos de paz con grupos armados ilegales, ceses del fuego bilaterales y anuncios de conversaciones, incluso con bandas criminales al servicio del narcotr\u00e1fico como el llamado Clan del Golfo, la violencia en Colombia parece no tener contenci\u00f3n ni dar tregua. El hecho m\u00e1s reciente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449612,"url":"https:\/\/noticiasya.com\/kansas\/2024\/05\/20\/petro-nuevo-comandante-ejercito-mayor-despliegue-militar-inseguridad-orix\/","url_meta":{"origin":1451060,"position":4},"title":"Petro nombra a un nuevo comandante del Ej\u00e9rcito mientras busca un mayor despliegue militar contra la inseguridad","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de Colombia, Gustavo Petro, nombr\u00f3 este lunes al mayor general retirado Luis Emilio Cardozo Santamar\u00eda como nuevo comandante del Ej\u00e9rcito, una decisi\u00f3n con la que el Gobierno busca \u201ccontinuar fortaleciendo la seguridad y defensa de la naci\u00f3n\u201d, inform\u00f3 el Ministerio de Defensa en un comunicado.El nombramiento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457692,"url":"https:\/\/noticiasya.com\/kansas\/2025\/01\/21\/petro-estado-de-conmocion-interior-catatumbo-orix\/","url_meta":{"origin":1451060,"position":5},"title":"Petro declara estado de conmoci\u00f3n interior tras los hechos de violencia en el Catatumbo","author":"","date":"enero 21, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, declar\u00f3 el lunes estado de conmoci\u00f3n interior y de emergencia econ\u00f3mica, luego de los hechos de violencia ocurridos desde el jueves en la regi\u00f3n del Catatumbo, en el noreste del pa\u00eds, donde al menos 80 personas han muerto en enfrentamientos de la guerrilla del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1451060"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451060\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1451060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1451060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1451060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}