{"id":1451076,"date":"2024-07-12T14:03:38","date_gmt":"2024-07-12T21:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/"},"modified":"2024-07-12T14:03:38","modified_gmt":"2024-07-12T21:03:38","slug":"gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/","title":{"rendered":"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0\u201cDelito de adulto, pena de adulto\u201d. As\u00ed defend\u00eda Javier Milei el proyecto presentado por los ministros de Seguridad y de Justicia \u2013Patricia Bullrich y Mariano C\u00faneo Libarona, respectivamente\u2013 para bajar la edad de imputabilidad en Argentina.<\/p>\n<p>Fue una de sus promesas de campa\u00f1a \u2013con la que\u00a0tambi\u00e9n coincid\u00edan los candidatos Sergio Massa, Horacio Rodr\u00edguez Larreta y\u00a0 Bullrich, por entonces contrincante al frente de Juntos por el Cambio\u2013 que finalmente\u00a0su gobierno present\u00f3 como proyecto de\u00a0ley a finales de junio.<\/p>\n<p>Luego de un debate respecto de la edad m\u00ednima con la que se puede juzgar a un menor por un delito, finalmente el oficialismo coincidi\u00f3 en que el l\u00edmite llegar\u00e1 a los 13 a\u00f1os. En la actualidad, la edad m\u00ednima para juzgar a un menor en Argentina es de 16 a\u00f1os, la misma que se necesita para ejercer el voto.<\/p>\n<p>Durante la presentaci\u00f3n, Bullrich y C\u00faneo Libarona coincidieron en que \u201cresulta imposible combatir a los delincuentes sin leyes que amparen a las Fuerzas Federales de Seguridad y a la Justicia a la hora de proteger a los argentinos de bien. Es por eso que, por decisi\u00f3n del presidente Milei, los equipos conjuntos del Ministerio de Seguridad y del Ministerio de Justicia trabajaron en la redacci\u00f3n del Proyecto de Baja de Edad de Imputabilidad, con el objetivo de terminar con la impunidad, frenar la puerta giratoria y darle respuesta a la gente\u201d.<\/p>\n<p>Prisi\u00f3n en Argentina (Cr\u00e9dito EITAN ABRAMOVICH\/AFP via Getty Images)<\/p>\n<p>Principales puntos del proyecto<\/p>\n<p>Desde ambos ministerios dieron a conocer algunos de los puntos m\u00e1s destacados del proyecto de Ley del R\u00e9gimen Penal Juvenil. Adem\u00e1s del cambio en la edad m\u00ednima para poder ser juzgado, la presentaci\u00f3n explica que los menores que sean privados de su libertad estar\u00e1n en \u201cestablecimientos especiales o secciones separadas de los establecimientos penitenciarios, bajo la direcci\u00f3n de personal id\u00f3neo\u201d, es decir que no tendr\u00e1n contacto con presos mayores de edad.<\/p>\n<p>Adem\u00e1s, asegura los \u201cderechos y garant\u00edas reconocidos en la Constituci\u00f3n Nacional y los instrumentos internacionales\u201d, y establece que en el caso de las penas de entre 3 y 6 a\u00f1os en las que no haya \u201cexistido muerte de la v\u00edctima, grave violencia f\u00edsica o ps\u00edquica sobre las personas, no haya lesiones grav\u00edsimas en delitos culposos y no se registren otros procesos o condenas\u201d, el menor tendr\u00e1 la oportunidad de reemplazar dicha sanci\u00f3n por \u201camonestaci\u00f3n, prohibici\u00f3n de aproximarse a la v\u00edctima o sus familiares, prohibici\u00f3n de conducir veh\u00edculos, prohibici\u00f3n de concurrir a determinados lugares, prohibici\u00f3n de salir del pa\u00eds o de un \u00e1mbito territorial, prestaci\u00f3n de servicios a la comunidad y monitoreo electr\u00f3nico\u201d.<\/p>\n<p>Por otra parte, establece penas m\u00e1ximas de 20 a\u00f1os que podr\u00e1n ser revisadas al cumplirse dos tercios de su cumplimiento y penas m\u00e1s severas en caso de incumplimiento.<\/p>\n<p>Un punto relevante es la inclusi\u00f3n de la v\u00edctima: seg\u00fan explican desde los ministerios, de sancionarse la ley\u00a0\u201cel cumplimiento de las penas deber\u00e1 ser verificado por el juez o el fiscal. Tambi\u00e9n por la v\u00edctima, si es su deseo\u201c. Por \u00faltimo, se invita a las provincias a adherir los c\u00f3digos provinciales al c\u00f3digo nacional.<\/p>\n<p>Cr\u00edticas a los cambios<\/p>\n<p>Asociaciones a favor de los derechos del ni\u00f1o\u00a0se pronunciaron en contra de medidas como la que propone el Gobierno de Argentina.\u00a0Por ejemplo, en el documento \u201cIdeas para contribuir al debate sobre la Ley de Justicia Penal Juvenil\u201d que publica el Fondo de las Naciones Unidas para la Infancia, Unicef por sus siglas en ingl\u00e9s,\u00a0aseguran que es de suma importancia que \u201cArgentina tenga una Ley de Justicia Penal Juvenil en l\u00ednea con los est\u00e1ndares internacionales\u201d.<\/p>\n<p>En ese sentido, se pronuncian en contra de la baja en la edad con la que se puede juzgar a los menores en el pa\u00eds: \u201cEn Argentina la reforma del sistema de justicia penal juvenil no requiere bajar la edad de punibilidad, algo que podr\u00eda ser interpretado como un retroceso en materia de derechos humanos y como una medida regresiva. Existen experiencias internacionales que han demostrado que disminuir la edad de punibilidad no ha sido una medida efectiva en el combate a la inseguridad\u201d.<\/p>\n<p>Y agregan ejemplos de pa\u00edses en los que se baj\u00f3 la edad de imputabilidad y luego volvi\u00f3 a elevarse al no registrar mejoras en los casos de inseguridad: Dinamarca, en 2010, baja la edad de 15 a 14 a\u00f1os y en 2012 la sube a 15 nuevamente, y Georgia, donde bajaron la edad a 12 a\u00f1os y luego, en 2010, fue elevada a 14.<\/p>\n<p>Prisi\u00f3n en Argentina (Cr\u00e9dito EITAN ABRAMOVICH \/ AFP) (Photo credit should read EITAN ABRAMOVICH\/AFP via Getty Images)<\/p>\n<p>Las experiencias en pa\u00edses de la regi\u00f3n<\/p>\n<p>En pa\u00edses como Chile o Uruguay, la ley distingue la situaci\u00f3n de los menores de edad de la de los mayores de 18 a\u00f1os.<\/p>\n<p>En Chile, si bien la edad de imputabilidad es de 18 a\u00f1os, hay un sistema de justicia penal especial, como en los otros pa\u00edses, para mayores de 14 a\u00f1os. Seg\u00fan la Ley 20.084 \u201ctodos los y las adolescentes entre 14 y 17 a\u00f1os que son responsables ante la ley penal, tienen derecho a defensa gratuita y especializada, y en el evento de ser condenados a sanciones privativas de libertad, no ser\u00e1n derivados a recintos carcelarios adultos, sino a centros especiales para adolescentes. Adem\u00e1s, reciben un conjunto de garant\u00edas, como acceso a educaci\u00f3n y programas de rehabilitaci\u00f3n antidrogas y alcohol\u201d.<\/p>\n<p>Adem\u00e1s, distingue la responsabilidad penal en dos segmentos: de 14 a 16 a\u00f1os y de 16 a 17 a\u00f1os, y s\u00f3lo se establecen penas privativas de libertad para delitos graves.<\/p>\n<p>En el caso de Uruguay, en el art\u00edculo 34 del C\u00f3digo Penal se explica que \u201cno es imputable el que ejecuta el hecho antes de haber cumplido la edad de 18 a\u00f1os\u201d. Sin embargo, en el C\u00f3digo de la Ni\u00f1ez y Adolescencia se indica cu\u00e1les son las infracciones a la ley penal por parte de adolescentes y asegura que \u201cs\u00f3lo puede ser sometido a proceso especial, regulado por este C\u00f3digo, el adolescente mayor de 13 y menor de 18 a\u00f1os de edad, imputado de infracci\u00f3n a la ley penal\u201d.<\/p>\n<p>El C\u00f3digo Penal de Brasil establece en su art\u00edculo 27 que \u201clos menores de 18 a\u00f1os no son penalmente responsables, quedando sujetos a las normas establecidas en legislaci\u00f3n especial\u201d.<\/p>\n<p>Para los adolescentes de entre 12 y 17 a\u00f1os se aplica un r\u00e9gimen diferenciado que est\u00e1 contemplado en el Estatuto del Ni\u00f1o y del Adolescente y no en el C\u00f3digo Penal. De comprobarse \u201cla comisi\u00f3n de una infracci\u00f3n, la autoridad competente podr\u00e1 solicitar al adolescente las siguientes medidas: advertencia, obligaci\u00f3n de reparar el da\u00f1o, prestaci\u00f3n de servicios a la comunidad, libertad asistida, inserci\u00f3n en semilibertad u\u00a0 internaci\u00f3n\u00a0en un establecimiento educativo\u201d, entre otras.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0\u201cDelito de adulto, pena de adulto\u201d. As\u00ed defend\u00eda Javier Milei el proyecto presentado por los ministros de Seguridad y de Justicia \u2013Patricia Bullrich y Mariano C\u00faneo Libarona, respectivamente\u2013 para bajar la edad de imputabilidad en Argentina. Fue una de sus promesas de campa\u00f1a \u2013con la que\u00a0tambi\u00e9n coincid\u00edan los candidatos Sergio Massa, Horacio Rodr\u00edguez [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451076","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0\u201cDelito de adulto, pena de adulto\u201d. As\u00ed defend\u00eda Javier Milei el proyecto presentado por los ministros de Seguridad y de Justicia \u2013Patricia Bullrich y Mariano C\u00faneo Libarona, respectivamente\u2013 para bajar la edad de imputabilidad en Argentina. Fue una de sus promesas de campa\u00f1a \u2013con la que\u00a0tambi\u00e9n coincid\u00edan los candidatos Sergio Massa, Horacio Rodr\u00edguez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T21:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina\",\"datePublished\":\"2024-07-12T21:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/\"},\"wordCount\":1229,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/\",\"name\":\"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-12T21:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0\u201cDelito de adulto, pena de adulto\u201d. As\u00ed defend\u00eda Javier Milei el proyecto presentado por los ministros de Seguridad y de Justicia \u2013Patricia Bullrich y Mariano C\u00faneo Libarona, respectivamente\u2013 para bajar la edad de imputabilidad en Argentina. Fue una de sus promesas de campa\u00f1a \u2013con la que\u00a0tambi\u00e9n coincid\u00edan los candidatos Sergio Massa, Horacio Rodr\u00edguez [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-12T21:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina","datePublished":"2024-07-12T21:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/"},"wordCount":1229,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/","name":"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-12T21:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPresos a los 13 a\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/12\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-12T21:03:38Z","datePublished":"2024-07-12T21:03:38Z","dateModified":"2024-07-12T21:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPresos a los 13 a\\u00f1os? El Gobierno de Javier Milei impulsa una baja en la edad de imputabilidad en Argentina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/12\\\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/12\\\/gobierno-javier-milei-impulsa-baja-edad-imputabilidad-argentina-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-12T21:03:38Z\",\"datePublished\":\"2024-07-12T21:03:38Z\",\"dateModified\":\"2024-07-12T21:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459291,"url":"https:\/\/noticiasya.com\/kansas\/2025\/02\/27\/conmocion-argentina-muerte-kim-gomez-orix\/","url_meta":{"origin":1451076,"position":0},"title":"Conmoci\u00f3n en Argentina por la muerte de la ni\u00f1a Kim G\u00f3mez, de siete a\u00f1os, en medio de un robo","author":"","date":"febrero 27, 2025","format":false,"excerpt":"Una ni\u00f1a de siete a\u00f1os muri\u00f3 en medio de un robo el martes por la noche en las afueras de la ciudad de La Plata, a unos 50 kil\u00f3metros al sur de Buenos Aires, la capital argentina.Kim Anura G\u00f3mez falleci\u00f3 cuando dos j\u00f3venes, tambi\u00e9n menores de edad, robaron el auto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463554,"url":"https:\/\/noticiasya.com\/kansas\/2025\/06\/14\/menores-imputabilidad-delito-argentina-orix\/","url_meta":{"origin":1451076,"position":1},"title":"Brian ten\u00eda 12 a\u00f1os y ya robaba: la historia que ilustra el debate por la baja de edad de imputabilidad en Argentina","author":"","date":"junio 14, 2025","format":false,"excerpt":"En el centro para menores detenidos Francisco Legarra las puertas no tienen picaporte. Los accesos al exterior, pero tambi\u00e9n entre los ambientes internos de la instituci\u00f3n del sistema penal juvenil, est\u00e1n asegurados. Y las manijas que permiten abrir y cerrarlos son de dominio personal.Cada directivo, miembro del equipo t\u00e9cnico y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462290,"url":"https:\/\/noticiasya.com\/kansas\/2025\/05\/13\/coco-oderigo-y-el-proyecto-de-baja-de-edad-de-imputabilidad-sacar-una-ley-sin-respaldo-posterior-es-una-bomba-de-tiempo\/","url_meta":{"origin":1451076,"position":2},"title":"\u2018Coco\u2019 Oderigo y el proyecto de baja de edad de imputabilidad: &#171;Sacar una ley sin respaldo posterior es una bomba de tiempo&#187;","author":"","date":"mayo 13, 2025","format":false,"excerpt":"Eduardo \u201cCoco\u201d Oderigo, cofundador de Fundaci\u00f3n Espartanos, habl\u00f3 este martes en CNN Radio con Nacho Gir\u00f3n sobre la resocializaci\u00f3n en las c\u00e1rceles, su visi\u00f3n sobre el proyecto para bajar la edad de imputabilidad y la importancia del rol del Estado.\u201cCuanto antes haya una mano del Estado estoy de acuerdo\u201d, opin\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460180,"url":"https:\/\/noticiasya.com\/kansas\/2025\/03\/20\/ana-valverde-de-jubilados-en-lucha-el-gobierno-nos-tiene-en-la-pobreza\/","url_meta":{"origin":1451076,"position":3},"title":"Ana Valverde, referente de los jubilados: &#171;El Gobierno nos tiene en la pobreza&#187;","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Ana Valverde, integrante de la Uni\u00f3n de Trabajadores Jubilados En Lucha (UTJEL), convers\u00f3 con Nacho Gir\u00f3n en La Ma\u00f1ana de CNN sobre las jubilaciones, las marchas de jubilados, el Gobierno Nacional y los precios.\u201cNos tienen bajo la l\u00ednea de pobreza. La jubilaci\u00f3n no son 349 mil pesos porque a eso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459276,"url":"https:\/\/noticiasya.com\/kansas\/2025\/02\/27\/larreta-en-la-manana-de-cnn-en-la-campana-hubiera-mandado-a-la-mierda-a-bullrich\/","url_meta":{"origin":1451076,"position":4},"title":"Larreta en La Ma\u00f1ana de CNN: &#171;En la campa\u00f1a hubiera mandado a la mierda a Bullrich&#187;","author":"","date":"febrero 27, 2025","format":false,"excerpt":"Horacio Rodr\u00edguez Larreta, exjefe de Gobierno porte\u00f1o y excandidato a Presidente, visit\u00f3 este jueves los estudios de CNN Radio Argentina para conversar con Nacho Gir\u00f3n sobre su decisi\u00f3n de regresar a la pol\u00edtica con su candidatura, hizo una fuerte autocr\u00edtica, record\u00f3 el d\u00eda que perdi\u00f3 la interna con Patricia Bullrich,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459383,"url":"https:\/\/noticiasya.com\/kansas\/2025\/03\/01\/milei-asamblea-legislativa-reformas-orix\/","url_meta":{"origin":1451076,"position":5},"title":"Milei habl\u00f3 ante la Asamblea Legislativa y anunci\u00f3 fuertes reformas en Argentina","author":"","date":"marzo 1, 2025","format":false,"excerpt":"Este 1 de marzo, el presidente de Argentina, Javier Milei, habl\u00f3 ante la Asamblea Legislativa durante la inauguraci\u00f3n del 143\u00b0 per\u00edodo de sesiones ordinarias del Congreso Nacional, que se extender\u00e1 hasta el 30 de noviembre.Milei expuso durante casi una hora e hizo un balance de su gesti\u00f3n y del estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1451076"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451076\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1451076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1451076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1451076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}