{"id":1451090,"date":"2024-07-13T08:03:37","date_gmt":"2024-07-13T15:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/"},"modified":"2024-07-13T08:03:37","modified_gmt":"2024-07-13T15:03:37","slug":"por-que-tenistas-visten-blanco-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","title":{"rendered":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?"},"content":{"rendered":"<p>(CNN) &#8212; Pr\u00edstinos, n\u00edtidos y totalmente blancos: los blancos en el tenis han sido una tradici\u00f3n que se remonta a siglos atr\u00e1s. Su aspecto distintivo no s\u00f3lo ha hecho que el deporte de la raqueta se destaque, sino que tambi\u00e9n se ha convertido en un pilar de la vestimenta fuera de las canchas.<\/p>\n<p>Y aunque la mayor\u00eda de los grandes torneos han acabado con la uniformidad del blanco, Wimbledon, el primero de ellos, ha mantenido una pol\u00edtica estricta al respecto (al igual que muchos clubes privados de todo el mundo). El prestigioso campeonato incluso tom\u00f3 medidas dr\u00e1sticas hace una d\u00e9cada, prohibiendo los acentos coloridos que se hab\u00edan vuelto cada vez m\u00e1s comunes, un a\u00f1o despu\u00e9s de que el ahora infame par de zapatillas con suela naranja de Roger Federer fuera prohibido despu\u00e9s de su primera ronda en 2013.<\/p>\n<p>Wimbledon 2024: Jasmine Paolini se enfrenta a Barbora Krej\u010d\u00edkov\u00e1 en la final femenina y ya hacen historia<\/p>\n<p>Las reglas alguna vez exig\u00edan vestimenta &#171;predominantemente blanca&#187;, lo que permit\u00eda a algunos competidores jugar con combinaciones de colores, como el tributo de Serena Williams a Wimbledon con fresas y crema en 2010. Pero la redacci\u00f3n cambi\u00f3 m\u00e1s tarde a &#171;casi completamente blanco&#187;, seg\u00fan los organizadores: no blanquecino, ni paneles de color, ni combinaciones de colores diferentes en las zapatillas. La \u00fanica flexibilizaci\u00f3n reciente de las reglas fue en 2023, para permitir que las mujeres usaran pantalones cortos de colores oscuros en la cancha luego de las cr\u00edticas de que las reglas no se adaptaban a posibles filtraciones por menstruaci\u00f3n.<\/p>\n<p>Naomi Osaka luci\u00f3 un vestido de tenis con vuelo en Wimbledon 2024, respetando la regla de los torneos de vestir todo de blanco y con un logotipo m\u00ednimo, con una excepci\u00f3n para los pantalones cortos de color oscuro, que es un nuevo permiso para las mujeres. (Robert Prange\/Getty Images)<\/p>\n<p>Las zapatillas Nike de suela naranja de Roger Federer fueron prohibidas en Wimbledon tras su partido de primera ronda en 2013, y al a\u00f1o siguiente las normas se endurecieron para los acentos de color. (Clive Brunskill\/Getty Images)<\/p>\n<p>Pero, \u00bfpor qu\u00e9 los blancos en tenis se convirtieron en el est\u00e1ndar? Las razones que se citan a menudo son pr\u00e1cticas, desde el calor hasta el enmascaramiento del sudor. Pero el curador senior Kevin Jones del museo Fashion Institute of Design &#038; Merchandising (FIDM) en Los \u00c1ngeles, quien organiz\u00f3 la reciente exposici\u00f3n itinerante &#171;Sporting Fashion: Outdoor Girls 1800 &#8211; 1960&#187;, dijo que en realidad todo se reduce a una larga historia de clubes que imponen estatus social, y que comenz\u00f3 cuando el tenis sobre c\u00e9sped se dispar\u00f3 en popularidad en la Inglaterra de la \u00e9poca victoriana como deporte de ocio, con la caracter\u00edstica poco com\u00fan para el momento de que se permit\u00eda que las mujeres lo practique.<\/p>\n<p>&#171;Es completamente elitista porque la ropa blanca es dif\u00edcil de mantener&#187;, dijo Jones en una llamada telef\u00f3nica con CNN. &#171;Y los tipos de materiales con los que estaban hechos estos vestidos, que eran algod\u00f3n y lino, se arrugaban f\u00e1cilmente, por lo que mantenerlos bonitos y reci\u00e9n almidonados tambi\u00e9n era un aspecto de ese cuidado&#187;.<\/p>\n<p>La princesa Kate asistir\u00e1 el domingo a la final masculina de Wimbledon<\/p>\n<p>Desafiando las reglas<\/p>\n<p>Por supuesto, el estilo del tenis ha cambiado dr\u00e1sticamente en un siglo y medio desde que se convirti\u00f3 por primera vez en una sensaci\u00f3n recreativa para la clase alta, reci\u00e9n salida del croquet (para el que utilizaba el mismo c\u00e9sped cuidadosamente recortado). La primera vestimenta de tenis se parec\u00eda m\u00e1s a la ropa informal del siglo XIX: las mujeres vest\u00edan prendas a rayas y estampadas con faldas largas, cors\u00e9s y sombreros de ala ancha; los hombres se pon\u00edan pantalones de lana, camisas con botones o su\u00e9teres.<\/p>\n<p>Debido a que los espectadores y los jugadores a menudo compart\u00edan estilos similares, la moda y el tenis han tenido un &#171;intercambio mutuo a lo largo del tiempo, donde varias tendencias del tenis tambi\u00e9n se han filtrado en una cultura m\u00e1s amplia&#187;, dijo el periodista deportivo Ben Rothenberg, autor de &#171;Tennis: The Stylish Life&#187;, as\u00ed como de una biograf\u00eda reciente sobre Naomi Osaka.<\/p>\n<p>Suzanne Lenglen se convirti\u00f3 en una jugadora de primer nivel y en una de las favoritas de la moda por sus dobladillos m\u00e1s cortos y sus pa\u00f1uelos en la cabeza, que le permit\u00edan m\u00e1s movilidad en la pista. (George Rinhart\/Corbis\/Getty Images)<\/p>\n<p>Eso ha sido m\u00e1s que evidente en los \u00faltimos meses, cuando Zendaya present\u00f3 una serie de looks de alfombra roja de alta costura inspirados en el tenis que coincid\u00edan con el drama dentro y fuera de la cancha de la pel\u00edcula &#171;Challengers&#187;, y recientemente, cuando se enfrent\u00f3 a Federer en un &#171;partido de tenis a\u00e9reo&#187; para una campa\u00f1a de la marca de ropa deportiva On. La estrecha alineaci\u00f3n con la moda tambi\u00e9n ha llevado al \u00e9xito de marcas cl\u00e1sicas nacidas del tenis como Lacoste y Fred Perry, as\u00ed como a nuevas innovaciones radicales en la moda introducidas en la cancha, como\u00a0Elsa Schiaparelli vistiendo a la jugadora espa\u00f1ola Lil\u00ed de \u00c1lvarez con culottes, una falda dividida, para Wimbledon en 1931, ante la estupefacci\u00f3n de los espectadores.<\/p>\n<p>Al igual que sucedi\u00f3 De \u00c1lvarez, los c\u00f3digos de vestimenta en el tenis a menudo han cambiado despu\u00e9s de un esc\u00e1ndalo inicial. La jugadora francesa Suzanne Lenglen protagoniz\u00f3 uno de los primeros y m\u00e1s memorables casos, cuando en Wimbledon en 1919 abandon\u00f3 los vestidos largos en capas y us\u00f3 una falda m\u00e1s vaporosa hasta la pantorrilla y mangas m\u00e1s cortas. Lenglen, musa del dise\u00f1ador Jean Patou, se convirti\u00f3 en el primer \u00edcono de la moda del tenis con su caracter\u00edstico pa\u00f1uelo en la cabeza y sus entonces provocativos dobladillos m\u00e1s cortos.<\/p>\n<p>A Anne White se le prohibi\u00f3 llevar un catsuit blanco en Wimbledon cuatro d\u00e9cadas antes de que Serena Williams causara revuelo con una prenda similar en el Abierto de Francia. (Neville Marriner\/Daily Mail\/Shutterstock)<\/p>\n<p>Las fresas con crema son un manjar tradicional en la cancha de Wimbledon, pero el homenaje de Williams en 2010 no estar\u00eda permitido hoy en d\u00eda, ya que los tejidos blanquecinos est\u00e1n prohibidos, adem\u00e1s de los pantalones cortos brillantes o las zapatillas deportivas con acentos de color. (Ian Kington\/AFP\/Getty Images)<\/p>\n<p>En los abiertos de Estados Unidos, Francia y Australia, los jugadores han cuestionado las definiciones de lo que puede ser la ropa de tenis gracias a reglas m\u00e1s flexibles (sujetas a la opini\u00f3n de los \u00e1rbitros). Ninguna lo ha hecho m\u00e1s que las hermanas Williams, con Serena luciendo un minifalda de mezclilla, tut\u00fas y siluetas tipo capa y el conjunto de encaje negro y rojo de Venus que suscit\u00f3 comparaciones con la lencer\u00eda.<\/p>\n<p>M\u00e1s recientemente, el uniforme Nike de Serena Williams se convirti\u00f3 en el tema de conversaci\u00f3n en el Abierto de Francia de 2018 cuando opt\u00f3 por un catsuit de compresi\u00f3n negro que no inclu\u00eda la falda de tenis obligatoria. Aunque cit\u00f3 sus beneficios para la circulaci\u00f3n luego de un grave susto de co\u00e1gulos de sangre con el nacimiento de su hijo, el Abierto de Francia dijo que prohibir\u00eda el estilo en el futuro. Sin embargo, la Asociaci\u00f3n de Tenis Femenino lo permiti\u00f3 formalmente y Williams continu\u00f3 usando versiones del mono en los Abiertos de Australia de 2019 y 2021, normalizando el corte \u00e1gil y simplificado para la cancha de tenis.<\/p>\n<p>Serena y Venus Williams en la pista del Abierto de Francia 2018. El torneo dijo que no permitir\u00eda catsuits en futuras ediciones, pero la Asociaci\u00f3n de Tenis Femenino modific\u00f3 sus reglas para permitir leggings sin falda. (Matthew Stockman\/Getty Images)<\/p>\n<p>&#171;Me encanta usar faldas&#187;, dijo a CNN en abril mientras reflexionaba sobre la controversia. &#171;Pero quer\u00eda asegurarme de que mi sangre estuviera siempre circulando y hab\u00eda estado en una experiencia cercana a la muerte&#187;.<\/p>\n<p>&#171;As\u00ed que creo que deber\u00eda haber habido\u2026 comprensi\u00f3n en torno a ese conjunto&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Distinciones de marca<\/p>\n<p>La mayor\u00eda de los torneos de Grand Slam eliminaron las reglas de usar exclusivamente blanco hace d\u00e9cadas, probablemente en un intento por atraer a m\u00e1s espectadores en televisi\u00f3n y anunciantes en una era de mayor visibilidad para el deporte.<\/p>\n<p>&#171;El color es vital para llamar la atenci\u00f3n y especialmente para que las empresas deportivas puedan anunciar sus logotipos y colores&#187;, explic\u00f3 James.<\/p>\n<p>Las marcas deportivas y de lujo se anuncian a trav\u00e9s de la moda de m\u00faltiples maneras, desde vestir a jugadores estrella con piezas personalizadas hasta promocionar dise\u00f1os comercializados entre los competidores.<\/p>\n<p>Las restrictivas reglas de Wimbledon han sido &#171;frustrantes&#187; para las marcas que intentan vender sus colecciones en los torneos, dijo Rothenberg. Cuando Fila present\u00f3 las camisetas retro de Bjorn Borg en 2001, replicando las que us\u00f3 la estrella del tenis durante su racha de cinco victorias consecutivas en Wimbledon de 1976 a 1980, los funcionarios de Wimbledon dijeron que ya no cumpl\u00edan con las reglas. La decisi\u00f3n hizo que la marca deportiva &#171;luchara&#187; para conseguir camisetas nuevas para los jugadores que las usaban, explic\u00f3 Rothenberg. Y, despu\u00e9s de que se prohibieron los zapatos con suela naranja de Federer, Nike tuvo que actuar r\u00e1pido para darle un giro a su breve aparici\u00f3n, publicit\u00e1ndolos como &#171;One Match Wonders&#187; en un anuncio impreso.<\/p>\n<p>Coco Gauff en el Abierto de Australia de 2024, que tiene normas m\u00e1s relajadas para la ropa deportiva que sus hom\u00f3logos de Grand Slam. (Eloisa L\u00f3pez\/Reuters)<\/p>\n<p>Andre Agassi boicote\u00f3 Wimbledon entre 1988 y 1990 por su restrictiva regla de jugar todo de blanco, pero en 1991 se present\u00f3 con tonos naranjas. (Rebecca Naden\/PA Images\/Getty Images)<\/p>\n<p>Para los jugadores, las infracciones m\u00e1s peque\u00f1as han resultado controvertidas, y algunos de ellos se han negado rotundamente a seguir el juego, como lo hizo Andre Agassi entre 1988 y 1990, cuando boicote\u00f3 Wimbledon por completo. En 2017, a Jurij Rodionov le dijeron que se cambiara la ropa interior azul que asomaba por debajo de sus camisas, mientras que Sabine Lisicki dijo recientemente que a ella y a las mujeres a menudo se les ped\u00eda que cambiaran sus sujetadores de color piel.<\/p>\n<p>Pero Rothenberg no ve que haya m\u00e1s indulgencia en el corto plazo por parte de quienes toman las decisiones en Wimbledon.<\/p>\n<p>&#171;Creo que Wimbledon ve sus anacronismos como una gran parte de su marca y su valor&#187;, explic\u00f3. &#171;Wimbledon se ha aferrado a ello como una forma de ser\u00a0 diferente, y creo que en gran medida ha sido un \u00e9xito. No se parece a ning\u00fan otro torneo&#187;.<\/p>\n<p>Ha habido cr\u00edticas contra los grandes torneos cada vez que las jugadoras parecen verse afectadas desproporcionadamente por sus c\u00f3digos de vestimenta, y aunque Rothenberg est\u00e1 de acuerdo, tambi\u00e9n se\u00f1ala que los estilos de las mujeres han sido m\u00e1s creativos. La ropa de tenis masculina se ha desviado menos de los pantalones cortos y los polos ligeros o las camisetas deportivas de manga corta desde que se introdujeron.<\/p>\n<p>&#171;Sin embargo, en los \u00faltimos 12 meses se ha acortado notablemente la longitud de los pantalones cortos de los hombres, sobre todo de los jugadores que se los han subido mucho&#187;, coment\u00f3 riendo.<\/p>\n<p>&#171;Tal vez alg\u00fan d\u00eda habr\u00e1 reglas que proh\u00edban eso si empiezan a mostrar demasiado descaro&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Pr\u00edstinos, n\u00edtidos y totalmente blancos: los blancos en el tenis han sido una tradici\u00f3n que se remonta a siglos atr\u00e1s. Su aspecto distintivo no s\u00f3lo ha hecho que el deporte de la raqueta se destaque, sino que tambi\u00e9n se ha convertido en un pilar de la vestimenta fuera de las canchas. Y aunque [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451090","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Pr\u00edstinos, n\u00edtidos y totalmente blancos: los blancos en el tenis han sido una tradici\u00f3n que se remonta a siglos atr\u00e1s. Su aspecto distintivo no s\u00f3lo ha hecho que el deporte de la raqueta se destaque, sino que tambi\u00e9n se ha convertido en un pilar de la vestimenta fuera de las canchas. Y aunque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-13T15:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?\",\"datePublished\":\"2024-07-13T15:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/\"},\"wordCount\":1966,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/\",\"name\":\"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-13T15:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco? - Noticias","og_description":"(CNN) &#8212; Pr\u00edstinos, n\u00edtidos y totalmente blancos: los blancos en el tenis han sido una tradici\u00f3n que se remonta a siglos atr\u00e1s. Su aspecto distintivo no s\u00f3lo ha hecho que el deporte de la raqueta se destaque, sino que tambi\u00e9n se ha convertido en un pilar de la vestimenta fuera de las canchas. Y aunque [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-13T15:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?","datePublished":"2024-07-13T15:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/"},"wordCount":1966,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","name":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-13T15:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?","url":"http:\/\/noticiasya.com\/kansas\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-13T15:03:37Z","datePublished":"2024-07-13T15:03:37Z","dateModified":"2024-07-13T15:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3digo de vestimenta: \\u00bfPor qu\\u00e9 los tenistas visten de blanco?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/13\\\/por-que-tenistas-visten-blanco-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2024\\\/07\\\/13\\\/por-que-tenistas-visten-blanco-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-13T15:03:37Z\",\"datePublished\":\"2024-07-13T15:03:37Z\",\"dateModified\":\"2024-07-13T15:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444735,"url":"https:\/\/noticiasya.com\/kansas\/2024\/02\/01\/investigadores-reportan-el-primer-avistamiento-de-un-tiburon-blanco-recien-nacido\/","url_meta":{"origin":1451090,"position":0},"title":"Investigadores reportan el primer avistamiento de un tibur\u00f3n blanco reci\u00e9n nacido","author":"","date":"febrero 1, 2024","format":false,"excerpt":"(CNN) -- Im\u00e1genes tomadas con drones frente a la costa del sur de California pueden haber revelado el primer vistazo de un tibur\u00f3n blanco reci\u00e9n nacido en estado salvaje.El tibur\u00f3n blanco, de 1,5 metros de largo fue avistado el 9 de julio de 2023, a 400 metros de la costa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451091,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/13\/barbora-krejcikova-gana-wimbledon-tensa-final-trax\/","url_meta":{"origin":1451090,"position":1},"title":"Barbora Krej\u010d\u00edkov\u00e1 gana su primer t\u00edtulo de Wimbledon al derrotar a Jasmine Paolini en una tensa final","author":"","date":"julio 13, 2024","format":false,"excerpt":"(CNN) --\u00a0Barbora Krej\u010d\u00edkov\u00e1 gan\u00f3 su segundo Grand Slam y su primer t\u00edtulo de Wimbledon este s\u00e1bado y finalmente venci\u00f3 a la italiana Jasmine Paolini por 6-2, 2-6 y 6-4 en una emocionante final femenina.C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?La checa ha atravesado una temporada dif\u00edcil, interrumpida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461565,"url":"https:\/\/noticiasya.com\/kansas\/2025\/04\/24\/papa-francisco-icono-moda-trax\/","url_meta":{"origin":1451090,"position":2},"title":"El papa Francisco tambi\u00e9n fue un inesparado \u00edcono de la moda","author":"","date":"abril 24, 2025","format":false,"excerpt":"Puede que la moda no sea lo primero que se nos viene a la mente al pensar en el legado papal, pero el papa Francisco, fallecido el lunes, ten\u00eda un estilo \u00fanico, que no incluy\u00f3 una chaqueta acolchada blanca ce\u00f1ida al estilo de Balenciaga (eso s\u00ed que era Inteligencia Artificial),\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456890,"url":"https:\/\/noticiasya.com\/kansas\/2024\/12\/23\/codigos-vestimenta-papa-noel-rojo-blanco\/","url_meta":{"origin":1451090,"position":3},"title":"C\u00f3digos de vestimenta: \u00bfPor qu\u00e9 Pap\u00e1 Noel usa un traje rojo y blanco?","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"Un traje de terciopelo rojo, fest\u00f3n de piel blanca, botas altas negras, un c\u00f3modo (aunque indulgente) gorro con pomp\u00f3n. El uniforme de Pap\u00e1 Noel puede tener algunas variaciones, desde los atuendos fuera de servicio de Tim Allen en \u201cThe Santa Clause\u201d, mientras se transforma lentamente en el legendario repartidor de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450937,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/07\/iga-swiatek-eliminada-wimbledon-sorpresiva-derrota-yulia-putintseva-trax\/","url_meta":{"origin":1451090,"position":4},"title":"Eliminan a Iga \u015awi\u0105tek de Wimbledon en una sorpresiva derrota en tercera ronda ante Yulia Putintseva","author":"","date":"julio 7, 2024","format":false,"excerpt":"(CNN) -- La n\u00famero 1 del mundo, Iga \u015awi\u0105tek, se despidi\u00f3 de Wimbledon el s\u00e1bado al sufrir una sorprendente derrota en tercera ronda ante la kazaja Yulia Putintseva, con lo que puso fin a su racha de 21 partidos ganados.\u015awi\u0105tek llevaba casi tres meses sin perder un partido, una racha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450971,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/09\/front-patriot-lo-que-sabemos-grupo-nacionalista-blanco-nashville-tennessee-trax\/","url_meta":{"origin":1451090,"position":5},"title":"Lo que sabemos sobre el grupo nacionalista blanco Patriot Front del que algunos de sus miembros marcharon en Nashville","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN) -- Con sus rostros ocultos tras telas blancas y gafas de sol, decenas de manifestantes marcharon este fin de semana por las calles del centro de Nashville al grito de \"Sieg Heil\" y \"La deportaci\u00f3n salva a la naci\u00f3n\", seg\u00fan un comunicado del Partido Dem\u00f3crata de Tennessee.\"Recuperemos Am\u00e9rica\", rezaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1451090"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1451090\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1451090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1451090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1451090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}