{"id":1466594,"date":"2025-09-18T15:03:49","date_gmt":"2025-09-18T22:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/"},"modified":"2025-09-18T15:03:49","modified_gmt":"2025-09-18T22:03:49","slug":"ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/","title":{"rendered":"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &#171;ilegales de reventa de boletos&#187;"},"content":{"rendered":"<p>El Gobierno federal de Estados Unidos y siete estados demandaron a Ticketmaster y a su empresa matriz, Live Nation Entertainment, por no frenar a los revendedores de boletos, lo que obliga a los clientes a \u201cpagar sustancialmente m\u00e1s que el valor nominal\u201d por conciertos y eventos populares.<\/p>\n<p>La Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s) present\u00f3 una serie de acusaciones contra Live Nation en un comunicado el jueves, entre ellas la de aplicar precios \u201cenga\u00f1osos\u201d, en los que los consumidores a menudo terminan pagando m\u00e1s de lo anunciado, y sostuvo que las afirmaciones de la compa\u00f1\u00eda sobre \u201cl\u00edmites estrictos\u201d en la compra de boletos son falsas, ya que \u201clos revendedores superaron de manera rutinaria y sustancial esos l\u00edmites\u201d.<\/p>\n<p>Las acciones de Live Nation (LYV) cayeron m\u00e1s de 2 % en la jornada del mediod\u00eda. La empresa no respondi\u00f3 de inmediato a la solicitud de comentarios de CNN.<\/p>\n<p>\u201cEl entretenimiento en vivo estadounidense es el mejor del mundo y deber\u00eda ser accesible para todos nosotros\u201d, dijo en un comunicado Andrew Ferguson, presidente de la FTC. \u201cNo deber\u00eda costar un ojo de la cara llevar a la familia a un partido de b\u00e9isbol o al concierto de tu m\u00fasico favorito\u201d.<\/p>\n<p>Ticketmaster domina el mercado, con el control de la boleter\u00eda de alrededor del 80 % de los principales recintos de Estados Unidos. Los consumidores gastaron casi US$ 83.000 millones en boletos de la compa\u00f1\u00eda entre 2019 y 2024, seg\u00fan la FTC.<\/p>\n<p>La agencia tambi\u00e9n apunt\u00f3 contra las tarifas de la empresa. Se\u00f1al\u00f3 que a menudo son ocultas y no aparecen hasta el final de la compra, y que pueden llegar hasta 44% del costo final del boleto. Ticketmaster recaud\u00f3 US$ 16.000 millones en tarifas entre 2019 y 2024.<\/p>\n<p>La FTC afirma que las pr\u00e1cticas de Live Nation y Ticketmaster violan un decreto firmado durante el primer mandato del presidente Donald Trump en 2016, llamado Better Online Ticket Sales (BOTS) Act, una ley que permite a la agencia actuar contra individuos y compa\u00f1\u00edas que usan bots para comprar boletos de conciertos al por mayor y revenderlos.<\/p>\n<p>Trump firm\u00f3 un decreto similar en marzo, pocos meses despu\u00e9s de iniciar su segundo mandato. En ese momento, dijo que no sab\u00eda mucho sobre la especulaci\u00f3n de precios, \u201cpero lo investigu\u00e9, y es un gran problema\u201d.<\/p>\n<p>El tema de la especulaci\u00f3n atrajo m\u00e1s atenci\u00f3n durante la gira Eras Tour de Taylor Swift en 2022, cuando los precios de reventa alcanzaron decenas de miles de d\u00f3lares. Los precios desorbitados provocaron una fuerte reacci\u00f3n contra Ticketmaster \u2014el mayor sitio de boleter\u00eda y promotor de conciertos del pa\u00eds\u2014 por parte de legisladores que acusaron a la empresa de actuar como un monopolio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno federal de Estados Unidos y siete estados demandaron a Ticketmaster y a su empresa matriz, Live Nation Entertainment, por no frenar a los revendedores de boletos, lo que obliga a los clientes a \u201cpagar sustancialmente m\u00e1s que el valor nominal\u201d por conciertos y eventos populares. La Comisi\u00f3n Federal de Comercio (FTC, por sus [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466594","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &quot;ilegales de reventa de boletos&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &quot;ilegales de reventa de boletos&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno federal de Estados Unidos y siete estados demandaron a Ticketmaster y a su empresa matriz, Live Nation Entertainment, por no frenar a los revendedores de boletos, lo que obliga a los clientes a \u201cpagar sustancialmente m\u00e1s que el valor nominal\u201d por conciertos y eventos populares. La Comisi\u00f3n Federal de Comercio (FTC, por sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T22:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &#171;ilegales de reventa de boletos&#187;\",\"datePublished\":\"2025-09-18T22:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/\"},\"wordCount\":499,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/\",\"name\":\"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas \\\"ilegales de reventa de boletos\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-18T22:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &#171;ilegales de reventa de boletos&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas \"ilegales de reventa de boletos\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas \"ilegales de reventa de boletos\" - Noticias","og_description":"El Gobierno federal de Estados Unidos y siete estados demandaron a Ticketmaster y a su empresa matriz, Live Nation Entertainment, por no frenar a los revendedores de boletos, lo que obliga a los clientes a \u201cpagar sustancialmente m\u00e1s que el valor nominal\u201d por conciertos y eventos populares. La Comisi\u00f3n Federal de Comercio (FTC, por sus [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-18T22:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/"},"author":{"name":"","@id":""},"headline":"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &#171;ilegales de reventa de boletos&#187;","datePublished":"2025-09-18T22:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/"},"wordCount":499,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/","name":"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas \"ilegales de reventa de boletos\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-18T22:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &#171;ilegales de reventa de boletos&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Comisi\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\u00e1cticas &#171;ilegales de reventa de boletos&#187;","url":"http:\/\/noticiasya.com\/kansas\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2025\/09\/18\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-18T22:03:49Z","datePublished":"2025-09-18T22:03:49Z","dateModified":"2025-09-18T22:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Comisi\\u00f3n Federal de Comercio demanda a Live Nation y Ticketmaster por pr\\u00e1cticas &#171;ilegales de reventa de boletos&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2025\\\/09\\\/18\\\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2025\\\/09\\\/18\\\/ftc-demanda-live-nation-ticketmaster-practicas-ilegales-boletos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-18T22:03:49Z\",\"datePublished\":\"2025-09-18T22:03:49Z\",\"dateModified\":\"2025-09-18T22:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473208,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/15\/jurado-determina-live-nation-ticketmaster-monopolio-trax\/","url_meta":{"origin":1466594,"position":0},"title":"Un jurado determina que Live Nation y Ticketmaster operaron como un monopolio y cobraron de m\u00e1s a los fans","author":"","date":"abril 15, 2026","format":false,"excerpt":"Un jurado determin\u00f3 que Live Nation y Ticketmaster operaron como un monopolio en su dominio de la industria de eventos en vivo y venta de boletos, validando las quejas de que el gigante del sector limitaba la competencia y elevaba las tarifas para los aficionados.El veredicto se alcanz\u00f3 tras un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449715,"url":"https:\/\/noticiasya.com\/kansas\/2024\/05\/23\/estados-unidos-demanda-ticketmaster-live-nation-monopolio-trax\/","url_meta":{"origin":1466594,"position":1},"title":"Estados Unidos busca dividir a Ticketmaster y Live Nation en una innovadora demanda por monopolio","author":"","date":"mayo 23, 2024","format":false,"excerpt":"(CNN) -- En una innovadora demanda antimonopolio que amenaza con alterar la forma en que los asistentes a los conciertos pagan las entradas, el Gobierno de Estados Unidos y decenas de estados demandaron a Live Nation este jueves, y alegaron que durante a\u00f1os la empresa matriz de Ticketmaster abus\u00f3 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460675,"url":"https:\/\/noticiasya.com\/kansas\/2025\/03\/31\/decreto-fin-especulacion-precio-entradas-espectaculos-trax\/","url_meta":{"origin":1466594,"position":2},"title":"Donald Trump firm\u00f3 un decreto para poner fin a la especulaci\u00f3n con el precio de los boletos para espect\u00e1culos en directo","author":"","date":"marzo 31, 2025","format":false,"excerpt":"El presidente Donald Trump firm\u00f3 elste lunes un decreto destinado a poner fin a la especulaci\u00f3n en los precios de los boletoss para espect\u00e1culos en vivo.El decreto ordena a la Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s) que colabore con la secretaria de Justicia Pam Bondi para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466605,"url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/19\/5-cosas-19-septiembre-orix\/","url_meta":{"origin":1466594,"position":3},"title":"Las 5 cosas que debes saber este 19 de septiembre: Venezuela, examen de ciudadan\u00eda estadounidense y papa Le\u00f3n XIV","author":"","date":"septiembre 19, 2025","format":false,"excerpt":"Ahora el examen para la ciudadan\u00eda de EE.UU. es m\u00e1s exigente. A Le\u00f3n XIV le preocupa EE.UU. \u00bfC\u00f3mo participar en el Simulacro Nacional 2025 en M\u00e9xico? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1439051,"url":"https:\/\/noticiasya.com\/kansas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","url_meta":{"origin":1466594,"position":4},"title":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel","author":"Eduardo Salinas","date":"mayo 19, 2023","format":false,"excerpt":"La gira de Luis Miguel ha causado una locura en todo el continente y es que era de esperarse que el regreso de \"El Sol\" se convertir\u00eda en uno de los m\u00e1s esperados en a\u00f1os no solo por el furor tras su serie de Netflix, sino por el acervo musical\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/kansas\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470935,"url":"https:\/\/noticiasya.com\/kansas\/2026\/02\/06\/boletos-super-bowl-2026-patriots-seahawks-orix\/","url_meta":{"origin":1466594,"position":5},"title":"\u00bfCu\u00e1nto cuestan los boletos del Super Bowl 2026? \u00bfCu\u00e1les son los m\u00e1s caros?","author":"Eduardo Salinas","date":"febrero 6, 2026","format":false,"excerpt":"El Super Bowl LX que se llevar\u00e1 a cabo el domingo 8 de febrero consolida su posici\u00f3n como uno de los eventos deportivos m\u00e1s costosos y lucrativos del planeta.En 1967, dos a\u00f1os antes de conocerse como Super Bowl, la primera final entre equipos de los dos organismos que ten\u00edan las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1466594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1466594"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1466594\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1466594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1466594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1466594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}