{"id":1470464,"date":"2026-01-25T12:03:49","date_gmt":"2026-01-25T20:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/"},"modified":"2026-01-25T12:03:49","modified_gmt":"2026-01-25T20:03:49","slug":"congresista-frost-agredido-festival-sundance-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/","title":{"rendered":"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda"},"content":{"rendered":"<p>La Polic\u00eda de Utah arrest\u00f3 a un hombre que supuestamente grit\u00f3 que el representante Maxwell Frost ser\u00eda deportado antes de golpearlo en la cara en un evento del Festival de Cine de Sundance, dijo el dem\u00f3crata de Florida.<\/p>\n<p>El Departamento de Polic\u00eda de Park City inform\u00f3 que el sospechoso, Christian Young, ingres\u00f3 al evento privado tras haber sido rechazado previamente y agredi\u00f3 al congresista y a una mujer que asist\u00edan al evento. El departamento indic\u00f3 que Young fue arrestado y encarcelado por robo con agravantes y agresi\u00f3n simple.<\/p>\n<p>\u201cAnoche, un hombre me agredi\u00f3 en el Festival de Sundance. Me dijo que Trump me iba a deportar antes de golpearme en la cara\u201d, <a href=\"https:\/\/x.com\/RepMaxwellFrost\/status\/2015210347758825698?s=20\">public\u00f3 Frost en X<\/a> el s\u00e1bado por la noche, al responder a un art\u00edculo <a href=\"https:\/\/variety.com\/2026\/film\/news\/man-arrested-sundance-racist-incident-caa-party-1236640115\/\">de Variety<\/a> que describ\u00eda el incidente. \u201cSe le oy\u00f3 gritar comentarios racistas mientras hu\u00eda ebrio. El individuo fue arrestado y estoy bien\u201d.<\/p>\n<p>Frost, de 29 a\u00f1os, expres\u00f3 su gratitud hacia la seguridad del lugar y la polic\u00eda local en Park City por su ayuda.<\/p>\n<p>CNN se comunic\u00f3 con la Polic\u00eda del Capitolio de EE.UU. y la oficina de Frost para solicitar comentarios.<\/p>\n<p>El l\u00edder de la minor\u00eda de la C\u00e1mara de Representantes, Hakeem Jeffries, conden\u00f3 el incidente y pidi\u00f3 que el sospechoso sea procesado.<\/p>\n<p>\u201cEl odio y la violencia pol\u00edtica no tienen cabida en nuestro pa\u00eds, y toda la familia del Caucus Dem\u00f3crata de la C\u00e1mara de Representantes apoya a Maxwell\u201d, <a href=\"https:\/\/x.com\/RepJeffries\/status\/2015228602879447333?s=20\">public\u00f3 Jeffries el s\u00e1bado en<\/a> X.<\/p>\n<p>Frost hizo historia como al ser el <a href=\"https:\/\/www.cnn.com\/2022\/08\/24\/politics\/gen-z-maxwell-frost-florida-democrat\">primer miembro de la Generaci\u00f3n Z<\/a> en ser elegido para el Congreso en 2022. Desde entonces, se ha expresado abiertamente sobre una serie de temas, incluidos el derecho al voto y la prevenci\u00f3n de la violencia armada.<\/p>\n<p>Los recientes actos de violencia pol\u00edtica han reavivado la antigua pregunta de c\u00f3mo proteger mejor a los miembros del Congreso y a sus familias. En junio pasado, la representante estatal de Minnesota Melissa Hortman y su esposo, Mark, fueron baleados mortalmente en su casa. En septiembre, el activista conservador Charlie Kirk fue asesinado en un evento en la Universidad del Valle de Utah.<\/p>\n<p>El Sargento de Armas de la C\u00e1mara anunci\u00f3 en una carta de diciembre que cada miembro recibir\u00eda US$ 20.000 al mes para seguridad y protecci\u00f3n personal, luego de la exitosa implementaci\u00f3n de un programa piloto lanzado el verano pasado.<\/p>\n<p>Sundance, el popular festival de cine independiente, se celebra en Utah desde hace m\u00e1s de 40 a\u00f1os. El pr\u00f3ximo a\u00f1o se trasladar\u00e1 a Boulder, Colorado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Utah arrest\u00f3 a un hombre que supuestamente grit\u00f3 que el representante Maxwell Frost ser\u00eda deportado antes de golpearlo en la cara en un evento del Festival de Cine de Sundance, dijo el dem\u00f3crata de Florida. El Departamento de Polic\u00eda de Park City inform\u00f3 que el sospechoso, Christian Young, ingres\u00f3 al evento privado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470464","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Polic\u00eda de Utah arrest\u00f3 a un hombre que supuestamente grit\u00f3 que el representante Maxwell Frost ser\u00eda deportado antes de golpearlo en la cara en un evento del Festival de Cine de Sundance, dijo el dem\u00f3crata de Florida. El Departamento de Polic\u00eda de Park City inform\u00f3 que el sospechoso, Christian Young, ingres\u00f3 al evento privado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-25T20:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda\",\"datePublished\":\"2026-01-25T20:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/\",\"name\":\"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-25T20:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda - Noticias","og_description":"La Polic\u00eda de Utah arrest\u00f3 a un hombre que supuestamente grit\u00f3 que el representante Maxwell Frost ser\u00eda deportado antes de golpearlo en la cara en un evento del Festival de Cine de Sundance, dijo el dem\u00f3crata de Florida. El Departamento de Polic\u00eda de Park City inform\u00f3 que el sospechoso, Christian Young, ingres\u00f3 al evento privado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-25T20:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/"},"author":{"name":"","@id":""},"headline":"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda","datePublished":"2026-01-25T20:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/","name":"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-25T20:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\u00fan la Polic\u00eda","url":"http:\/\/noticiasya.com\/kansas\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/01\/25\/congresista-frost-agredido-festival-sundance-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-25T20:03:49Z","datePublished":"2026-01-25T20:03:49Z","dateModified":"2026-01-25T20:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El congresista de Florida Maxwell Frost fue agredido en un evento del Festival de Cine de Sundance, seg\\u00fan la Polic\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/01\\\/25\\\/congresista-frost-agredido-festival-sundance-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/01\\\/25\\\/congresista-frost-agredido-festival-sundance-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-25T20:03:49Z\",\"datePublished\":\"2026-01-25T20:03:49Z\",\"dateModified\":\"2026-01-25T20:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466517,"url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/16\/robert-redford-sundance-cine-independiente-orix\/","url_meta":{"origin":1470464,"position":0},"title":"C\u00f3mo Robert Redford impuls\u00f3 el cine independiente con el Festival de Sundance","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Robert Redford, el actor y director que falleci\u00f3 este martes en su casa de Utah, cambi\u00f3 el cine estadounidense para siempre al fundar el Festival de Cine de Sundance, en Salt Lake City, Utah, en 1978.All\u00ed se estrenar\u00edan las primeras pel\u00edculas de directores estadounidenses, financiadas de manera independiente fuera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473174,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/14\/otra-mujer-eric-swalwell-agredio-sexualmente-trax\/","url_meta":{"origin":1470464,"position":1},"title":"Otra mujer dice que el representante Eric Swalwell la agredi\u00f3 sexualmente","author":"","date":"abril 14, 2026","format":false,"excerpt":"Una mujer acus\u00f3 este martes al representante Eric Swalwell de haberla agredido sexualmente, al afirmar en una conferencia de prensa que el congresista la viol\u00f3 en 2018 en un hotel del \u00e1rea de Los \u00c1ngeles.Lonna Drewes y su abogada, Lisa Bloom, dijeron que planeaban denunciar la presunta agresi\u00f3n ante el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466511,"url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/16\/robert-redford-vida-peliculas-familia-trax\/","url_meta":{"origin":1470464,"position":2},"title":"As\u00ed fueron la vida y carrera de Robert Redford: sus mejores pel\u00edculas, premios, familia","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"La carrera de Robert Redford abarc\u00f3 60 a\u00f1os y fue tan variada como sus papeles. No solo fue uno de los actores m\u00e1s apuestos de Hollywood en la d\u00e9cada de 1970, sino que fue un director ganador del premio Oscar y un promotor esencial del cine independiente en los ochenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466504,"url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/16\/quien-fue-robert-redford-galan-sundance-trax\/","url_meta":{"origin":1470464,"position":3},"title":"Qui\u00e9n fue Robert Redford, el gal\u00e1n de Hollywood pionero del cine independiente y defensor del medio ambiente","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Robert Redford, el fallecido actor, director y activista ambiental, protagoniz\u00f3 cl\u00e1sicos de Hollywood, gan\u00f3 un \u00d3scar como director y fund\u00f3 el Festival de Sundance, dejando un legado que transform\u00f3 el cine independiente y la defensa del medio ambiente.Conocido por sus papeles protag\u00f3nicos en \u201cButch Cassidy and the Sundance Kid\u201d y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466545,"url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/17\/legado-robert-redford-filantropo-ambientalista-trax\/","url_meta":{"origin":1470464,"position":4},"title":"El legado del fil\u00e1ntropo y ambientalista Robert Redford va mucho m\u00e1s all\u00e1 de Hollywood","author":"","date":"septiembre 17, 2025","format":false,"excerpt":"Aunque Robert Redford dej\u00f3 su huella con pel\u00edculas de Hollywood como \u201cAll the President\u2019s Men\u201d, \u201cBarefoot in the Park\u201d y \u201cButch Cassidy and the Sundance Kid\u201d, el ambientalista y fil\u00e1ntropo de toda la vida tambi\u00e9n se comprometi\u00f3 a impulsar el cambio, proteger la tierra y apoyar a cineastas emergentes.\u201cSoy actor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466503,"url":"https:\/\/noticiasya.com\/kansas\/2025\/09\/16\/muere-robert-redford-actor-cine-trax\/","url_meta":{"origin":1470464,"position":5},"title":"Muere Robert Redford, actor, director y ambientalista, a los 89 a\u00f1os","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Robert Redford, el apuesto actor y director ganador del Oscar que rechaz\u00f3 su estatus de gal\u00e1n de Hollywood para defender causas cercanas a su coraz\u00f3n, muri\u00f3 el martes, seg\u00fan supo CNN. Ten\u00eda 89 a\u00f1os.Conocido por sus papeles protag\u00f3nicos en \u201cButch Cassidy and the Sundance Kid\u201d y \u201cAll the President\u2019s Men\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1470464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1470464"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1470464\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1470464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1470464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1470464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}