{"id":1473337,"date":"2026-04-20T11:03:51","date_gmt":"2026-04-20T18:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/"},"modified":"2026-04-20T11:03:51","modified_gmt":"2026-04-20T18:03:51","slug":"d4vd-asesinato-rivas-tesla-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","title":{"rendered":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista"},"content":{"rendered":"<p>David Anthony Burke, m\u00e1s conocido como el artista de pop alternativo d4vd, est\u00e1 siendo acusado en relaci\u00f3n con el homicidio de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, siete meses despu\u00e9s de que el cuerpo en descomposici\u00f3n de la ni\u00f1a fuera descubierto en su Tesla aparentemente abandonado, seg\u00fan anunci\u00f3 el lunes la Fiscal\u00eda del Condado de Los \u00c1ngeles.<\/p>\n<p>El cantante de 21 a\u00f1os fue arrestado el jueves. El cuerpo de la chica fue hallado m\u00e1s de un a\u00f1o despu\u00e9s de que se reportara su desaparici\u00f3n en el sur de California.<\/p>\n<p>D4vd est\u00e1 acusado de asesinato bajo el cargo de homicidio con agravantes agravantes, actos sexuales continuados, actos sexuales lascivos y obscenos con una persona menor de 14 a\u00f1os y mutilaci\u00f3n de restos humanos, seg\u00fan anunci\u00f3 el fiscal de distrito del condado de Los \u00c1ngeles, Nathan Hochman, en una conferencia de prensa.<\/p>\n<p>Los fiscales indicaron que el caso est\u00e1 siendo revisado por la Divisi\u00f3n de Delitos Graves de la fiscal\u00eda, la cual se encarga de determinar si los hechos conocidos y las pruebas disponibles cumplen con los requisitos para presentar cargos penales.<\/p>\n<p>\u201cPor el momento, no hay informaci\u00f3n adicional disponible\u201d, declar\u00f3 la fiscal\u00eda a CNN el viernes. \u201cCompartiremos una actualizaci\u00f3n el lunes una vez que se haya tomado una decisi\u00f3n sobre la presentaci\u00f3n de cargos\u201d.<\/p>\n<p>La familia de Celeste, que se ha mantenido alejada del ojo p\u00fablico desde el descubrimiento de su cuerpo, planea asistir a la conferencia de prensa del lunes, seg\u00fan su abogado.<\/p>\n<p>\u201cLa familia Rivas Hern\u00e1ndez est\u00e1 comprometida a garantizar que la voz de Celeste sea escuchada y su memoria honrada durante todo este proceso\u201d, afirm\u00f3 Patrick Steinfeld, abogado de la familia.<\/p>\n<p>Un altar improvisado con flores, velas y peluches en honor a Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, se observa cerca de la calle Jamieson en Lake Elsinore, California, el viernes.<\/p>\n<p>Mientras tanto, los abogados de d4vd declararon que pretenden \u201cdefender en\u00e9rgicamente la inocencia de David\u201d, a\u00f1adiendo que el cantante \u201csolo ha sido detenido bajo sospecha\u201d.<\/p>\n<p>\u201cSeamos claros: las pruebas en este caso demostrar\u00e1n que David Burke no asesin\u00f3 a Celeste Rivas Hern\u00e1ndez y que no fue la causa de su muerte\u201d, declararon los abogados Blair Berk, Marilyn Bednarski y Regina Peter en un comunicado.<\/p>\n<p>\u201cNing\u00fan gran jurado ha presentado una acusaci\u00f3n formal en este caso ni se ha interpuesto ninguna denuncia penal\u201d, a\u00f1ade el comunicado.<\/p>\n<p>Documentos judiciales publicados en febrero indican que un gran jurado ha estado investigando al cantante, cuyo nombre legal es David Anthony Burke, en relaci\u00f3n con la muerte de Celeste. Los documentos no detallan el papel que las autoridades sospechan que pudo haber desempe\u00f1ado en su muerte, pero lo identifican como un \u201cobjetivo\u201d de la investigaci\u00f3n que podr\u00eda haber estado \u201cinvolucrado\u201d.<\/p>\n<p>El lunes se cumplen casi dos a\u00f1os de la tercera \u2014y \u00faltima\u2014 vez que Celeste fue reportada como desaparecida por su familia, culminando una serie de urgentes s\u00faplicas a principios de 2024, cuando seres queridos y amigos se alarmaron cada vez m\u00e1s por la seguridad y el paradero de la joven de s\u00e9ptimo grado.<\/p>\n<p>Ten\u00eda 13 a\u00f1os en ese momento; una adolescente recordada en fotos por su dulce sonrisa y su abundante cabello rizado.<\/p>\n<p>Celeste Rivas Hern\u00e1ndez posa en una foto sin fecha proporcionada por el abogado que representa a la familia de la adolescente.<\/p>\n<p>En septiembre de 2025, un d\u00eda despu\u00e9s de lo que habr\u00eda sido su decimoquinto cumplea\u00f1os, su cuerpo desmembrado y en descomposici\u00f3n fue descubierto en el maletero de un Tesla registrado a nombre de d4vd mientras este se encontraba en Minneapolis promocionando su \u00e1lbum debut, \u201cWithered\u201d.<\/p>\n<p>Las autoridades no han establecido una cronolog\u00eda precisa de cu\u00e1ndo fue asesinada Celeste, aunque los registros judiciales indican que ten\u00eda 14 a\u00f1os al momento de su muerte. Fotograf\u00edas obtenidas por CNN sugieren que segu\u00eda viva casi un a\u00f1o despu\u00e9s de que se reportara su desaparici\u00f3n.<\/p>\n<p>Los vecinos afirman que el auto parec\u00eda abandonado, estacionado en una calle cercana a la casa de Hollywood Hills donde viv\u00eda d4vd. Posteriormente fue remolcado, y un empleado del dep\u00f3sito alert\u00f3 a la polic\u00eda tras percibir un fuerte y f\u00e9tido olor proveniente del veh\u00edculo.<\/p>\n<p>Las autoridades arrestaron al cantante el 16 de abril bajo sospecha de asesinar a Celeste, deteni\u00e9ndolo en una residencia en Hollywood Hills, a poco m\u00e1s de un kil\u00f3metro del dep\u00f3sito de veh\u00edculos donde se encontr\u00f3 el cuerpo de la ni\u00f1a dentro de su auto.<\/p>\n<p>Se encuentra detenido sin derecho a fianza.<\/p>\n<p>Fotograf\u00edas publicadas por el Departamento de Polic\u00eda de Los \u00c1ngeles muestran el operativo que condujo al arresto del cantante d4vd el jueves por el asesinato de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os.<\/p>\n<p>Indicadores apuntan a una conexi\u00f3n entre Celeste y d4vd incluso antes de que se reportara su desaparici\u00f3n. En enero de 2024, ambos aparecieron juntos en una transmisi\u00f3n en vivo en Twitch, bromeando y conversando hasta altas horas de la madrugada, antes de que d4vd, entre risas, dijera: \u201cB\u00f3rralo todo\u201d.<\/p>\n<p>Entre enero y marzo de 2024, la cantante fue fotografiada saliendo de un Tesla negro a pocas cuadras de la casa de Celeste. Un adolescente local public\u00f3 posteriormente las im\u00e1genes en TikTok. CNN geolocaliz\u00f3 y cronolocaliz\u00f3 las fotos para verificar cu\u00e1ndo y d\u00f3nde fueron tomadas.<\/p>\n<p>En junio de 2024, Celeste fue fotografiada entre bastidores en un concierto con entradas agotadas que d4vd ofreci\u00f3 en el Teatro Fonda de Los \u00c1ngeles. Un investigador privado descubri\u00f3 posteriormente im\u00e1genes adicionales que parec\u00edan mostrar a ambos juntos a finales de diciembre de 2024 y principios de enero de 2025.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Anthony Burke, m\u00e1s conocido como el artista de pop alternativo d4vd, est\u00e1 siendo acusado en relaci\u00f3n con el homicidio de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, siete meses despu\u00e9s de que el cuerpo en descomposici\u00f3n de la ni\u00f1a fuera descubierto en su Tesla aparentemente abandonado, seg\u00fan anunci\u00f3 el lunes la Fiscal\u00eda del Condado de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473337","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista - Noticias\" \/>\n<meta property=\"og:description\" content=\"David Anthony Burke, m\u00e1s conocido como el artista de pop alternativo d4vd, est\u00e1 siendo acusado en relaci\u00f3n con el homicidio de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, siete meses despu\u00e9s de que el cuerpo en descomposici\u00f3n de la ni\u00f1a fuera descubierto en su Tesla aparentemente abandonado, seg\u00fan anunci\u00f3 el lunes la Fiscal\u00eda del Condado de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T18:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista\",\"datePublished\":\"2026-04-20T18:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/\"},\"wordCount\":1021,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/\",\"name\":\"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-20T18:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista - Noticias","og_description":"David Anthony Burke, m\u00e1s conocido como el artista de pop alternativo d4vd, est\u00e1 siendo acusado en relaci\u00f3n con el homicidio de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, siete meses despu\u00e9s de que el cuerpo en descomposici\u00f3n de la ni\u00f1a fuera descubierto en su Tesla aparentemente abandonado, seg\u00fan anunci\u00f3 el lunes la Fiscal\u00eda del Condado de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-20T18:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/"},"author":{"name":"","@id":""},"headline":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista","datePublished":"2026-04-20T18:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/"},"wordCount":1021,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","name":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-20T18:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-20T18:03:51Z","datePublished":"2026-04-20T18:03:51Z","dateModified":"2026-04-20T18:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/d4vd-asesinato-rivas-tesla-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/d4vd-asesinato-rivas-tesla-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-20T18:03:51Z\",\"datePublished\":\"2026-04-20T18:03:51Z\",\"dateModified\":\"2026-04-20T18:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473449,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/23\/pornografia-infantil-d4vd-asesinato-trax\/","url_meta":{"origin":1473337,"position":0},"title":"Hallan pornograf\u00eda infantil entre las pruebas en el caso contra el cantante d4vd, acusado de asesinar a una ni\u00f1a de 14 a\u00f1os","author":"","date":"abril 23, 2026","format":false,"excerpt":"La pornograf\u00eda infantil figura entre las pruebas clave que, seg\u00fan los fiscales de Los \u00c1ngeles, reforzar\u00e1n su caso contra el cantante de alt-pop d4vd, quien ha sido acusado de asesinato y abuso sexual prolongado de una ni\u00f1a en edad de escuela secundaria cuyos restos fueron hallados el a\u00f1o pasado en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473666,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","url_meta":{"origin":1473337,"position":1},"title":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven","author":"","date":"abril 30, 2026","format":false,"excerpt":"Los fiscales expusieron el mi\u00e9rcoles una cronolog\u00eda detallada y macabra en el caso contra el cantante d4vd, acusado de matar a Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, incluidas acusaciones de que comenz\u00f3 a abusar sexualmente de ella cuando ten\u00eda 13 a\u00f1os y luego la apu\u00f1al\u00f3 mortalmente cuando ella amenaz\u00f3 con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473426,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/23\/d4vd-celeste-rivas-hernandez-autopsia-trax\/","url_meta":{"origin":1473337,"position":2},"title":"Autopsia de Celeste Rivas Hern\u00e1ndez confirma que muri\u00f3 por m\u00faltiples heridas penetrantes. El cantante d4vd est\u00e1 acusado","author":"","date":"abril 23, 2026","format":false,"excerpt":"La joven de 14 a\u00f1os que, seg\u00fan la acusaci\u00f3n, fue asesinada y desmembrada por el cantante d4vd muri\u00f3 por \u201cm\u00faltiples heridas penetrantes\u201d, seg\u00fan una autopsia publicada el mi\u00e9rcolesLos hallazgos arrojan m\u00e1s luz sobre la muerte de Celeste Rivas Hern\u00e1ndez, meses despu\u00e9s de que la adolescente fuera encontrada en el maletero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473297,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/18\/d4vd-asesinato-celeste-rivas-hernandez-trax\/","url_meta":{"origin":1473337,"position":3},"title":"Un autom\u00f3vil abandonado, una fotograf\u00eda y una ni\u00f1a desaparecida: \u00bfQu\u00e9 llev\u00f3 al arresto de d4vd bajo sospecha de asesinato?","author":"","date":"abril 18, 2026","format":false,"excerpt":"Meses despu\u00e9s de que el cuerpo de una ni\u00f1a fuera hallado en el maletero de su coche abandonado, el cantante d4vd fue arrestado cerca del dep\u00f3sito de veh\u00edculos de Los \u00c1ngeles donde se descubrieron sus restos.La fiscal\u00eda ahora evaluar\u00e1 si presenta cargos penales contra el artista de pop alternativo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473486,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/24\/quien-fue-celeste-rivas-hernandez-d4vd-muerte-trax\/","url_meta":{"origin":1473337,"position":4},"title":"\u00bfQui\u00e9n fue Celeste Rivas Hern\u00e1ndez, la chica de 14 a\u00f1os por cuya muerte se acusa al cantante d4vid?","author":"","date":"abril 24, 2026","format":false,"excerpt":"La unida y familiar ciudad de Lake Elsinore, en el condado de Riverside, se encuentra a unos 110 kil\u00f3metros al sureste, un mundo aparte del brillo y el glamour de Hollywood Hills.Celeste Rivas Hern\u00e1ndez creci\u00f3 en Lake Elsinore, donde era una habitual de la tienda de la esquina calle abajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445945,"url":"https:\/\/noticiasya.com\/kansas\/2024\/02\/23\/causa-muerte-audrii-cunningham-trax\/","url_meta":{"origin":1473337,"position":5},"title":"Forense determina la causa de muerte de Audrii Cunningham","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) -- Audrii Cunningham, la ni\u00f1a de 11 a\u00f1os que fue encontrada muerta tras desaparecer de camino al colegio la semana pasada, muri\u00f3 por \"violencia homicida, incluido un traumatismo craneal contundente\", seg\u00fan la oficina del forense.Cunningham sali\u00f3 de su casa en Livingston, Texas, la semana pasada con un amigo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473337"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473337\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}