{"id":1473342,"date":"2026-04-20T14:03:43","date_gmt":"2026-04-20T21:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/"},"modified":"2026-04-20T14:03:43","modified_gmt":"2026-04-20T21:03:43","slug":"delegacion-estadounidense-visita-cuba-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","title":{"rendered":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla"},"content":{"rendered":"<p>Una delegaci\u00f3n estadounidense de alto nivel se reuni\u00f3 con funcionarios del Gobierno de Cuba mientras el Gobierno de Trump intensifica sus esfuerzos para presionar a La Habana a llegar a un acuerdo, al tiempo que contin\u00faa ejerciendo su asfixia econ\u00f3mica sobre la isla.<\/p>\n<p>Fue una de las visitas de m\u00e1s alto nivel de funcionarios estadounidenses en aproximadamente una d\u00e9cada y se produce mientras el presidente Donald Trump contin\u00faa avivando el espectro de una posible acci\u00f3n militar. Tambi\u00e9n ocurre mientras la crisis econ\u00f3mica de Cuba sigue profundiz\u00e1ndose en medio de fuertes restricciones, incluidas las de combustible, por parte del Gobierno de EE.UU. El presidente de Cuba, por su parte, ha hecho llamados cada vez m\u00e1s desafiantes en los \u00faltimos d\u00edas para resistir la agresi\u00f3n militar de Estados Unidos.<\/p>\n<p>La delegaci\u00f3n de alto nivel del Departamento de Estado, que visit\u00f3 la isla en las \u00faltimas semanas, subray\u00f3 que se estaba acabando el tiempo para que La Habana \u201crealice reformas clave respaldadas por Estados Unidos antes de que las circunstancias empeoren de manera irreversible\u201d, dijo a CNN un funcionario del Departamento de Estado de Estados Unidos.<\/p>\n<p>Fue la primera vez que una aeronave del Gobierno de Estados Unidos aterriz\u00f3 en Cuba \u2014aparte de la base estadounidense en la bah\u00eda de Guant\u00e1namo\u2014 desde 2016, cuando el expresidente Barack Obama visit\u00f3 en el marco de un esfuerzo por ampliar las relaciones con La Habana.<\/p>\n<p>Seg\u00fan el funcionario del Departamento de Estado, la delegaci\u00f3n estadounidense enfatiz\u00f3 \u201cla necesidad de que Cuba realice importantes reformas econ\u00f3micas y de gobernanza para mejorar la competitividad, atraer inversi\u00f3n extranjera y permitir un crecimiento liderado por el sector privado\u201d.<\/p>\n<p>Hablaron de una propuesta para llevar el internet satelital Starlink de Elon Musk a Cuba, as\u00ed como de propuestas para compensar a personas y corporaciones estadounidenses \u201cpor activos y propiedades confiscados\u201d, algo que probablemente ser\u00eda bien recibido por la di\u00e1spora cubana en Estados Unidos.<\/p>\n<p>La delegaci\u00f3n present\u00f3 exigencias de que el Gobierno de Cuba libere a los presos pol\u00edticos e incremente las \u201clibertades pol\u00edticas\u201d para la poblaci\u00f3n, dijo el funcionario del Departamento de Estado. Tambi\u00e9n expresaron preocupaciones \u201csobre servicios de inteligencia extranjeros, grupos militares y terroristas que operan con permiso del Gobierno cubano a menos de 100 millas (160 kil\u00f3metros) del territorio continental estadounidense\u201d, se\u00f1al\u00f3 el funcionario.<\/p>\n<p>El funcionario declin\u00f3 proporcionar detalles sobre los miembros de la delegaci\u00f3n. Indic\u00f3 que un alto funcionario del Departamento de Estado se reuni\u00f3 por separado con el nieto de Ra\u00fal Castro durante la visita.<\/p>\n<p>El lunes, un alto funcionario cubano confirm\u00f3 que una reuni\u00f3n entre delegaciones cubanas y estadounidenses \u201cse celebr\u00f3 recientemente\u201d en la isla.<\/p>\n<p>En declaraciones a los medios estatales, Alejandro Garc\u00eda del Toro describi\u00f3 la reuni\u00f3n como \u201crespetuosa y profesional\u201d, y dijo que \u201celiminar el bloqueo energ\u00e9tico contra el pa\u00eds era una prioridad principal para nuestra delegaci\u00f3n\u201d.<\/p>\n<p>A finales de marzo, el Gobierno de Trump permiti\u00f3 que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/02\/latinoamerica\/rusia-prepara-envio-segundo-buque-petroleo-cuba-orix\">un petrolero con bandera rusa<\/a> ingresara en aguas cubanas, rompiendo el bloqueo de combustible, diciendo: \u201cTienen que sobrevivir\u201d. Posteriormente, la Casa Blanca dijo que esto \u201cno es un cambio de pol\u00edtica\u201d. Aun as\u00ed, el bloqueo general ha limitado significativamente a la isla.<\/p>\n<p>Mientras tanto, Trump ha sugerido repetidamente que Estados Unidos podr\u00eda emprender una acci\u00f3n militar contra La Habana, tras lo que ha descrito como un importante \u00e9xito militar contra Nicol\u00e1s Maduro en Venezuela.<\/p>\n<p>\u201cEn enero, nuestros guerreros volaron directamente al coraz\u00f3n de la capital venezolana, capturaron al dictador forajido Nicol\u00e1s Maduro y lo llevaron para que enfrentara la justicia estadounidense\u201d, dijo Trump en un evento el viernes. \u201cY muy pronto, esta gran fortaleza traer\u00e1 un d\u00eda esperado durante 70 a\u00f1os. Se llama un nuevo amanecer para Cuba\u201d.<\/p>\n<p>El asediado presidente de Cuba Miguel D\u00edaz-Canel, al conmemorar el 65.\u00ba aniversario de la victoria de soldados cubanos en Bah\u00eda de Cochinos sobre fuerzas de exiliados entrenadas por la CIA, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/16\/latinoamerica\/cotidianidad-duele-cuba-diaz-canel-listos-agresion-mlitar-eeuu-orix\">prometi\u00f3 \u201cabrir fuego\u201d<\/a> ante cualquier nuevo intento de Estados Unidos de invadir la isla.<\/p>\n<p>El domingo, D\u00edaz-Canel fue mostrado en la televisi\u00f3n cubana junto con otros funcionarios firmando una declaraci\u00f3n para nunca \u201cnegociar los principios de la revoluci\u00f3n cubana\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una delegaci\u00f3n estadounidense de alto nivel se reuni\u00f3 con funcionarios del Gobierno de Cuba mientras el Gobierno de Trump intensifica sus esfuerzos para presionar a La Habana a llegar a un acuerdo, al tiempo que contin\u00faa ejerciendo su asfixia econ\u00f3mica sobre la isla. Fue una de las visitas de m\u00e1s alto nivel de funcionarios estadounidenses [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473342","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una delegaci\u00f3n estadounidense de alto nivel se reuni\u00f3 con funcionarios del Gobierno de Cuba mientras el Gobierno de Trump intensifica sus esfuerzos para presionar a La Habana a llegar a un acuerdo, al tiempo que contin\u00faa ejerciendo su asfixia econ\u00f3mica sobre la isla. Fue una de las visitas de m\u00e1s alto nivel de funcionarios estadounidenses [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T21:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla\",\"datePublished\":\"2026-04-20T21:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/\"},\"wordCount\":747,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/\",\"name\":\"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-20T21:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla - Noticias","og_description":"Una delegaci\u00f3n estadounidense de alto nivel se reuni\u00f3 con funcionarios del Gobierno de Cuba mientras el Gobierno de Trump intensifica sus esfuerzos para presionar a La Habana a llegar a un acuerdo, al tiempo que contin\u00faa ejerciendo su asfixia econ\u00f3mica sobre la isla. Fue una de las visitas de m\u00e1s alto nivel de funcionarios estadounidenses [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-20T21:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/"},"author":{"name":"","@id":""},"headline":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla","datePublished":"2026-04-20T21:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/"},"wordCount":747,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","name":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-20T21:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-20T21:03:43Z","datePublished":"2026-04-20T21:03:43Z","dateModified":"2026-04-20T21:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Delegaci\\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\\u00f3n sobre la isla\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/delegacion-estadounidense-visita-cuba-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/delegacion-estadounidense-visita-cuba-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-20T21:03:43Z\",\"datePublished\":\"2026-04-20T21:03:43Z\",\"dateModified\":\"2026-04-20T21:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472209,"url":"https:\/\/noticiasya.com\/kansas\/2026\/03\/14\/cuba-nieto-raul-castro-conversaciones-eeuu-quien-es-orix\/","url_meta":{"origin":1473342,"position":0},"title":"Mientras EE.UU. presiona a Cuba, un Castro conocido como &#171;el Cangrejo&#187; est\u00e1 haciendo apariciones p\u00fablicas. Por esto importa","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Ra\u00fal Guillermo Rodr\u00edguez Castro, nieto del expresidente de Cuba Ra\u00fal Castro, apareci\u00f3 por primera vez este viernes en dos actos p\u00fablicos junto al presidente Miguel D\u00edaz-Canel, un hecho que, seg\u00fan analistas, plantea interrogantes sobre su cu\u00e1l es su papel en el liderazgo de Cuba, mientras la isla enfrenta llamados a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470873,"url":"https:\/\/noticiasya.com\/kansas\/2026\/02\/04\/cuba-dialogo-eeuu-cambio-regimen-trump-presion-orix\/","url_meta":{"origin":1473342,"position":1},"title":"Exclusiva CNN: Cuba dice que dialogar\u00eda con EE.UU., pero descarta un cambio de r\u00e9gimen, mientras Trump aumenta la presi\u00f3n","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Cuba est\u00e1 dispuesta a entablar un di\u00e1logo \u201csignificativo\u201d con Estados Unidos, pero no est\u00e1 dispuesta a discutir un cambio en su sistema de gobierno, dijo este mi\u00e9rcoles a CNN el viceministro de Relaciones Exteriores de Cuba, en declaraciones que llegan mientras el Gobierno de Trump incrementa la presi\u00f3n sobre la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473736,"url":"https:\/\/noticiasya.com\/kansas\/2026\/05\/02\/trump-control-cuba-diaz-canel-agresor-rendicion-orix\/","url_meta":{"origin":1473342,"position":2},"title":"Trump insiste en tomar el control de Cuba. D\u00edaz-Canel responde que &#171;ning\u00fan agresor encontrar\u00e1 rendici\u00f3n&#187; en la isla","author":"","date":"mayo 2, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, reiter\u00f3 el viernes su comentario sobre la posibilidad de que EE.UU. tome \u201cel control\u201d de Cuba de inmediato, sugiriendo que las fuerzas militares estadounidenses podr\u00edan avanzar sobre la isla de camino de regreso de la guerra en Ir\u00e1n.\u201cY \u00e9l viene originalmente de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456285,"url":"https:\/\/noticiasya.com\/kansas\/2024\/12\/05\/cuba-no-es-realista-deportaciones-masivas-desde-ee-uu-orix\/","url_meta":{"origin":1473342,"position":3},"title":"Viceministro de Exteriores de Cuba afirma que &#171;no es realista&#187; plantear deportaciones masivas desde EE.UU.","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"El gobierno de Cuba considera que \u201cno es realista pensar en deportaciones masivas\u201d, seg\u00fan dijo este mi\u00e9rcoles el viceministro de Exteriores cubano, Carlos Fern\u00e1ndez de Cossio, tras concluir la Ronda de Conversaciones Migratorias entre funcionarios de la isla y de Estados Unidos.\u201cNo es realista pensar que vaya a ocurrir una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472824,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","url_meta":{"origin":1473342,"position":4},"title":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos","author":"","date":"abril 2, 2026","format":false,"excerpt":"El Gobierno cubano anunciar\u00e1 el jueves la liberaci\u00f3n de 2.010 prisioneros, la mayor en a\u00f1os, mientras la isla se ve sometida a una presi\u00f3n cada vez mayor por parte de la administraci\u00f3n Trump.El Gobierno decidi\u00f3 conceder el indulto bas\u00e1ndose en la buena conducta de los reclusos, su estado de salud\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472428,"url":"https:\/\/noticiasya.com\/kansas\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","url_meta":{"origin":1473342,"position":5},"title":"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU.","author":"","date":"marzo 21, 2026","format":false,"excerpt":"El presidente de Cuba, Miguel D\u00edaz-Canel, habl\u00f3 este viernes sobre la presi\u00f3n que ejerce Estados Unidos sobre la isla y, en medio de las tensiones con el Gobierno de Donald Trump, reconoci\u00f3 que puede haber una agresi\u00f3n contra la isla y dijo que el pueblo cubano se prepara para defender\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473342"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473342\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}