{"id":1473345,"date":"2026-04-20T16:03:45","date_gmt":"2026-04-20T23:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/"},"modified":"2026-04-20T16:03:45","modified_gmt":"2026-04-20T23:03:45","slug":"gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/","title":{"rendered":"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid"},"content":{"rendered":"<p>El Gobierno de Venezuela cuestion\u00f3 con fuerza las consignas emitidas contra la presidenta encargada, Delcy Rodr\u00edguez, durante la actuaci\u00f3n del cantante Carlos Baute en Madrid este s\u00e1bado, en un acto de la l\u00edder opositora Mar\u00eda Corina Machado.<\/p>\n<p>En el acto, celebrado en la Puerta del Sol de la capital espa\u00f1ola, uno de los c\u00e1nticos que se escucharon fue \u201c\u00a1Fuera la mona!\u201d, lo que el Gobierno de Venezuela interpret\u00f3 como una referencia a la presidenta encargada. Baute, reconocido m\u00fasico venezolano espa\u00f1ol, <a href=\"https:\/\/www.instagram.com\/reel\/DXTBHmnjjp3\/\">cant\u00f3 la frase<\/a> al micr\u00f3fono tambi\u00e9n. La multitud reunida repiti\u00f3 a coro.<\/p>\n<p>CNN contact\u00f3 al equipo de representantes del m\u00fasico para solicitar comentarios y est\u00e1 a la espera de una respuesta.<\/p>\n<p>En tanto, el cantante respondi\u00f3 a las cr\u00edticas <a href=\"https:\/\/x.com\/carlosbaute\/status\/2045576248869486803?s=20\">en un posteo en su cuenta de X<\/a>, en el que pidi\u00f3 disculpas.<\/p>\n<p>\u201cNo soy racista. Soy un cantante que ama a su pa\u00eds, a su familia y a Dios. Este s\u00e1bado me dej\u00e9 llevar por la emoci\u00f3n de un momento muy fuerte\u2026 y tambi\u00e9n s\u00e9 reconocer cuando algo no estuvo bien\u201d, dijo Baute. \u201cNo creo en el insulto como camino. Venezuela ha vivido durante muchos a\u00f1os momentos dif\u00edciles, donde el respeto muchas veces ha faltado\u201d, a\u00f1adi\u00f3, y reiter\u00f3 sus disculpas \u201cpor las formas\u201d. \u201cPero no por mis valores ni por lo que represento y mucho menos por lo que pienso. Mi compromiso sigue siendo el mismo: mi pa\u00eds, mi gente\u2026 y construir desde el respeto, la uni\u00f3n y una Venezuela libre, en democracia y pr\u00f3spera en el futuro\u201d, concluy\u00f3 el m\u00fasico.<\/p>\n<p>Baute, nacido en Caracas y con doble nacionalidad venezolana y espa\u00f1ola, vive desde hace d\u00e9cadas en Espa\u00f1a y es abiertamente cr\u00edtico del chavismo.<\/p>\n<p>Fue uno de los primeros artistas en celebrar la captura de Nicol\u00e1s Maduro en un operativo militar estadounidense en Caracas el 3 de enero, con una serie de videos en <a href=\"https:\/\/www.instagram.com\/reel\/DTC-IqODIW_\/?utm_source=ig_embed&#038;ig_rid=8d2c16a6-5c4c-4347-9652-47d7bc959fa4\">sus redes sociales<\/a> en los que se lo ve\u00eda visiblemente emocionado.<\/p>\n<p>En un comunicado, la embajadora venezolana en Espa\u00f1a, Gladys Guti\u00e9rrez, consider\u00f3 que los c\u00e1nticos \u201cconstituyen una manifestaci\u00f3n inaceptable de discurso de odio\u201d. Guti\u00e9rrez manifest\u00f3 \u201csus m\u00e1s sinceras disculpas al pueblo de Espa\u00f1a, que conoce en su propia historia el horror del fascismo y de los cr\u00edmenes de odio\u201d, y tambi\u00e9n a todas aquellas personas que hayan podido sentirse ofendidas.<\/p>\n<p>\u201cEs a\u00fan m\u00e1s grave cuando este tipo de expresiones se dirigen contra una mujer, pues configuran una forma de violencia pol\u00edtica basada en la misoginia y el racismo que no puede ser relativizada bajo ninguna circunstancia\u201d, a\u00f1adi\u00f3 Guti\u00e9rrez.<\/p>\n<p>El rechazo tambi\u00e9n fue manifestado por el ministro de Relaciones Interiores de Venezuela, Diosdado Cabello, quien consider\u00f3 que estas consignas fueron \u201cterribles\u201d y que no fueron \u201ccontra Delcy nada m\u00e1s\u201d, sino tambi\u00e9n \u201ccontra la mujer venezolana\u201d en general. Cabello sostuvo durante <a href=\"https:\/\/x.com\/polianalitica\/status\/2045939663806881954?s=20\">un acto<\/a> transmitido este domingo por el canal estatal Venezolana de Televisi\u00f3n (VTV) que la \u201ccampa\u00f1a de odio tiene que cesar\u201d.<\/p>\n<p>CNN pidi\u00f3 comentarios al equipo de prensa de Machado y est\u00e1 a la espera de respuesta.<\/p>\n<p>En <a href=\"https:\/\/efs.efeservicios.com\/texto\/gobierno-venezolano-tacha-racismo-canticos-delcy-rodriguez-madrid\/55020036588\">entrevista con la agencia espa\u00f1ola EFE<\/a>, Machado rechaz\u00f3 los c\u00e1nticos. \u201cJam\u00e1s se escuchar\u00e1 en mi boca una palabra o una expresi\u00f3n que juzgue o descalifique a una persona por su religi\u00f3n, por su g\u00e9nero o por su raza\u201d, dijo la l\u00edder opositora. Y agreg\u00f3: \u201cEso es lo que ha hecho el r\u00e9gimen (de Nicol\u00e1s Maduro) en Venezuela: dividirnos por esos motivos\u201d.<\/p>\n<p>Machado se encontraba el s\u00e1bado en Madrid, donde recibi\u00f3 la Medalla de Oro de la Comunidad de Madrid de manos de la presidenta de la Comunidad, Isabel D\u00edaz-Ayuso. Tras el acto en el que se produjeron los c\u00e1nticos denunciados como racistas, D\u00edaz-Ayuso y Machado aparecieron en el balc\u00f3n y luego la l\u00edder opositora venezolana habl\u00f3 al p\u00fablico.<\/p>\n<p>La visita de Machado a Espa\u00f1a termina este lunes y no incluye una reuni\u00f3n con el presidente del Gobierno espa\u00f1ol, Pedro S\u00e1nchez. El mandatario espa\u00f1ol dijo que Machado hab\u00eda rechazado una invitaci\u00f3n para reunirse con \u00e9l. Por su parte, en uno de sus discursos durante su gira por Espa\u00f1a, Machado argument\u00f3 que \u201clo sucedido en Barcelona ha demostrado que una reuni\u00f3n con S\u00e1nchez no era oportuna\u201d, en referencia a <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/18\/mundo\/cumbre-progresista-democracia-trump-cuba-orix\">la cumbre de l\u00edderes progresistas celebrada el s\u00e1bado<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Venezuela cuestion\u00f3 con fuerza las consignas emitidas contra la presidenta encargada, Delcy Rodr\u00edguez, durante la actuaci\u00f3n del cantante Carlos Baute en Madrid este s\u00e1bado, en un acto de la l\u00edder opositora Mar\u00eda Corina Machado. En el acto, celebrado en la Puerta del Sol de la capital espa\u00f1ola, uno de los c\u00e1nticos que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473345","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Venezuela cuestion\u00f3 con fuerza las consignas emitidas contra la presidenta encargada, Delcy Rodr\u00edguez, durante la actuaci\u00f3n del cantante Carlos Baute en Madrid este s\u00e1bado, en un acto de la l\u00edder opositora Mar\u00eda Corina Machado. En el acto, celebrado en la Puerta del Sol de la capital espa\u00f1ola, uno de los c\u00e1nticos que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T23:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid\",\"datePublished\":\"2026-04-20T23:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/\"},\"wordCount\":794,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/\",\"name\":\"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-20T23:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid - Noticias","og_description":"El Gobierno de Venezuela cuestion\u00f3 con fuerza las consignas emitidas contra la presidenta encargada, Delcy Rodr\u00edguez, durante la actuaci\u00f3n del cantante Carlos Baute en Madrid este s\u00e1bado, en un acto de la l\u00edder opositora Mar\u00eda Corina Machado. En el acto, celebrado en la Puerta del Sol de la capital espa\u00f1ola, uno de los c\u00e1nticos que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-20T23:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid","datePublished":"2026-04-20T23:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/"},"wordCount":794,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/","name":"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-20T23:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\u00edguez durante un mitin en Madrid","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-20T23:03:45Z","datePublished":"2026-04-20T23:03:45Z","dateModified":"2026-04-20T23:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Venezuela rechaza las consignas contra Delcy Rodr\\u00edguez durante un mitin en Madrid\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/gobierno-rechaza-consignas-delcy-rodriguez-mitin-madrid-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-20T23:03:45Z\",\"datePublished\":\"2026-04-20T23:03:45Z\",\"dateModified\":\"2026-04-20T23:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473477,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/24\/entrevista-carlos-baute-canticos-racistas-madrid-orix\/","url_meta":{"origin":1473345,"position":0},"title":"&#171;Me dej\u00e9 llevar por el momento&#187;, dice a CNN Carlos Baute sobre la pol\u00e9mica por los c\u00e1nticos racistas contra Delcy Rodr\u00edguez","author":"","date":"abril 24, 2026","format":false,"excerpt":"El cantante Carlos Baute dijo a CNN que, durante su presentaci\u00f3n en Madrid, en la que el p\u00fablico core\u00f3 consignas racistas contra la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, reaccion\u00f3 de forma impulsiva. Tambi\u00e9n volvi\u00f3 a pedir disculpas tras la controversia desatada.\u201cMe dej\u00e9 llevar por el momento y nada m\u00e1s\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470577,"url":"https:\/\/noticiasya.com\/kansas\/2026\/01\/28\/delcy-rodriguez-dialogo-comandante-fanb-orix\/","url_meta":{"origin":1473345,"position":1},"title":"Delcy Rodr\u00edguez pide que quienes &#171;pretendan perpetrar da\u00f1o y agresi\u00f3n contra Venezuela&#187; se queden en Washington","author":"","date":"enero 28, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, afirm\u00f3 este mi\u00e9rcoles que su Gobierno ha abierto un \u201cespacio para el di\u00e1logo pol\u00edtico\u201d, pero advirti\u00f3 que quienes \u201cpretendan perpetrar el da\u00f1o y la agresi\u00f3n\u201d contra Venezuela deben permanecer en Washington.\u201cLe tengo un mensaje muy claro al extremismo de Venezuela y a sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469883,"url":"https:\/\/noticiasya.com\/kansas\/2026\/01\/07\/delcy-rodriguez-nuevo-momento-politico-orix\/","url_meta":{"origin":1473345,"position":2},"title":"Delcy Rodr\u00edguez dice que Venezuela vive &#171;nuevo momento pol\u00edtico&#187;: critica ataque pero afirma que el pa\u00eds &#171;no est\u00e1 en guerra&#187;","author":"","date":"enero 7, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, dijo este mi\u00e9rcoles que el pa\u00eds vive \u201cun nuevo momento pol\u00edtico\u201d luego del ataque militar de Estados Unidos que deriv\u00f3 en la captura del presidente Nicol\u00e1s Maduro y de su esposa, Cilia Flores, quienes fueron llevados de Caracas a Nueva York para enfrentar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469807,"url":"https:\/\/noticiasya.com\/kansas\/2026\/01\/05\/delcy-rodriguez-jura-presidenta-encargada-orix\/","url_meta":{"origin":1473345,"position":3},"title":"Delcy Rodr\u00edguez asume formalmente como presidenta encargada y rechaza &#171;agresi\u00f3n militar ileg\u00edtima&#187; contra Venezuela","author":"","date":"enero 5, 2026","format":false,"excerpt":"La vicepresidenta Delcy Rodr\u00edguez asumi\u00f3 este lunes formalmente como presidenta encargada de Venezuela, luego de la captura del presidente Nicol\u00e1s Maduro en un operativo militar de Estados Unidos.La juramentaci\u00f3n se dio en una ceremonia en la Asamblea Nacional, encabezada por el diputado Jorge Rodr\u00edguez, hermano de la presidenta encargada y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472776,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/01\/eeuu-levanta-sanciones-delcy-rodriguez-orix\/","url_meta":{"origin":1473345,"position":4},"title":"EE.UU. levanta las sanciones que hab\u00eda impuesto a Delcy Rodr\u00edguez en 2018","author":"","date":"abril 1, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos levant\u00f3 este mi\u00e9rcoles las sanciones que desde 2018 manten\u00eda contra la actual presidenta encargada de Venezuela, Delcy Rodr\u00edguez, de acuerdo con una actualizaci\u00f3n de la lista de personas sancionadas de la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s), perteneciente al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470505,"url":"https:\/\/noticiasya.com\/kansas\/2026\/01\/26\/delcy-rodriguez-eeuu-no-tenemos-miedo-orix\/","url_meta":{"origin":1473345,"position":5},"title":"Delcy Rodr\u00edguez insiste en que Venezuela no se subordina a EE.UU.: &#171;No tenemos miedo a relaciones de respeto&#187;","author":"","date":"enero 26, 2026","format":false,"excerpt":"La presidenta interina de Venezuela, Delcy Rodr\u00edguez, insisti\u00f3 este lunes en que el pa\u00eds sudamericano no se subordina a Estados Unidos, con el argumento de que no obedece a factores externos y no tiene miedo a \u201crelaciones de respeto\u201d con la naci\u00f3n gobernada por Donald Trump.\u201cNo tenemos otro factor externo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473345"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473345\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}