{"id":1473346,"date":"2026-04-20T16:03:45","date_gmt":"2026-04-20T23:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/"},"modified":"2026-04-20T16:03:45","modified_gmt":"2026-04-20T23:03:45","slug":"tim-cook-ceo-apple-dejara-cargo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/","title":{"rendered":"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada"},"content":{"rendered":"<p>Tim Cook, el ejecutivo que llev\u00f3 a Apple a convertirse en una empresa de US$ 4 billones y defini\u00f3 su identidad en la era posterior a Steve Jobs, dejar\u00e1 el cargo de director ejecutivo, inform\u00f3 Apple el lunes.<\/p>\n<p>John Ternus, vicepresidente s\u00e9nior de ingenier\u00eda de hardware de Apple, asumir\u00e1 como CEO a partir del 1 de septiembre. Cook se convertir\u00e1 en presidente ejecutivo del consejo de administraci\u00f3n de Apple y seguir\u00e1 como CEO durante el verano para garantizar una transici\u00f3n fluida, dijo la empresa.<\/p>\n<p>\u201cHa sido el mayor privilegio de mi vida ser el CEO de Apple y haber sido digno de confianza para liderar una empresa tan extraordinaria\u201d, dijo Cook en un comunicado de prensa\u201d.<\/p>\n<p>La noticia llega en medio de una <a href=\"https:\/\/www.cnn.com\/2025\/12\/06\/tech\/apple-tim-cook-leadership-changes\">serie de cambios en los rangos ejecutivos<\/a> de Apple a finales de 2025, incluidas las salidas de su jefe de IA, su responsable de pol\u00edticas y uno de sus principales l\u00edderes de dise\u00f1o.<\/p>\n<p>Cook, quien se convirti\u00f3 en director ejecutivo de Apple en 2011 tras desempe\u00f1arse como su director de operaciones, fue responsable de impulsar a Apple m\u00e1s all\u00e1 del pu\u00f1ado de productos por los que la empresa era conocida inicialmente, como la Mac, el iPod y el iPhone. Bajo el liderazgo de Cook, Apple se convirti\u00f3 en un actor importante en nuevas \u00e1reas como el entretenimiento, la salud y los dispositivos vestibles.<\/p>\n<p>Tambi\u00e9n orient\u00f3 a la empresa a trav\u00e9s de momentos definitorios en la historia mundial que tuvieron un profundo impacto en la compa\u00f1\u00eda, como la pandemia de covid-19, las pol\u00edticas arancelarias del presidente Donald Trump y la guerra comercial con China.<\/p>\n<p>Steve Jobs present\u00f3 el iPhone, pero fue Cook quien lo convirti\u00f3 en una plataforma para lanzar otros productos exitosos, desde el Apple Watch hasta los AirPods y Apple TV+; todos los cuales solo tienen \u00e9xito porque el iPhone es el <a href=\"https:\/\/www.cnn.com\/2026\/04\/01\/tech\/iphone-apple-ipod-product-history\">segundo smartphone m\u00e1s popular<\/a> del mundo.<\/p>\n<p>Esas apuestas han dado resultado. El negocio de servicios de Apple es ahora la segunda unidad m\u00e1s grande, detr\u00e1s del iPhone, y Apple ha posicionado con frecuencia al Apple Watch como un dispositivo que salva vidas. El Apple Watch fue la primera nueva categor\u00eda de producto lanzada bajo Cook, quien <a href=\"https:\/\/www.cnbc.com\/2019\/01\/08\/tim-cook-teases-new-apple-services-tied-to-health-care.html\">le dijo a CNBC<\/a> en 2019 que cre\u00eda que la mayor contribuci\u00f3n de Apple a la humanidad \u201ctendr\u00eda que ver con la salud\u201d.<\/p>\n<p>En una carta en el sitio web de Apple, Cook describi\u00f3 c\u00f3mo ha comenzado cada d\u00eda durante los \u00faltimos 15 a\u00f1os leyendo correos electr\u00f3nicos de usuarios de Apple de todo el mundo.<\/p>\n<p>\u201cUstedes comparten conmigo peque\u00f1os fragmentos de sus vidas y me cuentan cosas que quieren que sepa sobre c\u00f3mo Apple los ha impactado\u201d, escribi\u00f3, y agreg\u00f3 que el nuevo rol es una transici\u00f3n y \u201cno un adi\u00f3s\u201d.<\/p>\n<p>Pero las expansiones m\u00e1s recientes de Apple hacia \u00e1reas como la realidad virtual y la inteligencia artificial no han sido tan exitosas. Su <a href=\"https:\/\/www.cnn.com\/videos\/tech\/2024\/02\/02\/apple-headset-3500-scott-stein-cnet-cnntm-vpx.cnn\">costoso visor Vision Pro<\/a> sigue siendo en gran medida un producto de nicho y a\u00fan no ha logrado un atractivo masivo como los productos anteriores de Apple. La empresa retras\u00f3 este a\u00f1o una actualizaci\u00f3n importante de Siri que habr\u00eda ayudado a ponerla al d\u00eda con competidores como ChatGPT de OpenAI y Gemini de Google. Los tropiezos de Apple en IA han sido un punto focal durante todo el a\u00f1o, ya que los analistas han presionado a Cook en las llamadas de resultados sobre su estrategia de IA y si la empresa est\u00e1 preparada para un futuro m\u00e1s all\u00e1 del iPhone.<\/p>\n<p>Se recordar\u00e1 a Cook por m\u00e1s que los lanzamientos de productos de Apple. Condujo la relaci\u00f3n de la empresa con Trump durante ambos mandatos presidenciales, y m\u00e1s recientemente se comprometi\u00f3 a invertir US$ 600.000 millones en expandir la presencia de Apple en EE.UU. tras enfrentar presi\u00f3n del presidente para fabricar los iPhone en el pa\u00eds. Cook le regal\u00f3 a Trump una placa de vidrio de uno de los socios de suministro de la empresa en EE.UU. a principios de este a\u00f1o.<\/p>\n<p>Tambi\u00e9n condujo a Apple a trav\u00e9s de la pandemia de covid-19, tomando decisiones r\u00e1pidas sobre c\u00f3mo gestionar las tiendas minoristas de la empresa y la cadena de suministro con base en China. Apple fue una de las primeras empresas en cerrar sus tiendas minoristas globales en los primeros d\u00edas de la pandemia.<\/p>\n<p>Ternus, un veterano ejecutivo de Apple, era ampliamente esperado como el sucesor de Cook en el cargo. Comenz\u00f3 en Apple en el equipo de dise\u00f1o de productos en 2001 y fue ascendiendo en la empresa, primero convirti\u00e9ndose en vicepresidente de ingenier\u00eda de hardware en 2013 y luego asumiendo el cargo de vicepresidente s\u00e9nior en 2021.<\/p>\n<p>Desempe\u00f1\u00f3 un papel importante en el desarrollo de productos como el iPad y los AirPods, seg\u00fan Apple. M\u00e1s recientemente encabez\u00f3 el <a href=\"https:\/\/www.cnn.com\/2026\/03\/04\/tech\/apple-event-macbook-neo-release\">lanzamiento del MacBook Neo<\/a>, el primer MacBook de bajo costo de Apple, el mes pasado.<\/p>\n<p>\u201cMe siento honrado de asumir este cargo, y prometo liderar con los valores y la visi\u00f3n que han llegado a definir este lugar especial durante medio siglo\u201d, dijo Ternus en un comunicado de prensa.<\/p>\n<p>Ternus tomar\u00e1 las riendas durante un a\u00f1o crucial para Apple, que se espera que incluya una renovaci\u00f3n de productos populares como Siri y el iPhone. Es probable que Apple presente la esperada actualizaci\u00f3n de Siri durante su Conferencia Mundial de Desarrolladores en junio, lo que podr\u00eda ayudar a Apple a ponerse al d\u00eda con ChatGPT de OpenAI y Gemini de Google. Y, seg\u00fan <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2026-04-07\/apple-s-foldable-iphone-remains-on-track-for-september-debut\">Bloomberg<\/a>, Apple supuestamente planea lanzar el primer iPhone plegable en septiembre.<\/p>\n<p>\u201cCook deja un legado duradero en Cupertino\u201d, coment\u00f3 el analista Dan Ives, de Wedbush Securities, en una nota de investigaci\u00f3n. \u201cY habr\u00e1 mucha presi\u00f3n sobre Ternus para producir \u00e9xito desde el inicio, especialmente en el frente de la IA\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tim Cook, el ejecutivo que llev\u00f3 a Apple a convertirse en una empresa de US$ 4 billones y defini\u00f3 su identidad en la era posterior a Steve Jobs, dejar\u00e1 el cargo de director ejecutivo, inform\u00f3 Apple el lunes. John Ternus, vicepresidente s\u00e9nior de ingenier\u00eda de hardware de Apple, asumir\u00e1 como CEO a partir del 1 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473346","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tim Cook, el ejecutivo que llev\u00f3 a Apple a convertirse en una empresa de US$ 4 billones y defini\u00f3 su identidad en la era posterior a Steve Jobs, dejar\u00e1 el cargo de director ejecutivo, inform\u00f3 Apple el lunes. John Ternus, vicepresidente s\u00e9nior de ingenier\u00eda de hardware de Apple, asumir\u00e1 como CEO a partir del 1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T23:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada\",\"datePublished\":\"2026-04-20T23:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/\"},\"wordCount\":1033,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/\",\"name\":\"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-20T23:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada - Noticias","og_description":"Tim Cook, el ejecutivo que llev\u00f3 a Apple a convertirse en una empresa de US$ 4 billones y defini\u00f3 su identidad en la era posterior a Steve Jobs, dejar\u00e1 el cargo de director ejecutivo, inform\u00f3 Apple el lunes. John Ternus, vicepresidente s\u00e9nior de ingenier\u00eda de hardware de Apple, asumir\u00e1 como CEO a partir del 1 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-20T23:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/"},"author":{"name":"","@id":""},"headline":"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada","datePublished":"2026-04-20T23:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/"},"wordCount":1033,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/","name":"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-20T23:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tim Cook, CEO de Apple, dejar\u00e1 el cargo tras m\u00e1s de una d\u00e9cada","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/20\/tim-cook-ceo-apple-dejara-cargo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-20T23:03:45Z","datePublished":"2026-04-20T23:03:45Z","dateModified":"2026-04-20T23:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tim Cook, CEO de Apple, dejar\\u00e1 el cargo tras m\\u00e1s de una d\\u00e9cada\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/tim-cook-ceo-apple-dejara-cargo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/20\\\/tim-cook-ceo-apple-dejara-cargo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-20T23:03:45Z\",\"datePublished\":\"2026-04-20T23:03:45Z\",\"dateModified\":\"2026-04-20T23:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473349,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/20\/quien-es-john-ternus-proximo-ceo-apple-trax\/","url_meta":{"origin":1473346,"position":0},"title":"\u00bfQui\u00e9n es John Ternus, el pr\u00f3ximo CEO de Apple?","author":"","date":"abril 20, 2026","format":false,"excerpt":"El veterano de Apple John Ternus tomar\u00e1 las riendas de la empresa de US$ 4 billones como CEO a partir del 1 de septiembre.\u201cHabiendo pasado casi toda mi carrera en Apple, he tenido la suerte de haber trabajado bajo Steve Jobs y de haber tenido a Tim Cook como mi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473394,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/22\/tim-cook-carrera-apple-cifras-trax\/","url_meta":{"origin":1473346,"position":1},"title":"La extraordinaria carrera de Tim Cook en cuatro gr\u00e1ficas","author":"","date":"abril 22, 2026","format":false,"excerpt":"Desde sus inicios en Apple, Tim Cook fue un hombre de n\u00fameros.Poco despu\u00e9s de que Steve Jobs regresara a Apple a finales de los a\u00f1os 90 para rescatar la empresa que hab\u00eda fundado, contrat\u00f3 a Cook \u2014quien ven\u00eda de Compaq\u2014 para dirigir la cadena de suministro y las operaciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473368,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/apple-nombramiento-ia-tim-cook-trax\/","url_meta":{"origin":1473346,"position":2},"title":"La elecci\u00f3n de Apple del sucesor de Tim Cook sugiere cu\u00e1les son sus planes para la era de la IA","author":"","date":"abril 21, 2026","format":false,"excerpt":"El anuncio realizado el lunes por Apple \u2014de que su presidente ejecutivo, Tim Cook, dejar\u00e1 el cargo y John Ternus asumir\u00e1 el mando\u2014 se\u00f1ala un cambio significativo para la compa\u00f1\u00eda: Apple est\u00e1 apostando su futuro a la tecnolog\u00eda que evoluciona con mayor rapidez en la historia de la inform\u00e1tica.Apple sigue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462713,"url":"https:\/\/noticiasya.com\/kansas\/2025\/05\/23\/trump-apple-arancel-iphone-ee-uu-trax\/","url_meta":{"origin":1473346,"position":3},"title":"Trump amenaza a Apple con aplicar un arancel del 25 % si no fabrica sus iPhone en EE.UU.","author":"","date":"mayo 23, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, exigi\u00f3 este viernes a Apple que fabrique sus iPhone en Estados Unidos o se enfrentar\u00e1 a un arancel del 25 %.\u201cHace tiempo que inform\u00e9 a Tim Cook, de Apple, que espero que sus iPhone que se venden en Estados Unidos se fabriquen y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462887,"url":"https:\/\/noticiasya.com\/kansas\/2025\/05\/28\/apple-iphone-trump-estados-unidos-china-trax\/","url_meta":{"origin":1473346,"position":4},"title":"Por qu\u00e9 Apple no fabrica iPhones en EE.UU., y probablemente no lo har\u00e1","author":"","date":"mayo 28, 2025","format":false,"excerpt":"En 2011, el entonces presidente Barack Obama presion\u00f3 al CEO de Apple, Steve Jobs, sobre qu\u00e9 se necesitar\u00eda para traer la producci\u00f3n del iPhone a Estados Unidos, seg\u00fan The New York Times.Catorce a\u00f1os despu\u00e9s, el presidente Donald Trump le plantea esa pregunta al actual CEO de Apple, Tim Cook, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469023,"url":"https:\/\/noticiasya.com\/kansas\/2025\/12\/06\/apple-tim-cook-cambios-iderazgo-trax\/","url_meta":{"origin":1473346,"position":5},"title":"\u00bfQu\u00e9 est\u00e1 cambiando en Apple?","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"Apple durante d\u00e9cadas ha sido conocida por una serie consistente de productos de consumo con dise\u00f1o vanguardista, que definen y han dado forma al modo en que las personas usan la tecnolog\u00eda.Ahora, la compa\u00f1\u00eda conocida por su estabilidad est\u00e1 pasando por una reestructuraci\u00f3n en la cima, ya que tanto Apple\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473346"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473346\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}