{"id":1473360,"date":"2026-04-21T07:03:52","date_gmt":"2026-04-21T14:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/"},"modified":"2026-04-21T07:03:52","modified_gmt":"2026-04-21T14:03:52","slug":"uganda-recuperacion-tumbas-de-kasubi-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/","title":{"rendered":"Se reabre un portal hacia un reino antiguo e invisible en Uganda"},"content":{"rendered":"<p>Al caminar por el recinto que alberga las Tumbas de Kasubi, el sendero principal conduce hacia lo que deber\u00eda ser una entrada. Sin embargo, termina justo en una de las capas de paja que recubren la estructura de 7,6 metros de altura conocida como Muzibu Azala Mpanga. Su aspecto recuerda al de una cesta gigante invertida. De no ser por las hileras de calzado, ordenadas pulcramente en el exterior, nadie sospechar\u00eda que existe una forma de acceder al interior.<\/p>\n<p>Al apartar la larga hierba seca, uno se adentra en otro mundo. El calor ecuatorial de Uganda queda atr\u00e1s; en el interior, un techo de doble capa, tejido con ca\u00f1as y hierbas, regula la temperatura, manteniendo el aire fresco y en calma. A ambos lados de la entrada, sentadas sobre esteras de hierba, aguardan unas mujeres: las \u201cviudas\u201d de los reyes difuntos, descendientes de la familia real que cumplen turnos de un mes para recibir a los peregrinos y atender a los esp\u00edritus de los monarcas que se hallan tras la cortina.<\/p>\n<p>Los peregrinos se arrodillan ante cuatro fotograf\u00edas, una por cada rey sepultado en el lugar. Detr\u00e1s de ellas cuelga una cortina que se extiende desde el suelo hasta el techo, confeccionada con tela de corteza de color pardo rojizo: un distintivo textil ugand\u00e9s que se elabora machacando la corteza de una higuera aut\u00f3ctona.<\/p>\n<p>La cortina semeja una pared. No obstante, para los habitantes del reino de Buganda, constituye un portal hacia un bosque sagrado e invisible. Seg\u00fan sus creencias, los reyes nunca mueren; simplemente se adentran en el bosque y contin\u00faan comunic\u00e1ndose con los vivos a trav\u00e9s de m\u00e9diums espirituales.<\/p>\n<p>Las Tumbas de Kasubi, declaradas Patrimonio de la Humanidad por la Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura (UNESCO, por sus siglas en ingl\u00e9s) y situadas en Kampala, la capital de Uganda, representan el coraz\u00f3n espiritual del reino de Buganda.<\/p>\n<p>Sin embargo, durante 16 a\u00f1os, dicho portal permaneci\u00f3 cerrado.<\/p>\n<p>En el a\u00f1o 2010, un incendio arras\u00f3 el recinto, y destruy\u00f3 su estructura principal. Construido originalmente en 1882 y con una extensi\u00f3n de m\u00e1s de 30 metros, el edificio apenas tuvo posibilidades de sobrevivir, dado que hab\u00eda sido erigido casi en su totalidad con materiales vegetales. Un conjunto de columnas de madera sosten\u00eda el inmenso techo de paja; cada una de ellas se hallaba revestida con tela de corteza. Si bien algunos de los edificios circundantes lograron salvarse, la tumba central qued\u00f3 reducida a cenizas.<\/p>\n<p>La causa del incendio nunca se hizo p\u00fablica; no obstante, el siniestro desat\u00f3 una oleada de dolor e indignaci\u00f3n que deriv\u00f3 en disturbios con consecuencias fatales.<\/p>\n<p>Ahora, las tumbas han vuelto a abrirse al p\u00fablico, tras un minucioso proceso que implic\u00f3 mucho m\u00e1s que simples obras de construcci\u00f3n. Cuando el arquitecto Jonathan Nsubuga asumi\u00f3 el proyecto, descubri\u00f3 que muchas de las t\u00e9cnicas de construcci\u00f3n tradicionales utilizadas para crear la estructura original corr\u00edan el riesgo de desaparecer. Fue necesario formar a nuevos artesanos y restaurar con esmero los elementos espirituales que definen el espacio.<\/p>\n<p>\u201cEn mis investigaciones, y bas\u00e1ndome en las normas culturales, formulamos un nuevo concepto: la recuperaci\u00f3n del patrimonio. No es reconstrucci\u00f3n, es recuperaci\u00f3n\u201d, afirma. \u201cPorque eso es lo que llevo haciendo desde hace 15 a\u00f1os: recuperar el patrimonio que fue destruido\u201d.<\/p>\n<p>Pocas ciudades de \u00c1frica conservan este tipo de arquitectura tradicional y de espacio sagrado en el coraz\u00f3n de una capital moderna. Cuando los misioneros brit\u00e1nicos \u2014y, m\u00e1s tarde, los colonizadores\u2014 llegaron a finales del siglo XIX, las colinas de lo que hoy es Kampala ya constitu\u00edan el centro del reino de Buganda.<\/p>\n<p>Seg\u00fan la tradici\u00f3n de Buganda, cuando un rey fallec\u00eda, su palacio se convert\u00eda en su lugar de sepultura. El lugar de descanso f\u00edsico permanece oculto tras una cortina de tela de corteza, accesible \u00fanicamente para los familiares cercanos. Cada nuevo monarca constru\u00eda un nuevo palacio en las proximidades, desplazando as\u00ed la sede del poder con el paso del tiempo. A medida que el asentamiento brit\u00e1nico se expand\u00eda, fue creciendo alrededor de este paisaje real preexistente.<\/p>\n<p>En Kasubi, la estructura original fue construida en 1882 por Kabaka Mutesa I. Falleci\u00f3 dos a\u00f1os despu\u00e9s, y el reino se vio sumido en d\u00e9cadas de agitaci\u00f3n a consecuencia de la colonizaci\u00f3n y la lucha por la independencia. En total, cuatro reyes se hallan sepultados en este lugar.<\/p>\n<p>Cuando el edificio ardi\u00f3, la p\u00e9rdida no fue meramente arquitect\u00f3nica. Para muchos habitantes de Buganda, las tumbas representan tanto un espacio sagrado como un s\u00edmbolo de unidad y resistencia.<\/p>\n<p>En el interior, el inmenso techo se sostiene sobre enormes postes de madera y 52 anillos conc\u00e9ntricos tejidos con hierba. Cada anillo representa a un clan del reino de Buganda, y cada clan tiene una funci\u00f3n definida. En el exterior, en una de las dependencias con techo de paja, los guardias reales permanecen sentados a la entrada del recinto, manteniendo una vigilia que, seg\u00fan se dice, se remonta a m\u00e1s de 800 a\u00f1os atr\u00e1s. Se cree que el actual jefe de la guardia tiene 101 a\u00f1os. Cuando este fallezca, su clan, llamado el clan del B\u00fafalo, deber\u00e1 nombrar de inmediato a un sucesor para que contin\u00fae la vigilia.<\/p>\n<p>Restaurar la presencia espiritual del lugar le exigi\u00f3 a Nsubuga profundizar en tradiciones que nunca hab\u00eda llegado a asimilar por completo. Educado en Gran Breta\u00f1a, creci\u00f3 hasta cierto punto alejado de las antiguas pr\u00e1cticas de Buganda. Y, a pesar de toda su formaci\u00f3n acad\u00e9mica, exist\u00edan l\u00edmites respecto a lo que se le permit\u00eda hacer: no ten\u00eda autorizaci\u00f3n ni siquiera para clavar un clavo si dicha tarea quedaba fuera del \u00e1mbito de responsabilidad de su propio clan. Del mismo modo, los encargados de colocar los techos de paja deben pertenecer al clan del Mono Colobo, y los decoradores, al clan del Leopardo. Si un anciano fallece sin haber transmitido sus conocimientos a la siguiente generaci\u00f3n, esa parte del edificio simplemente no podr\u00e1 terminarse.<\/p>\n<p>\u201cHay mucho de intangible en todo esto; es algo que no se ve\u201d, afirma Nsubuga. \u201cMi labor consist\u00eda en crear un espacio propicio para que los esp\u00edritus pudieran manifestarse y para permitirles sintonizar con nuestro propio proceso de pensamiento. Por eso, siempre describo a Muzibu Azala Mpanga como algo m\u00e1s que una simple casa: es un recept\u00e1culo. Es como una nave espacial. Y su \u00fanica funci\u00f3n es captar la esencia espiritual de los reyes y los m\u00e9diums del pasado\u201d.<\/p>\n<p>Para aprender a respetar la espiritualidad de las tumbas, Nsubuga recurri\u00f3 a la actual m\u00e9dium espiritual, quien sirve de canal para el primer rey de Buganda: Kubaka Kintu. Establecer un v\u00ednculo de confianza y forjar esa relaci\u00f3n fue tambi\u00e9n un proceso que requiri\u00f3 tiempo. Finalmente, ella le proporcion\u00f3 instrucciones detalladas sobre las pr\u00e1cticas correctas que deb\u00edan seguirse en el edificio.<\/p>\n<p>Nsubuga descubri\u00f3, asimismo, que deb\u00eda actuar como un puente entre las tradiciones ugandesas y el mundo moderno de los organismos financiadores y de la UNESCO, organismo que ha incluido las tumbas \u2014as\u00ed como el tejido de corteza de \u00e1rbol\u2014 en su lista de Patrimonio de la Humanidad. Mantener dicha categor\u00eda durante el proceso de reconstrucci\u00f3n exigi\u00f3 un exhaustivo trabajo de coordinaci\u00f3n. Aunque las tumbas ya han reabierto al p\u00fablico, tanto para peregrinos como para turistas, la reapertura oficial a\u00fan est\u00e1 por llegar. Ser\u00e1 entonces cuando se corte la capa de paja que cubre la entrada, en una ceremonia tradicional que marcar\u00e1 la reapertura formal.<\/p>\n<p>Mientras tanto, los peregrinos llegan en un flujo constante para solicitar la intercesi\u00f3n de los reyes, rezar o simplemente rendir homenaje. Los gu\u00edas ofrecen a los turistas una visi\u00f3n general de la historia y la importancia del lugar. En el exterior, en el patio, la gente acude para bailar, grabar videos y celebrar la restauraci\u00f3n.<\/p>\n<p>\u201cUn colega brit\u00e1nico me dijo: \u2018Jonathan, \u00bfcu\u00e1ntos arquitectos pueden decir que trabajan en un proyecto que define a una naci\u00f3n?\u2019. Le respond\u00ed: \u2018No muchos\u2019\u201d, comenta Nsubuga. \u201cAs\u00ed que me considero muy afortunado\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al caminar por el recinto que alberga las Tumbas de Kasubi, el sendero principal conduce hacia lo que deber\u00eda ser una entrada. Sin embargo, termina justo en una de las capas de paja que recubren la estructura de 7,6 metros de altura conocida como Muzibu Azala Mpanga. Su aspecto recuerda al de una cesta gigante [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473360","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se reabre un portal hacia un reino antiguo e invisible en Uganda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se reabre un portal hacia un reino antiguo e invisible en Uganda - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al caminar por el recinto que alberga las Tumbas de Kasubi, el sendero principal conduce hacia lo que deber\u00eda ser una entrada. Sin embargo, termina justo en una de las capas de paja que recubren la estructura de 7,6 metros de altura conocida como Muzibu Azala Mpanga. Su aspecto recuerda al de una cesta gigante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T14:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se reabre un portal hacia un reino antiguo e invisible en Uganda\",\"datePublished\":\"2026-04-21T14:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/\"},\"wordCount\":1428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/\",\"name\":\"Se reabre un portal hacia un reino antiguo e invisible en Uganda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-21T14:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se reabre un portal hacia un reino antiguo e invisible en Uganda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se reabre un portal hacia un reino antiguo e invisible en Uganda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se reabre un portal hacia un reino antiguo e invisible en Uganda - Noticias","og_description":"Al caminar por el recinto que alberga las Tumbas de Kasubi, el sendero principal conduce hacia lo que deber\u00eda ser una entrada. Sin embargo, termina justo en una de las capas de paja que recubren la estructura de 7,6 metros de altura conocida como Muzibu Azala Mpanga. Su aspecto recuerda al de una cesta gigante [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-21T14:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/"},"author":{"name":"","@id":""},"headline":"Se reabre un portal hacia un reino antiguo e invisible en Uganda","datePublished":"2026-04-21T14:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/"},"wordCount":1428,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/","name":"Se reabre un portal hacia un reino antiguo e invisible en Uganda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-21T14:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se reabre un portal hacia un reino antiguo e invisible en Uganda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se reabre un portal hacia un reino antiguo e invisible en Uganda","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/21\/uganda-recuperacion-tumbas-de-kasubi-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-21T14:03:52Z","datePublished":"2026-04-21T14:03:52Z","dateModified":"2026-04-21T14:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se reabre un portal hacia un reino antiguo e invisible en Uganda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/21\\\/uganda-recuperacion-tumbas-de-kasubi-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/21\\\/uganda-recuperacion-tumbas-de-kasubi-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-21T14:03:52Z\",\"datePublished\":\"2026-04-21T14:03:52Z\",\"dateModified\":\"2026-04-21T14:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447209,"url":"https:\/\/noticiasya.com\/kansas\/2024\/03\/21\/planta-esta-todas-partes-avivando-creciente-riesgo-catastrofe-incendios-forestales-trax\/","url_meta":{"origin":1473360,"position":0},"title":"Una planta omnipresente alimenta un creciente riesgo de cat\u00e1strofe por incendios forestales","author":"","date":"marzo 21, 2024","format":false,"excerpt":"(CNN) -- Una planta omnipresente, resistente y aparentemente inofensiva est\u00e1 ayudando al aumento en la cantidad de grandes incendios forestales, destructivos y de r\u00e1pido movimiento en Estados Unidos.La hierba es tan abundante como el sol y, en las condiciones meteorol\u00f3gicas adecuadas, funciona como la gasolina para los incendios forestales: basta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470199,"url":"https:\/\/noticiasya.com\/kansas\/2026\/01\/17\/uganda-museveni-reeleccion-reux\/","url_meta":{"origin":1473360,"position":1},"title":"El veterano presidente de Uganda, Yoweri Museveni, gana la reelecci\u00f3n mientras se desconoce el paradero del l\u00edder opositor","author":"","date":"enero 17, 2026","format":false,"excerpt":"El veterano presidente Yoweri Museveni fue declarado el vencedor por abrumadora mayor\u00eda en las elecciones presidenciales de Uganda este s\u00e1bado, extendiendo su Gobierno hacia una quinta d\u00e9cada tras una contienda empa\u00f1ada por incidentes violentos y acusaciones de fraude.El resultado otorga a Museveni, de 81 a\u00f1os, la victoria decisiva que buscaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465835,"url":"https:\/\/noticiasya.com\/kansas\/2025\/08\/25\/abrego-deportacion-uganda-ice-trax\/","url_meta":{"origin":1473360,"position":2},"title":"Kilmar \u00c1brego Garc\u00eda lucha contra su deportaci\u00f3n a Uganda tras quedar bajo custodia del ICE","author":"","date":"agosto 25, 2025","format":false,"excerpt":"Minutos despu\u00e9s de que Kilmar \u00c1brego Garc\u00eda fuera detenido por funcionarios de inmigraci\u00f3n en Baltimore, sus abogados presentaron una nueva demanda instando a una jueza federal a ordenar su liberaci\u00f3n y agilizar su proceso de deportaci\u00f3n para que pueda tener la oportunidad de impugnar su posible env\u00edo a Uganda.La jueza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465949,"url":"https:\/\/noticiasya.com\/kansas\/2025\/08\/28\/uganda-criticas-acuerdo-migratorio-eeuu-trax\/","url_meta":{"origin":1473360,"position":3},"title":"Uganda, el pa\u00eds africano que acoge a m\u00e1s refugiados, enfrenta cr\u00edticas por el acuerdo migratorio con EE.UU.","author":"","date":"agosto 28, 2025","format":false,"excerpt":"La decisi\u00f3n de Uganda de aprobar la oferta del Gobierno de Trump para recibir migrantes no deseados por Estados Unidos ha generado cr\u00edticas en la naci\u00f3n del este de \u00c1frica, que ya alberga la mayor poblaci\u00f3n de refugiados del continente.\u201cTodo el esquema es p\u00e9simo\u201d sin supervisi\u00f3n parlamentaria, dijo a AP\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465945,"url":"https:\/\/noticiasya.com\/kansas\/2025\/08\/28\/abrego-garcia-deportaciones-africa-trump-analisis-orix\/","url_meta":{"origin":1473360,"position":4},"title":"El caso de \u00c1brego Garc\u00eda revela c\u00f3mo Trump convirti\u00f3 la deportaci\u00f3n en un arma pol\u00edtica","author":"","date":"agosto 28, 2025","format":false,"excerpt":"Imagina que vives en Estados Unidos. Eres inmigrante, pero llevas m\u00e1s tiempo all\u00ed que en tu pa\u00eds de origen. Te detienen, cualquiera sea el motivo. Pero tu destino no es una c\u00e1rcel estadounidense. Es otro pa\u00eds, que ni siquiera es el tuyo: alg\u00fan lugar remoto en \u00c1frica o tal vez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452695,"url":"https:\/\/noticiasya.com\/kansas\/2024\/09\/14\/atleta-ugandesa-murio-despues-pareja-prendiera-fuego-recibe-funeral-militar-ap\/","url_meta":{"origin":1473360,"position":5},"title":"Atleta ugandesa que muri\u00f3 despu\u00e9s de que su pareja la prendiera fuego recibe funeral militar","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(AP) -- Miles de personas en Uganda rindieron homenaje a Rebecca Cheptegei, la atleta ol\u00edmpica que muri\u00f3 la semana pasada en Kenia despu\u00e9s de que su pareja la prendiera fuego, en un funeral militar en un pueblo remoto cerca de la frontera con Kenia.Los oficiales militares desempe\u00f1aron un papel destacado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473360"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473360\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}